{"id":7801,"date":"2026-05-15T13:22:45","date_gmt":"2026-05-15T11:22:45","guid":{"rendered":"https:\/\/tevipa.com\/blog\/?p=7801"},"modified":"2026-05-15T13:22:47","modified_gmt":"2026-05-15T11:22:47","slug":"lencreuament-dels-davanters","status":"publish","type":"post","link":"https:\/\/tevipa.com\/blog\/ca\/lencreuament-dels-davanters\/","title":{"rendered":"L\u2019encreuament dels davanters"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png\" alt=\"Logo C\u00f3mo Cubrir un Cuerpo\" class=\"wp-image-6\" style=\"width:270px;height:auto\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png 512w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512-300x300.png 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512-150x150.png 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure>\n<\/div>\n\n\n<h1 class=\"wp-block-heading has-text-align-center\">L\u2019encreuament dels davanters<\/h1>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_01-1024x576.png\" alt=\"Diferents peces superiors amb tancaments d\u2019alamares, botons, cremalleres i doble pit.\" class=\"wp-image-7729\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_01-1024x576.png 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_01-300x169.png 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_01-768x432.png 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_01-1536x864.png 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_01-2048x1152.png 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_01-1320x743.png 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Moltes peces superiors tenen un sistema de tancament. Generalment a la part del davant. Els tipus de tancament m\u00e9s habituals s\u00f3n les alamares, els botons o les cremalleres.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_02-1024x576.png\" alt=\"Alamares, botons, gafets de pressi\u00f3 i cremallera utilitzats com a sistemes de tancament.\" class=\"wp-image-7734\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_02-1024x576.png 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_02-300x169.png 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_02-768x432.png 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_02-1536x864.png 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_02-2048x1152.png 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_02-1320x743.png 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Segons la forma de tancament de les peces superiors, podem diferenciar entre peces vora contra vora (a), peces de tancament simple (b) i peces creuades (c).<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_03-1024x576.png\" alt=\"Comparaci\u00f3 entre peces superiors amb tancament vora amb vora, tancament senzill i tancament creuat.\" class=\"wp-image-7739\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_03-1024x576.png 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_03-300x169.png 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_03-768x432.png 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_03-1536x864.png 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_03-2048x1152.png 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_03-1320x743.png 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Segons el m\u00e8tode de tancament de les peces superiors, necessitem un marge per poder mantenir la pe\u00e7a tancada.<br>El marge a la vora \u00e9s el rellarg que donem des de l\u2019eix de meitat davant fins a la vora \u00a0del davant.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_04-1024x576.png\" alt=\"Esquema del marge entre l\u2019eix de meitat davant i el cant del davant d\u2019una pe\u00e7a.\" class=\"wp-image-7744\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_04-1024x576.png 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_04-300x169.png 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_04-768x432.png 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_04-1536x864.png 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_04-2048x1152.png 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_04-1320x743.png 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Per exemple, en el cas d\u2019un tancament amb botons, necessitem un marge igual al radi del bot\u00f3, m\u00e9s un rellarg des de la vora del bot\u00f3 fins a la vora de la pe\u00e7a. A aquest rellarg l\u2019anomenem aire del bot\u00f3.<br>L\u2019aire del bot\u00f3 pot variar des de tres mil\u00b7l\u00edmetres fins a un cent\u00edmetre, segons el gruix dels teixits utilitzats. Aquest marge tamb\u00e9 pot variar segons l\u2019estil de la pe\u00e7a.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_05-1024x576.png\" alt=\"Esquema t\u00e8cnic de l\u2019aire al bot\u00f3 i del marge necessari per a un tancament amb botons.\" class=\"wp-image-7749\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_05-1024x576.png 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_05-300x169.png 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_05-768x432.png 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_05-1536x864.png 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_05-2048x1152.png 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_05-1320x743.png 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">En les peces que es tanquen amb alamares o amb cremallera, el marge a la vora no existeix.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">La vora del davant pot ser vora contra vora o b\u00e9 pot creuar-se. El creuament pot correspondre \u00fanicament al marge a la vora o b\u00e9 superar aquest marge.<br>Si el creuament de les vores del davant \u00e9s superior al marge a la vora, direm que la pe\u00e7a \u00e9s creuada.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_06-1024x576.png\" alt=\"Teknika skemo de rand-al-randa anta\u016do, simple fermita anta\u016do kaj krucita anta\u016do.\" class=\"wp-image-7754\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_06-1024x576.png 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_06-300x169.png 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_06-768x432.png 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_06-1536x864.png 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_06-2048x1152.png 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_06-1320x743.png 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">L\u2019encreuament pot ser paral\u00b7lel a l\u2019eix de meitat davant o b\u00e9 oblic.<br>Si el davanter creuat \u00e9s paral\u00b7lel, l\u2019anomenarem creuat recte o sim\u00e8tric; si \u00e9s oblic, l\u2019anomenarem creuat asim\u00e8tric.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_07-1024x576.png\" alt=\"Comparaci\u00f3 entre un davant creuat recte o sim\u00e8tric i un davant creuat oblic o asim\u00e8tric.\" class=\"wp-image-7759\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_07-1024x576.png 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_07-300x169.png 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_07-768x432.png 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_07-1536x864.png 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_07-2048x1152.png 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_07-1320x743.png 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">El davanter creuat \u2014tamb\u00e9 anomenat de doble pit\u2014 es tanca generalment amb botons.<br>En la majoria dels casos, els botons es col\u00b7loquen especulats respecte a l\u2019eix de simetria. Classificarem els botons d\u2019aquestes peces en botons reals i botons d\u2019ornament.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Els botons reals (grocs) permeten tancar la pe\u00e7a, mentre que els botons d\u2019ornament (taronges) s\u00f3n \u00fanicament decoratius.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_08-1024x576.png\" alt=\"Pe\u00e7a creuada de doble pit amb botons reals en groc i botons decoratius en taronja.\" class=\"wp-image-7764\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_08-1024x576.png 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_08-300x169.png 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_08-768x432.png 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_08-1536x864.png 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_08-2048x1152.png 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/blogCrSup_08-1320x743.png 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Algunes peces superiors creuades es tanquen amb cremallera o alamares. Un exemple: la ca\u00e7adora biker.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/004_BikerOn-1024x576.jpg\" alt=\"Ca\u00e7adora biker de cuir negre amb tancament creuat mitjan\u00e7ant cremallera asim\u00e8trica.\" class=\"wp-image-7769\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/004_BikerOn-1024x576.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/004_BikerOn-300x169.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/004_BikerOn-768x432.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/004_BikerOn-1536x864.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/004_BikerOn-2048x1152.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/004_BikerOn-1320x743.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-7801_be684e-47 .kt-block-spacer{height:60px;}.wp-block-kadence-spacer.kt-block-spacer-7801_be684e-47 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-7801_be684e-47\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"El cruce de los delanteros | Cierres, cruces y prendas cruzadas en patronaje\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/-B-8tav3cB4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Estudi t\u00e8cnic del creuament dels davanters i dels diferents sistemes de tancament utilitzats en peces superiors. Analitzem el marge al cant, l\u2019aire al bot\u00f3, els tancaments senzills, les peces creuades i les difer\u00e8ncies entre davanters sim\u00e8trics i asim\u00e8trics en patronatge t\u00e8cnic.<\/p>\n","protected":false},"author":1,"featured_media":7802,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1016,1109,1353,1634,611,778],"tags":[406,408,435,2325,2335,1654,1748,518,696,574,572,766,862,584,687],"class_list":["post-7801","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-cat","category-blog-short-ca","category-complement","category-desmuntatge","category-patro","category-transformacio","tag-como-cubrir-un-cuerpo-ca","tag-comocubriruncuerpo-ca","tag-creacio-de-moda","tag-creuament","tag-davant","tag-desmuntatge","tag-modelatge","tag-patronatgemoda","tag-tecnica-de-patronatge","tag-tele-virtual-patronage-ca","tag-televirtualpatronage-ca","tag-transformacio","tag-transformacio-de-peces","tag-transformacionsdepatro","tag-tutorial-de-patronatge"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019encreuament dels davanters - Tele Virtual Patronage<\/title>\n<meta name=\"description\" content=\"An\u00e0lisi t\u00e8cnica del creuament dels davanters en peces superiors: tancaments vora amb vora, tancaments senzills, doble pit, marge al cant i sistemes de tancament en patronatge.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tevipa.com\/blog\/ca\/lencreuament-dels-davanters\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019encreuament dels davanters - Tele Virtual Patronage\" \/>\n<meta property=\"og:description\" content=\"An\u00e0lisi t\u00e8cnica del creuament dels davanters en peces superiors: tancaments vora amb vora, tancaments senzills, doble pit, marge al cant i sistemes de tancament en patronatge.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tevipa.com\/blog\/ca\/lencreuament-dels-davanters\/\" \/>\n<meta property=\"og:site_name\" content=\"Tele Virtual Patronage\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-15T11:22:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-15T11:22:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/BTR005_CA-scaled.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Tele Virtual Patronage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tele Virtual Patronage\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/ca\\\/lencreuament-dels-davanters\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/ca\\\/lencreuament-dels-davanters\\\/\"},\"author\":{\"name\":\"Tele Virtual Patronage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\"},\"headline\":\"L\u2019encreuament dels davanters\",\"datePublished\":\"2026-05-15T11:22:45+00:00\",\"dateModified\":\"2026-05-15T11:22:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/ca\\\/lencreuament-dels-davanters\\\/\"},\"wordCount\":376,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/ca\\\/lencreuament-dels-davanters\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/BTR005_CA-scaled.png\",\"keywords\":[\"como cubrir un cuerpo\",\"comocubriruncuerpo\",\"creaci\u00f3 de moda\",\"creuament\",\"davant\",\"Desmuntatge\",\"modelatge\",\"patronatgemoda\",\"t\u00e8cnica de patronatge\",\"tele virtual patronage\",\"televirtualpatronage\",\"Transformaci\u00f3\",\"transformaci\u00f3 de peces\",\"transformacionsdepatr\u00f3\",\"tutorial de patronatge\"],\"articleSection\":[\"Blog Cat\",\"Blog Short Ca\",\"Complement\",\"Desmuntatge\",\"Patr\u00f3\",\"Transformaci\u00f3\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/ca\\\/lencreuament-dels-davanters\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/ca\\\/lencreuament-dels-davanters\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/ca\\\/lencreuament-dels-davanters\\\/\",\"name\":\"L\u2019encreuament dels davanters - Tele Virtual Patronage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/ca\\\/lencreuament-dels-davanters\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/ca\\\/lencreuament-dels-davanters\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/BTR005_CA-scaled.png\",\"datePublished\":\"2026-05-15T11:22:45+00:00\",\"dateModified\":\"2026-05-15T11:22:47+00:00\",\"description\":\"An\u00e0lisi t\u00e8cnica del creuament dels davanters en peces superiors: tancaments vora amb vora, tancaments senzills, doble pit, marge al cant i sistemes de tancament en patronatge.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/ca\\\/lencreuament-dels-davanters\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/ca\\\/lencreuament-dels-davanters\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/ca\\\/lencreuament-dels-davanters\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/BTR005_CA-scaled.png\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/BTR005_CA-scaled.png\",\"width\":2560,\"height\":1440,\"caption\":\"Portada de l\u2019article \u201cEl creuament dels davanters\u201d amb una ruleta de patronatge sobre fons negre.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/ca\\\/lencreuament-dels-davanters\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019encreuament dels davanters\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"name\":\"Tele Virtual Patronage\",\"description\":\"Tevipa\",\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\",\"name\":\"Tele Virtual Patronage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"width\":512,\"height\":512,\"caption\":\"Tele Virtual Patronage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\",\"name\":\"Tele Virtual Patronage\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"caption\":\"Tele Virtual Patronage\"},\"sameAs\":[\"https:\\\/\\\/tevipa.com\\\/blog\"],\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/author\\\/tvpadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019encreuament dels davanters - Tele Virtual Patronage","description":"An\u00e0lisi t\u00e8cnica del creuament dels davanters en peces superiors: tancaments vora amb vora, tancaments senzills, doble pit, marge al cant i sistemes de tancament en patronatge.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tevipa.com\/blog\/ca\/lencreuament-dels-davanters\/","og_locale":"it_IT","og_type":"article","og_title":"L\u2019encreuament dels davanters - Tele Virtual Patronage","og_description":"An\u00e0lisi t\u00e8cnica del creuament dels davanters en peces superiors: tancaments vora amb vora, tancaments senzills, doble pit, marge al cant i sistemes de tancament en patronatge.","og_url":"https:\/\/tevipa.com\/blog\/ca\/lencreuament-dels-davanters\/","og_site_name":"Tele Virtual Patronage","article_published_time":"2026-05-15T11:22:45+00:00","article_modified_time":"2026-05-15T11:22:47+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/BTR005_CA-scaled.png","type":"image\/png"}],"author":"Tele Virtual Patronage","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Tele Virtual Patronage","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tevipa.com\/blog\/ca\/lencreuament-dels-davanters\/#article","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/ca\/lencreuament-dels-davanters\/"},"author":{"name":"Tele Virtual Patronage","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c"},"headline":"L\u2019encreuament dels davanters","datePublished":"2026-05-15T11:22:45+00:00","dateModified":"2026-05-15T11:22:47+00:00","mainEntityOfPage":{"@id":"https:\/\/tevipa.com\/blog\/ca\/lencreuament-dels-davanters\/"},"wordCount":376,"commentCount":0,"publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"image":{"@id":"https:\/\/tevipa.com\/blog\/ca\/lencreuament-dels-davanters\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/BTR005_CA-scaled.png","keywords":["como cubrir un cuerpo","comocubriruncuerpo","creaci\u00f3 de moda","creuament","davant","Desmuntatge","modelatge","patronatgemoda","t\u00e8cnica de patronatge","tele virtual patronage","televirtualpatronage","Transformaci\u00f3","transformaci\u00f3 de peces","transformacionsdepatr\u00f3","tutorial de patronatge"],"articleSection":["Blog Cat","Blog Short Ca","Complement","Desmuntatge","Patr\u00f3","Transformaci\u00f3"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tevipa.com\/blog\/ca\/lencreuament-dels-davanters\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tevipa.com\/blog\/ca\/lencreuament-dels-davanters\/","url":"https:\/\/tevipa.com\/blog\/ca\/lencreuament-dels-davanters\/","name":"L\u2019encreuament dels davanters - Tele Virtual Patronage","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tevipa.com\/blog\/ca\/lencreuament-dels-davanters\/#primaryimage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/ca\/lencreuament-dels-davanters\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/BTR005_CA-scaled.png","datePublished":"2026-05-15T11:22:45+00:00","dateModified":"2026-05-15T11:22:47+00:00","description":"An\u00e0lisi t\u00e8cnica del creuament dels davanters en peces superiors: tancaments vora amb vora, tancaments senzills, doble pit, marge al cant i sistemes de tancament en patronatge.","breadcrumb":{"@id":"https:\/\/tevipa.com\/blog\/ca\/lencreuament-dels-davanters\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tevipa.com\/blog\/ca\/lencreuament-dels-davanters\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/ca\/lencreuament-dels-davanters\/#primaryimage","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/BTR005_CA-scaled.png","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/05\/BTR005_CA-scaled.png","width":2560,"height":1440,"caption":"Portada de l\u2019article \u201cEl creuament dels davanters\u201d amb una ruleta de patronatge sobre fons negre."},{"@type":"BreadcrumbList","@id":"https:\/\/tevipa.com\/blog\/ca\/lencreuament-dels-davanters\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tevipa.com\/blog\/"},{"@type":"ListItem","position":2,"name":"L\u2019encreuament dels davanters"}]},{"@type":"WebSite","@id":"https:\/\/tevipa.com\/blog\/#website","url":"https:\/\/tevipa.com\/blog\/","name":"Tele Virtual Patronage","description":"Tevipa","publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tevipa.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/tevipa.com\/blog\/#organization","name":"Tele Virtual Patronage","url":"https:\/\/tevipa.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","width":512,"height":512,"caption":"Tele Virtual Patronage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c","name":"Tele Virtual Patronage","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","caption":"Tele Virtual Patronage"},"sameAs":["https:\/\/tevipa.com\/blog"],"url":"https:\/\/tevipa.com\/blog\/author\/tvpadm\/"}]}},"_links":{"self":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/7801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/comments?post=7801"}],"version-history":[{"count":3,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/7801\/revisions"}],"predecessor-version":[{"id":7805,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/7801\/revisions\/7805"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media\/7802"}],"wp:attachment":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media?parent=7801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/categories?post=7801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/tags?post=7801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}