{"id":7309,"date":"2026-04-21T12:53:34","date_gmt":"2026-04-21T10:53:34","guid":{"rendered":"https:\/\/tevipa.com\/blog\/?p=7309"},"modified":"2026-04-26T17:48:18","modified_gmt":"2026-04-26T15:48:18","slug":"tracciato-del-colletto-trasformabile-in-un-solo-pezzo","status":"publish","type":"post","link":"https:\/\/tevipa.com\/blog\/it\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\/","title":{"rendered":"Tracciato del colletto trasformabile in un solo pezzo"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png\" alt=\"Logo C\u00f3mo Cubrir un Cuerpo\" class=\"wp-image-6\" style=\"width:270px;height:auto\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png 512w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512-300x300.png 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512-150x150.png 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure>\n<\/div>\n\n\n<h1 class=\"wp-block-heading has-text-align-center\">Tracciato del colletto trasformabile in un solo pezzo<\/h1>\n\n\n\n<h2 class=\"wp-block-heading text-justify has-medium-font-size\">Definizione del collo trasformabile<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z00-1024x576.jpg\" alt=\"Collo trasformabile chiuso e aperto su giubbino biker in pelle\" class=\"wp-image-7235\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z00-1024x576.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z00-300x169.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z00-768x432.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z00-1536x864.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z00-2048x1152.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z00-1320x743.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify\">Il collo trasformabile \u00e8 un collo che ha la capacit\u00e0 di comportarsi come due senza smettere di essere uno solo.<\/p>\n\n\n\n<p class=\"text-justify\">Chiuso, con i bordi del davanti appoggiati al corpo, si presenta come un collo da camicia.<br>Aperto, quando i davanti si aprono, compaiono i revers e diventa un collo sartoriale.<\/p>\n\n\n\n<p class=\"text-justify\">Il pezzo non cambia. Cambia la lettura.<\/p>\n\n\n\n<p class=\"text-justify\">Il collo trasformabile pu\u00f2 essere realizzato in una o in due pezzi.<br>In questo video analizziamo la versione in un solo pezzo. Viene usato soprattutto in tessuti estremi: molto sottili e trasparenti, per evitare che si vedano i margini di cucitura; oppure molto spessi, per evitare accumuli di spessore nella giunzione tra il piede e la vela.<\/p>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-7309_8df1f0-43 .kt-block-spacer{height:60px;}.wp-block-kadence-spacer.kt-block-spacer-7309_8df1f0-43 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-7309_8df1f0-43\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading text-justify has-medium-font-size\">Tracciato<\/h2>\n\n\n\n<p class=\"text-justify\">Misuriamo, sul modello del corpo, la lunghezza degli scolli dietro e davanti senza margini di cucitura.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z001-1024x576.jpg\" alt=\"Misurazione dello scollo davanti e dietro per calcolare il mezzo contorno collo nel cartamodello\" class=\"wp-image-7241\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z001-1024x576.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z001-300x169.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z001-768x432.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z001-1536x864.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z001-2048x1152.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z001-1320x743.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify\">Aggiungiamo un centimetro di margine.<\/p>\n\n\n\n<p class=\"text-justify\">Questa misura corrisponde al mezzo contorno del collo.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z004-1024x576.jpg\" alt=\"Tracciamento di un arco con raggio pari allo scollo dietro pi\u00f9 0,5 cm per definire il piede del collo\" class=\"wp-image-7247\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z004-1024x576.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z004-300x169.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z004-768x432.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z004-1536x864.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z004-2048x1152.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z004-1320x743.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z006b-1024x576.jpg\" alt=\"Costruzione del piede del collo e della vela con misure di 3,5 cm e 4,5 cm nel cartamodello\" class=\"wp-image-7229\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z006b-1024x576.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z006b-300x169.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z006b-768x432.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z006b-1536x864.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z006b-2048x1152.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z006b-1320x743.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify\">A partire da un punto che rappresenta la settima vertebra cervicale, riportiamo il mezzo contorno del collo, aggiungendo il centimetro di cucitura.<\/p>\n\n\n\n<p class=\"text-justify\">Da questo primo punto, corrispondente alla settima cervicale, saliamo di un centimetro.<\/p>\n\n\n\n<p class=\"text-justify\">Da questo nuovo punto, tracciamo un arco con raggio pari alla lunghezza dello scollo dietro pi\u00f9 mezzo centimetro.<\/p>\n\n\n\n<p class=\"text-justify\">Segniamo il punto di intersezione tra questo arco e la linea di costruzione del piede del collo.<\/p>\n\n\n\n<p class=\"text-justify\">A met\u00e0 dello scollo davanti, segniamo un punto mezzo centimetro sotto la linea di costruzione del piede del collo.<\/p>\n\n\n\n<p>Tracciamo la linea definitiva del piede del collo. Partiamo dal punto della settima cervicale, in parallelo alla linea di costruzione, poi arotondiamo la linea fino a raggiungere il primo punto, e uniamo gli ultimi punti con una curva convessa continua.<\/p>\n\n\n\n<p>Dal primo punto della cucitura del piede del collo, quello sopra la settima cervicale, segniamo un punto sulla perpendicolare alla linea di costruzione, all\u2019altezza desiderata del piede del collo, aggiungendo un centimetro di cucitura.<\/p>\n\n\n\n<p>Su questo punto ne posizioniamo un altro corrispondente alla vela del collo, sempre con un centimetro di cucitura.<\/p>\n\n\n\n<p>In questo esempio: il piede del collo \u00e8 di due centimetri e mezzo pi\u00f9 un centimetro di cucitura, cio\u00e8 3centimetri e mezzo totali.<\/p>\n\n\n\n<p>La vela deve superare la linea della piega di 1\u20131,5 centimetro per coprire la cucitura del piede. In questo caso, la vela \u00e8 di 3 centimetri e mezzo, pi\u00f9 1 centimetro di cucitura, per un totale di 4,5 centimetro.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z009-1024x576.jpg\" alt=\"Vela del collo di 3,5 cm pi\u00f9 1 cm di margine di cucitura nel cartamodello\" class=\"wp-image-7253\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z009-1024x576.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z009-300x169.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z009-768x432.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z009-1536x864.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z009-2048x1152.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z009-1320x743.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify\">Dal punto del piede del collo tracciamo una linea parallela alla sua cucitura.<\/p>\n\n\n\n<p class=\"text-justify\">Questa \u00e8 la linea di piegha del collo.<\/p>\n\n\n\n<p class=\"text-justify\">Tracciamo una tangente nel punto di met\u00e0 davanti, e un\u2019altra nel punto di punta dello scollo sulla cucitura del piede del collo.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z010-1024x576.jpg\" alt=\"Tracciamento della normale perpendicolare alla tangente per definire la larghezza del collo nel cartamodello\" class=\"wp-image-7260\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z010-1024x576.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z010-300x169.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z010-768x432.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z010-1536x864.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z010-2048x1152.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z010-1320x743.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify\">Nel punto di punta dello scollo, tracciamo la normale, cio\u00e8 la perpendicolare alla tangente.<\/p>\n\n\n\n<p class=\"text-justify\">Su questa linea riportiamo la larghezza del collo, misurata dal centro dietro.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z011-1024x576.jpg\" alt=\"Tracciamento di una linea parallela alla linea di rottura del collo dal centro dietro fino al punto di larghezza\" class=\"wp-image-7267\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z011-1024x576.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z011-300x169.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z011-768x432.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z011-1536x864.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z011-2048x1152.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z011-1320x743.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify\">Dal punto superiore del centro dietro, tracciamo una linea parallela alla linea di piegha,<br>fino al punto precedentemente individuato.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z015-1024x576.jpg\" alt=\"Tracciamento della linea della vela dietro a 1 cm dal piede del collo con varianti di forma sul davanti\" class=\"wp-image-7272\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z015-1024x576.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z015-300x169.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z015-768x432.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z015-1536x864.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z015-2048x1152.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z015-1320x743.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify\">Tracciamo una linea a un centimetro sotto la linea del piede del collo. Questa \u00e8 la linea di cucitura della vela. Ci fermiamo in corrispondenza della punta dello scollo dietro. Sul davanti, possiamo disegnare la forma del collo desiderata. Nell\u2019esempio sono mostrate quattro varianti.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z016-1024x576.jpg\" alt=\"Uso della tangente come asse di simmetria per sviluppare la vela del collo nel cartamodello\" class=\"wp-image-7279\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z016-1024x576.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z016-300x169.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z016-768x432.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z016-1536x864.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z016-2048x1152.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z016-1320x743.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify\">La tangente al punto di met\u00e0 davanti, funge da asse di simmetria, per ribaltare la forma della vela. Una volta ribaltata, la uniamo all\u2019ultimo punto della vela.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z017-1024x576.jpg\" alt=\"Cartamodello finale del collo trasformabile in un pezzo senza linee di costruzione\" class=\"wp-image-7285\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z017-1024x576.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z017-300x169.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z017-768x432.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z017-1536x864.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z017-2048x1152.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z017-1320x743.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify\">Eliminiamo tutte le linee di costruzione.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z021-1024x576.jpg\" alt=\"Impuntura prima della linea di rottura per ridurre lo spessore nei materiali spessi\" class=\"wp-image-7291\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z021-1024x576.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z021-300x169.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z021-768x432.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z021-1536x864.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z021-2048x1152.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z021-1320x743.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify\">In molti capi, soprattutto quelli realizzati con materiali piuttosto spessi, per evitare spessore si evita il collo a due pezzi.<br>In questi casi si esegue un\u2019impuntura prima della linea di rottura affinch\u00e9 resti nascosta e non sia visibile dall\u2019esterno.<\/p>\n\n\n\n<p class=\"text-justify\">Finora abbiamo sviluppato il sotto-collo; il sopra-collo si taglia generalmente pi\u00f9 largo, affinch\u00e9 abbia lo sviluppo necessario, non tiri quando si gira e nasconda le cuciture all\u2019interno del sotto-collo.<br>Si d\u00e0 generalmente una lentezza su tutta la vela del collo e sulla parte anteriore, che varia in funzione dello spessore e della rigidit\u00e0 del tessuto o del materiale con cui si realizza il collo.<br>Nella cucitura del piede del collo si applica una seconda lentezza.<br>Valori orientativi, per un tessuto convenzionale, possono essere di mezzo centimetro sulla vela e sulla parte anteriore, e di tre millimetri sul piede del collo.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z022-1024x576.jpg\" alt=\"Indicazione delle linee di cucitura e dei margini nel collo trasformabile in un pezzo\" class=\"wp-image-7297\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z022-1024x576.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z022-300x169.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z022-768x432.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z022-1536x864.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z022-2048x1152.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z022-1320x743.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-7309_59fdaf-e6 .kt-block-spacer{height:60px;}.wp-block-kadence-spacer.kt-block-spacer-7309_59fdaf-e6 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-7309_59fdaf-e6\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading text-justify has-medium-font-size\">Margini di cucitura e diritto filo dei colli<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z090-1024x576.jpg\" alt=\"Collo trasformabile con taglio in sbieco, a piega e diritto filo sul centro dietro\" class=\"wp-image-7303\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z090-1024x576.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z090-300x169.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z090-768x432.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z090-1536x864.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z090-2048x1152.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/z090-1320x743.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify\">Presentiamo colli senza cucitura al centro dietro.<br>Molti tagliano il sotto-collo in sbieco, con cucitura al centro dietro, e il sopra-collo in dritto filo su piega.<br>Nel caso in cui si tagli con cucitura al centro dietro, si dovr\u00e0 aggiungere il margine di cucitura; nel nostro caso, 1 centimetro.<br>Se il sotto-collo si taglia su piega, si posizioner\u00e0 il diritto filo sulla linea del centro dietro.<\/p>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-7309_74a962-16 .kt-block-spacer{height:60px;}.wp-block-kadence-spacer.kt-block-spacer-7309_74a962-16 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-7309_74a962-16\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Trazado del cuello transformable de una pieza | Patronaje paso a paso\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/tdkTEEcP9UA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Il collo trasformabile in un pezzo \u00e8 una soluzione tecnica capace di comportarsi come due pur restando una sola struttura. Chiuso si legge come un collo camicia; aperto genera revers e funziona come un collo sartoriale.<\/p>\n<p>In questo articolo viene sviluppato il tracciato completo passo dopo passo: dalla misura dello scollo e costruzione del piede del collo, fino alla definizione della linea di rottura e allo sviluppo della vela. Si analizzano inoltre i casi in cui questo tipo di collo \u00e8 particolarmente utile, sia nei tessuti molto fini che nei materiali pi\u00f9 spessi.<\/p>\n","protected":false},"author":1,"featured_media":7204,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1008,603,2226,1626],"tags":[263,247,1427,2216,62,70,143,2155,183,461,255,511,167,690,46,54,678],"class_list":["post-7309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-it","category-cartamodello","category-collo","category-scomposizione","tag-cartamodelli","tag-cartamodello","tag-collo","tag-collo-trasformabile","tag-como-cubrir-un-cuerpo-it","tag-comocubriruncuerpo-it","tag-creazione-di-moda","tag-giubbino","tag-gradazione","tag-lentezzatecnica","tag-modellistica","tag-modellisticadimoda","tag-scuola-di-moda","tag-tecnica-di-modellistica","tag-tele-virtual-patronage-it","tag-televirtualpatronage-it","tag-tutorial-di-modellistica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tracciato del colletto trasformabile in un solo pezzo - Tele Virtual Patronage<\/title>\n<meta name=\"description\" content=\"Come tracciare un collo trasformabile in un pezzo passo dopo passo. Impara a costruire il piede del collo, la linea di rottura e la vela.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tevipa.com\/blog\/it\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tracciato del colletto trasformabile in un solo pezzo - Tele Virtual Patronage\" \/>\n<meta property=\"og:description\" content=\"Come tracciare un collo trasformabile in un pezzo passo dopo passo. Impara a costruire il piede del collo, la linea di rottura e la vela.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tevipa.com\/blog\/it\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\/\" \/>\n<meta property=\"og:site_name\" content=\"Tele Virtual Patronage\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-21T10:53:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-26T15:48:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/BPA014_IT-scaled.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Tele Virtual Patronage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tele Virtual Patronage\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\\\/\"},\"author\":{\"name\":\"Tele Virtual Patronage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\"},\"headline\":\"Tracciato del colletto trasformabile in un solo pezzo\",\"datePublished\":\"2026-04-21T10:53:34+00:00\",\"dateModified\":\"2026-04-26T15:48:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\\\/\"},\"wordCount\":786,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/BPA014_IT-scaled.png\",\"keywords\":[\"cartamodelli\",\"cartamodello\",\"collo\",\"collo trasformabile\",\"como cubrir un cuerpo\",\"comocubriruncuerpo\",\"creazione di moda\",\"giubbino\",\"gradazione\",\"lentezzatecnica\",\"modellistica\",\"modellisticadimoda\",\"scuola di moda\",\"tecnica di modellistica\",\"tele virtual patronage\",\"televirtualpatronage\",\"tutorial di modellistica\"],\"articleSection\":[\"Blog It\",\"Cartamodello\",\"collo\",\"Scomposizione\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\\\/\",\"name\":\"Tracciato del colletto trasformabile in un solo pezzo - Tele Virtual Patronage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/BPA014_IT-scaled.png\",\"datePublished\":\"2026-04-21T10:53:34+00:00\",\"dateModified\":\"2026-04-26T15:48:18+00:00\",\"description\":\"Come tracciare un collo trasformabile in un pezzo passo dopo passo. Impara a costruire il piede del collo, la linea di rottura e la vela.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/BPA014_IT-scaled.png\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/BPA014_IT-scaled.png\",\"width\":2560,\"height\":1440,\"caption\":\"Immagine di copertina del tracciato del collo trasformabile in un pezzo nel cartamodello\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tracciato del colletto trasformabile in un solo pezzo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"name\":\"Tele Virtual Patronage\",\"description\":\"Tevipa\",\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\",\"name\":\"Tele Virtual Patronage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"width\":512,\"height\":512,\"caption\":\"Tele Virtual Patronage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\",\"name\":\"Tele Virtual Patronage\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"caption\":\"Tele Virtual Patronage\"},\"sameAs\":[\"https:\\\/\\\/tevipa.com\\\/blog\"],\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/author\\\/tvpadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tracciato del colletto trasformabile in un solo pezzo - Tele Virtual Patronage","description":"Come tracciare un collo trasformabile in un pezzo passo dopo passo. Impara a costruire il piede del collo, la linea di rottura e la vela.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tevipa.com\/blog\/it\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\/","og_locale":"it_IT","og_type":"article","og_title":"Tracciato del colletto trasformabile in un solo pezzo - Tele Virtual Patronage","og_description":"Come tracciare un collo trasformabile in un pezzo passo dopo passo. Impara a costruire il piede del collo, la linea di rottura e la vela.","og_url":"https:\/\/tevipa.com\/blog\/it\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\/","og_site_name":"Tele Virtual Patronage","article_published_time":"2026-04-21T10:53:34+00:00","article_modified_time":"2026-04-26T15:48:18+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/BPA014_IT-scaled.png","type":"image\/png"}],"author":"Tele Virtual Patronage","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Tele Virtual Patronage","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tevipa.com\/blog\/it\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\/#article","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/it\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\/"},"author":{"name":"Tele Virtual Patronage","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c"},"headline":"Tracciato del colletto trasformabile in un solo pezzo","datePublished":"2026-04-21T10:53:34+00:00","dateModified":"2026-04-26T15:48:18+00:00","mainEntityOfPage":{"@id":"https:\/\/tevipa.com\/blog\/it\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\/"},"wordCount":786,"commentCount":0,"publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"image":{"@id":"https:\/\/tevipa.com\/blog\/it\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/BPA014_IT-scaled.png","keywords":["cartamodelli","cartamodello","collo","collo trasformabile","como cubrir un cuerpo","comocubriruncuerpo","creazione di moda","giubbino","gradazione","lentezzatecnica","modellistica","modellisticadimoda","scuola di moda","tecnica di modellistica","tele virtual patronage","televirtualpatronage","tutorial di modellistica"],"articleSection":["Blog It","Cartamodello","collo","Scomposizione"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tevipa.com\/blog\/it\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tevipa.com\/blog\/it\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\/","url":"https:\/\/tevipa.com\/blog\/it\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\/","name":"Tracciato del colletto trasformabile in un solo pezzo - Tele Virtual Patronage","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tevipa.com\/blog\/it\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\/#primaryimage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/it\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/BPA014_IT-scaled.png","datePublished":"2026-04-21T10:53:34+00:00","dateModified":"2026-04-26T15:48:18+00:00","description":"Come tracciare un collo trasformabile in un pezzo passo dopo passo. Impara a costruire il piede del collo, la linea di rottura e la vela.","breadcrumb":{"@id":"https:\/\/tevipa.com\/blog\/it\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tevipa.com\/blog\/it\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/it\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\/#primaryimage","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/BPA014_IT-scaled.png","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/04\/BPA014_IT-scaled.png","width":2560,"height":1440,"caption":"Immagine di copertina del tracciato del collo trasformabile in un pezzo nel cartamodello"},{"@type":"BreadcrumbList","@id":"https:\/\/tevipa.com\/blog\/it\/tracciato-del-colletto-trasformabile-in-un-solo-pezzo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tevipa.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Tracciato del colletto trasformabile in un solo pezzo"}]},{"@type":"WebSite","@id":"https:\/\/tevipa.com\/blog\/#website","url":"https:\/\/tevipa.com\/blog\/","name":"Tele Virtual Patronage","description":"Tevipa","publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tevipa.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/tevipa.com\/blog\/#organization","name":"Tele Virtual Patronage","url":"https:\/\/tevipa.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","width":512,"height":512,"caption":"Tele Virtual Patronage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c","name":"Tele Virtual Patronage","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","caption":"Tele Virtual Patronage"},"sameAs":["https:\/\/tevipa.com\/blog"],"url":"https:\/\/tevipa.com\/blog\/author\/tvpadm\/"}]}},"_links":{"self":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/7309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/comments?post=7309"}],"version-history":[{"count":7,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/7309\/revisions"}],"predecessor-version":[{"id":7404,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/7309\/revisions\/7404"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media\/7204"}],"wp:attachment":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media?parent=7309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/categories?post=7309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/tags?post=7309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}