{"id":611,"date":"2025-08-01T18:47:42","date_gmt":"2025-08-01T16:47:42","guid":{"rendered":"https:\/\/tevipa.com\/blog\/?p=611"},"modified":"2025-09-29T18:59:41","modified_gmt":"2025-09-29T16:59:41","slug":"mesures-1-mesures-verticales-principales-du-patron-de-base","status":"publish","type":"post","link":"https:\/\/tevipa.com\/blog\/fr\/mesures-1-mesures-verticales-principales-du-patron-de-base\/","title":{"rendered":"Mesures 1 &#8211; Mesures verticales principales du patron de base"},"content":{"rendered":"\n<p class=\"has-text-align-right has-small-font-size wp-block-paragraph\"><sup><em>Publicato originariamente il&nbsp;<strong>10 Marzo 2013<\/strong><\/em><\/sup><\/p>\n\n\n<style>.kb-image611_5b231f-6d .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image611_5b231f-6d is-style-default\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"222\" height=\"300\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg\" alt=\"Logo C\u00f3mo Cubrir un Cuerpo\" class=\"kb-img wp-image-68\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg 222w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-757x1024.jpg 757w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-768x1039.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1135x1536.jpg 1135w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1514x2048.jpg 1514w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran.jpg 1821w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/><\/figure><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\" style=\"font-size:27px\"><strong>Mesures 1<\/strong><br><strong>Mesures verticales principales du patron de base<\/strong><\/h1>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/08\/medidas01_medidasHor_fr-1024x576.png\" alt=\"Illustration avec mesures verticales du corps masculin et lignes directrices principales pour construire un patron de base.\" class=\"wp-image-827\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/08\/medidas01_medidasHor_fr-1024x576.png 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/08\/medidas01_medidasHor_fr-300x169.png 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/08\/medidas01_medidasHor_fr-768x432.png 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/08\/medidas01_medidasHor_fr-1536x864.png 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/08\/medidas01_medidasHor_fr-2048x1152.png 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading text-justify\" style=\"font-size:16px\"><strong><strong>Introduction<\/strong><\/strong><\/h2>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Pour d\u00e9buter toute cr\u00e9ation dans le monde de la mode, <strong>les mensurations corporelles<\/strong> sont indispensables. Dans cet article, nous expliquons les <strong>mesures verticales principales<\/strong> du corps humain. Par ailleurs, dans des posts ult\u00e9rieurs, nous aborderons les mesures horizontales, le drop, les conformations, et comment analyser et adapter les tableaux de mesures \u00e0 des besoins sp\u00e9cifiques.<\/p>\n\n\n\n<h2 class=\"wp-block-heading text-justify\" style=\"font-size:16px\"><strong><strong>Mesures verticales vs horizontales<\/strong><\/strong><\/h2>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Nous faisons la distinction entre mesures verticales \u2014 mesur\u00e9es perpendiculairement au sol \u2014 et horizontales. Aujourd\u2019hui, notre focus porte sur les mesures verticales principales ; les mesures des bras, la taille corporelle totale ou autres mesures secondaires seront trait\u00e9es plus tard.<\/p>\n\n\n\n<h2 class=\"wp-block-heading text-justify\" style=\"font-size:16px\"><strong><strong>Point de d\u00e9part : la septi\u00e8me vert\u00e8bre cervicale<\/strong><\/strong><\/h2>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">\u00c0 partir de quel point mesurer ? Quel est le point le plus \u00e9loign\u00e9 du sol su patron? Plusieurs m\u00e9thodes utilisent la couture d\u2019\u00e9paule ou le col de chemise comme r\u00e9f\u00e9rence. Pourtant, il est essentiel de rep\u00e9rer un point pr\u00e9cis. Le point le plus haut du patron correspond \u00e0 la septi\u00e8me vert\u00e8bre cervicale (vert\u00e8bre pro\u00e9minente).<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">La colonne vert\u00e9brale est trac\u00e9e comme une ligne droite \u2014 appel\u00e9e <strong>ligne du milieu du dos<\/strong> \u2014 sur laquelle on place les mesures verticales principales.<\/p>\n\n\n\n<h2 class=\"wp-block-heading text-justify\" style=\"font-size:16px\"><strong>1. <strong>Montant du dos<\/strong><\/strong><\/h2>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Cette mesure g\u00e9n\u00e8re la ligne d\u2019emmanchure. Bien qu\u2019importante dans la construction du patron masculin et f\u00e9minin, elle peut \u00eatre inf\u00e9r\u00e9e proportionnellement et n\u2019appara\u00eet pas toujours dans les tableaux standards. On passe le m\u00e8tre ruban sous les aisselles, avec les bras d\u00e9tendus et le ruban parall\u00e8le au sol. Le point d\u2019intersection avec la colonne d\u00e9signe la profondeur, mesur\u00e9e jusqu\u2019\u00e0 la septi\u00e8me vert\u00e8bre.<\/p>\n\n\n\n<h2 class=\"wp-block-heading text-justify\" style=\"font-size:16px\"><strong>2. <strong>Longueur de taille dos<\/strong><\/strong><\/h2>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Cette mesure d\u00e9finit la ligne de taille. On place le m\u00e8tre \u00e0 l\u2019endroit le plus \u00e9troit de la taille, puis on mesure jusqu\u2019\u00e0 la septi\u00e8me vert\u00e8bre cervicale en suivant la colonne. Notez que cette ligne de taille n\u2019est g\u00e9n\u00e9ralement pas parall\u00e8\u00adle au sol ; elle varie selon la prise (devant, derri\u00e8re ou c\u00f4t\u00e9).<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\" style=\"font-size:16px\"><strong>3. <strong>Montant du pantalon<\/strong><\/strong><\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\" style=\"font-size:16px\">On calcule cette mesure en soustrayant la d\u2019entrejambe \u00e0 la longueur de la jambe dos. La mesure d\u2019entrejambe part du sol, monte perpendiculairement jusqu\u2019\u00e0 l\u2019entrejambe sur le p\u00e9rin\u00e9e. Une alternative consiste \u00e0 mesurer assis, du niveau de la taille jusqu\u2019\u00e0 l\u2019assise, bien que cette m\u00e9thode soit moins pr\u00e9cise (+ 1\u20112\u202fcm).<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\" style=\"font-size:16px\"><strong>4. <strong>Hauteur genou<\/strong><\/strong><\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Celle-ci se mesure depuis la ligne de taille dos (intersection avec la colonne \u2013quatri\u00e8me vert\u00e8bre lombaire-) jusqu\u2019au niveau du genou (fosse poplit\u00e9e), le ruban toujours perpendiculaire au sol. C\u2019est essentiel pour le patron du pantalon.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\" style=\"font-size:16px\"><strong>5. <strong>Longueur totale de la jambe arri\u00e8re<\/strong><\/strong><\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Enfin, elle se mesure depuis la ligne de taille dos (intersection avec la colonne \u2013quatri\u00e8me vert\u00e8bre lombaire-) jusqu\u2019au sol, suivant la direction de la colonne vert\u00e9brale, le ruban toujours perpendiculaire au sol.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Publicato originariamente il&nbsp;10 Marzo 2013 Mesures 1Mesures verticales principales du patron de base Introduction Pour d\u00e9buter toute cr\u00e9ation dans le monde de la mode, les mensurations corporelles sont indispensables. Dans cet article, nous expliquons les mesures verticales principales du corps&#8230;<\/p>\n","protected":false},"author":1,"featured_media":827,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1022,11],"tags":[],"class_list":["post-611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archives","category-mesures"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mesures 1 - Mesures verticales principales du patron de base - Tele Virtual Patronage<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez les principales mesures verticales du patron de base : longueur du dos, entrejambe, jambe, genou et plus. Une ressource essentielle pour les mod\u00e9listes et amateurs de couture artisanale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tevipa.com\/blog\/fr\/mesures-1-mesures-verticales-principales-du-patron-de-base\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mesures 1 - Mesures verticales principales du patron de base - Tele Virtual Patronage\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez les principales mesures verticales du patron de base : longueur du dos, entrejambe, jambe, genou et plus. Une ressource essentielle pour les mod\u00e9listes et amateurs de couture artisanale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tevipa.com\/blog\/fr\/mesures-1-mesures-verticales-principales-du-patron-de-base\/\" \/>\n<meta property=\"og:site_name\" content=\"Tele Virtual Patronage\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-01T16:47:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-29T16:59:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/08\/medidas01_medidasHor_fr-scaled.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Tele Virtual Patronage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tele Virtual Patronage\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/fr\\\/mesures-1-mesures-verticales-principales-du-patron-de-base\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/fr\\\/mesures-1-mesures-verticales-principales-du-patron-de-base\\\/\"},\"author\":{\"name\":\"Tele Virtual Patronage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\"},\"headline\":\"Mesures 1 &#8211; Mesures verticales principales du patron de base\",\"datePublished\":\"2025-08-01T16:47:42+00:00\",\"dateModified\":\"2025-09-29T16:59:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/fr\\\/mesures-1-mesures-verticales-principales-du-patron-de-base\\\/\"},\"wordCount\":514,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/fr\\\/mesures-1-mesures-verticales-principales-du-patron-de-base\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/medidas01_medidasHor_fr-scaled.png\",\"articleSection\":[\"Archives\",\"Mesures\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/fr\\\/mesures-1-mesures-verticales-principales-du-patron-de-base\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/fr\\\/mesures-1-mesures-verticales-principales-du-patron-de-base\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/fr\\\/mesures-1-mesures-verticales-principales-du-patron-de-base\\\/\",\"name\":\"Mesures 1 - Mesures verticales principales du patron de base - Tele Virtual Patronage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/fr\\\/mesures-1-mesures-verticales-principales-du-patron-de-base\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/fr\\\/mesures-1-mesures-verticales-principales-du-patron-de-base\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/medidas01_medidasHor_fr-scaled.png\",\"datePublished\":\"2025-08-01T16:47:42+00:00\",\"dateModified\":\"2025-09-29T16:59:41+00:00\",\"description\":\"D\u00e9couvrez les principales mesures verticales du patron de base : longueur du dos, entrejambe, jambe, genou et plus. Une ressource essentielle pour les mod\u00e9listes et amateurs de couture artisanale.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/fr\\\/mesures-1-mesures-verticales-principales-du-patron-de-base\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/fr\\\/mesures-1-mesures-verticales-principales-du-patron-de-base\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/fr\\\/mesures-1-mesures-verticales-principales-du-patron-de-base\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/medidas01_medidasHor_fr-scaled.png\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/medidas01_medidasHor_fr-scaled.png\",\"width\":2560,\"height\":1440,\"caption\":\"Illustration avec mesures verticales du corps masculin et lignes directrices principales pour construire un patron de base.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/fr\\\/mesures-1-mesures-verticales-principales-du-patron-de-base\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mesures 1 &#8211; Mesures verticales principales du patron de base\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"name\":\"Tele Virtual Patronage\",\"description\":\"Tevipa\",\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\",\"name\":\"Tele Virtual Patronage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"width\":512,\"height\":512,\"caption\":\"Tele Virtual Patronage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\",\"name\":\"Tele Virtual Patronage\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"caption\":\"Tele Virtual Patronage\"},\"sameAs\":[\"https:\\\/\\\/tevipa.com\\\/blog\"],\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/author\\\/tvpadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mesures 1 - Mesures verticales principales du patron de base - Tele Virtual Patronage","description":"D\u00e9couvrez les principales mesures verticales du patron de base : longueur du dos, entrejambe, jambe, genou et plus. Une ressource essentielle pour les mod\u00e9listes et amateurs de couture artisanale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tevipa.com\/blog\/fr\/mesures-1-mesures-verticales-principales-du-patron-de-base\/","og_locale":"it_IT","og_type":"article","og_title":"Mesures 1 - Mesures verticales principales du patron de base - Tele Virtual Patronage","og_description":"D\u00e9couvrez les principales mesures verticales du patron de base : longueur du dos, entrejambe, jambe, genou et plus. Une ressource essentielle pour les mod\u00e9listes et amateurs de couture artisanale.","og_url":"https:\/\/tevipa.com\/blog\/fr\/mesures-1-mesures-verticales-principales-du-patron-de-base\/","og_site_name":"Tele Virtual Patronage","article_published_time":"2025-08-01T16:47:42+00:00","article_modified_time":"2025-09-29T16:59:41+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/08\/medidas01_medidasHor_fr-scaled.png","type":"image\/png"}],"author":"Tele Virtual Patronage","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Tele Virtual Patronage","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tevipa.com\/blog\/fr\/mesures-1-mesures-verticales-principales-du-patron-de-base\/#article","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/fr\/mesures-1-mesures-verticales-principales-du-patron-de-base\/"},"author":{"name":"Tele Virtual Patronage","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c"},"headline":"Mesures 1 &#8211; Mesures verticales principales du patron de base","datePublished":"2025-08-01T16:47:42+00:00","dateModified":"2025-09-29T16:59:41+00:00","mainEntityOfPage":{"@id":"https:\/\/tevipa.com\/blog\/fr\/mesures-1-mesures-verticales-principales-du-patron-de-base\/"},"wordCount":514,"commentCount":0,"publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"image":{"@id":"https:\/\/tevipa.com\/blog\/fr\/mesures-1-mesures-verticales-principales-du-patron-de-base\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/08\/medidas01_medidasHor_fr-scaled.png","articleSection":["Archives","Mesures"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tevipa.com\/blog\/fr\/mesures-1-mesures-verticales-principales-du-patron-de-base\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tevipa.com\/blog\/fr\/mesures-1-mesures-verticales-principales-du-patron-de-base\/","url":"https:\/\/tevipa.com\/blog\/fr\/mesures-1-mesures-verticales-principales-du-patron-de-base\/","name":"Mesures 1 - Mesures verticales principales du patron de base - Tele Virtual Patronage","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tevipa.com\/blog\/fr\/mesures-1-mesures-verticales-principales-du-patron-de-base\/#primaryimage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/fr\/mesures-1-mesures-verticales-principales-du-patron-de-base\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/08\/medidas01_medidasHor_fr-scaled.png","datePublished":"2025-08-01T16:47:42+00:00","dateModified":"2025-09-29T16:59:41+00:00","description":"D\u00e9couvrez les principales mesures verticales du patron de base : longueur du dos, entrejambe, jambe, genou et plus. Une ressource essentielle pour les mod\u00e9listes et amateurs de couture artisanale.","breadcrumb":{"@id":"https:\/\/tevipa.com\/blog\/fr\/mesures-1-mesures-verticales-principales-du-patron-de-base\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tevipa.com\/blog\/fr\/mesures-1-mesures-verticales-principales-du-patron-de-base\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/fr\/mesures-1-mesures-verticales-principales-du-patron-de-base\/#primaryimage","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/08\/medidas01_medidasHor_fr-scaled.png","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/08\/medidas01_medidasHor_fr-scaled.png","width":2560,"height":1440,"caption":"Illustration avec mesures verticales du corps masculin et lignes directrices principales pour construire un patron de base."},{"@type":"BreadcrumbList","@id":"https:\/\/tevipa.com\/blog\/fr\/mesures-1-mesures-verticales-principales-du-patron-de-base\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tevipa.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Mesures 1 &#8211; Mesures verticales principales du patron de base"}]},{"@type":"WebSite","@id":"https:\/\/tevipa.com\/blog\/#website","url":"https:\/\/tevipa.com\/blog\/","name":"Tele Virtual Patronage","description":"Tevipa","publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tevipa.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/tevipa.com\/blog\/#organization","name":"Tele Virtual Patronage","url":"https:\/\/tevipa.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","width":512,"height":512,"caption":"Tele Virtual Patronage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c","name":"Tele Virtual Patronage","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","caption":"Tele Virtual Patronage"},"sameAs":["https:\/\/tevipa.com\/blog"],"url":"https:\/\/tevipa.com\/blog\/author\/tvpadm\/"}]}},"_links":{"self":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/comments?post=611"}],"version-history":[{"count":5,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/611\/revisions"}],"predecessor-version":[{"id":834,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/611\/revisions\/834"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media\/827"}],"wp:attachment":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media?parent=611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/categories?post=611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/tags?post=611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}