{"id":6064,"date":"2026-02-23T18:48:31","date_gmt":"2026-02-23T17:48:31","guid":{"rendered":"https:\/\/tevipa.com\/blog\/?p=6064"},"modified":"2026-02-23T18:54:05","modified_gmt":"2026-02-23T17:54:05","slug":"el-frac-femenino","status":"publish","type":"post","link":"https:\/\/tevipa.com\/blog\/el-frac-femenino\/","title":{"rendered":"El Frac femenino"},"content":{"rendered":"\n<p class=\"has-text-align-right has-small-font-size wp-block-paragraph\"><sup><em>Publicado originalmente el&nbsp;<strong>18 Abril 2014<\/strong><\/em><\/sup><\/p>\n\n\n<style>.kb-image6064_fe14c0-54 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image6064_fe14c0-54 is-style-default\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"222\" height=\"300\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg\" alt=\"Logo C\u00f3mo Cubrir un Cuerpo\" class=\"kb-img wp-image-68\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg 222w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-757x1024.jpg 757w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-768x1039.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1135x1536.jpg 1135w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1514x2048.jpg 1514w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran.jpg 1821w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/><\/figure><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\" style=\"font-size:27px\">El Frac femenino<\/h1>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">En este post explicaremos como patronar un frac femenino a partir del fald\u00f3n base del cuerpo sastre femenino, para ello nos remitimos a dos post anteriores: \u201c<a href=\"https:\/\/tevipa.com\/blog\/faldones-del-cuerpo-sastre-femenino\/\" type=\"link\" id=\"https:\/\/tevipa.com\/blog\/faldones-del-cuerpo-sastre-femenino\/\">Faldones del cuerpo femenino<\/a>\u201d y \u201c<a href=\"https:\/\/tevipa.com\/blog\/el-spencer-femenino\/\" type=\"link\" id=\"https:\/\/tevipa.com\/blog\/el-spencer-femenino\/\">El Spencer femenino<\/a>\u201d.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Es interesante si no hab\u00e9is le\u00eddo estos post que los le\u00e1is y los teng\u00e1is presentes ya que haremos referencia a ellos, incluso saltaremos algunos pasos remiti\u00e9ndonos al contenido de \u00e9stos para no alargar los post y sobretodo no hacerlos reiterativos.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">En este post partir\u00e1 de la \u00faltima imagen del post: \u201cFaldones del cuerpo femenino\u00bb.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"842\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140417_-El-Frac-femenino_01.gif\" alt=\"Patr\u00f3n base del fald\u00f3n del cuerpo sastre femenino utilizado como punto de partida para el frac femenino\" class=\"wp-image-6071\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Patronaremos unas solapas chal tal y como mostramos en el post del \u201cSpencer femenino\u201d y cortaremos su respectivo cuello para el cuerpo base que tenemos.&nbsp;Nos remitimos a los pasos que dimos en el post del Spencer femenino.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Coloraremos el primer y \u00fanico bot\u00f3n sobre la l\u00ednea de cintura.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Patronaremos las dos piezas del bajo del delantero (pieza de mitad delante y pieza de entalle del delantero) como si fuera un Spencer: el frac es un Spencer con unos faldones que salen de la costura de avance del costadillo.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Nos remetimos al post para hacer esta primera transformaci\u00f3n, una vez acabada las piezas de partida ser\u00e1n:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"842\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140417_-El-Frac-femenino_02.gif\" alt=\"Modificaci\u00f3n de las piezas del delantero al estilo Spencer como base para el frac femenino\" class=\"wp-image-6072\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Retocaremos la forma del costadillo para que al final de dicha pieza el bajo entregue a la l\u00ednea de cintura. Hemos evidenciado en nuestro trazado el nuevo bajo con una l\u00ednea de color rojo continua.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Cortaremos el fald\u00f3n por el centro del entalle del avance de costadillo, l\u00ednea que hemos evidenciado con un trazo de color azul continuo.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"842\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140417_-El-Frac-femenino_03.gif\" alt=\"Modificaci\u00f3n del bajo del costadillo y corte del fald\u00f3n por el centro del entalle del avance de costadillo\" class=\"wp-image-6073\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Posicionaremos el costadillo encima del fald\u00f3n haciendo que coincidan las l\u00edneas de cintura, para recortar la parte que ahora tiene en exceso el fald\u00f3n de la prenda.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"842\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140417_-El-Frac-femenino_04.gif\" alt=\"Colocaci\u00f3n del costadillo sobre el fald\u00f3n alineando la cintura para eliminar el exceso de tejido\" class=\"wp-image-6074\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Calcaremos la punta del costadillo encima del fad\u00f3n y recortaremos el exceso.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"842\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140417_-El-Frac-femenino_05.gif\" alt=\"Calco de la punta del costadillo sobre el fald\u00f3n para eliminar el exceso de patr\u00f3n\" class=\"wp-image-6075\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Regularemos la entrega en la costura de avance de costadillo de la pieza del costadillo si hubiera diferencia.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"842\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140417_-El-Frac-femenino_06.gif\" alt=\"Ajuste de la entrega en la costura de avance de costadillo para equilibrar el fald\u00f3n del frac femenino\" class=\"wp-image-6076\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Calcularemos sobre la l\u00ednea de cadera, a partir de la l\u00ednea de mitad detr\u00e1s, la mitad del valor de cadera m\u00e1s un octavo de pecho: (K\/2+P\/8).<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Prolongaremos el centro del entalle de la pinza de la costura de omoplato hasta el bajo, l\u00ednea azul continua. Desde su intersecci\u00f3n con el bajo daremos P\/16 hacia la costura de mitad detr\u00e1s, este punto nos dar\u00e1 el vuelo de la costura de la parte anterior del fald\u00f3n. Uniremos este punto con su respectiva costura (l\u00ednea verde)<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"842\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140417_-El-Frac-femenino_07.gif\" alt=\"Prolongaci\u00f3n de la pinza de omoplato hasta el bajo y determinaci\u00f3n del vuelo mediante P\/16 en el frac femenino\" class=\"wp-image-6077\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">A partir de este \u00faltimo punto fijaremos un cuarto de pecho en la l\u00ednea del bajo hacia la mitad delante (P\/4).<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Uniremos este punto con el que hab\u00edamos fijado en la l\u00ednea de cadera y en la parte superior izquierda del trazado del fald\u00f3n: l\u00ednea de cintura, intersecci\u00f3n con la costura de avance de costadillo. Hemos evidenciado esta l\u00ednea con un trazado discontinuo de color rojo.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Trazaremos el borde anterior del fald\u00f3n abombando de 1 cm aproximadamente en el primer tercio del recorrido del descenso aproximadamente y qued\u00e1ndose unos 4 cm m\u00e1s adentro de la intersecci\u00f3n de esta l\u00ednea discontinua en su intersecci\u00f3n con la l\u00ednea del bajo. En la ilustraci\u00f3n siguiente lo hemos evidenciado con una l\u00ednea continua de color azul.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"842\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140417_-El-Frac-femenino_08.gif\" alt=\"Curvatura del borde anterior del fald\u00f3n del frac femenino con abombado de 1 cm y retranqueo de 4 cm en el bajo\" class=\"wp-image-6078\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Borrando las l\u00edneas de construcci\u00f3n y separando las piezas del fald\u00f3n obtendremos:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"842\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140417_-El-Frac-femenino_09.gif\" alt=\"Piezas del fald\u00f3n del frac femenino separadas tras eliminar las l\u00edneas de construcci\u00f3n\" class=\"wp-image-6079\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Por \u00faltimo juntaremos la pieza de la espalda de la cola de garza en la cinturilla de la pieza de mitad de espalda.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"842\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140417_-El-Frac-femenino_10.gif\" alt=\"Uni\u00f3n de la pieza de la cola de garza a la cinturilla de mitad de espalda en el patr\u00f3n del frac femenino\" class=\"wp-image-6080\"\/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Desarrollamos el patronaje completo del frac femenino partiendo del fald\u00f3n base del cuerpo sastre femenino. A trav\u00e9s de la transformaci\u00f3n del delantero tipo Spencer, la modificaci\u00f3n del costadillo y el c\u00e1lculo preciso del vuelo posterior, construimos la cola de garza caracter\u00edstica del frac. El proceso integra referencias a los posts anteriores sobre faldones y Spencer femenino, consolidando una evoluci\u00f3n t\u00e9cnica coherente dentro del patronaje sastre femenino.<\/p>\n","protected":false},"author":1,"featured_media":6080,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1018,23,768],"tags":[44,30,38,674,90,1997,2033,1043,104,80,362,82,1169,2009,672,40,42,756,752,396,402,676],"class_list":["post-6064","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo","category-patron","category-transformacion","tag-como-cubrir-un-cuerpo","tag-comocubriruncuerpo","tag-creacion-de-moda","tag-ensenanza-de-patronaje","tag-escuela-de-moda","tag-faldones-del-cuerpo","tag-frac","tag-moda-femenina","tag-patron","tag-patronaje","tag-patronajemoda","tag-patrones","tag-pinzas","tag-pliegue","tag-tecnica-de-patronaje","tag-tele-virtual-patronage","tag-televirtualpatronage","tag-transformacion","tag-transformacion-de-prendas","tag-transformacionesdepatron","tag-transformacionesdepatron-2","tag-tutorial-patonaje"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Frac femenino - Tele Virtual Patronage<\/title>\n<meta name=\"description\" content=\"Aprende a patronar un frac femenino a partir del fald\u00f3n base del cuerpo sastre femenino. Desarrollo t\u00e9cnico completo con solapas chal, transformaci\u00f3n tipo Spencer y construcci\u00f3n de la cola de garza paso a paso.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tevipa.com\/blog\/el-frac-femenino\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Frac femenino - Tele Virtual Patronage\" \/>\n<meta property=\"og:description\" content=\"Aprende a patronar un frac femenino a partir del fald\u00f3n base del cuerpo sastre femenino. Desarrollo t\u00e9cnico completo con solapas chal, transformaci\u00f3n tipo Spencer y construcci\u00f3n de la cola de garza paso a paso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tevipa.com\/blog\/el-frac-femenino\/\" \/>\n<meta property=\"og:site_name\" content=\"Tele Virtual Patronage\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-23T17:48:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-23T17:54:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140417_-El-Frac-femenino_10.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"595\" \/>\n\t<meta property=\"og:image:height\" content=\"842\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"Tele Virtual Patronage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tele Virtual Patronage\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-frac-femenino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-frac-femenino\\\/\"},\"author\":{\"name\":\"Tele Virtual Patronage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\"},\"headline\":\"El Frac femenino\",\"datePublished\":\"2026-02-23T17:48:31+00:00\",\"dateModified\":\"2026-02-23T17:54:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-frac-femenino\\\/\"},\"wordCount\":606,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-frac-femenino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/140417_-El-Frac-femenino_10.gif\",\"keywords\":[\"como cubrir un cuerpo\",\"comocubriruncuerpo\",\"creaci\u00f3n de moda\",\"ense\u00f1anza de patronaje\",\"escuela de moda\",\"Faldones del cuerpo\",\"frac\",\"moda femenina\",\"patron\",\"patronaje\",\"patronajemoda\",\"patrones\",\"pinzas\",\"pliegue\",\"t\u00e9cnica de patronaje\",\"tele virtual patronage\",\"televirtualpatronage\",\"Transformaci\u00f3n\",\"transformaci\u00f3n de prendas\",\"transformacionesdepatr\u00f3n\",\"transformacionesdepatron\",\"tutorial patonaje\"],\"articleSection\":[\"Archivo\",\"Patr\u00f3n\",\"Transformaci\u00f3n\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-frac-femenino\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-frac-femenino\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-frac-femenino\\\/\",\"name\":\"El Frac femenino - Tele Virtual Patronage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-frac-femenino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-frac-femenino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/140417_-El-Frac-femenino_10.gif\",\"datePublished\":\"2026-02-23T17:48:31+00:00\",\"dateModified\":\"2026-02-23T17:54:05+00:00\",\"description\":\"Aprende a patronar un frac femenino a partir del fald\u00f3n base del cuerpo sastre femenino. Desarrollo t\u00e9cnico completo con solapas chal, transformaci\u00f3n tipo Spencer y construcci\u00f3n de la cola de garza paso a paso.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-frac-femenino\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-frac-femenino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-frac-femenino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/140417_-El-Frac-femenino_10.gif\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/140417_-El-Frac-femenino_10.gif\",\"width\":595,\"height\":842,\"caption\":\"Uni\u00f3n de la pieza de la cola de garza a la cinturilla de mitad de espalda en el patr\u00f3n del frac femenino\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-frac-femenino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Frac femenino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"name\":\"Tele Virtual Patronage\",\"description\":\"Tevipa\",\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\",\"name\":\"Tele Virtual Patronage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"width\":512,\"height\":512,\"caption\":\"Tele Virtual Patronage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\",\"name\":\"Tele Virtual Patronage\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"caption\":\"Tele Virtual Patronage\"},\"sameAs\":[\"https:\\\/\\\/tevipa.com\\\/blog\"],\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/author\\\/tvpadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Frac femenino - Tele Virtual Patronage","description":"Aprende a patronar un frac femenino a partir del fald\u00f3n base del cuerpo sastre femenino. Desarrollo t\u00e9cnico completo con solapas chal, transformaci\u00f3n tipo Spencer y construcci\u00f3n de la cola de garza paso a paso.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tevipa.com\/blog\/el-frac-femenino\/","og_locale":"it_IT","og_type":"article","og_title":"El Frac femenino - Tele Virtual Patronage","og_description":"Aprende a patronar un frac femenino a partir del fald\u00f3n base del cuerpo sastre femenino. Desarrollo t\u00e9cnico completo con solapas chal, transformaci\u00f3n tipo Spencer y construcci\u00f3n de la cola de garza paso a paso.","og_url":"https:\/\/tevipa.com\/blog\/el-frac-femenino\/","og_site_name":"Tele Virtual Patronage","article_published_time":"2026-02-23T17:48:31+00:00","article_modified_time":"2026-02-23T17:54:05+00:00","og_image":[{"width":595,"height":842,"url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140417_-El-Frac-femenino_10.gif","type":"image\/gif"}],"author":"Tele Virtual Patronage","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Tele Virtual Patronage","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tevipa.com\/blog\/el-frac-femenino\/#article","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/el-frac-femenino\/"},"author":{"name":"Tele Virtual Patronage","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c"},"headline":"El Frac femenino","datePublished":"2026-02-23T17:48:31+00:00","dateModified":"2026-02-23T17:54:05+00:00","mainEntityOfPage":{"@id":"https:\/\/tevipa.com\/blog\/el-frac-femenino\/"},"wordCount":606,"commentCount":0,"publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"image":{"@id":"https:\/\/tevipa.com\/blog\/el-frac-femenino\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140417_-El-Frac-femenino_10.gif","keywords":["como cubrir un cuerpo","comocubriruncuerpo","creaci\u00f3n de moda","ense\u00f1anza de patronaje","escuela de moda","Faldones del cuerpo","frac","moda femenina","patron","patronaje","patronajemoda","patrones","pinzas","pliegue","t\u00e9cnica de patronaje","tele virtual patronage","televirtualpatronage","Transformaci\u00f3n","transformaci\u00f3n de prendas","transformacionesdepatr\u00f3n","transformacionesdepatron","tutorial patonaje"],"articleSection":["Archivo","Patr\u00f3n","Transformaci\u00f3n"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tevipa.com\/blog\/el-frac-femenino\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tevipa.com\/blog\/el-frac-femenino\/","url":"https:\/\/tevipa.com\/blog\/el-frac-femenino\/","name":"El Frac femenino - Tele Virtual Patronage","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tevipa.com\/blog\/el-frac-femenino\/#primaryimage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/el-frac-femenino\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140417_-El-Frac-femenino_10.gif","datePublished":"2026-02-23T17:48:31+00:00","dateModified":"2026-02-23T17:54:05+00:00","description":"Aprende a patronar un frac femenino a partir del fald\u00f3n base del cuerpo sastre femenino. Desarrollo t\u00e9cnico completo con solapas chal, transformaci\u00f3n tipo Spencer y construcci\u00f3n de la cola de garza paso a paso.","breadcrumb":{"@id":"https:\/\/tevipa.com\/blog\/el-frac-femenino\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tevipa.com\/blog\/el-frac-femenino\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/el-frac-femenino\/#primaryimage","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140417_-El-Frac-femenino_10.gif","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140417_-El-Frac-femenino_10.gif","width":595,"height":842,"caption":"Uni\u00f3n de la pieza de la cola de garza a la cinturilla de mitad de espalda en el patr\u00f3n del frac femenino"},{"@type":"BreadcrumbList","@id":"https:\/\/tevipa.com\/blog\/el-frac-femenino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tevipa.com\/blog\/"},{"@type":"ListItem","position":2,"name":"El Frac femenino"}]},{"@type":"WebSite","@id":"https:\/\/tevipa.com\/blog\/#website","url":"https:\/\/tevipa.com\/blog\/","name":"Tele Virtual Patronage","description":"Tevipa","publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tevipa.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/tevipa.com\/blog\/#organization","name":"Tele Virtual Patronage","url":"https:\/\/tevipa.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","width":512,"height":512,"caption":"Tele Virtual Patronage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c","name":"Tele Virtual Patronage","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","caption":"Tele Virtual Patronage"},"sameAs":["https:\/\/tevipa.com\/blog"],"url":"https:\/\/tevipa.com\/blog\/author\/tvpadm\/"}]}},"_links":{"self":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/6064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/comments?post=6064"}],"version-history":[{"count":7,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/6064\/revisions"}],"predecessor-version":[{"id":6081,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/6064\/revisions\/6081"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media\/6080"}],"wp:attachment":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media?parent=6064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/categories?post=6064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/tags?post=6064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}