{"id":5917,"date":"2026-02-22T16:39:57","date_gmt":"2026-02-22T15:39:57","guid":{"rendered":"https:\/\/tevipa.com\/blog\/?p=5917"},"modified":"2026-02-22T17:11:37","modified_gmt":"2026-02-22T16:11:37","slug":"gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos","status":"publish","type":"post","link":"https:\/\/tevipa.com\/blog\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\/","title":{"rendered":"Gradaci\u00f3n o escalado del pantal\u00f3n infantil desde los 4 a los 18 a\u00f1os"},"content":{"rendered":"\n<p class=\"has-text-align-right has-small-font-size wp-block-paragraph\"><sup><em>Publicado originalmente el&nbsp;<strong>18 Octubre 2013<\/strong><\/em><\/sup><\/p>\n\n\n<style>.kb-image5917_d92285-35 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image5917_d92285-35 is-style-default\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"222\" height=\"300\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg\" alt=\"Logo C\u00f3mo Cubrir un Cuerpo\" class=\"kb-img wp-image-68\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg 222w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-757x1024.jpg 757w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-768x1039.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1135x1536.jpg 1135w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1514x2048.jpg 1514w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran.jpg 1821w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/><\/figure><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\" style=\"font-size:27px\"><strong>Gradaci\u00f3n o escalado del pantal\u00f3n infantil desde los 4 a los 18 a\u00f1os<\/strong><\/h1>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Hemos gradado esta plancha en base al trazado del pantal\u00f3n base cl\u00e1sico enteramente proporcional que encontrar\u00e9is en: <a href=\"https:\/\/tevipa.com\/blog\/trazado-de-pantalon-clasico-para-hombre-mujer-nino-y-nina-trazado-enteramente-proporcional\/\" type=\"link\" id=\"https:\/\/tevipa.com\/blog\/trazado-de-pantalon-clasico-para-hombre-mujer-nino-y-nina-trazado-enteramente-proporcional\/\">Trazado del pantal\u00f3n cl\u00e1sico para hombre, mujer, ni\u00f1o y ni\u00f1a. Trazado \u00fanicamente proporcional<\/a>, y con las ratios de gradaci\u00f3n que dimos en su d\u00eda en el post\u00a0<a href=\"https:\/\/tevipa.com\/blog\/las-ratios-de-la-gradacion-del-pantalon-proporcional\/\" type=\"link\" id=\"https:\/\/tevipa.com\/blog\/las-ratios-de-la-gradacion-del-pantalon-proporcional\/\">Las ratios de la gradaci\u00f3n del patr\u00f3n proporcional<\/a>\u00a0y en base a la tabla de medidas:\u00a0<a href=\"https:\/\/tevipa.com\/blog\/tabla-de-medidas-nino-y-nina\/\" type=\"link\" id=\"https:\/\/tevipa.com\/blog\/tabla-de-medidas-nino-y-nina\/\">Tabla de medidas ni\u00f1os y ni\u00f1as<\/a>.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/333-1010CB-gradacion-pantalon-infantil-amb-punts-dancla-A4-667x1024.jpg\" alt=\"Plancha de gradaci\u00f3n del pantal\u00f3n infantil proporcional desde los 4 hasta los 18 a\u00f1os, mostrando delantero y espalda con puntos de ancla y progresi\u00f3n de tallas sobre base cl\u00e1sica proporcional.\" class=\"wp-image-5919\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/333-1010CB-gradacion-pantalon-infantil-amb-punts-dancla-A4-667x1024.jpg 667w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/333-1010CB-gradacion-pantalon-infantil-amb-punts-dancla-A4-195x300.jpg 195w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/333-1010CB-gradacion-pantalon-infantil-amb-punts-dancla-A4-768x1179.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/333-1010CB-gradacion-pantalon-infantil-amb-punts-dancla-A4-1001x1536.jpg 1001w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/333-1010CB-gradacion-pantalon-infantil-amb-punts-dancla-A4-1334x2048.jpg 1334w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/333-1010CB-gradacion-pantalon-infantil-amb-punts-dancla-A4-1320x2026.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/333-1010CB-gradacion-pantalon-infantil-amb-punts-dancla-A4-scaled.jpg 1668w\" sizes=\"auto, (max-width: 667px) 100vw, 667px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">La gradaci\u00f3n se ha realizado con los puntos de ancla en la intersecci\u00f3n de la l\u00ednea de cintura con la mitad delante para el delantero y desde e mismo punto para la parte posterior. En la plancha que os presentamos hemos cambiado los puntos de ancla para que la gradaci\u00f3n fuera m\u00e1s f\u00e1cil de comparar. En la imagen&nbsp;presentada, el punto de ancla est\u00e1 en la intersecci\u00f3n de la l\u00ednea de mitad de cuerpo con la l\u00ednea de cadera tanto para el delantero como para la parte posterior. No hemos trazado las entretallas para no emborronar la plancha pero podemos ver que quiebran en m\u00faltiples ocasiones.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Analizando esta plancha podemos sacar varias conclusiones sobre este trazado de escalado: Si miramos la plancha desde la l\u00ednea de cadera hasta el bajo del pantal\u00f3n vemos que el andamiento o progresi\u00f3n de todas las tallas en largos es bastante constante, s\u00f3lo el montante cambia, sobre los anchos vemos repercutido el quiebre&nbsp; de cadera en los laterales de las costuras de las perneras. Si observamos el delantero en su parte superior vemos que el trazado parece muy constante, ello es debido a que todo incremento o decremento de la ratio de cintura ser\u00e1 absorbido por la parte posterior. Si miramos la parte posterior del trazado desde la l\u00ednea de cadera hasta la l\u00ednea de cintura y especialmente la intersecci\u00f3n la costura lateral con la cintura encontraremos todas las diferencias de las ratios de cintura. Si queremos unas planchas de gradaci\u00f3n m\u00e1s regulares aconsejamos&nbsp; segmentar el tallaje en varias planchas y en su caso rectificar las medidas y construir una tabla m\u00e1s regular.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En este post analizamos la gradaci\u00f3n o escalado del pantal\u00f3n infantil desde los 4 hasta los 18 a\u00f1os, partiendo de un trazado base enteramente proporcional. Estudiamos la ubicaci\u00f3n de los puntos de ancla, la progresi\u00f3n de largos desde cadera hasta bajo, el comportamiento del montante y la absorci\u00f3n de las variaciones de cintura en la parte posterior. Un an\u00e1lisis t\u00e9cnico que permite comprender c\u00f3mo se distribuyen realmente las ratios de gradaci\u00f3n y cu\u00e1ndo conviene segmentar el tallaje para obtener planchas m\u00e1s regulares.<\/p>\n","protected":false},"author":1,"featured_media":5919,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1018,962,1,23,1461],"tags":[44,30,38,674,90,392,390,92,1463,104,80,362,82,672,40,42,676],"class_list":["post-5917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo","category-gradacion-es","category-medidas","category-patron","category-patron-del-pantalon","tag-como-cubrir-un-cuerpo","tag-comocubriruncuerpo","tag-creacion-de-moda","tag-ensenanza-de-patronaje","tag-escuela-de-moda","tag-gradacion-2","tag-gradacion","tag-gradacion-o-escalado","tag-pantalon","tag-patron","tag-patronaje","tag-patronajemoda","tag-patrones","tag-tecnica-de-patronaje","tag-tele-virtual-patronage","tag-televirtualpatronage","tag-tutorial-patonaje"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gradaci\u00f3n o escalado del pantal\u00f3n infantil desde los 4 a los 18 a\u00f1os - Tele Virtual Patronage<\/title>\n<meta name=\"description\" content=\"An\u00e1lisis t\u00e9cnico de la gradaci\u00f3n o escalado del pantal\u00f3n infantil desde los 4 hasta los 18 a\u00f1os, basado en un trazado proporcional cl\u00e1sico y en ratios de gradaci\u00f3n aplicadas sobre tabla de medidas infantil. Estudio de puntos de ancla, progresi\u00f3n de largos y comportamiento de cintura y cadera en el escalado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tevipa.com\/blog\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gradaci\u00f3n o escalado del pantal\u00f3n infantil desde los 4 a los 18 a\u00f1os - Tele Virtual Patronage\" \/>\n<meta property=\"og:description\" content=\"An\u00e1lisis t\u00e9cnico de la gradaci\u00f3n o escalado del pantal\u00f3n infantil desde los 4 hasta los 18 a\u00f1os, basado en un trazado proporcional cl\u00e1sico y en ratios de gradaci\u00f3n aplicadas sobre tabla de medidas infantil. Estudio de puntos de ancla, progresi\u00f3n de largos y comportamiento de cintura y cadera en el escalado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tevipa.com\/blog\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"Tele Virtual Patronage\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-22T15:39:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-22T16:11:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/333-1010CB-gradacion-pantalon-infantil-amb-punts-dancla-A4-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1668\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tele Virtual Patronage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tele Virtual Patronage\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\\\/\"},\"author\":{\"name\":\"Tele Virtual Patronage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\"},\"headline\":\"Gradaci\u00f3n o escalado del pantal\u00f3n infantil desde los 4 a los 18 a\u00f1os\",\"datePublished\":\"2026-02-22T15:39:57+00:00\",\"dateModified\":\"2026-02-22T16:11:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\\\/\"},\"wordCount\":403,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/333-1010CB-gradacion-pantalon-infantil-amb-punts-dancla-A4-scaled.jpg\",\"keywords\":[\"como cubrir un cuerpo\",\"comocubriruncuerpo\",\"creaci\u00f3n de moda\",\"ense\u00f1anza de patronaje\",\"escuela de moda\",\"gradacion\",\"gradaci\u00f3n\",\"gradaci\u00f3n o escalado\",\"pantal\u00f3n\",\"patron\",\"patronaje\",\"patronajemoda\",\"patrones\",\"t\u00e9cnica de patronaje\",\"tele virtual patronage\",\"televirtualpatronage\",\"tutorial patonaje\"],\"articleSection\":[\"Archivo\",\"Gradaci\u00f3n\",\"Medidas\",\"Patr\u00f3n\",\"Patr\u00f3n del pantal\u00f3n\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\\\/\",\"name\":\"Gradaci\u00f3n o escalado del pantal\u00f3n infantil desde los 4 a los 18 a\u00f1os - Tele Virtual Patronage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/333-1010CB-gradacion-pantalon-infantil-amb-punts-dancla-A4-scaled.jpg\",\"datePublished\":\"2026-02-22T15:39:57+00:00\",\"dateModified\":\"2026-02-22T16:11:37+00:00\",\"description\":\"An\u00e1lisis t\u00e9cnico de la gradaci\u00f3n o escalado del pantal\u00f3n infantil desde los 4 hasta los 18 a\u00f1os, basado en un trazado proporcional cl\u00e1sico y en ratios de gradaci\u00f3n aplicadas sobre tabla de medidas infantil. Estudio de puntos de ancla, progresi\u00f3n de largos y comportamiento de cintura y cadera en el escalado.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/333-1010CB-gradacion-pantalon-infantil-amb-punts-dancla-A4-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/333-1010CB-gradacion-pantalon-infantil-amb-punts-dancla-A4-scaled.jpg\",\"width\":1668,\"height\":2560,\"caption\":\"Plancha de gradaci\u00f3n del pantal\u00f3n infantil proporcional desde los 4 hasta los 18 a\u00f1os, mostrando delantero y espalda con puntos de ancla y progresi\u00f3n de tallas sobre base cl\u00e1sica proporcional.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gradaci\u00f3n o escalado del pantal\u00f3n infantil desde los 4 a los 18 a\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"name\":\"Tele Virtual Patronage\",\"description\":\"Tevipa\",\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\",\"name\":\"Tele Virtual Patronage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"width\":512,\"height\":512,\"caption\":\"Tele Virtual Patronage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\",\"name\":\"Tele Virtual Patronage\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"caption\":\"Tele Virtual Patronage\"},\"sameAs\":[\"https:\\\/\\\/tevipa.com\\\/blog\"],\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/author\\\/tvpadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gradaci\u00f3n o escalado del pantal\u00f3n infantil desde los 4 a los 18 a\u00f1os - Tele Virtual Patronage","description":"An\u00e1lisis t\u00e9cnico de la gradaci\u00f3n o escalado del pantal\u00f3n infantil desde los 4 hasta los 18 a\u00f1os, basado en un trazado proporcional cl\u00e1sico y en ratios de gradaci\u00f3n aplicadas sobre tabla de medidas infantil. Estudio de puntos de ancla, progresi\u00f3n de largos y comportamiento de cintura y cadera en el escalado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tevipa.com\/blog\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\/","og_locale":"it_IT","og_type":"article","og_title":"Gradaci\u00f3n o escalado del pantal\u00f3n infantil desde los 4 a los 18 a\u00f1os - Tele Virtual Patronage","og_description":"An\u00e1lisis t\u00e9cnico de la gradaci\u00f3n o escalado del pantal\u00f3n infantil desde los 4 hasta los 18 a\u00f1os, basado en un trazado proporcional cl\u00e1sico y en ratios de gradaci\u00f3n aplicadas sobre tabla de medidas infantil. Estudio de puntos de ancla, progresi\u00f3n de largos y comportamiento de cintura y cadera en el escalado.","og_url":"https:\/\/tevipa.com\/blog\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\/","og_site_name":"Tele Virtual Patronage","article_published_time":"2026-02-22T15:39:57+00:00","article_modified_time":"2026-02-22T16:11:37+00:00","og_image":[{"width":1668,"height":2560,"url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/333-1010CB-gradacion-pantalon-infantil-amb-punts-dancla-A4-scaled.jpg","type":"image\/jpeg"}],"author":"Tele Virtual Patronage","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Tele Virtual Patronage","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tevipa.com\/blog\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\/#article","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\/"},"author":{"name":"Tele Virtual Patronage","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c"},"headline":"Gradaci\u00f3n o escalado del pantal\u00f3n infantil desde los 4 a los 18 a\u00f1os","datePublished":"2026-02-22T15:39:57+00:00","dateModified":"2026-02-22T16:11:37+00:00","mainEntityOfPage":{"@id":"https:\/\/tevipa.com\/blog\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\/"},"wordCount":403,"commentCount":0,"publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"image":{"@id":"https:\/\/tevipa.com\/blog\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/333-1010CB-gradacion-pantalon-infantil-amb-punts-dancla-A4-scaled.jpg","keywords":["como cubrir un cuerpo","comocubriruncuerpo","creaci\u00f3n de moda","ense\u00f1anza de patronaje","escuela de moda","gradacion","gradaci\u00f3n","gradaci\u00f3n o escalado","pantal\u00f3n","patron","patronaje","patronajemoda","patrones","t\u00e9cnica de patronaje","tele virtual patronage","televirtualpatronage","tutorial patonaje"],"articleSection":["Archivo","Gradaci\u00f3n","Medidas","Patr\u00f3n","Patr\u00f3n del pantal\u00f3n"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tevipa.com\/blog\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tevipa.com\/blog\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\/","url":"https:\/\/tevipa.com\/blog\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\/","name":"Gradaci\u00f3n o escalado del pantal\u00f3n infantil desde los 4 a los 18 a\u00f1os - Tele Virtual Patronage","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tevipa.com\/blog\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\/#primaryimage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/333-1010CB-gradacion-pantalon-infantil-amb-punts-dancla-A4-scaled.jpg","datePublished":"2026-02-22T15:39:57+00:00","dateModified":"2026-02-22T16:11:37+00:00","description":"An\u00e1lisis t\u00e9cnico de la gradaci\u00f3n o escalado del pantal\u00f3n infantil desde los 4 hasta los 18 a\u00f1os, basado en un trazado proporcional cl\u00e1sico y en ratios de gradaci\u00f3n aplicadas sobre tabla de medidas infantil. Estudio de puntos de ancla, progresi\u00f3n de largos y comportamiento de cintura y cadera en el escalado.","breadcrumb":{"@id":"https:\/\/tevipa.com\/blog\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tevipa.com\/blog\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\/#primaryimage","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/333-1010CB-gradacion-pantalon-infantil-amb-punts-dancla-A4-scaled.jpg","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/333-1010CB-gradacion-pantalon-infantil-amb-punts-dancla-A4-scaled.jpg","width":1668,"height":2560,"caption":"Plancha de gradaci\u00f3n del pantal\u00f3n infantil proporcional desde los 4 hasta los 18 a\u00f1os, mostrando delantero y espalda con puntos de ancla y progresi\u00f3n de tallas sobre base cl\u00e1sica proporcional."},{"@type":"BreadcrumbList","@id":"https:\/\/tevipa.com\/blog\/gradacion-o-escalado-del-pantalon-infantil-desde-los-4-a-los-18-anos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tevipa.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Gradaci\u00f3n o escalado del pantal\u00f3n infantil desde los 4 a los 18 a\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/tevipa.com\/blog\/#website","url":"https:\/\/tevipa.com\/blog\/","name":"Tele Virtual Patronage","description":"Tevipa","publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tevipa.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/tevipa.com\/blog\/#organization","name":"Tele Virtual Patronage","url":"https:\/\/tevipa.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","width":512,"height":512,"caption":"Tele Virtual Patronage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c","name":"Tele Virtual Patronage","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","caption":"Tele Virtual Patronage"},"sameAs":["https:\/\/tevipa.com\/blog"],"url":"https:\/\/tevipa.com\/blog\/author\/tvpadm\/"}]}},"_links":{"self":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/5917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/comments?post=5917"}],"version-history":[{"count":3,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/5917\/revisions"}],"predecessor-version":[{"id":5921,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/5917\/revisions\/5921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media\/5919"}],"wp:attachment":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media?parent=5917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/categories?post=5917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/tags?post=5917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}