{"id":5825,"date":"2026-02-22T10:20:22","date_gmt":"2026-02-22T09:20:22","guid":{"rendered":"https:\/\/tevipa.com\/blog\/?p=5825"},"modified":"2026-02-22T12:37:04","modified_gmt":"2026-02-22T11:37:04","slug":"incoherencias-y-deformaciones-en-el-escalado","status":"publish","type":"post","link":"https:\/\/tevipa.com\/blog\/incoherencias-y-deformaciones-en-el-escalado\/","title":{"rendered":"Incoherencias y deformaciones en el escalado"},"content":{"rendered":"\n<p class=\"has-text-align-right has-small-font-size wp-block-paragraph\"><sup><em>Publicado originalmente el&nbsp;<strong>23 Mayo 2015<\/strong><\/em><\/sup><\/p>\n\n\n<style>.kb-image5825_d6c4b0-18 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image5825_d6c4b0-18 is-style-default\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"222\" height=\"300\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg\" alt=\"Logo C\u00f3mo Cubrir un Cuerpo\" class=\"kb-img wp-image-68\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg 222w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-757x1024.jpg 757w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-768x1039.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1135x1536.jpg 1135w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1514x2048.jpg 1514w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran.jpg 1821w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/><\/figure><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\" style=\"font-size:27px\">Incoherencias y deformaciones en el escalado<\/h1>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"479\" height=\"653\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/grad-nino-hombre.gif\" alt=\"Plancha de gradaci\u00f3n de pantal\u00f3n desde talla infantil hasta talla 48 de caballero mostrando progresi\u00f3n proporcional sin deformaciones\" class=\"wp-image-5828\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Escalar es el procedimiento por el que a partir de una talla encontramos otra, superior o inferior.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Una talla es la reuni\u00f3n de medidas pertenecientes a las dimensiones de una persona idealizada concreta. Decimos \u201cidealizada\u201d porque hacemos una abstracci\u00f3n.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Esta abstracci\u00f3n deber\u00eda hacerse en base a la media de muchas muestras de personas la misma conformaci\u00f3n que tuvieran la medida principal o referente igual.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">El resultado de la gradaci\u00f3n debe coincidir a las medidas de la talla destino partiendo de las medidas de la talla base.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Actualmente se est\u00e1n gradando prendas a nivel profesional partiendo de un modelo base sin tener una tabla de medidas, se grada a una talla superior o inferior s\u00f3lo conociendo los contornos de cadera, cintura y pecho.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">El resultado: prendas que se deforman.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">En reputadas escuelas de patronaje, las profesoras que dan clases de patronaje asistido por ordenador confiesan nunca haber escalado sobre mesa y desconocer el procedimiento de \u00e9ste. Nunca han o\u00eddo hablar de un comp\u00e1s de reducci\u00f3n ni de la proporcionalidad de los tri\u00e1ngulos.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">En sus lecciones aplican alegremente&nbsp; ratios de escalado sin conocer la proporci\u00f3n con que han sido trazados los patrones.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">El escalado se basa precisamente en la aplicaci\u00f3n de la &nbsp;proporci\u00f3n de la\/s medida\/s principal\/es para obtener el trazado base y aplica \u00e9sta\/s a las progresiones de las medidas en cuesti\u00f3n.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Es una irresponsabilidad escalar sin conocer las proporciones que han servido para trazar el patr\u00f3n ya que \u00e9stas son las que definen las ratios del escalado.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">El resultado: las prendas se deforman.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">La semana pasada se me dijo que era imposible hacer una plancha de gradaci\u00f3n de m\u00e1s de 3 tallas sin que hubiera deformaciones.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Con un poco de paciencia, y sin utilizar un sofisticado programa de patronaje, si se respetan las proporciones y se dispone de una tabla correcta de medidas se puede escalar cu\u00e1ntas tallas se quiera sin sufrir deformaciones de la prenda.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Damos como ejemplo el pantal\u00f3n cl\u00e1sico gradado desde la talla 4 a\u00f1os de la conformaci\u00f3n de ni\u00f1o hasta la talla 48 de la conformaci\u00f3n normal de caballero.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Es deplorable la desinformaci\u00f3n que se da en algunos centros que revierte en una serie de deformaciones, retoques y pruebas que hacen perder tiempo a los equipos de las empresas, dinero a las empresas y frescura en los patrones.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Debemos mirar hacia adelante, y progresar con nuestro tiempo, pero para progresar tenemos siempre que mirar hacia atr\u00e1s.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Gracias a Tales de Mileto y a Pit\u00e1goras un comp\u00e1s de reducci\u00f3n un poco de papel kraft un juego de escuadra y cartab\u00f3n y unas reglas, una de ellas de curvas hasta hace poco tiempo se pod\u00edan hacer cosas que hoy se dan por imposibles.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"479\" height=\"262\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/compas-reduccion.gif\" alt=\"Comp\u00e1s de reducci\u00f3n utilizado en patronaje para aplicar proporcionalidad en la gradaci\u00f3n de tallas sin deformaciones\" class=\"wp-image-5829\"\/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Escalar no consiste en aplicar ratios autom\u00e1ticos a contornos de pecho, cintura y cadera. El escalado en patronaje exige conocer las proporciones que dieron origen al trazado base y respetarlas en cada progresi\u00f3n de talla. Cuando se ignora la tabla de medidas y se grada sin criterio geom\u00e9trico, las prendas se deforman. En este art\u00edculo analizamos las incoherencias actuales del escalado profesional y recordamos la importancia de la proporcionalidad cl\u00e1sica en la gradaci\u00f3n.<\/p>\n","protected":false},"author":1,"featured_media":5828,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1018,962,1],"tags":[44,30,38,674,90,392,390,92,80,362,672,40,42,676],"class_list":["post-5825","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo","category-gradacion-es","category-medidas","tag-como-cubrir-un-cuerpo","tag-comocubriruncuerpo","tag-creacion-de-moda","tag-ensenanza-de-patronaje","tag-escuela-de-moda","tag-gradacion-2","tag-gradacion","tag-gradacion-o-escalado","tag-patronaje","tag-patronajemoda","tag-tecnica-de-patronaje","tag-tele-virtual-patronage","tag-televirtualpatronage","tag-tutorial-patonaje"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Incoherencias y deformaciones en el escalado - Tele Virtual Patronage<\/title>\n<meta name=\"description\" content=\"El escalado en patronaje no puede basarse \u00fanicamente en contornos. Analizamos las incoherencias de la gradaci\u00f3n profesional sin tabla de medidas y explicamos por qu\u00e9 las prendas se deforman cuando no se respetan las proporciones originales del trazado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tevipa.com\/blog\/incoherencias-y-deformaciones-en-el-escalado\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Incoherencias y deformaciones en el escalado - Tele Virtual Patronage\" \/>\n<meta property=\"og:description\" content=\"El escalado en patronaje no puede basarse \u00fanicamente en contornos. Analizamos las incoherencias de la gradaci\u00f3n profesional sin tabla de medidas y explicamos por qu\u00e9 las prendas se deforman cuando no se respetan las proporciones originales del trazado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tevipa.com\/blog\/incoherencias-y-deformaciones-en-el-escalado\/\" \/>\n<meta property=\"og:site_name\" content=\"Tele Virtual Patronage\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-22T09:20:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-22T11:37:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/grad-nino-hombre.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"479\" \/>\n\t<meta property=\"og:image:height\" content=\"653\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"Tele Virtual Patronage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tele Virtual Patronage\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/incoherencias-y-deformaciones-en-el-escalado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/incoherencias-y-deformaciones-en-el-escalado\\\/\"},\"author\":{\"name\":\"Tele Virtual Patronage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\"},\"headline\":\"Incoherencias y deformaciones en el escalado\",\"datePublished\":\"2026-02-22T09:20:22+00:00\",\"dateModified\":\"2026-02-22T11:37:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/incoherencias-y-deformaciones-en-el-escalado\\\/\"},\"wordCount\":498,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/incoherencias-y-deformaciones-en-el-escalado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/grad-nino-hombre.gif\",\"keywords\":[\"como cubrir un cuerpo\",\"comocubriruncuerpo\",\"creaci\u00f3n de moda\",\"ense\u00f1anza de patronaje\",\"escuela de moda\",\"gradacion\",\"gradaci\u00f3n\",\"gradaci\u00f3n o escalado\",\"patronaje\",\"patronajemoda\",\"t\u00e9cnica de patronaje\",\"tele virtual patronage\",\"televirtualpatronage\",\"tutorial patonaje\"],\"articleSection\":[\"Archivo\",\"Gradaci\u00f3n\",\"Medidas\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/incoherencias-y-deformaciones-en-el-escalado\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/incoherencias-y-deformaciones-en-el-escalado\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/incoherencias-y-deformaciones-en-el-escalado\\\/\",\"name\":\"Incoherencias y deformaciones en el escalado - Tele Virtual Patronage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/incoherencias-y-deformaciones-en-el-escalado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/incoherencias-y-deformaciones-en-el-escalado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/grad-nino-hombre.gif\",\"datePublished\":\"2026-02-22T09:20:22+00:00\",\"dateModified\":\"2026-02-22T11:37:04+00:00\",\"description\":\"El escalado en patronaje no puede basarse \u00fanicamente en contornos. Analizamos las incoherencias de la gradaci\u00f3n profesional sin tabla de medidas y explicamos por qu\u00e9 las prendas se deforman cuando no se respetan las proporciones originales del trazado.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/incoherencias-y-deformaciones-en-el-escalado\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/incoherencias-y-deformaciones-en-el-escalado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/incoherencias-y-deformaciones-en-el-escalado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/grad-nino-hombre.gif\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/grad-nino-hombre.gif\",\"width\":479,\"height\":653,\"caption\":\"Plancha de gradaci\u00f3n de pantal\u00f3n desde talla infantil hasta talla 48 de caballero mostrando progresi\u00f3n proporcional sin deformaciones\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/incoherencias-y-deformaciones-en-el-escalado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Incoherencias y deformaciones en el escalado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"name\":\"Tele Virtual Patronage\",\"description\":\"Tevipa\",\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\",\"name\":\"Tele Virtual Patronage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"width\":512,\"height\":512,\"caption\":\"Tele Virtual Patronage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\",\"name\":\"Tele Virtual Patronage\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"caption\":\"Tele Virtual Patronage\"},\"sameAs\":[\"https:\\\/\\\/tevipa.com\\\/blog\"],\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/author\\\/tvpadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Incoherencias y deformaciones en el escalado - Tele Virtual Patronage","description":"El escalado en patronaje no puede basarse \u00fanicamente en contornos. Analizamos las incoherencias de la gradaci\u00f3n profesional sin tabla de medidas y explicamos por qu\u00e9 las prendas se deforman cuando no se respetan las proporciones originales del trazado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tevipa.com\/blog\/incoherencias-y-deformaciones-en-el-escalado\/","og_locale":"it_IT","og_type":"article","og_title":"Incoherencias y deformaciones en el escalado - Tele Virtual Patronage","og_description":"El escalado en patronaje no puede basarse \u00fanicamente en contornos. Analizamos las incoherencias de la gradaci\u00f3n profesional sin tabla de medidas y explicamos por qu\u00e9 las prendas se deforman cuando no se respetan las proporciones originales del trazado.","og_url":"https:\/\/tevipa.com\/blog\/incoherencias-y-deformaciones-en-el-escalado\/","og_site_name":"Tele Virtual Patronage","article_published_time":"2026-02-22T09:20:22+00:00","article_modified_time":"2026-02-22T11:37:04+00:00","og_image":[{"width":479,"height":653,"url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/grad-nino-hombre.gif","type":"image\/gif"}],"author":"Tele Virtual Patronage","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Tele Virtual Patronage","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tevipa.com\/blog\/incoherencias-y-deformaciones-en-el-escalado\/#article","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/incoherencias-y-deformaciones-en-el-escalado\/"},"author":{"name":"Tele Virtual Patronage","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c"},"headline":"Incoherencias y deformaciones en el escalado","datePublished":"2026-02-22T09:20:22+00:00","dateModified":"2026-02-22T11:37:04+00:00","mainEntityOfPage":{"@id":"https:\/\/tevipa.com\/blog\/incoherencias-y-deformaciones-en-el-escalado\/"},"wordCount":498,"commentCount":0,"publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"image":{"@id":"https:\/\/tevipa.com\/blog\/incoherencias-y-deformaciones-en-el-escalado\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/grad-nino-hombre.gif","keywords":["como cubrir un cuerpo","comocubriruncuerpo","creaci\u00f3n de moda","ense\u00f1anza de patronaje","escuela de moda","gradacion","gradaci\u00f3n","gradaci\u00f3n o escalado","patronaje","patronajemoda","t\u00e9cnica de patronaje","tele virtual patronage","televirtualpatronage","tutorial patonaje"],"articleSection":["Archivo","Gradaci\u00f3n","Medidas"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tevipa.com\/blog\/incoherencias-y-deformaciones-en-el-escalado\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tevipa.com\/blog\/incoherencias-y-deformaciones-en-el-escalado\/","url":"https:\/\/tevipa.com\/blog\/incoherencias-y-deformaciones-en-el-escalado\/","name":"Incoherencias y deformaciones en el escalado - Tele Virtual Patronage","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tevipa.com\/blog\/incoherencias-y-deformaciones-en-el-escalado\/#primaryimage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/incoherencias-y-deformaciones-en-el-escalado\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/grad-nino-hombre.gif","datePublished":"2026-02-22T09:20:22+00:00","dateModified":"2026-02-22T11:37:04+00:00","description":"El escalado en patronaje no puede basarse \u00fanicamente en contornos. Analizamos las incoherencias de la gradaci\u00f3n profesional sin tabla de medidas y explicamos por qu\u00e9 las prendas se deforman cuando no se respetan las proporciones originales del trazado.","breadcrumb":{"@id":"https:\/\/tevipa.com\/blog\/incoherencias-y-deformaciones-en-el-escalado\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tevipa.com\/blog\/incoherencias-y-deformaciones-en-el-escalado\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/incoherencias-y-deformaciones-en-el-escalado\/#primaryimage","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/grad-nino-hombre.gif","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/grad-nino-hombre.gif","width":479,"height":653,"caption":"Plancha de gradaci\u00f3n de pantal\u00f3n desde talla infantil hasta talla 48 de caballero mostrando progresi\u00f3n proporcional sin deformaciones"},{"@type":"BreadcrumbList","@id":"https:\/\/tevipa.com\/blog\/incoherencias-y-deformaciones-en-el-escalado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tevipa.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Incoherencias y deformaciones en el escalado"}]},{"@type":"WebSite","@id":"https:\/\/tevipa.com\/blog\/#website","url":"https:\/\/tevipa.com\/blog\/","name":"Tele Virtual Patronage","description":"Tevipa","publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tevipa.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/tevipa.com\/blog\/#organization","name":"Tele Virtual Patronage","url":"https:\/\/tevipa.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","width":512,"height":512,"caption":"Tele Virtual Patronage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c","name":"Tele Virtual Patronage","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","caption":"Tele Virtual Patronage"},"sameAs":["https:\/\/tevipa.com\/blog"],"url":"https:\/\/tevipa.com\/blog\/author\/tvpadm\/"}]}},"_links":{"self":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/5825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/comments?post=5825"}],"version-history":[{"count":3,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/5825\/revisions"}],"predecessor-version":[{"id":5830,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/5825\/revisions\/5830"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media\/5828"}],"wp:attachment":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media?parent=5825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/categories?post=5825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/tags?post=5825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}