{"id":5798,"date":"2026-02-21T21:29:18","date_gmt":"2026-02-21T20:29:18","guid":{"rendered":"https:\/\/tevipa.com\/blog\/?p=5798"},"modified":"2026-02-22T17:09:52","modified_gmt":"2026-02-22T16:09:52","slug":"gradacion-como-hallar-las-ratios","status":"publish","type":"post","link":"https:\/\/tevipa.com\/blog\/gradacion-como-hallar-las-ratios\/","title":{"rendered":"Gradaci\u00f3n &#8211; C\u00f3mo hallar las ratios"},"content":{"rendered":"\n<p class=\"has-text-align-right has-small-font-size wp-block-paragraph\"><sup><em>Publicado originalmente el&nbsp;<strong>13 Junio 2013<\/strong><\/em><\/sup><\/p>\n\n\n<style>.kb-image5798_f8d2d4-31 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image5798_f8d2d4-31 is-style-default\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"222\" height=\"300\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg\" alt=\"Logo C\u00f3mo Cubrir un Cuerpo\" class=\"kb-img wp-image-68\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg 222w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-757x1024.jpg 757w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-768x1039.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1135x1536.jpg 1135w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1514x2048.jpg 1514w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran.jpg 1821w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/><\/figure><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\" style=\"font-size:27px\"><strong><strong>Gradaci\u00f3n<\/strong><\/strong><br><strong>C\u00f3mo hallar las ratios<\/strong><\/h1>\n\n\n\n<p class=\"text-justify wp-block-paragraph\"><em>Aconsejamos de haber le\u00eddo el post\u00a0relativo al patronaje\u00a0de la falda recta y el post anterior <\/em><a href=\"https:\/\/tevipa.com\/blog\/concepto-de-gradacion-o-escalado\/\" type=\"link\" id=\"https:\/\/tevipa.com\/blog\/concepto-de-gradacion-o-escalado\/\">Concepto de gradaci\u00f3n o escalado<\/a><em>.\u00a0<\/em><\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Llamaremos ratio (r) a la variaci\u00f3n de incremento constante entre dos variables de la misma secuencia que nos dar\u00e1 una l\u00ednea de entretalla constante y con una determinada inclinaci\u00f3n, &nbsp;sin puntos de quiebre.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Si en una entretalla&nbsp;encontramos uno o m\u00e1s puntos de quiebre, deberemos&nbsp; calcular tantas ratios&nbsp;como puntos de quiebre tenga la entretalla.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">La ratio, compuesta de dos valores, uno para el eje de las X y el, otro para el eje de la Y, &nbsp;el valor de X e Y ser\u00e1 lo que determinar\u00e1 la inclinaci\u00f3n de la l\u00ednea de entre talla entre des &nbsp;puntos de quiebre.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Si disponemos de una tabla completa de c\u00e1lculo como las que podemos encontrar de la falda en la categor\u00eda de tablas de medidas o consultando los post&nbsp;anteriores, podemos obtener las ratios restando la talla superior de la inferior mientras que la proporci\u00f3n se mantenga constante,&nbsp; o sea que no haya un punto de quiebre<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Si&nbsp; no disponemos de la tabla competa de c\u00e1lculos podemos deducir todas las ratios f\u00e1cilmente utilizando s\u00f3lo las proporciones de las variables.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Las f\u00f3rmulas, por ejemplo en el post relativo al corte de la falda,&nbsp; son unas proporciones (multiplicaciones y divisiones)&nbsp;y sumas o restas&nbsp;que se aplican a una serie de &nbsp;<em>variables<\/em> (letras que representan los datos de las tablas antropom\u00e9tricas).<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">De cada una de las f\u00f3rmulas s\u00f3lo nos interesar\u00e1 la multiplicaci\u00f3n y la divisi\u00f3n de la variable, no la del o la de los n\u00fameros ya que para todas las tallas nos dar\u00e1 un valor constante:<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">As\u00ed &nbsp;+(K\/2)+1 para lo que nos interesa ser\u00e1 + K\/2, o +P\/4+3+8 ser\u00e1 para nosotros +P\/4 y +((2(P+1)\/4)*3) ser\u00e1v2 P\/4 o lo que es lo mismo p\/2<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Si las variables son la secuencia de los n\u00fameros 4, 8, 12, 16<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">La &nbsp;f\u00f3rnula +(K\/2)+ 1 tendr\u00e1 la ratio rK\/2, o sea la proporci\u00f3n que calcula de la variable (K\/2), la calcularemos en la ratio de la secuencia. Vemos que los n\u00fameros de la secuencia crecen de 4 en 4 por lo que la ratio del punto ser\u00e1 4\/2= 2<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Para comprobarlo podemos calcular las f\u00f3rmulas para cada uno de los n\u00fameros dados y su resultado restarlo con el inmediatamente inferior:<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Si k es igual a 4: +(K+1)+1)&nbsp; =&nbsp; +(4\/2)+1= 3.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Si k es igual a 8: +(K+1)+1) &nbsp;=&nbsp; +(8\/2)+1= 5.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Si k es igual a 12: +(K+1)+1) &nbsp;=&nbsp; +(12\/2)+1= 7.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Si k es igual a 16 +(K+1)+1)&nbsp; =&nbsp; +(16\/2)+1= 9.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Como podemos comprobar los resultados se incrementan por 2 unidades como hab\u00edamos calculado anteriormente.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Cuando en un patr\u00f3n decidimos poner el valor de la tabla entero, sin proporci\u00f3n por ejemplo largo total (LG), en verdad estamos poniendo una variable, ya que la f\u00f3rmula puede ser +1(LT), o sea que la variable la estamos multiplicando por 1<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Las ratios se representan con dos flechas como en la ilustraci\u00f3n que sigue:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"839\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/130613-1024x839.jpg\" alt=\"Ratio de gradaci\u00f3n con incremento de 0.75 en eje Y y 0.50 en eje X desde punto de ancla\" class=\"wp-image-5801\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/130613-1024x839.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/130613-300x246.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/130613-768x630.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/130613-1536x1259.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/130613-2048x1679.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/130613-1320x1082.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Debemos leer la ratio de la siguiente manera, para cada talla superior encontraremos un incremento de 0.75 cm del punto en el eje de la Y lacia la direcci\u00f3n de la flecha y de 0,50 en el eje de las X, para cada talla inferior encontraremos los mismos valores pero con las direcciones opuestas de las tallas que aparecen en la ilustraci\u00f3n.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Pondremos en pr\u00e1ctica todos estos conceptos en el pr\u00f3ximo post: La gradaci\u00f3n de la falda.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Aunque parezca confuso en el pr\u00f3ximo post ver\u00e9is que es&nbsp;\u00a1un juego de ni\u00f1os!.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Este post contin\u00faa en &#8220;<a href=\"http:\/\/www.comocubriruncuerpo.org\/escalado-3-teorema-de-tales-de-mileto-para-dividir-las-entretallas\/\" target=\"_blank\" rel=\"noreferrer noopener\">Gradaci\u00f3n 3: Teorema de Tales de Mileto para dividir las entretallas<\/a>&#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Explicamos c\u00f3mo hallar las ratios en gradaci\u00f3n de patrones a partir de f\u00f3rmulas y secuencias proporcionales. Analizamos la relaci\u00f3n entre variables, incremento constante y l\u00edneas de entretalla sin puntos de quiebre.<\/p>\n","protected":false},"author":1,"featured_media":5801,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1018,962,1],"tags":[44,30,38,674,90,390,392,92,80,362,672,40,42,676],"class_list":["post-5798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo","category-gradacion-es","category-medidas","tag-como-cubrir-un-cuerpo","tag-comocubriruncuerpo","tag-creacion-de-moda","tag-ensenanza-de-patronaje","tag-escuela-de-moda","tag-gradacion","tag-gradacion-2","tag-gradacion-o-escalado","tag-patronaje","tag-patronajemoda","tag-tecnica-de-patronaje","tag-tele-virtual-patronage","tag-televirtualpatronage","tag-tutorial-patonaje"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gradaci\u00f3n - C\u00f3mo hallar las ratios - Tele Virtual Patronage<\/title>\n<meta name=\"description\" content=\"Aprende c\u00f3mo calcular las ratios en gradaci\u00f3n de patrones y entender la inclinaci\u00f3n de las l\u00edneas de entretalla sin puntos de quiebre.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tevipa.com\/blog\/gradacion-como-hallar-las-ratios\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gradaci\u00f3n - C\u00f3mo hallar las ratios - Tele Virtual Patronage\" \/>\n<meta property=\"og:description\" content=\"Aprende c\u00f3mo calcular las ratios en gradaci\u00f3n de patrones y entender la inclinaci\u00f3n de las l\u00edneas de entretalla sin puntos de quiebre.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tevipa.com\/blog\/gradacion-como-hallar-las-ratios\/\" \/>\n<meta property=\"og:site_name\" content=\"Tele Virtual Patronage\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-21T20:29:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-22T16:09:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/130613.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2480\" \/>\n\t<meta property=\"og:image:height\" content=\"2033\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tele Virtual Patronage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tele Virtual Patronage\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/gradacion-como-hallar-las-ratios\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/gradacion-como-hallar-las-ratios\\\/\"},\"author\":{\"name\":\"Tele Virtual Patronage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\"},\"headline\":\"Gradaci\u00f3n &#8211; C\u00f3mo hallar las ratios\",\"datePublished\":\"2026-02-21T20:29:18+00:00\",\"dateModified\":\"2026-02-22T16:09:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/gradacion-como-hallar-las-ratios\\\/\"},\"wordCount\":655,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/gradacion-como-hallar-las-ratios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/130613.jpg\",\"keywords\":[\"como cubrir un cuerpo\",\"comocubriruncuerpo\",\"creaci\u00f3n de moda\",\"ense\u00f1anza de patronaje\",\"escuela de moda\",\"gradaci\u00f3n\",\"gradacion\",\"gradaci\u00f3n o escalado\",\"patronaje\",\"patronajemoda\",\"t\u00e9cnica de patronaje\",\"tele virtual patronage\",\"televirtualpatronage\",\"tutorial patonaje\"],\"articleSection\":[\"Archivo\",\"Gradaci\u00f3n\",\"Medidas\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/gradacion-como-hallar-las-ratios\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/gradacion-como-hallar-las-ratios\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/gradacion-como-hallar-las-ratios\\\/\",\"name\":\"Gradaci\u00f3n - C\u00f3mo hallar las ratios - Tele Virtual Patronage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/gradacion-como-hallar-las-ratios\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/gradacion-como-hallar-las-ratios\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/130613.jpg\",\"datePublished\":\"2026-02-21T20:29:18+00:00\",\"dateModified\":\"2026-02-22T16:09:52+00:00\",\"description\":\"Aprende c\u00f3mo calcular las ratios en gradaci\u00f3n de patrones y entender la inclinaci\u00f3n de las l\u00edneas de entretalla sin puntos de quiebre.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/gradacion-como-hallar-las-ratios\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/gradacion-como-hallar-las-ratios\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/gradacion-como-hallar-las-ratios\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/130613.jpg\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/130613.jpg\",\"width\":2480,\"height\":2033,\"caption\":\"Ratio de gradaci\u00f3n con incremento de 0.75 en eje Y y 0.50 en eje X desde punto de ancla\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/gradacion-como-hallar-las-ratios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gradaci\u00f3n &#8211; C\u00f3mo hallar las ratios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"name\":\"Tele Virtual Patronage\",\"description\":\"Tevipa\",\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\",\"name\":\"Tele Virtual Patronage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"width\":512,\"height\":512,\"caption\":\"Tele Virtual Patronage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\",\"name\":\"Tele Virtual Patronage\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"caption\":\"Tele Virtual Patronage\"},\"sameAs\":[\"https:\\\/\\\/tevipa.com\\\/blog\"],\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/author\\\/tvpadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gradaci\u00f3n - C\u00f3mo hallar las ratios - Tele Virtual Patronage","description":"Aprende c\u00f3mo calcular las ratios en gradaci\u00f3n de patrones y entender la inclinaci\u00f3n de las l\u00edneas de entretalla sin puntos de quiebre.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tevipa.com\/blog\/gradacion-como-hallar-las-ratios\/","og_locale":"it_IT","og_type":"article","og_title":"Gradaci\u00f3n - C\u00f3mo hallar las ratios - Tele Virtual Patronage","og_description":"Aprende c\u00f3mo calcular las ratios en gradaci\u00f3n de patrones y entender la inclinaci\u00f3n de las l\u00edneas de entretalla sin puntos de quiebre.","og_url":"https:\/\/tevipa.com\/blog\/gradacion-como-hallar-las-ratios\/","og_site_name":"Tele Virtual Patronage","article_published_time":"2026-02-21T20:29:18+00:00","article_modified_time":"2026-02-22T16:09:52+00:00","og_image":[{"width":2480,"height":2033,"url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/130613.jpg","type":"image\/jpeg"}],"author":"Tele Virtual Patronage","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Tele Virtual Patronage","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tevipa.com\/blog\/gradacion-como-hallar-las-ratios\/#article","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/gradacion-como-hallar-las-ratios\/"},"author":{"name":"Tele Virtual Patronage","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c"},"headline":"Gradaci\u00f3n &#8211; C\u00f3mo hallar las ratios","datePublished":"2026-02-21T20:29:18+00:00","dateModified":"2026-02-22T16:09:52+00:00","mainEntityOfPage":{"@id":"https:\/\/tevipa.com\/blog\/gradacion-como-hallar-las-ratios\/"},"wordCount":655,"commentCount":0,"publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"image":{"@id":"https:\/\/tevipa.com\/blog\/gradacion-como-hallar-las-ratios\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/130613.jpg","keywords":["como cubrir un cuerpo","comocubriruncuerpo","creaci\u00f3n de moda","ense\u00f1anza de patronaje","escuela de moda","gradaci\u00f3n","gradacion","gradaci\u00f3n o escalado","patronaje","patronajemoda","t\u00e9cnica de patronaje","tele virtual patronage","televirtualpatronage","tutorial patonaje"],"articleSection":["Archivo","Gradaci\u00f3n","Medidas"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tevipa.com\/blog\/gradacion-como-hallar-las-ratios\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tevipa.com\/blog\/gradacion-como-hallar-las-ratios\/","url":"https:\/\/tevipa.com\/blog\/gradacion-como-hallar-las-ratios\/","name":"Gradaci\u00f3n - C\u00f3mo hallar las ratios - Tele Virtual Patronage","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tevipa.com\/blog\/gradacion-como-hallar-las-ratios\/#primaryimage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/gradacion-como-hallar-las-ratios\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/130613.jpg","datePublished":"2026-02-21T20:29:18+00:00","dateModified":"2026-02-22T16:09:52+00:00","description":"Aprende c\u00f3mo calcular las ratios en gradaci\u00f3n de patrones y entender la inclinaci\u00f3n de las l\u00edneas de entretalla sin puntos de quiebre.","breadcrumb":{"@id":"https:\/\/tevipa.com\/blog\/gradacion-como-hallar-las-ratios\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tevipa.com\/blog\/gradacion-como-hallar-las-ratios\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/gradacion-como-hallar-las-ratios\/#primaryimage","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/130613.jpg","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/130613.jpg","width":2480,"height":2033,"caption":"Ratio de gradaci\u00f3n con incremento de 0.75 en eje Y y 0.50 en eje X desde punto de ancla"},{"@type":"BreadcrumbList","@id":"https:\/\/tevipa.com\/blog\/gradacion-como-hallar-las-ratios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tevipa.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Gradaci\u00f3n &#8211; C\u00f3mo hallar las ratios"}]},{"@type":"WebSite","@id":"https:\/\/tevipa.com\/blog\/#website","url":"https:\/\/tevipa.com\/blog\/","name":"Tele Virtual Patronage","description":"Tevipa","publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tevipa.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/tevipa.com\/blog\/#organization","name":"Tele Virtual Patronage","url":"https:\/\/tevipa.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","width":512,"height":512,"caption":"Tele Virtual Patronage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c","name":"Tele Virtual Patronage","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","caption":"Tele Virtual Patronage"},"sameAs":["https:\/\/tevipa.com\/blog"],"url":"https:\/\/tevipa.com\/blog\/author\/tvpadm\/"}]}},"_links":{"self":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/5798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/comments?post=5798"}],"version-history":[{"count":4,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/5798\/revisions"}],"predecessor-version":[{"id":5807,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/5798\/revisions\/5807"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media\/5801"}],"wp:attachment":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media?parent=5798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/categories?post=5798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/tags?post=5798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}