{"id":5088,"date":"2026-02-02T22:06:12","date_gmt":"2026-02-02T21:06:12","guid":{"rendered":"https:\/\/tevipa.com\/blog\/?p=5088"},"modified":"2026-02-04T14:25:54","modified_gmt":"2026-02-04T13:25:54","slug":"ancho-del-rectangulo-de-sisa","status":"publish","type":"post","link":"https:\/\/tevipa.com\/blog\/ancho-del-rectangulo-de-sisa\/","title":{"rendered":"Ancho del rect\u00e1ngulo de sisa"},"content":{"rendered":"\n<p class=\"has-text-align-right has-small-font-size\"><sup><em>Publicado originalmente el&nbsp;<strong>20 Noviembre 2013<\/strong><\/em><\/sup><\/p>\n\n\n<style>.kb-image5088_4bdd62-2a .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image5088_4bdd62-2a is-style-default\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"222\" height=\"300\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg\" alt=\"Logo C\u00f3mo Cubrir un Cuerpo\" class=\"kb-img wp-image-68\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg 222w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-757x1024.jpg 757w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-768x1039.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1135x1536.jpg 1135w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1514x2048.jpg 1514w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran.jpg 1821w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/><\/figure><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\" style=\"font-size:27px\">Ancho del rect\u00e1ngulo de sisa<\/h1>\n\n\n\n<h2 class=\"wp-block-heading text-justify has-medium-font-size\">Ancho del rect\u00e1ngulo de sisa: c\u00f3mo hallarlo<\/h2>\n\n\n\n<p class=\"text-justify\">Partiendo de las medidas &nbsp;ancho de espalda, contorno de pecho y contorno de t\u00f3rax, el ancho del rect\u00e1ngulo de sisa o costadillo podemos obtenerlo de cuatro formas:<\/p>\n\n\n\n<p class=\"text-justify\">a)&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Tomar directamente la medida tripartida sobre el o la cliente. Con la cinta m\u00e9trica siempre paralela al suelo, empezaremos a tomar medida desde la columna vertebral, pasando por debajo del brazo, despu\u00e9s por la punta de pecho o pezones y acabando de nuevo en la columna vertebral. De esta forma encontraremos las medidas de&nbsp;<strong>ancho de espalda<\/strong>&nbsp;y&nbsp;<strong>rect\u00e1ngulo de sisa<\/strong>; el contorno de pecho entero dividido entre dos no dar\u00e1 la&nbsp;<strong>medida de pecho<\/strong>.<\/p>\n\n\n\n<p class=\"text-justify\">C\u00f3mo ya hablamos en post anteriores como \u201c<a href=\"https:\/\/tevipa.com\/blog\/medidas-5-el-contorno-de-pecho-femenino\/\" type=\"link\" id=\"https:\/\/tevipa.com\/blog\/medidas-5-el-contorno-de-pecho-femenino\/\">Medidas (5) El contorno de pecho femenino<\/a>\u201d de C\u00f3mo cubrir un cuerpo, sabemos que el hombre y la mujer \u00a0morfol\u00f3gicamente se diferencian en el desarrollo de pecho. Por eso es importante diferenciar y tener claras las medidas \u00a0de t\u00f3rax y pecho.<\/p>\n\n\n\n<p class=\"text-justify\">En el hombre el contorno de t\u00f3rax y el contorno de pecho se identifican, por tanto esta medida se corresponder\u00eda con la medida de t\u00f3rax femenino ya que no tenemos en cuenta el desarrollo horizontal de pecho (DHP), los pechos.<\/p>\n\n\n\n<p class=\"text-justify\">b)&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; El hombre de conformaci\u00f3n normal tiene el mismo ancho de espalda que el ancho de delantero. La segunda forma de obtener la medida del ancho del rect\u00e1ngulo de sisa es a partir de la medida de t\u00f3rax femenino (t\u00f3rax y pecho masculino), descontando el ancho delante y el ancho detr\u00e1s.<\/p>\n\n\n\n<p class=\"text-justify\">En el caso de no disponer de la medida de la caja del delantero podemos descontar dos veces el ancho de espalda ya que en una conformaci\u00f3n normal son iguales.<\/p>\n\n\n\n<p class=\"text-justify\">c)&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; La tercera forma ser\u00eda aplicando a la l\u00ednea de costadillo del ancho de espalda la proporci\u00f3n de 1\/6 de la medida de pecho que dar\u00eda como resultado la medida del ancho del rect\u00e1ngulo de sisa, obteniendo as\u00ed la l\u00ednea de avance de costadillo. Esta proporci\u00f3n s\u00f3lo funcionar\u00eda con tallas centrales y para prendas ce\u00f1idas al cuerpo, con holgura igual a cero.<\/p>\n\n\n\n<p class=\"text-justify\">d)&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Si no disponemos de la medida del ancho de espalda, tomamos la medida de t\u00f3rax y dividimos \u00e9sta entre dos obteniendo la l\u00ednea de mitad de cuerpo. A caballo de esta l\u00ednea aplicamos 1\/12 de pecho (la mitad del sexto del punto anterior). La l\u00ednea de costura lateral se situar\u00e1 a la mitad del cuadrado de sisa.<\/p>\n\n\n\n<p class=\"text-justify\">Recalcamos ya que es importante que esta proporci\u00f3n de 1\/6 s\u00f3lo funciona en tallas centrales y para prendas ce\u00f1idas al cuerpo, con holgura igual a cero.<\/p>\n\n\n\n<p class=\"text-justify\">La imagen siguiente ilustra nuestras explicaciones:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\" id=\"attachment_1806\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/131120rectangulo-de-sisa-724x1024.jpg\" alt=\"Esquema del ancho del rect\u00e1ngulo de sisa con ancho de espalda, contorno de pecho, contorno de t\u00f3rax y avance de costadillo\" class=\"wp-image-5090\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/131120rectangulo-de-sisa-724x1024.jpg 724w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/131120rectangulo-de-sisa-212x300.jpg 212w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/131120rectangulo-de-sisa-768x1086.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/131120rectangulo-de-sisa-1086x1536.jpg 1086w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/131120rectangulo-de-sisa-1448x2048.jpg 1448w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/131120rectangulo-de-sisa-1320x1867.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/131120rectangulo-de-sisa-scaled.jpg 1810w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><figcaption class=\"wp-element-caption\">ancho del rect\u00e1ngulo de sisa<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>En este post analizamos c\u00f3mo determinar el ancho del rect\u00e1ngulo de sisa en el patronaje base a partir de distintas medidas corporales fundamentales. Se explican varios m\u00e9todos de c\u00e1lculo, desde la medici\u00f3n directa sobre el cuerpo hasta la aplicaci\u00f3n de proporciones geom\u00e9tricas, teniendo en cuenta las diferencias morfol\u00f3gicas entre hombre y mujer. Un contenido clave para comprender la correcta colocaci\u00f3n del costadillo y de la costura lateral en prendas ce\u00f1idas al cuerpo.<\/p>\n","protected":false},"author":1,"featured_media":5090,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1018,1],"tags":[44,30,38,674,90,116,80,362,672,40,42,676],"class_list":["post-5088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo","category-medidas","tag-como-cubrir-un-cuerpo","tag-comocubriruncuerpo","tag-creacion-de-moda","tag-ensenanza-de-patronaje","tag-escuela-de-moda","tag-medidas","tag-patronaje","tag-patronajemoda","tag-tecnica-de-patronaje","tag-tele-virtual-patronage","tag-televirtualpatronage","tag-tutorial-patonaje"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ancho del rect\u00e1ngulo de sisa - Tele Virtual Patronage<\/title>\n<meta name=\"description\" content=\"C\u00f3mo hallar el ancho del rect\u00e1ngulo de sisa en patronaje a partir del ancho de espalda, el contorno de pecho y el contorno de t\u00f3rax. M\u00e9todos de medici\u00f3n, proporciones y criterios seg\u00fan conformaci\u00f3n y ajuste de la prenda.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tevipa.com\/blog\/ancho-del-rectangulo-de-sisa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ancho del rect\u00e1ngulo de sisa - Tele Virtual Patronage\" \/>\n<meta property=\"og:description\" content=\"C\u00f3mo hallar el ancho del rect\u00e1ngulo de sisa en patronaje a partir del ancho de espalda, el contorno de pecho y el contorno de t\u00f3rax. M\u00e9todos de medici\u00f3n, proporciones y criterios seg\u00fan conformaci\u00f3n y ajuste de la prenda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tevipa.com\/blog\/ancho-del-rectangulo-de-sisa\/\" \/>\n<meta property=\"og:site_name\" content=\"Tele Virtual Patronage\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-02T21:06:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-04T13:25:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/131120rectangulo-de-sisa-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1810\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tele Virtual Patronage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tele Virtual Patronage\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/ancho-del-rectangulo-de-sisa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/ancho-del-rectangulo-de-sisa\\\/\"},\"author\":{\"name\":\"Tele Virtual Patronage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\"},\"headline\":\"Ancho del rect\u00e1ngulo de sisa\",\"datePublished\":\"2026-02-02T21:06:12+00:00\",\"dateModified\":\"2026-02-04T13:25:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/ancho-del-rectangulo-de-sisa\\\/\"},\"wordCount\":513,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/ancho-del-rectangulo-de-sisa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/131120rectangulo-de-sisa-scaled.jpg\",\"keywords\":[\"como cubrir un cuerpo\",\"comocubriruncuerpo\",\"creaci\u00f3n de moda\",\"ense\u00f1anza de patronaje\",\"escuela de moda\",\"medidas\",\"patronaje\",\"patronajemoda\",\"t\u00e9cnica de patronaje\",\"tele virtual patronage\",\"televirtualpatronage\",\"tutorial patonaje\"],\"articleSection\":[\"Archivo\",\"Medidas\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/ancho-del-rectangulo-de-sisa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/ancho-del-rectangulo-de-sisa\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/ancho-del-rectangulo-de-sisa\\\/\",\"name\":\"Ancho del rect\u00e1ngulo de sisa - Tele Virtual Patronage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/ancho-del-rectangulo-de-sisa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/ancho-del-rectangulo-de-sisa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/131120rectangulo-de-sisa-scaled.jpg\",\"datePublished\":\"2026-02-02T21:06:12+00:00\",\"dateModified\":\"2026-02-04T13:25:54+00:00\",\"description\":\"C\u00f3mo hallar el ancho del rect\u00e1ngulo de sisa en patronaje a partir del ancho de espalda, el contorno de pecho y el contorno de t\u00f3rax. M\u00e9todos de medici\u00f3n, proporciones y criterios seg\u00fan conformaci\u00f3n y ajuste de la prenda.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/ancho-del-rectangulo-de-sisa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/ancho-del-rectangulo-de-sisa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/ancho-del-rectangulo-de-sisa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/131120rectangulo-de-sisa-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/131120rectangulo-de-sisa-scaled.jpg\",\"width\":1810,\"height\":2560,\"caption\":\"ancho del rect\u00e1ngulo de sisa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/ancho-del-rectangulo-de-sisa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ancho del rect\u00e1ngulo de sisa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"name\":\"Tele Virtual Patronage\",\"description\":\"Tevipa\",\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\",\"name\":\"Tele Virtual Patronage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"width\":512,\"height\":512,\"caption\":\"Tele Virtual Patronage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\",\"name\":\"Tele Virtual Patronage\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"caption\":\"Tele Virtual Patronage\"},\"sameAs\":[\"https:\\\/\\\/tevipa.com\\\/blog\"],\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/author\\\/tvpadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ancho del rect\u00e1ngulo de sisa - Tele Virtual Patronage","description":"C\u00f3mo hallar el ancho del rect\u00e1ngulo de sisa en patronaje a partir del ancho de espalda, el contorno de pecho y el contorno de t\u00f3rax. M\u00e9todos de medici\u00f3n, proporciones y criterios seg\u00fan conformaci\u00f3n y ajuste de la prenda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tevipa.com\/blog\/ancho-del-rectangulo-de-sisa\/","og_locale":"it_IT","og_type":"article","og_title":"Ancho del rect\u00e1ngulo de sisa - Tele Virtual Patronage","og_description":"C\u00f3mo hallar el ancho del rect\u00e1ngulo de sisa en patronaje a partir del ancho de espalda, el contorno de pecho y el contorno de t\u00f3rax. M\u00e9todos de medici\u00f3n, proporciones y criterios seg\u00fan conformaci\u00f3n y ajuste de la prenda.","og_url":"https:\/\/tevipa.com\/blog\/ancho-del-rectangulo-de-sisa\/","og_site_name":"Tele Virtual Patronage","article_published_time":"2026-02-02T21:06:12+00:00","article_modified_time":"2026-02-04T13:25:54+00:00","og_image":[{"width":1810,"height":2560,"url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/131120rectangulo-de-sisa-scaled.jpg","type":"image\/jpeg"}],"author":"Tele Virtual Patronage","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Tele Virtual Patronage","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tevipa.com\/blog\/ancho-del-rectangulo-de-sisa\/#article","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/ancho-del-rectangulo-de-sisa\/"},"author":{"name":"Tele Virtual Patronage","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c"},"headline":"Ancho del rect\u00e1ngulo de sisa","datePublished":"2026-02-02T21:06:12+00:00","dateModified":"2026-02-04T13:25:54+00:00","mainEntityOfPage":{"@id":"https:\/\/tevipa.com\/blog\/ancho-del-rectangulo-de-sisa\/"},"wordCount":513,"commentCount":0,"publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"image":{"@id":"https:\/\/tevipa.com\/blog\/ancho-del-rectangulo-de-sisa\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/131120rectangulo-de-sisa-scaled.jpg","keywords":["como cubrir un cuerpo","comocubriruncuerpo","creaci\u00f3n de moda","ense\u00f1anza de patronaje","escuela de moda","medidas","patronaje","patronajemoda","t\u00e9cnica de patronaje","tele virtual patronage","televirtualpatronage","tutorial patonaje"],"articleSection":["Archivo","Medidas"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tevipa.com\/blog\/ancho-del-rectangulo-de-sisa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tevipa.com\/blog\/ancho-del-rectangulo-de-sisa\/","url":"https:\/\/tevipa.com\/blog\/ancho-del-rectangulo-de-sisa\/","name":"Ancho del rect\u00e1ngulo de sisa - Tele Virtual Patronage","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tevipa.com\/blog\/ancho-del-rectangulo-de-sisa\/#primaryimage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/ancho-del-rectangulo-de-sisa\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/131120rectangulo-de-sisa-scaled.jpg","datePublished":"2026-02-02T21:06:12+00:00","dateModified":"2026-02-04T13:25:54+00:00","description":"C\u00f3mo hallar el ancho del rect\u00e1ngulo de sisa en patronaje a partir del ancho de espalda, el contorno de pecho y el contorno de t\u00f3rax. M\u00e9todos de medici\u00f3n, proporciones y criterios seg\u00fan conformaci\u00f3n y ajuste de la prenda.","breadcrumb":{"@id":"https:\/\/tevipa.com\/blog\/ancho-del-rectangulo-de-sisa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tevipa.com\/blog\/ancho-del-rectangulo-de-sisa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/ancho-del-rectangulo-de-sisa\/#primaryimage","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/131120rectangulo-de-sisa-scaled.jpg","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/131120rectangulo-de-sisa-scaled.jpg","width":1810,"height":2560,"caption":"ancho del rect\u00e1ngulo de sisa"},{"@type":"BreadcrumbList","@id":"https:\/\/tevipa.com\/blog\/ancho-del-rectangulo-de-sisa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tevipa.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Ancho del rect\u00e1ngulo de sisa"}]},{"@type":"WebSite","@id":"https:\/\/tevipa.com\/blog\/#website","url":"https:\/\/tevipa.com\/blog\/","name":"Tele Virtual Patronage","description":"Tevipa","publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tevipa.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/tevipa.com\/blog\/#organization","name":"Tele Virtual Patronage","url":"https:\/\/tevipa.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","width":512,"height":512,"caption":"Tele Virtual Patronage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c","name":"Tele Virtual Patronage","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","caption":"Tele Virtual Patronage"},"sameAs":["https:\/\/tevipa.com\/blog"],"url":"https:\/\/tevipa.com\/blog\/author\/tvpadm\/"}]}},"_links":{"self":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/5088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/comments?post=5088"}],"version-history":[{"count":2,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/5088\/revisions"}],"predecessor-version":[{"id":5091,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/5088\/revisions\/5091"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media\/5090"}],"wp:attachment":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media?parent=5088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/categories?post=5088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/tags?post=5088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}