{"id":5040,"date":"2026-02-02T15:29:17","date_gmt":"2026-02-02T14:29:17","guid":{"rendered":"https:\/\/tevipa.com\/blog\/?p=5040"},"modified":"2026-02-02T15:34:44","modified_gmt":"2026-02-02T14:34:44","slug":"patron-de-las-polainas","status":"publish","type":"post","link":"https:\/\/tevipa.com\/blog\/patron-de-las-polainas\/","title":{"rendered":"Patr\u00f3n de las polainas"},"content":{"rendered":"\n<p class=\"has-text-align-right has-small-font-size wp-block-paragraph\"><sup><em>Publicado originalmente el&nbsp;<strong>24 Enero 2014<\/strong><\/em><\/sup><\/p>\n\n\n<style>.kb-image5040_713699-cb .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image5040_713699-cb is-style-default\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"222\" height=\"300\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg\" alt=\"Logo C\u00f3mo Cubrir un Cuerpo\" class=\"kb-img wp-image-68\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg 222w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-757x1024.jpg 757w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-768x1039.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1135x1536.jpg 1135w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1514x2048.jpg 1514w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran.jpg 1821w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/><\/figure><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\" style=\"font-size:27px\">Patr\u00f3n de las polainas<\/h1>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"563\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_00-563x1024.jpg\" alt=\"Ilustraci\u00f3n dibujada de una polaina con hebilla de sujeci\u00f3n al pie\" class=\"wp-image-5044\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_00-563x1024.jpg 563w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_00-165x300.jpg 165w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_00-768x1397.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_00-845x1536.jpg 845w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_00-1126x2048.jpg 1126w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_00-1320x2401.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_00-scaled.jpg 1408w\" sizes=\"auto, (max-width: 563px) 100vw, 563px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Ya hablamos en C\u00f3mo cubrir un cuerpo del\u00a0<a href=\"https:\/\/tevipa.com\/blog\/patron-base-de-la-polaina\/\" type=\"link\" id=\"https:\/\/tevipa.com\/blog\/patron-base-de-la-polaina\/\">patr\u00f3n base de las polainas<\/a>, pod\u00e9is pinchar en el enlace para consultarlo.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Para saber m\u00e1s de las polaina pod\u00e9is consultar el post \u00ab<a href=\"https:\/\/tevipa.com\/blog\/historia-de-las-polainas\/\" type=\"link\" id=\"https:\/\/tevipa.com\/blog\/historia-de-las-polainas\/\">Historia de las polainas<\/a>\u00bb donde encontrareis la descripci\u00f3n, tipolog\u00edas, origen y evoluci\u00f3n de las mismas, en la p\u00e1gina C\u00f3mo se patron\u00f3 un cuerpo.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">En este post patronaremos una polaina que ir\u00e1 desde la l\u00ednea de jarrete hasta el empeine. Se sujetar\u00e1 por debajo del zapato mediante una hebilla y tendr\u00e1 dos costuras, una delante y otra detr\u00e1s de la pierna.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Veremos en la siguiente ilustraci\u00f3n, las piezas de la pierna que sacamos del moulage que realizamos a partir del modelo. De \u00e9stas utilizaremos la cuatro y la cinco, que hemos evidenciado en rojo.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"920\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_01-920x1024.jpg\" alt=\"Despiece de la pierna obtenido del moulage con las piezas cuatro y cinco destacadas para patronar la polaina\" class=\"wp-image-5045\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_01-920x1024.jpg 920w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_01-270x300.jpg 270w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_01-768x854.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_01-1381x1536.jpg 1381w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_01-1841x2048.jpg 1841w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_01-1320x1469.jpg 1320w\" sizes=\"auto, (max-width: 920px) 100vw, 920px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Retomaremos la imagen del post \u201c<a href=\"https:\/\/tevipa.com\/blog\/despiece-de-la-pierna-en-dos-niveles-y-patronaje\/\" type=\"link\" id=\"https:\/\/tevipa.com\/blog\/despiece-de-la-pierna-en-dos-niveles-y-patronaje\/\">Despiece de la pierna en dos niveles y patronaje<\/a>\u201d, en la cual hemos unidos las piezas de forma que nos ha quedado una costura en la parte de atr\u00e1s de la pierna y otra costura delante.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Observamos tres pinzas, marcadas en l\u00edneas discontinuas, que no tendremos en cuenta en el patr\u00f3n, la propia holgura de la polaina las absorber\u00e1.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"961\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_02-1024x961.jpg\" alt=\"Uni\u00f3n por patronaje de las piezas de la pierna con costura delantera y trasera y pinzas indicadas en l\u00ednea discontinua\" class=\"wp-image-5046\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_02-1024x961.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_02-300x281.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_02-768x721.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_02-1536x1441.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_02-2048x1922.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_02-1320x1239.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Mediante circunferencias de radio igual a 0.75 cm para provocar una holgura de 3 cm que se repartir\u00e1n en las 4 costuras, dos mitad delante y dos mitad detr\u00e1s.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Retrazaremos las costuras teniendo en cuenta esta holgura de tres cent\u00edmetros.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"693\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_03-1024x693.jpg\" alt=\"Retr trazado de las costuras de la polaina aplicando una holgura total de 3 cm mediante circunferencias de 0,75 cm\" class=\"wp-image-5047\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_03-1024x693.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_03-300x203.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_03-768x520.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_03-1536x1040.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_03-2048x1387.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_03-1320x894.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Bajaremos la costura superior de la pieza&nbsp;cuatro en 5 cm, para que la polaina llegue exactamente debajo de la rodilla. Recordemos que esta pieza cuatro empezaba en&nbsp;la l\u00ednea de rodilla, la cual tiene unos cinco&nbsp;cm de diferencia con la l\u00ednea de jarrete.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Esta modificaci\u00f3n de la costura la realizaremos mediante circunferencias con radio igual a 5 cm y volveremos a trazar las l\u00edneas, en la imagen se ha evidenciado la nueva l\u00ednea en color azul.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"639\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_04-1024x639.jpg\" alt=\"Bajada de la costura superior de la pieza cuatro en 5 cm mediante circunferencias para ajustar la polaina bajo la rodilla\" class=\"wp-image-5048\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_04-1024x639.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_04-300x187.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_04-768x479.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_04-1536x958.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_04-2048x1278.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_04-1320x823.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Por \u00faltimo patronaremos la pieza que sujetar\u00e1 la polaina propiamente dicha con el pie, junto la hebilla que nos dar\u00e1 la sujeci\u00f3n.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Teniendo en cuenta las medidas, &nbsp;de tobillo a suelo tenemos unos 7 cm para la polaina, 6cm para el ancho del pie o hebilla, &nbsp;la pieza m\u00e1s larga del cierre medir\u00e1 3 cm m\u00e1s, o sea 9cm para poder abrocharla.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"978\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_05-978x1024.jpg\" alt=\"Patr\u00f3n de la pieza de sujeci\u00f3n de la polaina al pie con hebilla y medidas de cierre\" class=\"wp-image-5049\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_05-978x1024.jpg 978w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_05-286x300.jpg 286w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_05-768x804.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_05-1467x1536.jpg 1467w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_05-1956x2048.jpg 1956w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_05-1320x1382.jpg 1320w\" sizes=\"auto, (max-width: 978px) 100vw, 978px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Suavizaremos las l\u00edneas que hemos trazado en azul y las puntas que vemos en el trazado.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Comprobaremos que las costuras que tendr\u00e1n que coserse tengan la misma medida para que sea correcta la confecci\u00f3n posterior.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">El patr\u00f3n de la polaina ser\u00e1 el siguiente:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"911\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_06-911x1024.jpg\" alt=\"Patr\u00f3n final de la polaina con l\u00edneas suavizadas y costuras comprobadas para la confecci\u00f3n\" class=\"wp-image-5050\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_06-911x1024.jpg 911w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_06-267x300.jpg 267w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_06-768x864.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_06-1366x1536.jpg 1366w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_06-1821x2048.jpg 1821w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_06-1320x1484.jpg 1320w\" sizes=\"auto, (max-width: 911px) 100vw, 911px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>En este post se desarrolla el patr\u00f3n de una polaina a partir del moulage de la pierna, desde la l\u00ednea de jarrete hasta el empeine. A partir de las piezas obtenidas del modelado, se construye una polaina con dos costuras \u2014delantera y trasera\u2014 incorporando la holgura necesaria para su correcta funcionalidad.<\/p>\n<p>Se explica c\u00f3mo redistribuir las costuras, ajustar la altura bajo la rodilla, eliminar pinzas innecesarias y dise\u00f1ar el sistema de sujeci\u00f3n al pie mediante hebilla. Un proceso completo de patronaje t\u00e9cnico pensado tanto para la comprensi\u00f3n del volumen como para una confecci\u00f3n precisa y coherente.<\/p>\n","protected":false},"author":1,"featured_media":5044,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1018,1341,23,1814],"tags":[44,30,1377,38,674,90,104,80,362,82,1816,672,40,42,676],"class_list":["post-5040","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo","category-complemento","category-patron","category-polainas","tag-como-cubrir-un-cuerpo","tag-comocubriruncuerpo","tag-complemento","tag-creacion-de-moda","tag-ensenanza-de-patronaje","tag-escuela-de-moda","tag-patron","tag-patronaje","tag-patronajemoda","tag-patrones","tag-polainas","tag-tecnica-de-patronaje","tag-tele-virtual-patronage","tag-televirtualpatronage","tag-tutorial-patonaje"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Patr\u00f3n de las polainas - Tele Virtual Patronage<\/title>\n<meta name=\"description\" content=\"Patronaje paso a paso de una polaina desde el moulage de la pierna. Desarrollo del patr\u00f3n con dos costuras, holguras controladas y sistema de sujeci\u00f3n al pie mediante hebilla.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tevipa.com\/blog\/patron-de-las-polainas\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Patr\u00f3n de las polainas - Tele Virtual Patronage\" \/>\n<meta property=\"og:description\" content=\"Patronaje paso a paso de una polaina desde el moulage de la pierna. Desarrollo del patr\u00f3n con dos costuras, holguras controladas y sistema de sujeci\u00f3n al pie mediante hebilla.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tevipa.com\/blog\/patron-de-las-polainas\/\" \/>\n<meta property=\"og:site_name\" content=\"Tele Virtual Patronage\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-02T14:29:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-02T14:34:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_00-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1408\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tele Virtual Patronage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tele Virtual Patronage\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/patron-de-las-polainas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/patron-de-las-polainas\\\/\"},\"author\":{\"name\":\"Tele Virtual Patronage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\"},\"headline\":\"Patr\u00f3n de las polainas\",\"datePublished\":\"2026-02-02T14:29:17+00:00\",\"dateModified\":\"2026-02-02T14:34:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/patron-de-las-polainas\\\/\"},\"wordCount\":454,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/patron-de-las-polainas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/140124_Patron_polaina_00-scaled.jpg\",\"keywords\":[\"como cubrir un cuerpo\",\"comocubriruncuerpo\",\"Complemento\",\"creaci\u00f3n de moda\",\"ense\u00f1anza de patronaje\",\"escuela de moda\",\"patron\",\"patronaje\",\"patronajemoda\",\"patrones\",\"polainas\",\"t\u00e9cnica de patronaje\",\"tele virtual patronage\",\"televirtualpatronage\",\"tutorial patonaje\"],\"articleSection\":[\"Archivo\",\"Complemento\",\"Patr\u00f3n\",\"Polainas\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/patron-de-las-polainas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/patron-de-las-polainas\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/patron-de-las-polainas\\\/\",\"name\":\"Patr\u00f3n de las polainas - Tele Virtual Patronage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/patron-de-las-polainas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/patron-de-las-polainas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/140124_Patron_polaina_00-scaled.jpg\",\"datePublished\":\"2026-02-02T14:29:17+00:00\",\"dateModified\":\"2026-02-02T14:34:44+00:00\",\"description\":\"Patronaje paso a paso de una polaina desde el moulage de la pierna. Desarrollo del patr\u00f3n con dos costuras, holguras controladas y sistema de sujeci\u00f3n al pie mediante hebilla.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/patron-de-las-polainas\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/patron-de-las-polainas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/patron-de-las-polainas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/140124_Patron_polaina_00-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/140124_Patron_polaina_00-scaled.jpg\",\"width\":1408,\"height\":2560,\"caption\":\"Ilustraci\u00f3n dibujada de una polaina con hebilla de sujeci\u00f3n al pie\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/patron-de-las-polainas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Patr\u00f3n de las polainas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"name\":\"Tele Virtual Patronage\",\"description\":\"Tevipa\",\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\",\"name\":\"Tele Virtual Patronage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"width\":512,\"height\":512,\"caption\":\"Tele Virtual Patronage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\",\"name\":\"Tele Virtual Patronage\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"caption\":\"Tele Virtual Patronage\"},\"sameAs\":[\"https:\\\/\\\/tevipa.com\\\/blog\"],\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/author\\\/tvpadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Patr\u00f3n de las polainas - Tele Virtual Patronage","description":"Patronaje paso a paso de una polaina desde el moulage de la pierna. Desarrollo del patr\u00f3n con dos costuras, holguras controladas y sistema de sujeci\u00f3n al pie mediante hebilla.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tevipa.com\/blog\/patron-de-las-polainas\/","og_locale":"it_IT","og_type":"article","og_title":"Patr\u00f3n de las polainas - Tele Virtual Patronage","og_description":"Patronaje paso a paso de una polaina desde el moulage de la pierna. Desarrollo del patr\u00f3n con dos costuras, holguras controladas y sistema de sujeci\u00f3n al pie mediante hebilla.","og_url":"https:\/\/tevipa.com\/blog\/patron-de-las-polainas\/","og_site_name":"Tele Virtual Patronage","article_published_time":"2026-02-02T14:29:17+00:00","article_modified_time":"2026-02-02T14:34:44+00:00","og_image":[{"width":1408,"height":2560,"url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_00-scaled.jpg","type":"image\/jpeg"}],"author":"Tele Virtual Patronage","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Tele Virtual Patronage","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tevipa.com\/blog\/patron-de-las-polainas\/#article","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/patron-de-las-polainas\/"},"author":{"name":"Tele Virtual Patronage","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c"},"headline":"Patr\u00f3n de las polainas","datePublished":"2026-02-02T14:29:17+00:00","dateModified":"2026-02-02T14:34:44+00:00","mainEntityOfPage":{"@id":"https:\/\/tevipa.com\/blog\/patron-de-las-polainas\/"},"wordCount":454,"commentCount":0,"publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"image":{"@id":"https:\/\/tevipa.com\/blog\/patron-de-las-polainas\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_00-scaled.jpg","keywords":["como cubrir un cuerpo","comocubriruncuerpo","Complemento","creaci\u00f3n de moda","ense\u00f1anza de patronaje","escuela de moda","patron","patronaje","patronajemoda","patrones","polainas","t\u00e9cnica de patronaje","tele virtual patronage","televirtualpatronage","tutorial patonaje"],"articleSection":["Archivo","Complemento","Patr\u00f3n","Polainas"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tevipa.com\/blog\/patron-de-las-polainas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tevipa.com\/blog\/patron-de-las-polainas\/","url":"https:\/\/tevipa.com\/blog\/patron-de-las-polainas\/","name":"Patr\u00f3n de las polainas - Tele Virtual Patronage","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tevipa.com\/blog\/patron-de-las-polainas\/#primaryimage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/patron-de-las-polainas\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_00-scaled.jpg","datePublished":"2026-02-02T14:29:17+00:00","dateModified":"2026-02-02T14:34:44+00:00","description":"Patronaje paso a paso de una polaina desde el moulage de la pierna. Desarrollo del patr\u00f3n con dos costuras, holguras controladas y sistema de sujeci\u00f3n al pie mediante hebilla.","breadcrumb":{"@id":"https:\/\/tevipa.com\/blog\/patron-de-las-polainas\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tevipa.com\/blog\/patron-de-las-polainas\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/patron-de-las-polainas\/#primaryimage","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_00-scaled.jpg","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/02\/140124_Patron_polaina_00-scaled.jpg","width":1408,"height":2560,"caption":"Ilustraci\u00f3n dibujada de una polaina con hebilla de sujeci\u00f3n al pie"},{"@type":"BreadcrumbList","@id":"https:\/\/tevipa.com\/blog\/patron-de-las-polainas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tevipa.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Patr\u00f3n de las polainas"}]},{"@type":"WebSite","@id":"https:\/\/tevipa.com\/blog\/#website","url":"https:\/\/tevipa.com\/blog\/","name":"Tele Virtual Patronage","description":"Tevipa","publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tevipa.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/tevipa.com\/blog\/#organization","name":"Tele Virtual Patronage","url":"https:\/\/tevipa.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","width":512,"height":512,"caption":"Tele Virtual Patronage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c","name":"Tele Virtual Patronage","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","caption":"Tele Virtual Patronage"},"sameAs":["https:\/\/tevipa.com\/blog"],"url":"https:\/\/tevipa.com\/blog\/author\/tvpadm\/"}]}},"_links":{"self":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/5040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/comments?post=5040"}],"version-history":[{"count":5,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/5040\/revisions"}],"predecessor-version":[{"id":5053,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/5040\/revisions\/5053"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media\/5044"}],"wp:attachment":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media?parent=5040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/categories?post=5040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/tags?post=5040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}