{"id":4743,"date":"2026-01-27T21:37:46","date_gmt":"2026-01-27T20:37:46","guid":{"rendered":"https:\/\/tevipa.com\/blog\/?p=4743"},"modified":"2026-01-27T22:17:23","modified_gmt":"2026-01-27T21:17:23","slug":"puesta-a-plano-de-la-glasilla-del-bustier","status":"publish","type":"post","link":"https:\/\/tevipa.com\/blog\/puesta-a-plano-de-la-glasilla-del-bustier\/","title":{"rendered":"Puesta a plano de la glasilla del bustier"},"content":{"rendered":"\n<p class=\"has-text-align-right has-small-font-size wp-block-paragraph\"><sup><em>Publicado originalmente el&nbsp;<strong>1 Abril 2014<\/strong><\/em><\/sup><\/p>\n\n\n<style>.kb-image4743_cc28c2-34 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image4743_cc28c2-34 is-style-default\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"222\" height=\"300\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg\" alt=\"Logo C\u00f3mo Cubrir un Cuerpo\" class=\"kb-img wp-image-68\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg 222w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-757x1024.jpg 757w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-768x1039.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1135x1536.jpg 1135w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1514x2048.jpg 1514w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran.jpg 1821w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/><\/figure><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\" style=\"font-size:27px\">Puesta a plano de la glasilla del bustier<\/h1>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">La puesta a plano de la glasilla consiste en transformar las piezas de la glasilla en un patr\u00f3n.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Este post es la continuaci\u00f3n del anterior. \u201c<a href=\"https:\/\/tevipa.com\/blog\/moulage-del-bustier-de-cuatro-piezas\/\" type=\"link\" id=\"https:\/\/tevipa.com\/blog\/moulage-del-bustier-de-cuatro-piezas\/\">Moulage del bustier de cuatro piezas<\/a>\u201d<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Para realizar esta operaci\u00f3n necesitaremos una tabla de patronaje o una tabla de madera, una ruleta, papel kraft, regla escuadra y regla de curvas.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">La tabla de patronaje es una tabla de madera recubierta de guata y forrada con una loneta, suelen ser de colores sufridos para que no se manchen. Una tabla de madera sirve de la misma forma o un cart\u00f3n grueso prensado. Para pasar la ruleta es necesario tener una superficie blanda.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Dejamos nuestro bustier en el siguiente estado:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"789\" height=\"521\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/140328_-moulage-bustier_12.gif\" alt=\"Glasilla del bustier de cuatro piezas puesta a plano por ambas caras\" class=\"wp-image-4738\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">El primer paso para poner a plano una glasilla es desmontar cada una de las piezas. Sacaremos los alfileres con cuidado y antes de ello miraremos que hayamos marcado los piquetes que correspondan y&nbsp; la costura del lado en la pieza que no tiene pesta\u00f1a, tal y como mostramos en la siguiente ilustraci\u00f3n.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Con la u\u00f1a marcaremos el pliegue que presente la tela tanto en la parte de costura como el escote&nbsp;y el bajo.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"842\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/02.gif\" alt=\"Desmontaje de las piezas de la glasilla del bustier con los piquetes y la costura del lado previamente marcados antes de ponerlas a plano.\" class=\"wp-image-4745\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Luego abriremos las pesta\u00f1as&nbsp;que nos mostrar\u00e1n claramente los pliegues que hemos re-marcado con la u\u00f1a.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"842\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/03.gif\" alt=\"Apertura de las pesta\u00f1as de la glasilla del bustier mostrando los pliegues marcados previamente con la u\u00f1a.\" class=\"wp-image-4746\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Evidenciaremos, mediante una serie de puntos, la marca del pliegue que nos determinar\u00e1n las costuras de la pieza.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"842\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/04.gif\" alt=\"Marcado mediante puntos de los pliegues de la glasilla del bustier para determinar las l\u00edneas de costura de la pieza.\" class=\"wp-image-4747\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Trazaremos las l\u00edneas siguiendo las marcas con la ayuda de la regla recta o la regla de curvas.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"842\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/05.gif\" alt=\"Trazado de las l\u00edneas de costura sobre la glasilla del bustier siguiendo las marcas del pliegue con regla recta y regla de curvas.\" class=\"wp-image-4751\"\/><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"842\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/06.gif\" alt=\"Continuaci\u00f3n del trazado de las l\u00edneas de la pieza del bustier sobre la glasilla utilizando regla de curvas.\" class=\"wp-image-4752\"\/><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"842\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/07.gif\" alt=\"Ajuste del trazado definitivo de la pieza de glasilla del bustier antes de su puesta a plano.\" class=\"wp-image-4753\"\/><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"842\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/08.gif\" alt=\"Definici\u00f3n completa del contorno de la pieza de glasilla del bustier tras el trazado de las l\u00edneas.\" class=\"wp-image-4754\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">La pieza trazada sobre la glasilla tendr\u00e1 este aspecto final:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"842\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/09.gif\" alt=\"Aspecto final de la pieza del bustier trazada sobre la glasilla antes de la puesta a plano.\" class=\"wp-image-4757\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Marcaremos en el piquete de uni\u00f3n de las piezas, en nuestro caso hemos decidido hacerlo en la cintura, un n\u00famero o una letra para que en la fase de montaje sepamos el orden y la orientaci\u00f3n de cada una de las piezas \u00ad.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Procederemos con las piezas sucesivas de la misma forma.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">En algunos puntos, como en la imagen que sigue, veremos que la l\u00ednea de curvas no nos da la l\u00ednea que deseamos: en este caso est\u00e1 muy claro que queremos que la parte del descote siga una l\u00ednea curva continua y no que tenga dos partes c\u00f3ncavas y una convexa. Rectificaremos la l\u00ednea.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"842\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/10.gif\" alt=\"Rectificaci\u00f3n del trazado del escote sobre la glasilla para obtener una curva continua cuando la regla de curvas no da la l\u00ednea deseada.\" class=\"wp-image-4761\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">La costura del entalle de pecho es la m\u00e1s delicada ya que es la que nos moldear\u00e1 la forma del seno. Por ello pondremos especial atenci\u00f3n al trazo de las costuras con la l\u00ednea de curvas o pistola. No debemos olvidar el piquete de la punta de pecho ni el de cintura, que nos ser\u00e1n esenciales a la hora de montar el cuerpo.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"842\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/11.gif\" alt=\"Trazado de la costura del entalle de pecho en la glasilla del bustier con especial atenci\u00f3n a la l\u00ednea de curvas y los piquetes.\" class=\"wp-image-4762\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Las piezas de glasilla puestas a plano tendr\u00e1n el siguiente aspecto:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"842\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/12.gif\" alt=\"Conjunto de piezas de la glasilla del bustier una vez puestas a plano tras el trazado completo.\" class=\"wp-image-4763\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Colocaremos papel kraft por&nbsp;encima de la tabla y por debajo de las piezas, luego ruletearemos todas las l\u00edneas que hemos trazado en las piezas de la glasilla.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"842\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/122.gif\" alt=\"Ruleteado de las piezas de la glasilla del bustier sobre papel kraft para transferir las l\u00edneas trazadas.\" class=\"wp-image-4764\"\/><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"842\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/14.gif\" alt=\"L\u00edneas transferidas al papel kraft tras el ruleteado de las piezas de la glasilla del bustier.\" class=\"wp-image-4765\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Una vez ruleteadas todas las l\u00edneas las re-trazaremos en el papel.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">En la pieza de mitad de espalda acabaremos la pieza a 90 grados con la l\u00ednea de mitad de espalda, as\u00ed si debi\u00e9ramos dar un re-largo, lo trazar\u00edamos a escuadra a la mitad detr\u00e1s simplificando la forma de cierre detr\u00e1s.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"842\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/15.gif\" alt=\"Escuadrado a 90 grados de la pieza de mitad de espalda del bustier respecto a la l\u00ednea de mitad detr\u00e1s.\" class=\"wp-image-4766\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Las otras piezas no tienen ning\u00fan retoque. Por lo tanto ser\u00e1 un trabajo mec\u00e1nico de reproducci\u00f3n de tela a papel.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">En el pr\u00f3ximo post ense\u00f1aremos c\u00f3mo montar un bustier o cors\u00e9 envarillado.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Este post contin\u00faa en \u00ab<a href=\"https:\/\/tevipa.com\/blog\/montaje-de-la-base-del-bustier\/\" type=\"link\" id=\"https:\/\/tevipa.com\/blog\/montaje-de-la-base-del-bustier\/\">Montaje de la base del bustier<\/a>\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En este art\u00edculo se explica el proceso completo de puesta a plano de la glasilla del bustier, transformando las piezas obtenidas por moulage en un patr\u00f3n t\u00e9cnico preciso. Se detallan los materiales necesarios, el desmontaje correcto de las piezas, el marcado de pliegues, costuras y piquetes, as\u00ed como el trazado definitivo sobre papel. Un paso fundamental para pasar del volumen al plano antes del montaje del bustier o cors\u00e9 envarillado.<\/p>\n","protected":false},"author":1,"featured_media":4766,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1018,1670,1760,23],"tags":[44,30,38,674,90,1745,1743,104,80,362,82,372,672,40,42,676],"class_list":["post-4743","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo","category-corse-es","category-moulage","category-patron","tag-como-cubrir-un-cuerpo","tag-comocubriruncuerpo","tag-creacion-de-moda","tag-ensenanza-de-patronaje","tag-escuela-de-moda","tag-modelaje","tag-moulage","tag-patron","tag-patronaje","tag-patronajemoda","tag-patrones","tag-sastreria","tag-tecnica-de-patronaje","tag-tele-virtual-patronage","tag-televirtualpatronage","tag-tutorial-patonaje"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Puesta a plano de la glasilla del bustier - Tele Virtual Patronage<\/title>\n<meta name=\"description\" content=\"La puesta a plano de la glasilla del bustier paso a paso. C\u00f3mo transformar el moulage en patr\u00f3n, marcar pliegues, costuras y piquetes con precisi\u00f3n t\u00e9cnica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tevipa.com\/blog\/puesta-a-plano-de-la-glasilla-del-bustier\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Puesta a plano de la glasilla del bustier - Tele Virtual Patronage\" \/>\n<meta property=\"og:description\" content=\"La puesta a plano de la glasilla del bustier paso a paso. C\u00f3mo transformar el moulage en patr\u00f3n, marcar pliegues, costuras y piquetes con precisi\u00f3n t\u00e9cnica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tevipa.com\/blog\/puesta-a-plano-de-la-glasilla-del-bustier\/\" \/>\n<meta property=\"og:site_name\" content=\"Tele Virtual Patronage\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-27T20:37:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-27T21:17:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/15.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"595\" \/>\n\t<meta property=\"og:image:height\" content=\"842\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"Tele Virtual Patronage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tele Virtual Patronage\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/puesta-a-plano-de-la-glasilla-del-bustier\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/puesta-a-plano-de-la-glasilla-del-bustier\\\/\"},\"author\":{\"name\":\"Tele Virtual Patronage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\"},\"headline\":\"Puesta a plano de la glasilla del bustier\",\"datePublished\":\"2026-01-27T20:37:46+00:00\",\"dateModified\":\"2026-01-27T21:17:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/puesta-a-plano-de-la-glasilla-del-bustier\\\/\"},\"wordCount\":612,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/puesta-a-plano-de-la-glasilla-del-bustier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/15.gif\",\"keywords\":[\"como cubrir un cuerpo\",\"comocubriruncuerpo\",\"creaci\u00f3n de moda\",\"ense\u00f1anza de patronaje\",\"escuela de moda\",\"modelaje\",\"moulage\",\"patron\",\"patronaje\",\"patronajemoda\",\"patrones\",\"sastrer\u00eda\",\"t\u00e9cnica de patronaje\",\"tele virtual patronage\",\"televirtualpatronage\",\"tutorial patonaje\"],\"articleSection\":[\"Archivo\",\"Cors\u00e9\",\"moulage\",\"Patr\u00f3n\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/puesta-a-plano-de-la-glasilla-del-bustier\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/puesta-a-plano-de-la-glasilla-del-bustier\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/puesta-a-plano-de-la-glasilla-del-bustier\\\/\",\"name\":\"Puesta a plano de la glasilla del bustier - Tele Virtual Patronage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/puesta-a-plano-de-la-glasilla-del-bustier\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/puesta-a-plano-de-la-glasilla-del-bustier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/15.gif\",\"datePublished\":\"2026-01-27T20:37:46+00:00\",\"dateModified\":\"2026-01-27T21:17:23+00:00\",\"description\":\"La puesta a plano de la glasilla del bustier paso a paso. C\u00f3mo transformar el moulage en patr\u00f3n, marcar pliegues, costuras y piquetes con precisi\u00f3n t\u00e9cnica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/puesta-a-plano-de-la-glasilla-del-bustier\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/puesta-a-plano-de-la-glasilla-del-bustier\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/puesta-a-plano-de-la-glasilla-del-bustier\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/15.gif\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/15.gif\",\"width\":595,\"height\":842,\"caption\":\"Escuadrado a 90 grados de la pieza de mitad de espalda del bustier respecto a la l\u00ednea de mitad detr\u00e1s.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/puesta-a-plano-de-la-glasilla-del-bustier\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Puesta a plano de la glasilla del bustier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"name\":\"Tele Virtual Patronage\",\"description\":\"Tevipa\",\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\",\"name\":\"Tele Virtual Patronage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"width\":512,\"height\":512,\"caption\":\"Tele Virtual Patronage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\",\"name\":\"Tele Virtual Patronage\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"caption\":\"Tele Virtual Patronage\"},\"sameAs\":[\"https:\\\/\\\/tevipa.com\\\/blog\"],\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/author\\\/tvpadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Puesta a plano de la glasilla del bustier - Tele Virtual Patronage","description":"La puesta a plano de la glasilla del bustier paso a paso. C\u00f3mo transformar el moulage en patr\u00f3n, marcar pliegues, costuras y piquetes con precisi\u00f3n t\u00e9cnica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tevipa.com\/blog\/puesta-a-plano-de-la-glasilla-del-bustier\/","og_locale":"it_IT","og_type":"article","og_title":"Puesta a plano de la glasilla del bustier - Tele Virtual Patronage","og_description":"La puesta a plano de la glasilla del bustier paso a paso. C\u00f3mo transformar el moulage en patr\u00f3n, marcar pliegues, costuras y piquetes con precisi\u00f3n t\u00e9cnica.","og_url":"https:\/\/tevipa.com\/blog\/puesta-a-plano-de-la-glasilla-del-bustier\/","og_site_name":"Tele Virtual Patronage","article_published_time":"2026-01-27T20:37:46+00:00","article_modified_time":"2026-01-27T21:17:23+00:00","og_image":[{"width":595,"height":842,"url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/15.gif","type":"image\/gif"}],"author":"Tele Virtual Patronage","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Tele Virtual Patronage","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tevipa.com\/blog\/puesta-a-plano-de-la-glasilla-del-bustier\/#article","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/puesta-a-plano-de-la-glasilla-del-bustier\/"},"author":{"name":"Tele Virtual Patronage","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c"},"headline":"Puesta a plano de la glasilla del bustier","datePublished":"2026-01-27T20:37:46+00:00","dateModified":"2026-01-27T21:17:23+00:00","mainEntityOfPage":{"@id":"https:\/\/tevipa.com\/blog\/puesta-a-plano-de-la-glasilla-del-bustier\/"},"wordCount":612,"commentCount":0,"publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"image":{"@id":"https:\/\/tevipa.com\/blog\/puesta-a-plano-de-la-glasilla-del-bustier\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/15.gif","keywords":["como cubrir un cuerpo","comocubriruncuerpo","creaci\u00f3n de moda","ense\u00f1anza de patronaje","escuela de moda","modelaje","moulage","patron","patronaje","patronajemoda","patrones","sastrer\u00eda","t\u00e9cnica de patronaje","tele virtual patronage","televirtualpatronage","tutorial patonaje"],"articleSection":["Archivo","Cors\u00e9","moulage","Patr\u00f3n"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tevipa.com\/blog\/puesta-a-plano-de-la-glasilla-del-bustier\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tevipa.com\/blog\/puesta-a-plano-de-la-glasilla-del-bustier\/","url":"https:\/\/tevipa.com\/blog\/puesta-a-plano-de-la-glasilla-del-bustier\/","name":"Puesta a plano de la glasilla del bustier - Tele Virtual Patronage","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tevipa.com\/blog\/puesta-a-plano-de-la-glasilla-del-bustier\/#primaryimage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/puesta-a-plano-de-la-glasilla-del-bustier\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/15.gif","datePublished":"2026-01-27T20:37:46+00:00","dateModified":"2026-01-27T21:17:23+00:00","description":"La puesta a plano de la glasilla del bustier paso a paso. C\u00f3mo transformar el moulage en patr\u00f3n, marcar pliegues, costuras y piquetes con precisi\u00f3n t\u00e9cnica.","breadcrumb":{"@id":"https:\/\/tevipa.com\/blog\/puesta-a-plano-de-la-glasilla-del-bustier\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tevipa.com\/blog\/puesta-a-plano-de-la-glasilla-del-bustier\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/puesta-a-plano-de-la-glasilla-del-bustier\/#primaryimage","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/15.gif","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/15.gif","width":595,"height":842,"caption":"Escuadrado a 90 grados de la pieza de mitad de espalda del bustier respecto a la l\u00ednea de mitad detr\u00e1s."},{"@type":"BreadcrumbList","@id":"https:\/\/tevipa.com\/blog\/puesta-a-plano-de-la-glasilla-del-bustier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tevipa.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Puesta a plano de la glasilla del bustier"}]},{"@type":"WebSite","@id":"https:\/\/tevipa.com\/blog\/#website","url":"https:\/\/tevipa.com\/blog\/","name":"Tele Virtual Patronage","description":"Tevipa","publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tevipa.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/tevipa.com\/blog\/#organization","name":"Tele Virtual Patronage","url":"https:\/\/tevipa.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","width":512,"height":512,"caption":"Tele Virtual Patronage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c","name":"Tele Virtual Patronage","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","caption":"Tele Virtual Patronage"},"sameAs":["https:\/\/tevipa.com\/blog"],"url":"https:\/\/tevipa.com\/blog\/author\/tvpadm\/"}]}},"_links":{"self":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/4743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/comments?post=4743"}],"version-history":[{"count":5,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/4743\/revisions"}],"predecessor-version":[{"id":4801,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/4743\/revisions\/4801"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media\/4766"}],"wp:attachment":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media?parent=4743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/categories?post=4743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/tags?post=4743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}