{"id":4619,"date":"2026-01-25T12:40:16","date_gmt":"2026-01-25T11:40:16","guid":{"rendered":"https:\/\/tevipa.com\/blog\/?p=4619"},"modified":"2026-01-25T13:41:21","modified_gmt":"2026-01-25T12:41:21","slug":"chaleco-de-ceremonia","status":"publish","type":"post","link":"https:\/\/tevipa.com\/blog\/chaleco-de-ceremonia\/","title":{"rendered":"Chaleco de ceremonia"},"content":{"rendered":"\n<p class=\"has-text-align-right has-small-font-size wp-block-paragraph\"><sup><em>Publicado originalmente el&nbsp;<strong>18 Noviembre 2013<\/strong><\/em><\/sup><\/p>\n\n\n<style>.kb-image4619_c64eb9-9f .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image4619_c64eb9-9f is-style-default\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"222\" height=\"300\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg\" alt=\"Logo C\u00f3mo Cubrir un Cuerpo\" class=\"kb-img wp-image-68\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg 222w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-757x1024.jpg 757w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-768x1039.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1135x1536.jpg 1135w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1514x2048.jpg 1514w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran.jpg 1821w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/><\/figure><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\" style=\"font-size:27px\">Chaleco de ceremonia<\/h1>\n\n\n\n<h2 class=\"wp-block-heading text-justify has-medium-font-size\">Disposiciones previas antes de transformar<\/h2>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">En&nbsp; este post ense\u00f1aremos como transformar el patr\u00f3n del chaleco base en el chaleco de ceremonia sin espalda.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">El modelo que presentaremos ser\u00e1 recto con tres botones y solapa \u201cfa\u00e7on trottoir\u201d.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\" id=\"attachment_137\"><img loading=\"lazy\" decoding=\"async\" width=\"1014\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131113_patron_chaleco_modX2013001131113_02-1-1014x1024.jpg\" alt=\"Patr\u00f3n base del chaleco masculino utilizado como punto de partida para el chaleco de ceremonia sin espalda\" class=\"wp-image-4622\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131113_patron_chaleco_modX2013001131113_02-1-1014x1024.jpg 1014w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131113_patron_chaleco_modX2013001131113_02-1-297x300.jpg 297w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131113_patron_chaleco_modX2013001131113_02-1-150x150.jpg 150w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131113_patron_chaleco_modX2013001131113_02-1-768x776.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131113_patron_chaleco_modX2013001131113_02-1-1521x1536.jpg 1521w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131113_patron_chaleco_modX2013001131113_02-1-2028x2048.jpg 2028w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131113_patron_chaleco_modX2013001131113_02-1-1320x1333.jpg 1320w\" sizes=\"auto, (max-width: 1014px) 100vw, 1014px\" \/><figcaption class=\"wp-element-caption\">Patr\u00f3n base de chaleco masculino<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Para patronar este chaleco de ceremonia servir\u00e1 la base de un patr\u00f3n de chaleco normal.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">En este caso hemos tenido en cuenta el patr\u00f3n base que mostramos en el post \u00ab<a href=\"https:\/\/tevipa.com\/blog\/trazado-base-del-patron-del-chaleco-masculino\/\" type=\"link\" id=\"https:\/\/tevipa.com\/blog\/trazado-base-del-patron-del-chaleco-masculino\/\">Trazado base del patr\u00f3n del chaleco masculino<\/a>\u00bb<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">El primer paso ser\u00e1 reconstruir el chaleco colocando las dos piezas encima de una l\u00ednea recta horizontal que representar\u00e1 la cintura.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">La parte de delante, ya que en su d\u00eda cerramos una pinza t\u00e9cnica de pecho, no seguir\u00e1 la horizontalidad, tal y como muestra la siguiente ilustraci\u00f3n.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">No hemos vuelto a trazar los RH ya que cambiar\u00e1n a modelo acabado.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"931\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_01-1024x931.jpg\" alt=\"Reconstrucci\u00f3n del patr\u00f3n base del chaleco masculino mostrando la falta de horizontalidad del delantero tras el cierre de la pinza t\u00e9cnica de pecho\" class=\"wp-image-4623\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_01-1024x931.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_01-300x273.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_01-768x698.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_01-1536x1397.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_01-2048x1862.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_01-1320x1200.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading text-justify has-medium-font-size\">Transformaci\u00f3n del cuerpo.<\/h2>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">A caballo de la l\u00ednea de cintura de la mitad del delantero del patr\u00f3n, sobre la l\u00ednea de mitad delante trazaremos los tres ojales, para una talla de caballero unos 5 cm ser\u00e1n correctos.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\"><em>En el caso en que queramos&nbsp;<strong>proporcionar<\/strong>&nbsp;esta medida para las tallas superiores o para utilizar este trazado para las&nbsp;<strong>planchas infantiles<\/strong>&nbsp;deberemos hacerlo en base al montante de pantal\u00f3n. Vemos que en el caso de la talla 50 que estamos utilizando el montante de pantal\u00f3n es igual a 24, por lo que podr\u00edamos establecerlo en una quinta parte del montante, mil\u00edmetro abajo, mil\u00edmetro arriba.<\/em><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"text-justify wp-block-paragraph\"><em>Nos interesa establecerlo en base al montante porque es la medida que tiene la ratio m\u00e1s peque\u00f1a (0.5 cm frente a 2cm de ratio de pecho) en primer lugar y en segundo lugar porque deberemos tener en cuenta de no descender demasiado desde la cintura hacia la entrepierna, \u00a0para permitir la movilidad y hacer que el chaleco se transforme en un cintur\u00f3n. No debemos superar la l\u00ednea de las \u201cpetites hanches\u201d, que se sit\u00faa en el primer tercio del montante. Para m\u00e1s informaci\u00f3n sobre la l\u00ednea de las petites hanches, consultad el post \u00ab<\/em><a href=\"https:\/\/tevipa.com\/blog\/moulage-o-modelaje-procedimiento-de-colocacion-de-los-bolducs\/\" type=\"link\" id=\"https:\/\/tevipa.com\/blog\/moulage-o-modelaje-procedimiento-de-colocacion-de-los-bolducs\/\">Moulage o modelaje &#8211; Procedimiento de colocaci\u00f3n de los bolducs<\/a><em>\u00bb de la p\u00e1gina principal de \u201cC\u00f3mo cubrir un cuerpo&#8221; o clicad en el link. \u00a0\u00a0<\/em><\/p>\n<\/blockquote>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Hemos evidenciado los ojales de color rojo.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Como segundo paso, se\u00f1alaremos la misma distancia que hemos dado de lado y lado de los ojales a una perpendicular que trazaremos en el punto de intersecci\u00f3n de la hoja del delantero y del trasero sobre la l\u00ednea de cintura que hemos trazado. L\u00ednea y arco verde discontinuo.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Luego, trazaremos el quiebre desde la punta de caja delante hasta 1.5 cm m\u00e1s arriba del nivel del primer bot\u00f3n en la l\u00ednea del borde delantero.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Por \u00faltimo decidiremos el ancho del cuello del chaleco, nosotros hemos optado por la misma medida (o proporci\u00f3n) que hemos utilizado para el espaciado de los botones del delantero, en nuestro caso 5 cm (o una quinta parte del montante si lo queremos hacer proporcional). En la siguiente ilustraci\u00f3n hemos evidenciados estas marcas con l\u00ednea discontinua de color violeta.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">En la parte de la mitad espalda daremos a caballo de la cintura 2,5 cm.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">La distancia de 2.5 cm es la mitad de la distancia que hemos decidido entre los botones. Hacer la proporci\u00f3n de esta medida es un tanto peligrosa, ya que en el caso del patronaje infantil podr\u00eda ser demasiado angosta, por lo que creemos que tal distancia no se debe proporcionar. Adem\u00e1s est\u00e1 en funci\u00f3n del tama\u00f1o del bot\u00f3n. Creemos que dejar fija a 2,5 cm esta medida es correcto.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Trazaremos a partir del final del patr\u00f3n un c\u00edrculo cuyo radio sea la mitad de 2.5, o sea 1.25 cm. En nuestro trazado lo hemos evidenciado con color naranja.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1008\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_02-1008x1024.jpg\" alt=\"Determinaci\u00f3n de la medida de 2,5 cm en la mitad espalda del patr\u00f3n del chaleco de ceremonia y trazado del arco de 1,25 cm como referencia\" class=\"wp-image-4624\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_02-1008x1024.jpg 1008w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_02-295x300.jpg 295w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_02-768x780.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_02-1512x1536.jpg 1512w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_02-2016x2048.jpg 2016w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_02-1320x1341.jpg 1320w\" sizes=\"auto, (max-width: 1008px) 100vw, 1008px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Trazaremos las l\u00edneas del nuevo chaleco como se muestra en la ilustraci\u00f3n, l\u00ednea gruesa continua en rojo.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1004\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_03-1024x1004.jpg\" alt=\"Trazado de las l\u00edneas definitivas del chaleco de ceremonia sobre el patr\u00f3n base, indicadas con l\u00ednea continua gruesa en color rojo\" class=\"wp-image-4625\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_03-1024x1004.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_03-300x294.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_03-768x753.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_03-1536x1505.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_03-2048x2007.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_03-1320x1294.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">El pico y el bajo del delantero deber\u00e1n ser consecuentes con la forma del trazado de este chaleco. Una l\u00ednea muy abrupta para conseguir la cota marcada en la costura lateral no es est\u00e9tica ni funcional. Es mejor subir el pico del delantero para suavizar la l\u00ednea del bajo.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">En este caso hemos subido el pico unos 3 cm. Ser\u00e1 el buen criterio del patronista y del dise\u00f1ador los que determinar\u00e1n si tocar o no esta punta del delantero.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"960\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_04-1024x960-1.jpg\" alt=\"Ajuste del pico del delantero del chaleco de ceremonia para suavizar la l\u00ednea del bajo y evitar un trazado abrupto\" class=\"wp-image-4626\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_04-1024x960-1.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_04-1024x960-1-300x281.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_04-1024x960-1-768x720.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Descontaremos el valor de la pinza del entalle detr\u00e1s en la costura lateral.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Descontaremos el valor m\u00e1ximo de entalle de la cintura.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"959\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_05-1024x959.jpg\" alt=\"Descuento del valor de la pinza del entalle espalda y del entalle m\u00e1ximo de la cintura en la costura lateral del chaleco de ceremonia\" class=\"wp-image-4627\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_05-1024x959.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_05-300x281.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_05-768x719.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_05-1536x1438.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_05-2048x1917.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_05-1320x1236.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Regularemos el trazado para que no queden escalones en el montaje y borraremos las l\u00edneas que nos han servido como base del trazado.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Marcaremos el ojal en la&nbsp; pieza de la martingala.<\/p>\n\n\n\n<h2 class=\"wp-block-heading text-justify has-medium-font-size\">Solapa<a href=\"http:\/\/patrones.comocubriruncuerpo.org\/wp-content\/uploads\/2013\/11\/131118_-chaleco-de-ceremonia_06.jpg\"><\/a><\/h2>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Trazaremos encima de la hoja del patr\u00f3n del delantero la forma que queramos de la solapa.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">La solapa deber\u00e1 ser m\u00e1s estrecha que el cuello del chaleco.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">En la ilustraci\u00f3n lo hemos evidenciado con un trazo continuo en rojo.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"890\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_06-1024x890.jpg\" alt=\"Regularizaci\u00f3n del trazado del chaleco de ceremonia para evitar escalones en el montaje y marcado del ojal en la pieza de la martingala\" class=\"wp-image-4628\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_06-1024x890.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_06-300x261.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_06-768x667.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_06-1536x1335.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_06-2048x1780.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_06-1320x1147.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Especularemos la vista sobre la l\u00ednea de quiebre y trazaremos los RH.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">El RH del cuello detr\u00e1s coincidir\u00e1 con la l\u00ednea de pliegue,&nbsp; el RH de la martingala ser\u00e1 perpendicular a la l\u00ednea de cintura y el RH del delantero ser\u00e1 paralelo a&nbsp; la l\u00ednea de mitad de cuerpo o botonadura. \u00ad\u00ad<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_07-1024x1024.jpg\" alt=\"Trazado de la forma de la solapa sobre el patr\u00f3n del delantero del chaleco de ceremonia, m\u00e1s estrecha que el cuello\" class=\"wp-image-4629\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_07-1024x1024.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_07-300x300.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_07-150x150.jpg 150w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_07-768x768.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_07-1536x1536.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_07-1320x1321.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_07.jpg 1868w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading text-justify has-medium-font-size\">Despiece<\/h2>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">El despiece de este tipo de chaleco es un tanto especial.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Las piezas del cuello y de la martingala se consideran como delantero en lo que entretela se refiere.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Cortaremos dos plastrones iguales del delantero, pero en uno descontaremos la solapa.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Generalmente no se forran, se cortan 2x tela principal.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">El despiece completo de este chaleco de ceremonia ser\u00e1:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"827\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_09-1024x827.jpg\" alt=\"Despiece completo del chaleco de ceremonia ModX2013002131118 con diferenciaci\u00f3n de piezas de tela principal y entretela de crin\" class=\"wp-image-4630\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_09-1024x827.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_09-300x242.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_09-768x621.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_09-1536x1241.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_09-2048x1655.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_09-1320x1067.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Las piezas rojas indicar\u00e1n la tela principal, mientras que las piezas en amarillo indicar\u00e1n entretela de&nbsp;crin.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En este post se muestra, paso a paso, la transformaci\u00f3n del patr\u00f3n base del chaleco masculino en un chaleco de ceremonia sin espalda. A partir de un modelo recto de tres botones con solapa fa\u00e7on trottoir, se explican las disposiciones previas, los criterios de proporci\u00f3n y las decisiones t\u00e9cnicas necesarias para adaptar el patr\u00f3n al nuevo uso.<\/p>\n<p>El art\u00edculo aborda la colocaci\u00f3n de ojales en relaci\u00f3n con el montante de pantal\u00f3n, el trazado del quiebre y del cuello, la regulaci\u00f3n del bajo del delantero y los ajustes de entalle en cintura y costuras. Se presta especial atenci\u00f3n a la funcionalidad, la est\u00e9tica y la movilidad de la prenda.<\/p>\n<p>Finalmente, se detalla el despiece espec\u00edfico de este tipo de chaleco de ceremonia, diferenciando claramente las piezas de tela principal y las de entretela de crin, as\u00ed como los criterios de corte y orientaci\u00f3n del hilo para un montaje correcto en sastrer\u00eda cl\u00e1sica.<\/p>\n","protected":false},"author":1,"featured_media":4630,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1018,1612,23,360,1719],"tags":[1731,44,30,38,1646,674,90,104,80,362,364,366,82,372,672,40,42,396,402,676],"class_list":["post-4619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo","category-despiece","category-patron","category-patron-base","category-patron-de-lo-chaleco","tag-chaleco","tag-como-cubrir-un-cuerpo","tag-comocubriruncuerpo","tag-creacion-de-moda","tag-despiece","tag-ensenanza-de-patronaje","tag-escuela-de-moda","tag-patron","tag-patronaje","tag-patronajemoda","tag-patronbase","tag-patronbase-2","tag-patrones","tag-sastreria","tag-tecnica-de-patronaje","tag-tele-virtual-patronage","tag-televirtualpatronage","tag-transformacionesdepatron","tag-transformacionesdepatron-2","tag-tutorial-patonaje"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chaleco de ceremonia - Tele Virtual Patronage<\/title>\n<meta name=\"description\" content=\"Transformar el patr\u00f3n base del chaleco masculino en un chaleco de ceremonia sin espalda con solapa fa\u00e7on trottoir.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tevipa.com\/blog\/chaleco-de-ceremonia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chaleco de ceremonia - Tele Virtual Patronage\" \/>\n<meta property=\"og:description\" content=\"Transformar el patr\u00f3n base del chaleco masculino en un chaleco de ceremonia sin espalda con solapa fa\u00e7on trottoir.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tevipa.com\/blog\/chaleco-de-ceremonia\/\" \/>\n<meta property=\"og:site_name\" content=\"Tele Virtual Patronage\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-25T11:40:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-25T12:41:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_09.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2328\" \/>\n\t<meta property=\"og:image:height\" content=\"1881\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tele Virtual Patronage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tele Virtual Patronage\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/chaleco-de-ceremonia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/chaleco-de-ceremonia\\\/\"},\"author\":{\"name\":\"Tele Virtual Patronage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\"},\"headline\":\"Chaleco de ceremonia\",\"datePublished\":\"2026-01-25T11:40:16+00:00\",\"dateModified\":\"2026-01-25T12:41:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/chaleco-de-ceremonia\\\/\"},\"wordCount\":1009,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/chaleco-de-ceremonia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/131118_-chaleco-de-ceremonia_09.jpg\",\"keywords\":[\"chaleco\",\"como cubrir un cuerpo\",\"comocubriruncuerpo\",\"creaci\u00f3n de moda\",\"Despiece\",\"ense\u00f1anza de patronaje\",\"escuela de moda\",\"patron\",\"patronaje\",\"patronajemoda\",\"patr\u00f3nbase\",\"patronbase\",\"patrones\",\"sastrer\u00eda\",\"t\u00e9cnica de patronaje\",\"tele virtual patronage\",\"televirtualpatronage\",\"transformacionesdepatr\u00f3n\",\"transformacionesdepatron\",\"tutorial patonaje\"],\"articleSection\":[\"Archivo\",\"Despiece\",\"Patr\u00f3n\",\"Patr\u00f3n base\",\"Patr\u00f3n de lo chaleco\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/chaleco-de-ceremonia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/chaleco-de-ceremonia\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/chaleco-de-ceremonia\\\/\",\"name\":\"Chaleco de ceremonia - Tele Virtual Patronage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/chaleco-de-ceremonia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/chaleco-de-ceremonia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/131118_-chaleco-de-ceremonia_09.jpg\",\"datePublished\":\"2026-01-25T11:40:16+00:00\",\"dateModified\":\"2026-01-25T12:41:21+00:00\",\"description\":\"Transformar el patr\u00f3n base del chaleco masculino en un chaleco de ceremonia sin espalda con solapa fa\u00e7on trottoir.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/chaleco-de-ceremonia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/chaleco-de-ceremonia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/chaleco-de-ceremonia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/131118_-chaleco-de-ceremonia_09.jpg\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/131118_-chaleco-de-ceremonia_09.jpg\",\"width\":2328,\"height\":1881,\"caption\":\"Despiece completo del chaleco de ceremonia ModX2013002131118 con diferenciaci\u00f3n de piezas de tela principal y entretela de crin\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/chaleco-de-ceremonia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chaleco de ceremonia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"name\":\"Tele Virtual Patronage\",\"description\":\"Tevipa\",\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\",\"name\":\"Tele Virtual Patronage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"width\":512,\"height\":512,\"caption\":\"Tele Virtual Patronage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\",\"name\":\"Tele Virtual Patronage\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"caption\":\"Tele Virtual Patronage\"},\"sameAs\":[\"https:\\\/\\\/tevipa.com\\\/blog\"],\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/author\\\/tvpadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chaleco de ceremonia - Tele Virtual Patronage","description":"Transformar el patr\u00f3n base del chaleco masculino en un chaleco de ceremonia sin espalda con solapa fa\u00e7on trottoir.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tevipa.com\/blog\/chaleco-de-ceremonia\/","og_locale":"it_IT","og_type":"article","og_title":"Chaleco de ceremonia - Tele Virtual Patronage","og_description":"Transformar el patr\u00f3n base del chaleco masculino en un chaleco de ceremonia sin espalda con solapa fa\u00e7on trottoir.","og_url":"https:\/\/tevipa.com\/blog\/chaleco-de-ceremonia\/","og_site_name":"Tele Virtual Patronage","article_published_time":"2026-01-25T11:40:16+00:00","article_modified_time":"2026-01-25T12:41:21+00:00","og_image":[{"width":2328,"height":1881,"url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_09.jpg","type":"image\/jpeg"}],"author":"Tele Virtual Patronage","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Tele Virtual Patronage","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tevipa.com\/blog\/chaleco-de-ceremonia\/#article","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/chaleco-de-ceremonia\/"},"author":{"name":"Tele Virtual Patronage","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c"},"headline":"Chaleco de ceremonia","datePublished":"2026-01-25T11:40:16+00:00","dateModified":"2026-01-25T12:41:21+00:00","mainEntityOfPage":{"@id":"https:\/\/tevipa.com\/blog\/chaleco-de-ceremonia\/"},"wordCount":1009,"commentCount":0,"publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"image":{"@id":"https:\/\/tevipa.com\/blog\/chaleco-de-ceremonia\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_09.jpg","keywords":["chaleco","como cubrir un cuerpo","comocubriruncuerpo","creaci\u00f3n de moda","Despiece","ense\u00f1anza de patronaje","escuela de moda","patron","patronaje","patronajemoda","patr\u00f3nbase","patronbase","patrones","sastrer\u00eda","t\u00e9cnica de patronaje","tele virtual patronage","televirtualpatronage","transformacionesdepatr\u00f3n","transformacionesdepatron","tutorial patonaje"],"articleSection":["Archivo","Despiece","Patr\u00f3n","Patr\u00f3n base","Patr\u00f3n de lo chaleco"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tevipa.com\/blog\/chaleco-de-ceremonia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tevipa.com\/blog\/chaleco-de-ceremonia\/","url":"https:\/\/tevipa.com\/blog\/chaleco-de-ceremonia\/","name":"Chaleco de ceremonia - Tele Virtual Patronage","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tevipa.com\/blog\/chaleco-de-ceremonia\/#primaryimage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/chaleco-de-ceremonia\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_09.jpg","datePublished":"2026-01-25T11:40:16+00:00","dateModified":"2026-01-25T12:41:21+00:00","description":"Transformar el patr\u00f3n base del chaleco masculino en un chaleco de ceremonia sin espalda con solapa fa\u00e7on trottoir.","breadcrumb":{"@id":"https:\/\/tevipa.com\/blog\/chaleco-de-ceremonia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tevipa.com\/blog\/chaleco-de-ceremonia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/chaleco-de-ceremonia\/#primaryimage","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_09.jpg","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131118_-chaleco-de-ceremonia_09.jpg","width":2328,"height":1881,"caption":"Despiece completo del chaleco de ceremonia ModX2013002131118 con diferenciaci\u00f3n de piezas de tela principal y entretela de crin"},{"@type":"BreadcrumbList","@id":"https:\/\/tevipa.com\/blog\/chaleco-de-ceremonia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tevipa.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Chaleco de ceremonia"}]},{"@type":"WebSite","@id":"https:\/\/tevipa.com\/blog\/#website","url":"https:\/\/tevipa.com\/blog\/","name":"Tele Virtual Patronage","description":"Tevipa","publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tevipa.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/tevipa.com\/blog\/#organization","name":"Tele Virtual Patronage","url":"https:\/\/tevipa.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","width":512,"height":512,"caption":"Tele Virtual Patronage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c","name":"Tele Virtual Patronage","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","caption":"Tele Virtual Patronage"},"sameAs":["https:\/\/tevipa.com\/blog"],"url":"https:\/\/tevipa.com\/blog\/author\/tvpadm\/"}]}},"_links":{"self":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/4619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/comments?post=4619"}],"version-history":[{"count":4,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/4619\/revisions"}],"predecessor-version":[{"id":4658,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/4619\/revisions\/4658"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media\/4630"}],"wp:attachment":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media?parent=4619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/categories?post=4619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/tags?post=4619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}