{"id":4491,"date":"2026-01-24T17:03:13","date_gmt":"2026-01-24T16:03:13","guid":{"rendered":"https:\/\/tevipa.com\/blog\/?p=4491"},"modified":"2026-01-24T19:01:34","modified_gmt":"2026-01-24T18:01:34","slug":"despiece-del-patron-del-chalecoforro-enformas-y-plastrones","status":"publish","type":"post","link":"https:\/\/tevipa.com\/blog\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\/","title":{"rendered":"Despiece del patr\u00f3n del chaleco"},"content":{"rendered":"\n<p class=\"has-text-align-right has-small-font-size wp-block-paragraph\"><sup><em>Publicado originalmente el&nbsp;<strong>11 Noviembre 2013<\/strong><\/em><\/sup><\/p>\n\n\n<style>.kb-image4491_529621-b3 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image4491_529621-b3 is-style-default\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"222\" height=\"300\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg\" alt=\"Logo C\u00f3mo Cubrir un Cuerpo\" class=\"kb-img wp-image-68\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg 222w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-757x1024.jpg 757w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-768x1039.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1135x1536.jpg 1135w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1514x2048.jpg 1514w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran.jpg 1821w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/><\/figure><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\" style=\"font-size:27px\"><strong>Despiece del patr\u00f3n del chaleco:<\/strong><br>forro, enformas y plastrones<\/h1>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">Forro y&nbsp;enformas generadas por el patr\u00f3n base del chaleco<\/h2>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Tomaremos como base para generar&nbsp;el forro y las enformas del chaleco&nbsp;para este post el \u201cTrazado base del patr\u00f3n del chaleco masculino\u201d que pod\u00e9is encontrar en nuestro men\u00fa superior, en el \u00edndice de la escuela o bien clicando en el t\u00edtulo del post. Reproducimos aqu\u00ed la \u00faltima imagen de aqu\u00e9l post.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\" id=\"attachment_1698\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"958\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_01-1024x958.jpg\" alt=\"Patr\u00f3n base del chaleco masculino utilizado como base para forro y enformas\" class=\"wp-image-4494\" title=\"Patr\u00f3n del chaleco base masculino talla 50 Drop -6\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_01-1024x958.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_01-300x281.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_01-768x719.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_01-1536x1438.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_01-2048x1917.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_01-1320x1235.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Patr\u00f3n del chaleco base masculino de la talla 50 drop -6<\/figcaption><\/figure>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Hay varias formas de montar un chaleco. Seg\u00fan el tipo de confecci\u00f3n, el coste de la misma y la forma de montar la prenda har\u00e1 que var\u00ede el patronaje del despiece del forro y de las enformas. En este post daremos un despiece que ser\u00e1 \u00fatil para la mayor\u00eda de procedimientos de montaje.<\/p>\n\n\n\n<h2 class=\"wp-block-heading text-justify has-medium-font-size\">C\u00f3mo patronar las enformas y el forro del chaleco.<\/h2>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Empezaremos marcando en la sisa del delantero, en el escote del delantero que seguir\u00e1 por la mitad del delante y que continuar\u00e1 por el bajo del delantero y en el escote del cuello de la hoja posterior una enforma o vista de unos 4 cm de ancho. En la ilustraci\u00f3n que sigue hemos evidenciado con color rojo y l\u00edneas discontinuas las enformas referidas<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\" id=\"attachment_1699\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"959\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_02-1024x959.jpg\" alt=\"Trazado de las enformas del chaleco masculino en delantero y espalda\" class=\"wp-image-4496\" title=\"Trazado de las enformas en el patr\u00f3n del chaleco base \" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_02-1024x959.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_02-300x281.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_02-768x719.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_02-1536x1439.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_02-2048x1918.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_02-1320x1236.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Trazado de las enformas en el patr\u00f3n del chaleco base<\/figcaption><\/figure>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">El patr\u00f3n del post anterior, la primera imagen de \u00e9ste. Vemos el delantero y la parte posterior. Tradicionalmente el chaleco se realiza con el delantero de tela y la parte posterior de forro. La parte interior de forro descontando las enformas ser\u00e1 realizado tambi\u00e9n de forro. Generalmente los forros interiores y exteriores ( el de la espalda) son de texturas y pesos diferentes, y a veces incluso de color. En nuestro post diferenciaremos los dos tipos de forro como si fueran telas diferentes. La enforma dibujada en el patr\u00f3n generar\u00e1 una serie de piquetes de montaje en la hoja exterior del patr\u00f3n. En la imagen que sigue vemos la parte exterior del chaleco con sus piquetes. La hoja de tela la hemos evidenciado de color rojo y la de forro m\u00e1s grueso, probablemente de acetato la hemos evidenciado de color azul celeste.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\" id=\"attachment_1700\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"905\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_03-1024x905.jpg\" alt=\"Delantero y espalda del chaleco masculino diferenciados por tela y forro\" class=\"wp-image-4498\" title=\"Despiece del delantero y parte posterior del patr\u00f3n base del chaleco masculino\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_03-1024x905.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_03-300x265.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_03-768x679.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_03-1536x1358.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_03-2048x1810.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_03-1320x1167.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Despiece del delantero y parte posterior del patr\u00f3n base del chaleco masculino<\/figcaption><\/figure>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Empezaremos el despiece por la espalda. Recortaremos el patr\u00f3n por la l\u00ednea discontinua y obtendremos dos partes, la parte de la enforma la juntaremos por patronaje con su especulada, la parte de forro no podremos juntarla ya que la espalda es vestida (no es en l\u00ednea recta).<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\" id=\"attachment_1701\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"918\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_04-1024x918.jpg\" alt=\"Despiece de la espalda del chaleco masculino en enforma y forro\" class=\"wp-image-4503\" title=\"Recorte de las enformas de la pieza de espalda del patr\u00f3n del chaleco base masculino \" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_04-1024x918.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_04-300x269.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_04-768x689.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_04-1536x1377.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_04-2048x1836.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_04-1320x1183.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Recorte de las enformas de la pieza de espalda del patr\u00f3n del chaleco base masculino<\/figcaption><\/figure>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Para el delantero procederemos de la misma forma, En el caso del delantero daremos cuatro variantes: a.- la enforma del delante\/bajo en una sola pieza. b.- la enforma del delante hasta la pinza de pecho en unas sola pieza y un complemento para el bajo desde la pinza y la costura lateral. c.- la enforma de delante en una pieza, y la del bajo en otra. d.- la enforma del delante en una sola pieza y el bajo en dos. &nbsp; La enforma de la sisa delante se mantendr\u00e1 igual para todos los cuatro despieces. El forro interior lo hemos evidenciado del mismo color que lo hemos hecho en la tercera imagen de este post, en la que hemos hecho el despiece de la parte de atr\u00e1s.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\" id=\"attachment_1702\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_05-724x1024.jpg\" alt=\"Variantes de despiece del delantero del chaleco masculino con enformas\" class=\"wp-image-4505\" title=\"Recorte de las enformas del deantero del patr\u00f3n base del chaleco masculino\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_05-724x1024.jpg 724w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_05-212x300.jpg 212w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_05-768x1086.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_05-1086x1536.jpg 1086w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_05-1448x2048.jpg 1448w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_05-1320x1867.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_05-scaled.jpg 1810w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><figcaption class=\"wp-element-caption\">Recorte de las enformas del deantero del patr\u00f3n base del chaleco masculino<\/figcaption><\/figure>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Algunas formas de montaje cosen las enformas directamente encima de una plancha de forro igual a la del delantero, si mont\u00e1ramos el chaleco siguiendo estos procedimientos considerar\u00edamos el patr\u00f3n de la tela&nbsp; y del forro exterior de la parte del delantero y trasero del chaleco como patrones del forro interior.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">Los plastrones, despiece del patr\u00f3n base del chaleco cl\u00e1sico.<\/h2>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">En el caso en que montemos el chaleco seg\u00fan la tradici\u00f3n de sastrer\u00eda cl\u00e1sica necesitaremos el doble plastr\u00f3n de crin. Los dos plastrones ser\u00e1n cortados al pleno bies. Las cotas que necesitamos para cortar los plastrones ser\u00e1n: 3 cm por debajo de la costura lateral y &nbsp;8 cm por debajo del v\u00e9rtice superior de la pinza del delantero. Trazaremos el plastr\u00f3n dibujando una circunferencia desde el v\u00e9rtice de la pinza de entalle del delantero cuyo arco sea de unos 8 cm, y luego iremos a morir\u00e9 a unos 3 cm por debajo de la costura lateral intersecci\u00f3n sisa. Hemos decidido 3 cm porque hab\u00edamos dado a las enformas un valor de 4 cm. Como veremos m\u00e1s adelante, en post dedicados al montaje de las prendas, &nbsp;para que no se noten gruesos en la prenda acabada deberemos escalar las costuras interiores que no son de construcci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\" id=\"attachment_1703\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_06-1024x768.jpg\" alt=\"Plastrones del chaleco masculino cortados al bies en sastrer\u00eda cl\u00e1sica\" class=\"wp-image-4507\" title=\"Plastrones del chaleco masculino en sastrer\u00eda cl\u00e1sica\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_06-1024x768.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_06-300x225.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_06-768x576.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_06-1536x1151.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_06-2048x1535.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_06-1320x989.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Plastrones del chaleco masculino en sastrer\u00eda cl\u00e1sica a partir del delantero del patr\u00f3n base<\/figcaption><\/figure>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">En pr\u00eat \u00e0 porter a veces utilizan el\/los&nbsp; patr\u00f3n\/es de los plastrones de la sastrer\u00eda clasicoa y \/o el patr\u00f3n del delantero para la entretela termocolante: la friselina.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Este post continua en \u00ab<a href=\"https:\/\/tevipa.com\/blog\/las-diferentes-formas-del-chaleco\/\" type=\"link\" id=\"https:\/\/tevipa.com\/blog\/las-diferentes-formas-del-chaleco\/\">Las diferentes formas del chaleco<\/a>\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En este art\u00edculo se desarrolla el despiece del patr\u00f3n base del chaleco masculino para generar el forro, las enformas y los plastrones. Partiendo del patr\u00f3n base, se analizan distintas formas de montaje seg\u00fan la t\u00e9cnica de confecci\u00f3n, desde procedimientos m\u00e1s industriales hasta la sastrer\u00eda cl\u00e1sica.<\/p>\n<p>El post explica c\u00f3mo trazar y recortar las enformas del delantero y de la espalda, c\u00f3mo organizar el forro interior y exterior y c\u00f3mo obtener los plastrones tradicionales de crin, fundamentales en el montaje cl\u00e1sico del chaleco. Un contenido pensado para comprender el porqu\u00e9 del despiece y no solo su ejecuci\u00f3n.<\/p>\n","protected":false},"author":1,"featured_media":4496,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1018,23,1719],"tags":[1731,44,30,38,674,90,104,80,362,366,364,82,372,672,40,42,676],"class_list":["post-4491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo","category-patron","category-patron-de-lo-chaleco","tag-chaleco","tag-como-cubrir-un-cuerpo","tag-comocubriruncuerpo","tag-creacion-de-moda","tag-ensenanza-de-patronaje","tag-escuela-de-moda","tag-patron","tag-patronaje","tag-patronajemoda","tag-patronbase-2","tag-patronbase","tag-patrones","tag-sastreria","tag-tecnica-de-patronaje","tag-tele-virtual-patronage","tag-televirtualpatronage","tag-tutorial-patonaje"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Despiece del patr\u00f3n del chaleco - Tele Virtual Patronage<\/title>\n<meta name=\"description\" content=\"Gu\u00eda t\u00e9cnica sobre el despiece del patr\u00f3n del chaleco masculino: forro, enformas y plastrones seg\u00fan la sastrer\u00eda cl\u00e1sica y el pr\u00eat-\u00e0-porter\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tevipa.com\/blog\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Despiece del patr\u00f3n del chaleco - Tele Virtual Patronage\" \/>\n<meta property=\"og:description\" content=\"Gu\u00eda t\u00e9cnica sobre el despiece del patr\u00f3n del chaleco masculino: forro, enformas y plastrones seg\u00fan la sastrer\u00eda cl\u00e1sica y el pr\u00eat-\u00e0-porter\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tevipa.com\/blog\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\/\" \/>\n<meta property=\"og:site_name\" content=\"Tele Virtual Patronage\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-24T16:03:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-24T18:01:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_02.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2068\" \/>\n\t<meta property=\"og:image:height\" content=\"1937\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tele Virtual Patronage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tele Virtual Patronage\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\\\/\"},\"author\":{\"name\":\"Tele Virtual Patronage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\"},\"headline\":\"Despiece del patr\u00f3n del chaleco\",\"datePublished\":\"2026-01-24T16:03:13+00:00\",\"dateModified\":\"2026-01-24T18:01:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\\\/\"},\"wordCount\":895,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/131111_02.jpg\",\"keywords\":[\"chaleco\",\"como cubrir un cuerpo\",\"comocubriruncuerpo\",\"creaci\u00f3n de moda\",\"ense\u00f1anza de patronaje\",\"escuela de moda\",\"patron\",\"patronaje\",\"patronajemoda\",\"patronbase\",\"patr\u00f3nbase\",\"patrones\",\"sastrer\u00eda\",\"t\u00e9cnica de patronaje\",\"tele virtual patronage\",\"televirtualpatronage\",\"tutorial patonaje\"],\"articleSection\":[\"Archivo\",\"Patr\u00f3n\",\"Patr\u00f3n de lo chaleco\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\\\/\",\"name\":\"Despiece del patr\u00f3n del chaleco - Tele Virtual Patronage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/131111_02.jpg\",\"datePublished\":\"2026-01-24T16:03:13+00:00\",\"dateModified\":\"2026-01-24T18:01:34+00:00\",\"description\":\"Gu\u00eda t\u00e9cnica sobre el despiece del patr\u00f3n del chaleco masculino: forro, enformas y plastrones seg\u00fan la sastrer\u00eda cl\u00e1sica y el pr\u00eat-\u00e0-porter\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/131111_02.jpg\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/131111_02.jpg\",\"width\":2068,\"height\":1937,\"caption\":\"Trazado de las enformas en el patr\u00f3n del chaleco base\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Despiece del patr\u00f3n del chaleco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"name\":\"Tele Virtual Patronage\",\"description\":\"Tevipa\",\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\",\"name\":\"Tele Virtual Patronage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"width\":512,\"height\":512,\"caption\":\"Tele Virtual Patronage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\",\"name\":\"Tele Virtual Patronage\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"caption\":\"Tele Virtual Patronage\"},\"sameAs\":[\"https:\\\/\\\/tevipa.com\\\/blog\"],\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/author\\\/tvpadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Despiece del patr\u00f3n del chaleco - Tele Virtual Patronage","description":"Gu\u00eda t\u00e9cnica sobre el despiece del patr\u00f3n del chaleco masculino: forro, enformas y plastrones seg\u00fan la sastrer\u00eda cl\u00e1sica y el pr\u00eat-\u00e0-porter","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tevipa.com\/blog\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\/","og_locale":"it_IT","og_type":"article","og_title":"Despiece del patr\u00f3n del chaleco - Tele Virtual Patronage","og_description":"Gu\u00eda t\u00e9cnica sobre el despiece del patr\u00f3n del chaleco masculino: forro, enformas y plastrones seg\u00fan la sastrer\u00eda cl\u00e1sica y el pr\u00eat-\u00e0-porter","og_url":"https:\/\/tevipa.com\/blog\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\/","og_site_name":"Tele Virtual Patronage","article_published_time":"2026-01-24T16:03:13+00:00","article_modified_time":"2026-01-24T18:01:34+00:00","og_image":[{"width":2068,"height":1937,"url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_02.jpg","type":"image\/jpeg"}],"author":"Tele Virtual Patronage","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Tele Virtual Patronage","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tevipa.com\/blog\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\/#article","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\/"},"author":{"name":"Tele Virtual Patronage","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c"},"headline":"Despiece del patr\u00f3n del chaleco","datePublished":"2026-01-24T16:03:13+00:00","dateModified":"2026-01-24T18:01:34+00:00","mainEntityOfPage":{"@id":"https:\/\/tevipa.com\/blog\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\/"},"wordCount":895,"commentCount":0,"publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"image":{"@id":"https:\/\/tevipa.com\/blog\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_02.jpg","keywords":["chaleco","como cubrir un cuerpo","comocubriruncuerpo","creaci\u00f3n de moda","ense\u00f1anza de patronaje","escuela de moda","patron","patronaje","patronajemoda","patronbase","patr\u00f3nbase","patrones","sastrer\u00eda","t\u00e9cnica de patronaje","tele virtual patronage","televirtualpatronage","tutorial patonaje"],"articleSection":["Archivo","Patr\u00f3n","Patr\u00f3n de lo chaleco"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tevipa.com\/blog\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tevipa.com\/blog\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\/","url":"https:\/\/tevipa.com\/blog\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\/","name":"Despiece del patr\u00f3n del chaleco - Tele Virtual Patronage","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tevipa.com\/blog\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\/#primaryimage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_02.jpg","datePublished":"2026-01-24T16:03:13+00:00","dateModified":"2026-01-24T18:01:34+00:00","description":"Gu\u00eda t\u00e9cnica sobre el despiece del patr\u00f3n del chaleco masculino: forro, enformas y plastrones seg\u00fan la sastrer\u00eda cl\u00e1sica y el pr\u00eat-\u00e0-porter","breadcrumb":{"@id":"https:\/\/tevipa.com\/blog\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tevipa.com\/blog\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\/#primaryimage","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_02.jpg","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131111_02.jpg","width":2068,"height":1937,"caption":"Trazado de las enformas en el patr\u00f3n del chaleco base"},{"@type":"BreadcrumbList","@id":"https:\/\/tevipa.com\/blog\/despiece-del-patron-del-chalecoforro-enformas-y-plastrones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tevipa.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Despiece del patr\u00f3n del chaleco"}]},{"@type":"WebSite","@id":"https:\/\/tevipa.com\/blog\/#website","url":"https:\/\/tevipa.com\/blog\/","name":"Tele Virtual Patronage","description":"Tevipa","publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tevipa.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/tevipa.com\/blog\/#organization","name":"Tele Virtual Patronage","url":"https:\/\/tevipa.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","width":512,"height":512,"caption":"Tele Virtual Patronage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c","name":"Tele Virtual Patronage","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","caption":"Tele Virtual Patronage"},"sameAs":["https:\/\/tevipa.com\/blog"],"url":"https:\/\/tevipa.com\/blog\/author\/tvpadm\/"}]}},"_links":{"self":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/4491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/comments?post=4491"}],"version-history":[{"count":6,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/4491\/revisions"}],"predecessor-version":[{"id":4535,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/4491\/revisions\/4535"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media\/4496"}],"wp:attachment":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media?parent=4491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/categories?post=4491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/tags?post=4491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}