{"id":4359,"date":"2026-01-07T23:43:28","date_gmt":"2026-01-07T22:43:28","guid":{"rendered":"https:\/\/tevipa.com\/blog\/?p=4359"},"modified":"2026-01-07T23:54:20","modified_gmt":"2026-01-07T22:54:20","slug":"sarouel-sarouel-sarruel-saroual-seroual-o-sirwal","status":"publish","type":"post","link":"https:\/\/tevipa.com\/blog\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\/","title":{"rendered":"Sarouel, sarouel, sarruel, saroual, seroual o sirwal"},"content":{"rendered":"\n<p class=\"has-text-align-right has-small-font-size wp-block-paragraph\"><sup><em>Publicado originalmente el\u00a0<strong>29 Octubre 2013<\/strong><\/em><\/sup><\/p>\n\n\n<style>.kb-image4359_20f72a-9d .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image4359_20f72a-9d is-style-default\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"208\" height=\"300\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/Historia-208x300.gif\" alt=\"Logo C\u00f3mo Se Cubri\u00f3 Un Cuerpo\" class=\"kb-img wp-image-3114\"\/><\/figure><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\" style=\"font-size:27px\">Sarouel, sarouel, sarruel, saroual, seroual o sirwal<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">El <strong>sarouel<\/strong>, \u0633\u0631\u0648\u0627\u0644, sarruel, saroual, seroual o sirwal es una prenda de origen incierto tanto geogr\u00e1ficamente como cronol\u00f3gicamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os presentamos un par de formas de patronarla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hemos dudado si presentarlo aqu\u00ed, en la p\u00e1gina de historia de la moda: <strong>\u201cC\u00f3mo se cubri\u00f3 un cuerpo\u201d<\/strong>, o en la p\u00e1gina principal: <strong>\u201cC\u00f3mo se cubrir un cuerpo.\u201d<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En <strong>C\u00f3mo cubrir un cuerpo<\/strong> pod\u00e9is ver el post de la <a href=\"https:\/\/tevipa.com\/blog\/base-del-pantalon-sarruel-o-sarouel\/\">Base del pantal\u00f3n sarruel o sarouel<\/a> en el que dimos una serie de nociones de historia a las que en esta sede nos remitimos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No debemos confundir el sarouel con la prenda h\u00edbrida llamada pantal\u00f3n-sarouel o pantal\u00f3n-sarruel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al final nos hemos decidido publicarla aqu\u00ed el patr\u00f3n del sarouel por ser una prenda hist\u00f3rica. No se sabe d\u00f3nde naci\u00f3 pero se extendi\u00f3 por Asia, los actuales pa\u00edses \u00e1rabes y parte de \u00c1frica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tenemos constancia de que este tipo de prenda ya se llevaba antes de la era Cristiana, hemos decidido ubicarla por ahora en el siglo I A.C. hasta disponer de m\u00e1s datos cronol\u00f3gicos. Si alguno de vosotros puede ayudar, os lo agradecer\u00edamos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte presentamos hace pocos post el <a href=\"https:\/\/tevipa.com\/blog\/pantalon-sarruel-de-ocho-cinturones\/\">Pantal\u00f3n-sarruel de ocho cinturones<\/a>, que bebe del base del pantal\u00f3n-sarruel de la p\u00e1gina principal C\u00f3mo cubrir un cuerpo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La que hoy presentamos es el patr\u00f3n de la prenda original, en el que nos inspiramos para desarrollar aquella plancha de corte base y la otra de patronaje.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Daremos dos modelos que tendr\u00e1n dos trazados de corte similares pero diferentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Empezaremos con el m\u00e1s simple: el de <strong>patr\u00f3n cuadrado<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ambos trazados ser\u00e1n tanto de hombre, como de mujer o de ni\u00f1o con las mismas proporciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Necesitaremos las siguientes medidas: Cintura, Cadera, Largo pierna y Contorno tobillo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Trazado de corte del Sarouel o Sarruel de patr\u00f3n cuadrado.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El trazado se limita a dibujar un cuadrado. El problema ser\u00e1 calcular las proporciones de \u00e9ste.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cortaremos el patr\u00f3n a lomo, pero el lomo ser\u00e1 el pleno bies y representar\u00e1 la l\u00ednea de entrepierna: ser\u00e1 la hipotenusa del cuadrado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Del v\u00e9rtice de los dos catetos (que formar\u00e1n un \u00e1ngulo de 90 grados) trazaremos con un arco un cuarto de circunferencia cuyo per\u00edmetro que sea igual a la medida del doble del contorno de cintura (C*4). Dos \u00e1ngulos de 90 suman 180 grados, media circunferencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el final de la circunferencia contaremos el largo de pierna o el largo total de la prenda y a partir de este punto calcularemos el radio de otro arco que deber\u00e1 medir cuatro veces el contorno de tobillo (el \u00e1ngulo ser\u00e1 de 45 grados que es un cuarto de 180 grados que es la mitad de una circunferencia).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La teor\u00eda parece mucho m\u00e1s complicada de lo que es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vayamos paso por paso:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para los dos sarrueles de este post utilizaremos las medidas de caballero T50\/Drop-5\/180: cintura 45, largo pierna (24.75&lt;montante>+78&lt;entrepierna>) 102.75 cm, medidas que pod\u00e9is encontrar en el post de la p\u00e1gina principal de C\u00f3mo cubrir un cuerpo \u00ab<a href=\"https:\/\/tevipa.com\/blog\/tabla-de-medidas-caballero-sintesis-de-largos-y-conformaciones\/\">Tabla de medidas caballero: s\u00edntesis de largos y conformaciones<\/a>\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ancho del bajo lo fijaremos a 40 cm.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Calcularemos los radios cuyos per\u00edmetros sean 45 cm y 40 cm respectivamente. Dividiremos las dos medidas anteriores por el n\u00famero \u03c0 y obtendremos 14.32 y 12.73 y multiplicaremos los radios obtenidos por 2: 28.64 y 25.46 respectivamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trazaremos un par de l\u00edneas perpendiculares, y anotaremos en cada una de ellas a partir de su intersecci\u00f3n el valor del radio de cintura, a partir de esta intersecci\u00f3n, alej\u00e1ndonos del punto com\u00fan, anotaremos el valor de la pierna, a partir de este \u00faltimo trazaremos una circunferencia con el valor del segundo radio.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1021\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_01-1024x1021.jpg\" alt=\"Trazado geom\u00e9trico del sarouel de patr\u00f3n cuadrado con radios y l\u00edneas perpendiculares\" class=\"wp-image-4360\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_01-1024x1021.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_01-300x300.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_01-150x150.jpg 150w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_01-768x766.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_01-1536x1532.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_01-2048x2042.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_01-1320x1316.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"977\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_02-1024x977.jpg\" alt=\"Construcci\u00f3n del patr\u00f3n del sarouel con l\u00edneas de referencia y radios de cintura y bajo\" class=\"wp-image-4361\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_02-1024x977.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_02-300x286.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_02-768x732.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_02-1536x1465.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_02-2048x1953.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_02-1320x1259.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"887\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_03-1024x887.jpg\" alt=\"Patr\u00f3n del sarouel con l\u00ednea de entrepierna al pliegue y divisiones del cuerpo\" class=\"wp-image-4362\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_03-1024x887.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_03-300x260.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_03-768x665.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_03-1536x1331.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_03-2048x1775.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_03-1320x1144.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"929\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_04-1024x929.jpg\" alt=\"Patr\u00f3n completo del sarouel de patr\u00f3n cuadrado listo para corte\" class=\"wp-image-4363\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_04-1024x929.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_04-300x272.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_04-768x696.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_04-1536x1393.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_04-2048x1857.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_04-1320x1197.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Juntaremos los dos centros de las dos \u00faltimas circunferencias, que ser\u00e1 la hipotenusa del \u00e1ngulo recto, esta l\u00ednea ser\u00e1 la l\u00ednea de entrepierna y a su vez el doble del patr\u00f3n. El patr\u00f3n del sarouel ya est\u00e1 acabado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\"><strong>Trazado de corte del Sarouel o Sarruel de patr\u00f3n rectangular.<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Utilizaremos las mismas medidas del trazado anterior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Calcularemos C\/4.41 o sea en nuestro caso 45\/4,41 = 10.20.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para el bajo daremos 4 veces este valor: 40.80 cm.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trazaremos cuadrado de la medida del largo pierna. En nuestro caso 102.75 cm.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A cada uno de los lados del cuadrado daremos el doble del valor de la proporci\u00f3n de cintura y repetiremos la misma operaci\u00f3n a partir de las l\u00edneas encontradas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alargaremos la base y la altura del cuadrado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestro trazado tendr\u00e1 el siguiente aspecto:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"602\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_05-1024x602.jpg\" alt=\"Ampliaci\u00f3n de la base y la altura del cuadrado en el trazado del sarouel\" class=\"wp-image-4365\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_05-1024x602.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_05-300x176.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_05-768x451.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_05-1536x903.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_05-2048x1204.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_05-1320x776.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Trazaremos dos diagonales tomando como rect\u00e1ngulo el formado por la base, la altura y las segundas l\u00edneas rectas que encontramos en los lados, una diagonal representar\u00e1 la mitad del cuerpo, la otra la l\u00ednea de entrepierna.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hemos puesto los nombres y ubicaciones del patr\u00f3n a fin de no perdernos en los pr\u00f3ximos pasos.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"666\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_06-1024x666.jpg\" alt=\"Identificaci\u00f3n de l\u00edneas, mitades y costuras en el patr\u00f3n rectangular del sarouel\" class=\"wp-image-4366\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_06-1024x666.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_06-300x195.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_06-768x500.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_06-1536x999.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_06-2048x1332.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_06-1320x859.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Bajaremos de C\/4.41 el nivel de la cintura delante y lo subiremos de la cintura detr\u00e1s. Trazaremos las cinturillas como indica la ilustraci\u00f3n.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"631\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_07-1024x631.jpg\" alt=\"Ajuste del nivel de la cintura delantera y trasera en el patr\u00f3n rectangular del sarouel\" class=\"wp-image-4367\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_07-1024x631.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_07-300x185.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_07-768x473.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_07-1536x947.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_07-2048x1263.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_07-1320x814.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Hemos dejado un cuarto del valor del bajo (C\/4,41) de frunce para los pu\u00f1os tobilleros para darles m\u00e1s amplitud. Dejaremos el pu\u00f1o a 40 cm como el primer patr\u00f3n y el resto lo montaremos con frunces o pliegues.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"346\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_08-1024x346.jpg\" alt=\"Distribuci\u00f3n del frunce en los pu\u00f1os tobilleros del patr\u00f3n rectangular del sarouel\" class=\"wp-image-4368\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_08-1024x346.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_08-300x101.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_08-768x260.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_08-1536x520.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_08-2048x693.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_08-1320x446.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Trazaremos las cinturillas de ancho 4 cm acabadas y los pu\u00f1os de los tobillos que hemos fijado en 20\u00d74 cm acabados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El sarouel o sarruel es una prenda hist\u00f3rica de origen incierto. En este post analizamos su contexto cultural y desarrollamos dos trazados completos de patronaje: patr\u00f3n cuadrado y patr\u00f3n rectangular.<\/p>\n","protected":false},"author":1,"featured_media":4363,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1018,1517,23,1461],"tags":[44,30,1694,34,674,90,1515,104,80,362,82,372,672,40,42,676],"class_list":["post-4359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo","category-historia","category-patron","category-patron-del-pantalon","tag-como-cubrir-un-cuerpo","tag-comocubriruncuerpo","tag-corse","tag-disenador","tag-ensenanza-de-patronaje","tag-escuela-de-moda","tag-historia","tag-patron","tag-patronaje","tag-patronajemoda","tag-patrones","tag-sastreria","tag-tecnica-de-patronaje","tag-tele-virtual-patronage","tag-televirtualpatronage","tag-tutorial-patonaje"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sarouel, sarouel, sarruel, saroual, seroual o sirwal - Tele Virtual Patronage<\/title>\n<meta name=\"description\" content=\"Historia y patronaje del sarouel. Explicamos su origen, evoluci\u00f3n y dos m\u00e9todos completos de trazado del patr\u00f3n tradicional paso a paso.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tevipa.com\/blog\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sarouel, sarouel, sarruel, saroual, seroual o sirwal - Tele Virtual Patronage\" \/>\n<meta property=\"og:description\" content=\"Historia y patronaje del sarouel. Explicamos su origen, evoluci\u00f3n y dos m\u00e9todos completos de trazado del patr\u00f3n tradicional paso a paso.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tevipa.com\/blog\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\/\" \/>\n<meta property=\"og:site_name\" content=\"Tele Virtual Patronage\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-07T22:43:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-07T22:54:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_04.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2480\" \/>\n\t<meta property=\"og:image:height\" content=\"2249\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tele Virtual Patronage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tele Virtual Patronage\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\\\/\"},\"author\":{\"name\":\"Tele Virtual Patronage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\"},\"headline\":\"Sarouel, sarouel, sarruel, saroual, seroual o sirwal\",\"datePublished\":\"2026-01-07T22:43:28+00:00\",\"dateModified\":\"2026-01-07T22:54:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\\\/\"},\"wordCount\":921,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/131028_04.jpg\",\"keywords\":[\"como cubrir un cuerpo\",\"comocubriruncuerpo\",\"Cors\u00e9\",\"dise\u00f1ador\",\"ense\u00f1anza de patronaje\",\"escuela de moda\",\"historia\",\"patron\",\"patronaje\",\"patronajemoda\",\"patrones\",\"sastrer\u00eda\",\"t\u00e9cnica de patronaje\",\"tele virtual patronage\",\"televirtualpatronage\",\"tutorial patonaje\"],\"articleSection\":[\"Archivo\",\"historia\",\"Patr\u00f3n\",\"Patr\u00f3n del pantal\u00f3n\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\\\/\",\"name\":\"Sarouel, sarouel, sarruel, saroual, seroual o sirwal - Tele Virtual Patronage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/131028_04.jpg\",\"datePublished\":\"2026-01-07T22:43:28+00:00\",\"dateModified\":\"2026-01-07T22:54:20+00:00\",\"description\":\"Historia y patronaje del sarouel. Explicamos su origen, evoluci\u00f3n y dos m\u00e9todos completos de trazado del patr\u00f3n tradicional paso a paso.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/131028_04.jpg\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/131028_04.jpg\",\"width\":2480,\"height\":2249,\"caption\":\"Patr\u00f3n completo del sarouel de patr\u00f3n cuadrado listo para corte\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sarouel, sarouel, sarruel, saroual, seroual o sirwal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"name\":\"Tele Virtual Patronage\",\"description\":\"Tevipa\",\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\",\"name\":\"Tele Virtual Patronage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"width\":512,\"height\":512,\"caption\":\"Tele Virtual Patronage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\",\"name\":\"Tele Virtual Patronage\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"caption\":\"Tele Virtual Patronage\"},\"sameAs\":[\"https:\\\/\\\/tevipa.com\\\/blog\"],\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/author\\\/tvpadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sarouel, sarouel, sarruel, saroual, seroual o sirwal - Tele Virtual Patronage","description":"Historia y patronaje del sarouel. Explicamos su origen, evoluci\u00f3n y dos m\u00e9todos completos de trazado del patr\u00f3n tradicional paso a paso.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tevipa.com\/blog\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\/","og_locale":"it_IT","og_type":"article","og_title":"Sarouel, sarouel, sarruel, saroual, seroual o sirwal - Tele Virtual Patronage","og_description":"Historia y patronaje del sarouel. Explicamos su origen, evoluci\u00f3n y dos m\u00e9todos completos de trazado del patr\u00f3n tradicional paso a paso.","og_url":"https:\/\/tevipa.com\/blog\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\/","og_site_name":"Tele Virtual Patronage","article_published_time":"2026-01-07T22:43:28+00:00","article_modified_time":"2026-01-07T22:54:20+00:00","og_image":[{"width":2480,"height":2249,"url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_04.jpg","type":"image\/jpeg"}],"author":"Tele Virtual Patronage","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Tele Virtual Patronage","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tevipa.com\/blog\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\/#article","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\/"},"author":{"name":"Tele Virtual Patronage","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c"},"headline":"Sarouel, sarouel, sarruel, saroual, seroual o sirwal","datePublished":"2026-01-07T22:43:28+00:00","dateModified":"2026-01-07T22:54:20+00:00","mainEntityOfPage":{"@id":"https:\/\/tevipa.com\/blog\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\/"},"wordCount":921,"commentCount":0,"publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"image":{"@id":"https:\/\/tevipa.com\/blog\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_04.jpg","keywords":["como cubrir un cuerpo","comocubriruncuerpo","Cors\u00e9","dise\u00f1ador","ense\u00f1anza de patronaje","escuela de moda","historia","patron","patronaje","patronajemoda","patrones","sastrer\u00eda","t\u00e9cnica de patronaje","tele virtual patronage","televirtualpatronage","tutorial patonaje"],"articleSection":["Archivo","historia","Patr\u00f3n","Patr\u00f3n del pantal\u00f3n"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tevipa.com\/blog\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tevipa.com\/blog\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\/","url":"https:\/\/tevipa.com\/blog\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\/","name":"Sarouel, sarouel, sarruel, saroual, seroual o sirwal - Tele Virtual Patronage","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tevipa.com\/blog\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\/#primaryimage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_04.jpg","datePublished":"2026-01-07T22:43:28+00:00","dateModified":"2026-01-07T22:54:20+00:00","description":"Historia y patronaje del sarouel. Explicamos su origen, evoluci\u00f3n y dos m\u00e9todos completos de trazado del patr\u00f3n tradicional paso a paso.","breadcrumb":{"@id":"https:\/\/tevipa.com\/blog\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tevipa.com\/blog\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\/#primaryimage","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_04.jpg","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2026\/01\/131028_04.jpg","width":2480,"height":2249,"caption":"Patr\u00f3n completo del sarouel de patr\u00f3n cuadrado listo para corte"},{"@type":"BreadcrumbList","@id":"https:\/\/tevipa.com\/blog\/sarouel-sarouel-sarruel-saroual-seroual-o-sirwal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tevipa.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Sarouel, sarouel, sarruel, saroual, seroual o sirwal"}]},{"@type":"WebSite","@id":"https:\/\/tevipa.com\/blog\/#website","url":"https:\/\/tevipa.com\/blog\/","name":"Tele Virtual Patronage","description":"Tevipa","publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tevipa.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/tevipa.com\/blog\/#organization","name":"Tele Virtual Patronage","url":"https:\/\/tevipa.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","width":512,"height":512,"caption":"Tele Virtual Patronage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c","name":"Tele Virtual Patronage","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","caption":"Tele Virtual Patronage"},"sameAs":["https:\/\/tevipa.com\/blog"],"url":"https:\/\/tevipa.com\/blog\/author\/tvpadm\/"}]}},"_links":{"self":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/4359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/comments?post=4359"}],"version-history":[{"count":4,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/4359\/revisions"}],"predecessor-version":[{"id":4375,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/4359\/revisions\/4375"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media\/4363"}],"wp:attachment":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media?parent=4359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/categories?post=4359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/tags?post=4359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}