{"id":4005,"date":"2025-12-23T12:14:28","date_gmt":"2025-12-23T11:14:28","guid":{"rendered":"https:\/\/tevipa.com\/blog\/?p=4005"},"modified":"2025-12-23T12:14:29","modified_gmt":"2025-12-23T11:14:29","slug":"pantalon-de-pinzas-clasico","status":"publish","type":"post","link":"https:\/\/tevipa.com\/blog\/pantalon-de-pinzas-clasico\/","title":{"rendered":"Pantal\u00f3n de pinzas cl\u00e1sico"},"content":{"rendered":"\n<p class=\"has-text-align-right has-small-font-size wp-block-paragraph\"><sup><em>Publicado originalmente el&nbsp;<strong>20 Noviembre 2013<\/strong><\/em><\/sup><\/p>\n\n\n<style>.kb-image4005_7ddbe8-5d .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image4005_7ddbe8-5d is-style-default\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"222\" height=\"300\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg\" alt=\"Logo C\u00f3mo Cubrir un Cuerpo\" class=\"kb-img wp-image-68\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg 222w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-757x1024.jpg 757w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-768x1039.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1135x1536.jpg 1135w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1514x2048.jpg 1514w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran.jpg 1821w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/><\/figure><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\" style=\"font-size:27px\">Pantal\u00f3n de pinzas cl\u00e1sico<\/h1>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Pantal\u00f3n cl\u00e1sico con dos pliegues cerrados al derecho (hacia la bragueta), con bolsillos de vivos en la costura y en la parte trasera<\/p>\n\n\n\n<h2 class=\"wp-block-heading text-justify has-medium-font-size\">Pantal\u00f3n de pinzas cl\u00e1sico: Post relacionados<\/h2>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Es interesante que teng\u00e1is en cuenta los siguientes post de la p\u00e1gina principal \u00a0\u00abC\u00f3mo cubrir un cuerpo\u00bb: \u201c<a href=\"https:\/\/tevipa.com\/blog\/el-pantalon-clasico-de-pliegues\/\">El pantal\u00f3n cl\u00e1sico con pliegues<\/a>\u201d<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">y \u201c<a href=\"https:\/\/tevipa.com\/blog\/patron-base-del-pantalon-clasico-de-caballero-conformacion-normal-atletica-y-junior\/\" target=\"_blank\" rel=\"noreferrer noopener\">Patr\u00f3n base del pantal\u00f3n cl\u00e1sico de caballero: conformaci\u00f3n normal, atl\u00e9tica y junior<\/a>.\u201d<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">En el primer post explicamos c\u00f3mo deb\u00edamos cerrar un pliegue y en el segundo lo utilizaremos como patr\u00f3n base.<\/p>\n\n\n\n<h2 class=\"wp-block-heading text-justify has-medium-font-size\">Pantal\u00f3n de pinzas cl\u00e1sico: Transformaci\u00f3n<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho01-724x1024.jpg\" alt=\"Patr\u00f3n del pantal\u00f3n cl\u00e1sico de caballero con dos pliegues cerrados al derecho, delantero y espalda\" class=\"wp-image-4007\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho01-724x1024.jpg 724w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho01-212x300.jpg 212w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho01-768x1086.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho01-1086x1536.jpg 1086w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho01-1448x2048.jpg 1448w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho01-1320x1867.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho01-scaled.jpg 1810w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">La transformaci\u00f3n llevar\u00e1 tres pasos: La&nbsp;<strong>creaci\u00f3n de los pliegues<\/strong>. El abrir los pliegues en la parte anterior repercutir\u00e1 en algunas peque\u00f1as modificaciones de la parte posterior, por lo que deberemos hacer una serie de&nbsp;<strong>modificaciones en la parte posterior<\/strong>. Y por \u00faltimo el&nbsp;<strong>desplazamiento de la costura lateral<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading text-justify has-medium-font-size\">1.- La creaci\u00f3n de los pliegues:<\/h3>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Al delantero le daremos dos pliegues: uno lo trazaremos por pivote y el otro abriendo una pinza por patronaje.<\/p>\n\n\n\n<h4 class=\"wp-block-heading text-justify has-medium-font-size\">El pliegue pivotado:<\/h4>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Empezaremos por el pliegue pivotado que ser\u00e1 el que marcar\u00e1 la raya del delantero del pantal\u00f3n. El pliegue de marca debe coincidir con el RH (recto hilo) para que la tela al marcarla a la plancha no se deforme.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Pivotaremos el delantero del pantal\u00f3n en la intersecci\u00f3n de l RH con l\u00ednea de bajo. El pivote se har\u00e1 sobre el RH. Pivotaremos la cinturilla marcando 3.5 cm hacia la bragueta.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">El pliegue ser\u00e1 cerrado al derecho por lo que se dirigir\u00e1 hacia la bragueta: el RH del nuevo trazado seguir\u00e1 siendo el del patr\u00f3n base.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Borraremos las l\u00edneas que no sirven. Las l\u00edneas de cadera y de rodilla ser\u00e1n las del patr\u00f3n base.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Si queremos conservar el ancho del pantal\u00f3n de rocilla hasta el bajo rectificaremos la costura haciendo morir la nueva costura de entrepierna en la l\u00ednea de rodilla.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Vemos que la punta de la horquilla ha bajado de 0.75 cm por lo que este incremento deberemos bajarlo de la punta de la horquilla del detr\u00e1s.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Re-trazaremos la cintura mediante una l\u00ednea recta d\u00e1ndole 1 cm m\u00e1s de altura al montante.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\" id=\"attachment_193\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho02-724x1024.jpg\" alt=\"Desarrollo de la transformaci\u00f3n del patr\u00f3n del pantal\u00f3n cl\u00e1sico de caballero con dos pliegues cerrados al derecho\" class=\"wp-image-4008\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho02-724x1024.jpg 724w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho02-212x300.jpg 212w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho02-768x1086.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho02-1086x1536.jpg 1086w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho02-1448x2048.jpg 1448w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho02-1320x1867.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho02-scaled.jpg 1810w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading text-justify has-medium-font-size\">El pliegue patronado.<\/h4>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">El segundo pliegue lo abriremos a mitad de recorrido entre el Rh y el costadillo. Provocaremos un pliegue de 2 cm. Para dar este suplemento en la pieza del delantero sin estrechar la cinturilla daremos la mitad de su valor en la costura lateral y la otra mitad en la parte trasera del patr\u00f3n.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Para dar la inclinaci\u00f3n justa a los labios del pliegue patronaremos el pliegue como si fuera una punza de fuerza dos que muere en la l\u00ednea de cadera.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Borraremos los excesos del pliegue y tendremos listo el delantero del pantal\u00f3n.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"765\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho03-1024x765.jpg\" alt=\"Apertura del segundo pliegue patronado en el delantero del pantal\u00f3n cl\u00e1sico con dos pliegues cerrados al derecho\" class=\"wp-image-4009\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho03-1024x765.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho03-300x224.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho03-768x574.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho03-1536x1148.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho03-2048x1530.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho03-1320x986.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading text-justify has-medium-font-size\">2.- Retoque de la parte posterior.<\/h3>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Primero haremos los retoques de la cinturilla que hemos hecho en el delantero: la subiremos de un cm y le daremos un cent\u00edmetro en la costura del lado. Volveremos a emplazar la pinza en el centro del recorrido de la cintura de la parte posterior del patr\u00f3n.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Luego bajaremos la punta del detr\u00e1s de 0.75, como lo hemos hecho en el delantero.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Para acabar el retoque de la punta de la horquilla detr\u00e1s deberemos dar la mitad del valor que hemos bajado m\u00e1s de holgura en la horquilla de la punta del detr\u00e1s.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"711\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho04-1024x711.jpg\" alt=\"Ajuste de la horquilla y de la parte posterior del pantal\u00f3n cl\u00e1sico tras la creaci\u00f3n de los pliegues delanteros\" class=\"wp-image-4010\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho04-1024x711.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho04-300x208.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho04-768x533.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho04-1536x1066.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho04-2048x1421.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho04-1320x916.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho05-724x1024.jpg\" alt=\"Desplazamiento de la costura lateral del pantal\u00f3n cl\u00e1sico para facilitar la entrada de la mano en el bolsillo\" class=\"wp-image-4011\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho05-724x1024.jpg 724w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho05-212x300.jpg 212w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho05-768x1086.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho05-1086x1536.jpg 1086w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho05-1448x2048.jpg 1448w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho05-1320x1867.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho05-scaled.jpg 1810w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading text-justify has-medium-font-size\">3.- El desplazamiento de la costura lateral.<\/h3>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Este modelo lleva los bolsillos abiertos en la costura lateral.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Es conveniente en los pantalones que llevan este tipo de bolsillos de desplazar la costura lateral para facilitar la entrada de la mano en el bolsillo.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">El desplazamiento de la costura se hace desde la cintura hasta la l\u00ednea de la rodilla.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Un desplazamiento de un par de cent\u00edmetros es suficiente.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho06-724x1024.jpg\" alt=\"Delantero y espalda del pantal\u00f3n cl\u00e1sico tras los ajustes finales derivados de la creaci\u00f3n de los pliegues\" class=\"wp-image-4012\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho06-724x1024.jpg 724w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho06-212x300.jpg 212w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho06-768x1086.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho06-1086x1536.jpg 1086w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho06-1448x2048.jpg 1448w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho06-1320x1867.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho06-scaled.jpg 1810w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Borrando las l\u00edneas que no nos sirven obtendremos la siguiente imagen en que hemos marcado la abertura del bolsillo. 4 cm desde la cintura para marcar el inicio del bolsillo y acabar\u00e1 16 cent\u00edmetros m\u00e1s all\u00e1. Para dejar el vivo recto deberemos retocar algunos mil\u00edmetros el dibujo de la cadera.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho07-724x1024.jpg\" alt=\"Marcaci\u00f3n de la abertura del bolsillo en la costura lateral del pantal\u00f3n cl\u00e1sico de caballero\" class=\"wp-image-4013\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho07-724x1024.jpg 724w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho07-212x300.jpg 212w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho07-768x1086.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho07-1086x1536.jpg 1086w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho07-1448x2048.jpg 1448w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho07-1320x1867.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho07-scaled.jpg 1810w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">El patr\u00f3n transformado ser\u00e1:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho08-724x1024.jpg\" alt=\"Patr\u00f3n final del pantal\u00f3n cl\u00e1sico de caballero con dos pliegues cerrados al derecho\" class=\"wp-image-4014\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho08-724x1024.jpg 724w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho08-212x300.jpg 212w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho08-768x1086.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho08-1086x1536.jpg 1086w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho08-1448x2048.jpg 1448w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho08-1320x1867.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho08-scaled.jpg 1810w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">En el pr\u00f3ximo post haremos el despiece de este mismo modelo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Transformaci\u00f3n del patr\u00f3n base del pantal\u00f3n cl\u00e1sico para obtener un modelo de caballero con dos pliegues cerrados al derecho. El proceso aborda la creaci\u00f3n de los pliegues, el ajuste de la parte posterior y el desplazamiento de la costura lateral para integrar bolsillos funcionales sin alterar el equilibrio del pantal\u00f3n.<\/p>\n","protected":false},"author":1,"featured_media":4014,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1018,23,360,1461],"tags":[44,30,38,34,674,90,1463,874,104,80,362,366,364,82,1169,372,672,40,42,396,402,676],"class_list":["post-4005","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo","category-patron","category-patron-base","category-patron-del-pantalon","tag-como-cubrir-un-cuerpo","tag-comocubriruncuerpo","tag-creacion-de-moda","tag-disenador","tag-ensenanza-de-patronaje","tag-escuela-de-moda","tag-pantalon","tag-pantalon-clasico","tag-patron","tag-patronaje","tag-patronajemoda","tag-patronbase-2","tag-patronbase","tag-patrones","tag-pinzas","tag-sastreria","tag-tecnica-de-patronaje","tag-tele-virtual-patronage","tag-televirtualpatronage","tag-transformacionesdepatron","tag-transformacionesdepatron-2","tag-tutorial-patonaje"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pantal\u00f3n de pinzas cl\u00e1sico - Tele Virtual Patronage<\/title>\n<meta name=\"description\" content=\"Transformaci\u00f3n del pantal\u00f3n cl\u00e1sico con dos pliegues cerrados al derecho. Pliegues, ajuste posterior y desplazamiento de la costura.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tevipa.com\/blog\/pantalon-de-pinzas-clasico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pantal\u00f3n de pinzas cl\u00e1sico - Tele Virtual Patronage\" \/>\n<meta property=\"og:description\" content=\"Transformaci\u00f3n del pantal\u00f3n cl\u00e1sico con dos pliegues cerrados al derecho. Pliegues, ajuste posterior y desplazamiento de la costura.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tevipa.com\/blog\/pantalon-de-pinzas-clasico\/\" \/>\n<meta property=\"og:site_name\" content=\"Tele Virtual Patronage\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-23T11:14:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-23T11:14:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho08-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1810\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tele Virtual Patronage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tele Virtual Patronage\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/pantalon-de-pinzas-clasico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/pantalon-de-pinzas-clasico\\\/\"},\"author\":{\"name\":\"Tele Virtual Patronage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\"},\"headline\":\"Pantal\u00f3n de pinzas cl\u00e1sico\",\"datePublished\":\"2025-12-23T11:14:28+00:00\",\"dateModified\":\"2025-12-23T11:14:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/pantalon-de-pinzas-clasico\\\/\"},\"wordCount\":746,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/pantalon-de-pinzas-clasico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/pantalon2pinzasDerecho08-scaled.jpg\",\"keywords\":[\"como cubrir un cuerpo\",\"comocubriruncuerpo\",\"creaci\u00f3n de moda\",\"dise\u00f1ador\",\"ense\u00f1anza de patronaje\",\"escuela de moda\",\"pantal\u00f3n\",\"pantal\u00f3n cl\u00e1sico\",\"patron\",\"patronaje\",\"patronajemoda\",\"patronbase\",\"patr\u00f3nbase\",\"patrones\",\"pinzas\",\"sastrer\u00eda\",\"t\u00e9cnica de patronaje\",\"tele virtual patronage\",\"televirtualpatronage\",\"transformacionesdepatr\u00f3n\",\"transformacionesdepatron\",\"tutorial patonaje\"],\"articleSection\":[\"Archivo\",\"Patr\u00f3n\",\"Patr\u00f3n base\",\"Patr\u00f3n del pantal\u00f3n\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/pantalon-de-pinzas-clasico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/pantalon-de-pinzas-clasico\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/pantalon-de-pinzas-clasico\\\/\",\"name\":\"Pantal\u00f3n de pinzas cl\u00e1sico - Tele Virtual Patronage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/pantalon-de-pinzas-clasico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/pantalon-de-pinzas-clasico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/pantalon2pinzasDerecho08-scaled.jpg\",\"datePublished\":\"2025-12-23T11:14:28+00:00\",\"dateModified\":\"2025-12-23T11:14:29+00:00\",\"description\":\"Transformaci\u00f3n del pantal\u00f3n cl\u00e1sico con dos pliegues cerrados al derecho. Pliegues, ajuste posterior y desplazamiento de la costura.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/pantalon-de-pinzas-clasico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/pantalon-de-pinzas-clasico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/pantalon-de-pinzas-clasico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/pantalon2pinzasDerecho08-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/pantalon2pinzasDerecho08-scaled.jpg\",\"width\":1810,\"height\":2560,\"caption\":\"Patr\u00f3n final del pantal\u00f3n cl\u00e1sico de caballero con dos pliegues cerrados al derecho\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/pantalon-de-pinzas-clasico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pantal\u00f3n de pinzas cl\u00e1sico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"name\":\"Tele Virtual Patronage\",\"description\":\"Tevipa\",\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\",\"name\":\"Tele Virtual Patronage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"width\":512,\"height\":512,\"caption\":\"Tele Virtual Patronage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\",\"name\":\"Tele Virtual Patronage\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"caption\":\"Tele Virtual Patronage\"},\"sameAs\":[\"https:\\\/\\\/tevipa.com\\\/blog\"],\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/author\\\/tvpadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pantal\u00f3n de pinzas cl\u00e1sico - Tele Virtual Patronage","description":"Transformaci\u00f3n del pantal\u00f3n cl\u00e1sico con dos pliegues cerrados al derecho. Pliegues, ajuste posterior y desplazamiento de la costura.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tevipa.com\/blog\/pantalon-de-pinzas-clasico\/","og_locale":"it_IT","og_type":"article","og_title":"Pantal\u00f3n de pinzas cl\u00e1sico - Tele Virtual Patronage","og_description":"Transformaci\u00f3n del pantal\u00f3n cl\u00e1sico con dos pliegues cerrados al derecho. Pliegues, ajuste posterior y desplazamiento de la costura.","og_url":"https:\/\/tevipa.com\/blog\/pantalon-de-pinzas-clasico\/","og_site_name":"Tele Virtual Patronage","article_published_time":"2025-12-23T11:14:28+00:00","article_modified_time":"2025-12-23T11:14:29+00:00","og_image":[{"width":1810,"height":2560,"url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho08-scaled.jpg","type":"image\/jpeg"}],"author":"Tele Virtual Patronage","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Tele Virtual Patronage","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tevipa.com\/blog\/pantalon-de-pinzas-clasico\/#article","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/pantalon-de-pinzas-clasico\/"},"author":{"name":"Tele Virtual Patronage","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c"},"headline":"Pantal\u00f3n de pinzas cl\u00e1sico","datePublished":"2025-12-23T11:14:28+00:00","dateModified":"2025-12-23T11:14:29+00:00","mainEntityOfPage":{"@id":"https:\/\/tevipa.com\/blog\/pantalon-de-pinzas-clasico\/"},"wordCount":746,"commentCount":0,"publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"image":{"@id":"https:\/\/tevipa.com\/blog\/pantalon-de-pinzas-clasico\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho08-scaled.jpg","keywords":["como cubrir un cuerpo","comocubriruncuerpo","creaci\u00f3n de moda","dise\u00f1ador","ense\u00f1anza de patronaje","escuela de moda","pantal\u00f3n","pantal\u00f3n cl\u00e1sico","patron","patronaje","patronajemoda","patronbase","patr\u00f3nbase","patrones","pinzas","sastrer\u00eda","t\u00e9cnica de patronaje","tele virtual patronage","televirtualpatronage","transformacionesdepatr\u00f3n","transformacionesdepatron","tutorial patonaje"],"articleSection":["Archivo","Patr\u00f3n","Patr\u00f3n base","Patr\u00f3n del pantal\u00f3n"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tevipa.com\/blog\/pantalon-de-pinzas-clasico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tevipa.com\/blog\/pantalon-de-pinzas-clasico\/","url":"https:\/\/tevipa.com\/blog\/pantalon-de-pinzas-clasico\/","name":"Pantal\u00f3n de pinzas cl\u00e1sico - Tele Virtual Patronage","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tevipa.com\/blog\/pantalon-de-pinzas-clasico\/#primaryimage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/pantalon-de-pinzas-clasico\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho08-scaled.jpg","datePublished":"2025-12-23T11:14:28+00:00","dateModified":"2025-12-23T11:14:29+00:00","description":"Transformaci\u00f3n del pantal\u00f3n cl\u00e1sico con dos pliegues cerrados al derecho. Pliegues, ajuste posterior y desplazamiento de la costura.","breadcrumb":{"@id":"https:\/\/tevipa.com\/blog\/pantalon-de-pinzas-clasico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tevipa.com\/blog\/pantalon-de-pinzas-clasico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/pantalon-de-pinzas-clasico\/#primaryimage","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho08-scaled.jpg","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/pantalon2pinzasDerecho08-scaled.jpg","width":1810,"height":2560,"caption":"Patr\u00f3n final del pantal\u00f3n cl\u00e1sico de caballero con dos pliegues cerrados al derecho"},{"@type":"BreadcrumbList","@id":"https:\/\/tevipa.com\/blog\/pantalon-de-pinzas-clasico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tevipa.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Pantal\u00f3n de pinzas cl\u00e1sico"}]},{"@type":"WebSite","@id":"https:\/\/tevipa.com\/blog\/#website","url":"https:\/\/tevipa.com\/blog\/","name":"Tele Virtual Patronage","description":"Tevipa","publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tevipa.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/tevipa.com\/blog\/#organization","name":"Tele Virtual Patronage","url":"https:\/\/tevipa.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","width":512,"height":512,"caption":"Tele Virtual Patronage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c","name":"Tele Virtual Patronage","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","caption":"Tele Virtual Patronage"},"sameAs":["https:\/\/tevipa.com\/blog"],"url":"https:\/\/tevipa.com\/blog\/author\/tvpadm\/"}]}},"_links":{"self":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/4005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/comments?post=4005"}],"version-history":[{"count":2,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/4005\/revisions"}],"predecessor-version":[{"id":4015,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/4005\/revisions\/4015"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media\/4014"}],"wp:attachment":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media?parent=4005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/categories?post=4005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/tags?post=4005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}