{"id":3972,"date":"2025-12-20T19:51:02","date_gmt":"2025-12-20T18:51:02","guid":{"rendered":"https:\/\/tevipa.com\/blog\/?p=3972"},"modified":"2025-12-20T19:55:26","modified_gmt":"2025-12-20T18:55:26","slug":"gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna","status":"publish","type":"post","link":"https:\/\/tevipa.com\/blog\/it\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\/","title":{"rendered":"Gonna con gheroni &#8211; Trasformazione del cartamodello base della gonna"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png\" alt=\"Logo C\u00f3mo Cubrir un Cuerpo\" class=\"wp-image-6\" style=\"width:270px;height:auto\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png 512w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512-300x300.png 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512-150x150.png 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure>\n<\/div>\n\n\n<h1 class=\"wp-block-heading has-text-align-center\"><strong>Gonna con gheroni<br>Trasformazione del cartamodello base della gonna<\/strong><\/h1>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/blog-02-1024x576.jpg\" alt=\"Cartamodello di gonna con gheroni e settori circolari\" class=\"wp-image-3961\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/blog-02-1024x576.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/blog-02-300x169.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/blog-02-768x432.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/blog-02.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Questa trasformazione consente di dare ampiezza alla gonna dritta in modo controllato e preciso.<br>Attraverso i gheroni \u00e8 possibile ottenere l\u2019ampiezza desiderata nel punto scelto della gonna, dall\u2019anca fino al fondo.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Molte gonne da prova per la danza flamenca vengono modellate seguendo questo procedimento, poich\u00e9 permette di ottenere grandi sviluppi al fondo senza alterare la vestibilit\u00e0 in vita e sui fianchi.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">I gheroni sono settori circolari inseriti nel cartamodello per generare volume o ampiezza al fondo, mantenendo invariato l\u2019assetto del cartamodello base.<br>Nel video analizziamo come definire correttamente questi settori, come posizionarli nel cartamodello e quali effetti producano sul risultato finale.<\/p>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-3972_dc34a7-86 .kt-block-spacer{height:60px;}.wp-block-kadence-spacer.kt-block-spacer-3972_dc34a7-86 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-3972_dc34a7-86\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Falda con nesgas | Transformaci\u00f3n del patr\u00f3n base de la falda recta\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/2zWzwziA75M?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-3972_3413fe-ee .kt-block-spacer{height:60px;}.wp-block-kadence-spacer.kt-block-spacer-3972_3413fe-ee .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-3972_3413fe-ee\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading text-justify has-medium-font-size\"><strong>Modalit\u00e0 di utilizzo dei gheroni<\/strong><\/h2>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">I gheroni possono essere:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"text-justify\">Integrati nel cartamodello<\/li>\n\n\n\n<li class=\"text-justify\">Realizzati come pezzi indipendenti<\/li>\n<\/ul>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">In entrambi i casi si parte dal cartamodello base della gonna dritta e i passaggi geometrici restano gli stessi.<\/p>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-3972_3c6267-5f .kt-block-spacer{height:60px;}.wp-block-kadence-spacer.kt-block-spacer-3972_3c6267-5f .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-3972_3c6267-5f\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading text-justify has-medium-font-size\"><strong>Calcolo dello sviluppo del fondo<\/strong><\/h2>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Il calcolo del fondo dipende da:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"text-justify\">altezza del gherone (raggio)<\/li>\n\n\n\n<li class=\"text-justify\">angolo del settore circolare<\/li>\n<\/ul>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-3972_baf8ee-d7 .kt-block-spacer{height:60px;}.wp-block-kadence-spacer.kt-block-spacer-3972_baf8ee-d7 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-3972_baf8ee-d7\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading text-justify has-medium-font-size\"><strong>Esempio pratico<\/strong><\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/transformacionesFalda-1024x576.jpg\" alt=\"Calcolo del volume della gonna con gheroni\" class=\"wp-image-3966\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/transformacionesFalda-1024x576.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/transformacionesFalda-300x169.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/transformacionesFalda-768x432.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/transformacionesFalda.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Misure:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"text-justify\">Mezzo contorno di fianchi: <strong>45 cm<\/strong><\/li>\n\n\n\n<li class=\"text-justify\">Lunghezza gamba dietro: <strong>100 cm<\/strong><\/li>\n\n\n\n<li class=\"text-justify\">Altezza dei fianchi: <strong>18 cm<\/strong><\/li>\n\n\n\n<li class=\"text-justify\">Altezza del ginocchio: <strong>56 cm<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Fondo mezza gonna base:<\/p>\n\n\n\n\\[\n45 + 1 = 46 \\text{ cm}\n\\]\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Fondo gonna base completa:<\/p>\n\n\n\n\\[\n\\text{bassoGonna} = (45 + 1) \\times 2 = 92 \\text{ cm}\n\\]\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading text-justify has-medium-font-size\"><strong>Primo gherone (anca)<\/strong><\/h3>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Raggio: 82 cm<\/p>\n\n\n\n\\[\n100 &#8211; 18 = 82 \\text{ cm}\n\\]\n\n\n\n<p class=\"wp-block-paragraph\"><br>Angolo: 21\u00b0<\/p>\n\n\n\n\\[\n\\text{gheroneAnca} =\n\\frac{2 \\cdot \\pi \\cdot 82 \\cdot 21}{360}\n= 30{,}05 \\text{ cm}\n\\]\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading text-justify has-medium-font-size\"><strong>Secondo gherone (ginocchio)<\/strong><\/h3>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Raggio: 44 cm<\/p>\n\n\n\n\\[\n100 &#8211; 56 = 44 \\text{ cm}\n\\]\n\n\n\n<p class=\"wp-block-paragraph\">Angolo: 90\u00b0<\/p>\n\n\n\n\\[\n\\text{gheroneGinocchio} =\n\\frac{2 \\cdot \\pi \\cdot 44 \\cdot 90}{360}\n= 69{,}11 \\text{ cm}\n\\]\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\"><strong>Terzo gherone (mezza gamba)<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Raggio: 22 cm<\/p>\n\n\n\n\\[\n\\frac{100 &#8211; 56}{2} = 22 \\text{ cm}\n\\]\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Angolo: 90\u00b0<\/p>\n\n\n\n\\[\n\\text{gheroneGamba} =\n\\frac{2 \\cdot \\pi \\cdot 22 \\cdot 90}{360}\n= 34{,}56 \\text{ cm}\n\\]\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-3972_aa0acc-35 .kt-block-spacer{height:60px;}.wp-block-kadence-spacer.kt-block-spacer-3972_aa0acc-35 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-3972_aa0acc-35\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading text-justify has-medium-font-size\"><strong>Sviluppo totale<\/strong><\/h2>\n\n\n\n\\[\n\\text{treGheroni} =\n30{,}05 + 69{,}11 + 34{,}56\n= 134 \\text{ cm}\n\\]\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Ripetuto 10 volte:<\/p>\n\n\n\n\\[\n\\text{sviluppoTotaleAmpiezza} =\n134 \\times 10 = 1340 \\text{ cm}\n\\]\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Ampiezza totale della gonna:<\/p>\n\n\n\n\\[\n\\text{sviluppoTotaleGonna} =\n92 + 1340 = 1432 \\text{ cm}\n\\]\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-3972_3d955e-dd .kt-block-spacer{height:60px;}.wp-block-kadence-spacer.kt-block-spacer-3972_3d955e-dd .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-3972_3d955e-dd\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading text-justify has-medium-font-size\"><strong>Risultato<\/strong><\/h2>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">La gonna presenta circa <strong>14,33 metri di ampiezza<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trasformazione del cartamodello base della gonna diritta mediante gheroni.<br \/>\nL\u2019articolo spiega come definire i settori circolari, calcolare lo sviluppo del fondo e controllare l\u2019ampiezza della gonna senza alterare l\u2019aderenza in vita e sui fianchi, con un esempio pratico completo.<\/p>\n","protected":false},"author":1,"featured_media":3930,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1008,603,770],"tags":[263,247,520,143,151,1307,255,511,1473,167,690,46,54,576,678],"class_list":["post-3972","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-it","category-cartamodello","category-trasformazione","tag-cartamodelli","tag-cartamodello","tag-cartamodellobase","tag-creazione-di-moda","tag-designer","tag-flamenco-it","tag-modellistica","tag-modellisticadimoda","tag-pantalone","tag-scuola-di-moda","tag-tecnica-di-modellistica","tag-tele-virtual-patronage-it","tag-televirtualpatronage-it","tag-trasformazionidicartamodello","tag-tutorial-di-modellistica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gonna con gheroni - Trasformazione del cartamodello base della gonna - Tele Virtual Patronage<\/title>\n<meta name=\"description\" content=\"Trasformazione della gonna diritta con gheroni. Calcolo del fondo, settori circolari e esempio pratico completo applicato alla modellistica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tevipa.com\/blog\/it\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gonna con gheroni - Trasformazione del cartamodello base della gonna - Tele Virtual Patronage\" \/>\n<meta property=\"og:description\" content=\"Trasformazione della gonna diritta con gheroni. Calcolo del fondo, settori circolari e esempio pratico completo applicato alla modellistica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tevipa.com\/blog\/it\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\/\" \/>\n<meta property=\"og:site_name\" content=\"Tele Virtual Patronage\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-20T18:51:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-20T18:55:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/BTR003_IT-scaled.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Tele Virtual Patronage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tele Virtual Patronage\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\\\/\"},\"author\":{\"name\":\"Tele Virtual Patronage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\"},\"headline\":\"Gonna con gheroni &#8211; Trasformazione del cartamodello base della gonna\",\"datePublished\":\"2025-12-20T18:51:02+00:00\",\"dateModified\":\"2025-12-20T18:55:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\\\/\"},\"wordCount\":300,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/BTR003_IT-scaled.png\",\"keywords\":[\"cartamodelli\",\"cartamodello\",\"cartamodellobase\",\"creazione di moda\",\"designer\",\"flamenco\",\"modellistica\",\"modellisticadimoda\",\"pantalone\",\"scuola di moda\",\"tecnica di modellistica\",\"tele virtual patronage\",\"televirtualpatronage\",\"trasformazionidicartamodello\",\"tutorial di modellistica\"],\"articleSection\":[\"Blog It\",\"Cartamodello\",\"Trasformazione\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\\\/\",\"name\":\"Gonna con gheroni - Trasformazione del cartamodello base della gonna - Tele Virtual Patronage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/BTR003_IT-scaled.png\",\"datePublished\":\"2025-12-20T18:51:02+00:00\",\"dateModified\":\"2025-12-20T18:55:26+00:00\",\"description\":\"Trasformazione della gonna diritta con gheroni. Calcolo del fondo, settori circolari e esempio pratico completo applicato alla modellistica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/BTR003_IT-scaled.png\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/BTR003_IT-scaled.png\",\"width\":2560,\"height\":1440,\"caption\":\"Trasformazione del cartamodello base in gonna con gheroni\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gonna con gheroni &#8211; Trasformazione del cartamodello base della gonna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"name\":\"Tele Virtual Patronage\",\"description\":\"Tevipa\",\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\",\"name\":\"Tele Virtual Patronage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"width\":512,\"height\":512,\"caption\":\"Tele Virtual Patronage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\",\"name\":\"Tele Virtual Patronage\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"caption\":\"Tele Virtual Patronage\"},\"sameAs\":[\"https:\\\/\\\/tevipa.com\\\/blog\"],\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/author\\\/tvpadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gonna con gheroni - Trasformazione del cartamodello base della gonna - Tele Virtual Patronage","description":"Trasformazione della gonna diritta con gheroni. Calcolo del fondo, settori circolari e esempio pratico completo applicato alla modellistica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tevipa.com\/blog\/it\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\/","og_locale":"it_IT","og_type":"article","og_title":"Gonna con gheroni - Trasformazione del cartamodello base della gonna - Tele Virtual Patronage","og_description":"Trasformazione della gonna diritta con gheroni. Calcolo del fondo, settori circolari e esempio pratico completo applicato alla modellistica.","og_url":"https:\/\/tevipa.com\/blog\/it\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\/","og_site_name":"Tele Virtual Patronage","article_published_time":"2025-12-20T18:51:02+00:00","article_modified_time":"2025-12-20T18:55:26+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/BTR003_IT-scaled.png","type":"image\/png"}],"author":"Tele Virtual Patronage","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Tele Virtual Patronage","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tevipa.com\/blog\/it\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\/#article","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/it\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\/"},"author":{"name":"Tele Virtual Patronage","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c"},"headline":"Gonna con gheroni &#8211; Trasformazione del cartamodello base della gonna","datePublished":"2025-12-20T18:51:02+00:00","dateModified":"2025-12-20T18:55:26+00:00","mainEntityOfPage":{"@id":"https:\/\/tevipa.com\/blog\/it\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\/"},"wordCount":300,"commentCount":0,"publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"image":{"@id":"https:\/\/tevipa.com\/blog\/it\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/BTR003_IT-scaled.png","keywords":["cartamodelli","cartamodello","cartamodellobase","creazione di moda","designer","flamenco","modellistica","modellisticadimoda","pantalone","scuola di moda","tecnica di modellistica","tele virtual patronage","televirtualpatronage","trasformazionidicartamodello","tutorial di modellistica"],"articleSection":["Blog It","Cartamodello","Trasformazione"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tevipa.com\/blog\/it\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tevipa.com\/blog\/it\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\/","url":"https:\/\/tevipa.com\/blog\/it\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\/","name":"Gonna con gheroni - Trasformazione del cartamodello base della gonna - Tele Virtual Patronage","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tevipa.com\/blog\/it\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\/#primaryimage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/it\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/BTR003_IT-scaled.png","datePublished":"2025-12-20T18:51:02+00:00","dateModified":"2025-12-20T18:55:26+00:00","description":"Trasformazione della gonna diritta con gheroni. Calcolo del fondo, settori circolari e esempio pratico completo applicato alla modellistica.","breadcrumb":{"@id":"https:\/\/tevipa.com\/blog\/it\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tevipa.com\/blog\/it\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/it\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\/#primaryimage","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/BTR003_IT-scaled.png","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/12\/BTR003_IT-scaled.png","width":2560,"height":1440,"caption":"Trasformazione del cartamodello base in gonna con gheroni"},{"@type":"BreadcrumbList","@id":"https:\/\/tevipa.com\/blog\/it\/gonna-con-gheroni-trasformazione-del-cartamodello-base-della-gonna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tevipa.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Gonna con gheroni &#8211; Trasformazione del cartamodello base della gonna"}]},{"@type":"WebSite","@id":"https:\/\/tevipa.com\/blog\/#website","url":"https:\/\/tevipa.com\/blog\/","name":"Tele Virtual Patronage","description":"Tevipa","publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tevipa.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/tevipa.com\/blog\/#organization","name":"Tele Virtual Patronage","url":"https:\/\/tevipa.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","width":512,"height":512,"caption":"Tele Virtual Patronage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c","name":"Tele Virtual Patronage","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","caption":"Tele Virtual Patronage"},"sameAs":["https:\/\/tevipa.com\/blog"],"url":"https:\/\/tevipa.com\/blog\/author\/tvpadm\/"}]}},"_links":{"self":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/3972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/comments?post=3972"}],"version-history":[{"count":6,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/3972\/revisions"}],"predecessor-version":[{"id":3989,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/3972\/revisions\/3989"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media\/3930"}],"wp:attachment":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media?parent=3972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/categories?post=3972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/tags?post=3972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}