{"id":2988,"date":"2025-10-26T20:46:47","date_gmt":"2025-10-26T19:46:47","guid":{"rendered":"https:\/\/tevipa.com\/blog\/?p=2988"},"modified":"2025-10-26T20:46:48","modified_gmt":"2025-10-26T19:46:48","slug":"pantalon-clasico-de-mujer","status":"publish","type":"post","link":"https:\/\/tevipa.com\/blog\/pantalon-clasico-de-mujer\/","title":{"rendered":"Pantal\u00f3n cl\u00e1sico de mujer"},"content":{"rendered":"\n<p class=\"has-text-align-right has-small-font-size wp-block-paragraph\"><sup><em>Publicado originalmente el&nbsp;<strong>19 Septiembre 2013<\/strong><\/em><\/sup><\/p>\n\n\n<style>.kb-image2988_05f73d-33 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image2988_05f73d-33 is-style-default\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"222\" height=\"300\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg\" alt=\"Logo C\u00f3mo Cubrir un Cuerpo\" class=\"kb-img wp-image-68\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg 222w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-757x1024.jpg 757w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-768x1039.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1135x1536.jpg 1135w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1514x2048.jpg 1514w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran.jpg 1821w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/><\/figure><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\" style=\"font-size:27px\"><strong><strong>Pantal\u00f3n cl\u00e1sico de mujer<\/strong><\/strong><\/h1>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">En este post ense\u00f1aremos como poner en pr\u00e1ctica lo que explicamos en\u00a0<em><a href=\"https:\/\/tevipa.com\/blog\/las-proporciones-del-pantalon-clasico-y-forma-de-trazar-el-patron-para-senora-y-ninos\/\">Las proporciones del pantal\u00f3n cl\u00e1sico y forma de trazar el patr\u00f3n para se\u00f1ora y ni\u00f1os<\/a>.\u00a0<\/em>Y nos remitiremos a lo explicado en el post precedente:\u00a0<a href=\"https:\/\/tevipa.com\/blog\/pantalon-base-clasico-infantil\/\"><em>Pantal\u00f3n base cl\u00e1sico infantil.<\/em><\/a><\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">En este post trazaremos el patr\u00f3n base de un pantal\u00f3n de mujer de la talla 40. Las medidas de la talla 40_160 normalizada femenina las pod\u00e9is encontrar en el men\u00fa superior\u00a0<em>Tabla medidas mujer\/Tablas medidas para se\u00f1ora\u00a0<\/em>o clicando aqu\u00ed encima (<em><a href=\"https:\/\/tevipa.com\/blog\/tabla-de-medidas-para-senora\/\">Tabla medidas para se\u00f1ora<\/a>.)<\/em><\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Las medidas de la tabla en cuesti\u00f3n ser\u00e1n: Cintura 36, Cadera 49,&nbsp; Largo pierna 98, Entrepierna 72 y deduciendo las medidas restantes obtendremos:<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Cintura 36<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Cadera 49<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Altura cadera 17.33<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Montante de pantal\u00f3n 26<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Altura de rodilla 55.12<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Largo pierna 89<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Largo ancho bajo: 22<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Las proporciones de la cadera y cintura que nos interesan:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><\/td><td>1\/1<\/td><td>1\/2<\/td><td>1\/4<\/td><td>1\/12<\/td><td>1\/24<\/td><\/tr><tr><td>Cadera (K)<\/td><td>49<\/td><td>24.5<\/td><td>12.25<\/td><td>4.08<\/td><td>2.04<\/td><\/tr><tr><td>Cintura (C)<\/td><td>36<\/td><td>18<\/td><td><\/td><td><\/td><td><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Las l\u00edneas horizontales y el rect\u00e1ngulo de cuerpo de patr\u00f3n ser\u00e1n<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"490\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_01-490x1024.jpg\" alt=\"Patr\u00f3n t\u00e9cnico del pantal\u00f3n cl\u00e1sico de mujer, con las l\u00edneas horizontales y el rect\u00e1ngulo de cuerpo inicial para la talla 40\" class=\"wp-image-2991\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_01-490x1024.jpg 490w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_01-144x300.jpg 144w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_01-768x1604.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_01-735x1536.jpg 735w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_01-980x2048.jpg 980w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_01-1320x2758.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_01-scaled.jpg 1225w\" sizes=\"auto, (max-width: 490px) 100vw, 490px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Trazaremos la punta de horquilla delante (K\/12), daremos el volumen del bajo de la pierna (Ancho de bajo \u2013 1 cm) copiaremos la mitad del ancho de la l\u00ednea de rodilla de la costura lateral en la costura de entrepierna y acabaremos el delantero re-pinzando 0.75 de la mitad delante\/cintura y subiremos de 2\/3 de la medida (0.5), 2 cm de cintura\/costura lateral, subiremos de 2\/3 de la medida (1.33). Le dadremos a la pinza del delantero una fuerza de 2 cm, el centro de la pinza lo situaremos a mitad de camino entre el RH y la l\u00ednea de costura de cadera. El largo de la pinza ser\u00e1 de 8 cm (un tercio del montante aproximadamente)<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">El delantero ser\u00e1:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"457\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_02-457x1024.jpg\" alt=\"Hoja delantera del patr\u00f3n base del pantal\u00f3n cl\u00e1sico de mujer, mostrando la horquilla delantera, la pinza y el ajuste de cintura\" class=\"wp-image-2992\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_02-457x1024.jpg 457w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_02-134x300.jpg 134w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_02-768x1722.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_02-685x1536.jpg 685w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_02-914x2048.jpg 914w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_02-1320x2959.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_02-scaled.jpg 1142w\" sizes=\"auto, (max-width: 457px) 100vw, 457px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Daremos a la punta de detr\u00e1s&nbsp; el mismo valor de la punta de delantero y quitaremos del cuerpo el mismo valor. Desde este \u00faltimo punto subiremos una perpendicular a la l\u00ednea de cadera la intersecci\u00f3n ser\u00e1 el primer punto para determinar la inclinaci\u00f3n de la costura de fondo. El segundo lo encontraremos a un tercio del recorrido en la l\u00ednea de cintura entre su intersecci\u00f3n del RH y la mitad delante.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Trazaremos la l\u00ednea de costura de fondo del pantal\u00f3n alargando m\u00e1s all\u00e1 de la cintura del valor de la punta de la horquilla del delantero (k\/12) y por debajo la alargaremos hasta la intersecci\u00f3n con la l\u00ednea de entrepierna.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Daremos el valor deseado de holgura a la punta de detr\u00e1s y bajaremos una paralela a la l\u00ednea de entrepierna que diste de \u00e9sta 2\/3 del valor de la holgura decidida.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Por encima de la intersecci\u00f3n de la l\u00ednea de cadera con la costura de fondo marcaremos el primer punto de inclinaci\u00f3n de la l\u00ednea de cadera de la parte posterior y lo juntaremos con el segundo punto (intersecci\u00f3n de la l\u00ednea de cadera delantera con costura lateral delantera). Acotaremos sobre la l\u00ednea de cadera de la espalda la mitad del valor de la cadera.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Ensancharemos la pernera delantera de 2 cm desde la rodilla hasta el bajo.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"457\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_03-457x1024.jpg\" alt=\"Desarrollo de la hoja trasera del pantal\u00f3n cl\u00e1sico de mujer con costura de fondo, holgura y correcci\u00f3n de pernera\" class=\"wp-image-2993\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_03-457x1024.jpg 457w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_03-134x300.jpg 134w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_03-768x1721.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_03-685x1536.jpg 685w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_03-914x2048.jpg 914w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_03-1320x2958.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_03-scaled.jpg 1142w\" sizes=\"auto, (max-width: 457px) 100vw, 457px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Pivotaremos la costura lateral por un lado y la cintura por el otro despu\u00e9s de haber descontado la medida de la cintura del delantero sin la pinza e incrementando el valor del remanente del valor de las pinzas de detr\u00e1s: 2+3= 5.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">El cruce de los dos arcos nos determinar\u00e1 la cinturilla del detr\u00e1s m\u00e1s las pinzas. Dividiremos el recorrido de la cintura del detr\u00e1s en tres partes iguales y provocaremos las dos pinzas de la parte trasera, una de tres cm de fuerza, la otra de dos cm de fuerza.<strong><\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"457\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_04-457x1024.jpg\" alt=\"Patr\u00f3n del pantal\u00f3n cl\u00e1sico de mujer con cinturilla trasera y distribuci\u00f3n de las dos pinzas posteriores\" class=\"wp-image-2994\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_04-457x1024.jpg 457w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_04-134x300.jpg 134w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_04-768x1721.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_04-685x1536.jpg 685w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_04-914x2048.jpg 914w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_04-1320x2958.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_04-scaled.jpg 1142w\" sizes=\"auto, (max-width: 457px) 100vw, 457px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Gu\u00eda pr\u00e1ctica para trazar el patr\u00f3n base del pantal\u00f3n cl\u00e1sico de mujer (talla 40).<br \/>\nIncluye medidas y proporciones, construcci\u00f3n de la hoja delantera y trasera, definici\u00f3n de horquilla, holguras y pinzas posteriores. Un paso a paso claro para patronaje femenino.<\/p>\n","protected":false},"author":1,"featured_media":2994,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1018,23,360,1461],"tags":[44,30,38,674,90,1463,874,104,80,362,364,366,82,372,672,40,42,676],"class_list":["post-2988","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo","category-patron","category-patron-base","category-patron-del-pantalon","tag-como-cubrir-un-cuerpo","tag-comocubriruncuerpo","tag-creacion-de-moda","tag-ensenanza-de-patronaje","tag-escuela-de-moda","tag-pantalon","tag-pantalon-clasico","tag-patron","tag-patronaje","tag-patronajemoda","tag-patronbase","tag-patronbase-2","tag-patrones","tag-sastreria","tag-tecnica-de-patronaje","tag-tele-virtual-patronage","tag-televirtualpatronage","tag-tutorial-patonaje"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pantal\u00f3n cl\u00e1sico de mujer - Tele Virtual Patronage<\/title>\n<meta name=\"description\" content=\"Traza el patr\u00f3n base del pantal\u00f3n cl\u00e1sico de mujer (talla 40): medidas, proporciones, horquilla, pinzas y holguras, explicado paso a paso\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tevipa.com\/blog\/pantalon-clasico-de-mujer\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pantal\u00f3n cl\u00e1sico de mujer - Tele Virtual Patronage\" \/>\n<meta property=\"og:description\" content=\"Traza el patr\u00f3n base del pantal\u00f3n cl\u00e1sico de mujer (talla 40): medidas, proporciones, horquilla, pinzas y holguras, explicado paso a paso\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tevipa.com\/blog\/pantalon-clasico-de-mujer\/\" \/>\n<meta property=\"og:site_name\" content=\"Tele Virtual Patronage\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-26T19:46:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-26T19:46:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_04-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1142\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tele Virtual Patronage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tele Virtual Patronage\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/pantalon-clasico-de-mujer\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/pantalon-clasico-de-mujer\\\/\"},\"author\":{\"name\":\"Tele Virtual Patronage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\"},\"headline\":\"Pantal\u00f3n cl\u00e1sico de mujer\",\"datePublished\":\"2025-10-26T19:46:47+00:00\",\"dateModified\":\"2025-10-26T19:46:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/pantalon-clasico-de-mujer\\\/\"},\"wordCount\":628,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/pantalon-clasico-de-mujer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/130917b_04-scaled.jpg\",\"keywords\":[\"como cubrir un cuerpo\",\"comocubriruncuerpo\",\"creaci\u00f3n de moda\",\"ense\u00f1anza de patronaje\",\"escuela de moda\",\"pantal\u00f3n\",\"pantal\u00f3n cl\u00e1sico\",\"patron\",\"patronaje\",\"patronajemoda\",\"patr\u00f3nbase\",\"patronbase\",\"patrones\",\"sastrer\u00eda\",\"t\u00e9cnica de patronaje\",\"tele virtual patronage\",\"televirtualpatronage\",\"tutorial patonaje\"],\"articleSection\":[\"Archivo\",\"Patr\u00f3n\",\"Patr\u00f3n base\",\"Patr\u00f3n del pantal\u00f3n\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/pantalon-clasico-de-mujer\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/pantalon-clasico-de-mujer\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/pantalon-clasico-de-mujer\\\/\",\"name\":\"Pantal\u00f3n cl\u00e1sico de mujer - Tele Virtual Patronage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/pantalon-clasico-de-mujer\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/pantalon-clasico-de-mujer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/130917b_04-scaled.jpg\",\"datePublished\":\"2025-10-26T19:46:47+00:00\",\"dateModified\":\"2025-10-26T19:46:48+00:00\",\"description\":\"Traza el patr\u00f3n base del pantal\u00f3n cl\u00e1sico de mujer (talla 40): medidas, proporciones, horquilla, pinzas y holguras, explicado paso a paso\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/pantalon-clasico-de-mujer\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/pantalon-clasico-de-mujer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/pantalon-clasico-de-mujer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/130917b_04-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/130917b_04-scaled.jpg\",\"width\":1142,\"height\":2560,\"caption\":\"Patr\u00f3n del pantal\u00f3n cl\u00e1sico de mujer con cinturilla trasera y distribuci\u00f3n de las dos pinzas posteriores\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/pantalon-clasico-de-mujer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pantal\u00f3n cl\u00e1sico de mujer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"name\":\"Tele Virtual Patronage\",\"description\":\"Tevipa\",\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\",\"name\":\"Tele Virtual Patronage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"width\":512,\"height\":512,\"caption\":\"Tele Virtual Patronage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\",\"name\":\"Tele Virtual Patronage\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"caption\":\"Tele Virtual Patronage\"},\"sameAs\":[\"https:\\\/\\\/tevipa.com\\\/blog\"],\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/author\\\/tvpadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pantal\u00f3n cl\u00e1sico de mujer - Tele Virtual Patronage","description":"Traza el patr\u00f3n base del pantal\u00f3n cl\u00e1sico de mujer (talla 40): medidas, proporciones, horquilla, pinzas y holguras, explicado paso a paso","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tevipa.com\/blog\/pantalon-clasico-de-mujer\/","og_locale":"it_IT","og_type":"article","og_title":"Pantal\u00f3n cl\u00e1sico de mujer - Tele Virtual Patronage","og_description":"Traza el patr\u00f3n base del pantal\u00f3n cl\u00e1sico de mujer (talla 40): medidas, proporciones, horquilla, pinzas y holguras, explicado paso a paso","og_url":"https:\/\/tevipa.com\/blog\/pantalon-clasico-de-mujer\/","og_site_name":"Tele Virtual Patronage","article_published_time":"2025-10-26T19:46:47+00:00","article_modified_time":"2025-10-26T19:46:48+00:00","og_image":[{"width":1142,"height":2560,"url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_04-scaled.jpg","type":"image\/jpeg"}],"author":"Tele Virtual Patronage","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Tele Virtual Patronage","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tevipa.com\/blog\/pantalon-clasico-de-mujer\/#article","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/pantalon-clasico-de-mujer\/"},"author":{"name":"Tele Virtual Patronage","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c"},"headline":"Pantal\u00f3n cl\u00e1sico de mujer","datePublished":"2025-10-26T19:46:47+00:00","dateModified":"2025-10-26T19:46:48+00:00","mainEntityOfPage":{"@id":"https:\/\/tevipa.com\/blog\/pantalon-clasico-de-mujer\/"},"wordCount":628,"commentCount":0,"publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"image":{"@id":"https:\/\/tevipa.com\/blog\/pantalon-clasico-de-mujer\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_04-scaled.jpg","keywords":["como cubrir un cuerpo","comocubriruncuerpo","creaci\u00f3n de moda","ense\u00f1anza de patronaje","escuela de moda","pantal\u00f3n","pantal\u00f3n cl\u00e1sico","patron","patronaje","patronajemoda","patr\u00f3nbase","patronbase","patrones","sastrer\u00eda","t\u00e9cnica de patronaje","tele virtual patronage","televirtualpatronage","tutorial patonaje"],"articleSection":["Archivo","Patr\u00f3n","Patr\u00f3n base","Patr\u00f3n del pantal\u00f3n"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tevipa.com\/blog\/pantalon-clasico-de-mujer\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tevipa.com\/blog\/pantalon-clasico-de-mujer\/","url":"https:\/\/tevipa.com\/blog\/pantalon-clasico-de-mujer\/","name":"Pantal\u00f3n cl\u00e1sico de mujer - Tele Virtual Patronage","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tevipa.com\/blog\/pantalon-clasico-de-mujer\/#primaryimage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/pantalon-clasico-de-mujer\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_04-scaled.jpg","datePublished":"2025-10-26T19:46:47+00:00","dateModified":"2025-10-26T19:46:48+00:00","description":"Traza el patr\u00f3n base del pantal\u00f3n cl\u00e1sico de mujer (talla 40): medidas, proporciones, horquilla, pinzas y holguras, explicado paso a paso","breadcrumb":{"@id":"https:\/\/tevipa.com\/blog\/pantalon-clasico-de-mujer\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tevipa.com\/blog\/pantalon-clasico-de-mujer\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/pantalon-clasico-de-mujer\/#primaryimage","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_04-scaled.jpg","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130917b_04-scaled.jpg","width":1142,"height":2560,"caption":"Patr\u00f3n del pantal\u00f3n cl\u00e1sico de mujer con cinturilla trasera y distribuci\u00f3n de las dos pinzas posteriores"},{"@type":"BreadcrumbList","@id":"https:\/\/tevipa.com\/blog\/pantalon-clasico-de-mujer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tevipa.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Pantal\u00f3n cl\u00e1sico de mujer"}]},{"@type":"WebSite","@id":"https:\/\/tevipa.com\/blog\/#website","url":"https:\/\/tevipa.com\/blog\/","name":"Tele Virtual Patronage","description":"Tevipa","publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tevipa.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/tevipa.com\/blog\/#organization","name":"Tele Virtual Patronage","url":"https:\/\/tevipa.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","width":512,"height":512,"caption":"Tele Virtual Patronage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c","name":"Tele Virtual Patronage","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","caption":"Tele Virtual Patronage"},"sameAs":["https:\/\/tevipa.com\/blog"],"url":"https:\/\/tevipa.com\/blog\/author\/tvpadm\/"}]}},"_links":{"self":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/2988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/comments?post=2988"}],"version-history":[{"count":3,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/2988\/revisions"}],"predecessor-version":[{"id":2995,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/2988\/revisions\/2995"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media\/2994"}],"wp:attachment":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media?parent=2988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/categories?post=2988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/tags?post=2988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}