{"id":2930,"date":"2025-10-24T21:36:23","date_gmt":"2025-10-24T19:36:23","guid":{"rendered":"https:\/\/tevipa.com\/blog\/?p=2930"},"modified":"2025-10-24T21:38:57","modified_gmt":"2025-10-24T19:38:57","slug":"el-bolsillo-revolver-del-pantalon","status":"publish","type":"post","link":"https:\/\/tevipa.com\/blog\/el-bolsillo-revolver-del-pantalon\/","title":{"rendered":"El bolsillo rev\u00f3lver del pantal\u00f3n"},"content":{"rendered":"\n<p class=\"has-text-align-right has-small-font-size wp-block-paragraph\"><sup><em>Publicado originalmente el&nbsp;<strong>14 Septiembre 2013<\/strong><\/em><\/sup><\/p>\n\n\n<style>.kb-image2930_cc4103-a7 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image2930_cc4103-a7 is-style-default\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"222\" height=\"300\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg\" alt=\"Logo C\u00f3mo Cubrir un Cuerpo\" class=\"kb-img wp-image-68\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg 222w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-757x1024.jpg 757w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-768x1039.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1135x1536.jpg 1135w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1514x2048.jpg 1514w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran.jpg 1821w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/><\/figure><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\" style=\"font-size:27px\"><strong><strong>El bolsillo rev\u00f3lver del pantal\u00f3n<\/strong><\/strong><\/h1>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Para realizar un bolsillo rev\u00f3lver necesitaremos de la hoja del delantero del patr\u00f3n del pantal\u00f3n que queramos transformar.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Sobre la hoja del patr\u00f3n trazaremos el bolsillo acabado, tal i como queremos que quede una vez montado.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">La apertura del bolsillo puede tener diferentes formas y puede ir desde la costura&nbsp; lateral hasta un cuarto de la cintura en su intersecci\u00f3n con la costura de cintura.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">En nuestro caso hemos elegido una l\u00ednea recta que dista de 4 cm desde la costura lateral del pantal\u00f3n.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">La parte inferior de la l\u00ednea morir\u00e1 en la intersecci\u00f3n de la l\u00ednea de cadera con la costura lateral. La apertura del bolsillo ser\u00e1 de 16.5 cm en nuestro caso.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"957\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_01-957x1024.jpg\" alt=\"Patr\u00f3n delantero del pantal\u00f3n con l\u00ednea de apertura del bolsillo rev\u00f3lver a 4 cm de la costura lateral\" class=\"wp-image-2931\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_01-957x1024.jpg 957w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_01-280x300.jpg 280w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_01-768x822.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_01.jpg 1083w\" sizes=\"auto, (max-width: 957px) 100vw, 957px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">En la ilustraci\u00f3n siguiente podemos ver otras variantes de bolsillo rev\u00f3lver. Podemos hacer tantas variantes como nos permita nuestra imaginaci\u00f3n.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">El bolsillo rev\u00f3lver que identifica su corte con la costura del bolsillo recibe el nombre de&nbsp;<em>bolsillo abierto en la costura lateral<\/em>. Del hecho que se corta y patrona de la misma forma no nos detendremos en \u00e9l m\u00e1s que en este momento para dar su nombre.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"497\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_02-1024x497.jpg\" alt=\"Tres ejemplos de bolsillo rev\u00f3lver con distintas formas de apertura y profundidad, mostrados en l\u00edneas de colores\" class=\"wp-image-2932\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_02-1024x497.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_02-300x146.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_02-768x373.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_02-1536x746.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_02-2048x995.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_02-1320x641.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Volvamos a&nbsp; nuestro trazado.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Como segundo paso trazaremos el fondo de bolsillo.<br>Para trazarlo haremos una l\u00ednea paralela al derecho hilo&nbsp; para determinar su ancho, unos 18 cm pueden ser suficientes. A escuadra de esta l\u00ednea determinaremos la l\u00ednea del bajo del fondo de bolsillo finando la profundidad deseada (l\u00ednea roja), en nuestro caso la profundidad es de 27 cm. A la mitad de recorrido de esta l\u00ednea subiremos hasta morir en la costura lateral unos cm por debajo de la l\u00ednea de cadera (en nuestro caso 4 cm). La costura de cintura y lateral ser\u00e1n id\u00e9nticas que las del pantal\u00f3n.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">El fondo de bolsillo se cortar\u00e1 generalmente en otra tela que el pantal\u00f3n. Se utilizan telas resistentes para que el fondo no se rompa con las llaves y monedas que suelen albergar.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Vemos en la ilustraci\u00f3n que sigue el fondo de bolsillo evidenciado en color azul.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"911\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_03-911x1024.jpg\" alt=\"Patr\u00f3n del delantero del pantal\u00f3n con fondo de bolsillo marcado en color azul y l\u00ednea inferior roja\" class=\"wp-image-2933\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_03-911x1024.jpg 911w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_03-267x300.jpg 267w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_03-768x863.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_03.jpg 1031w\" sizes=\"auto, (max-width: 911px) 100vw, 911px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Acto seguido trazaremos&nbsp; la vista del bolsillo. Esta l\u00ednea nos servir\u00e1 de vista para las dos partes del bolsillo tanto superior como inferior. Las vistas sirven para que no se vea la tela del fondo del bolsillo en la parte exterior de la prenda.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">En la ilustraci\u00f3n siguiente hemos evidenciado la l\u00ednea de la vista del bolsillo en color rojo. A partir de este trazado sacaremos las dos vistas que necesitamos&nbsp; para el despiece del bolsillo del pantal\u00f3n.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">La vista de la parte exterior del pantal\u00f3n ser\u00e1 la del \u00e1ngulo de cintura intersecci\u00f3n l\u00ednea de cadera comprendida en la figura geom\u00e9trica que determinan los puntos a-d-e-f-c-b&nbsp; y la vista interior del pantal\u00f3n ser\u00e1 la determinada por la figura de los puntos b-d-e-f-c.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"911\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_04-911x1024.jpg\" alt=\"Patr\u00f3n del delantero con l\u00ednea rosa que indica la vista del bolsillo y letras gu\u00eda para el despiece\" class=\"wp-image-2934\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_04-911x1024.jpg 911w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_04-267x300.jpg 267w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_04-768x863.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_04.jpg 1031w\" sizes=\"auto, (max-width: 911px) 100vw, 911px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">El fondo de bolsillo generalmente se corta al pliegue&nbsp; sobre la l\u00ednea recta que hemos trazado paralela al RH.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">El despiece completo del bolsillo del pantal\u00f3n rev\u00f3lver ser\u00e1:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"901\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_05-1024x901.jpg\" alt=\"Conjunto de piezas del patr\u00f3n del bolsillo rev\u00f3lver, incluyendo delantero, fondo, vistas interior y exterior\" class=\"wp-image-2935\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_05-1024x901.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_05-300x264.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_05-768x676.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_05-1536x1351.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_05-2048x1802.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_05-1320x1161.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aprende a patronar el bolsillo rev\u00f3lver del pantal\u00f3n.<br \/>\nEste post explica c\u00f3mo trazar su apertura, fondo y vistas, y c\u00f3mo realizar el despiece completo con las proporciones adecuadas.<br \/>\nIncluye variantes ilustradas y recomendaciones de confecci\u00f3n profesional.<\/p>\n","protected":false},"author":1,"featured_media":2935,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1018,23,360,1461],"tags":[44,30,38,34,674,90,1463,874,104,80,362,364,366,82,372,672,40,42,402,676],"class_list":["post-2930","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo","category-patron","category-patron-base","category-patron-del-pantalon","tag-como-cubrir-un-cuerpo","tag-comocubriruncuerpo","tag-creacion-de-moda","tag-disenador","tag-ensenanza-de-patronaje","tag-escuela-de-moda","tag-pantalon","tag-pantalon-clasico","tag-patron","tag-patronaje","tag-patronajemoda","tag-patronbase","tag-patronbase-2","tag-patrones","tag-sastreria","tag-tecnica-de-patronaje","tag-tele-virtual-patronage","tag-televirtualpatronage","tag-transformacionesdepatron-2","tag-tutorial-patonaje"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El bolsillo rev\u00f3lver del pantal\u00f3n - Tele Virtual Patronage<\/title>\n<meta name=\"description\" content=\"Aprende a trazar, descomponer y montar el bolsillo rev\u00f3lver del pantal\u00f3n, con vistas, fondo y despiece completo ilustrado\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tevipa.com\/blog\/el-bolsillo-revolver-del-pantalon\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El bolsillo rev\u00f3lver del pantal\u00f3n - Tele Virtual Patronage\" \/>\n<meta property=\"og:description\" content=\"Aprende a trazar, descomponer y montar el bolsillo rev\u00f3lver del pantal\u00f3n, con vistas, fondo y despiece completo ilustrado\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tevipa.com\/blog\/el-bolsillo-revolver-del-pantalon\/\" \/>\n<meta property=\"og:site_name\" content=\"Tele Virtual Patronage\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-24T19:36:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-24T19:38:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_05.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2393\" \/>\n\t<meta property=\"og:image:height\" content=\"2105\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tele Virtual Patronage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tele Virtual Patronage\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-bolsillo-revolver-del-pantalon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-bolsillo-revolver-del-pantalon\\\/\"},\"author\":{\"name\":\"Tele Virtual Patronage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\"},\"headline\":\"El bolsillo rev\u00f3lver del pantal\u00f3n\",\"datePublished\":\"2025-10-24T19:36:23+00:00\",\"dateModified\":\"2025-10-24T19:38:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-bolsillo-revolver-del-pantalon\\\/\"},\"wordCount\":538,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-bolsillo-revolver-del-pantalon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/130914_05.jpg\",\"keywords\":[\"como cubrir un cuerpo\",\"comocubriruncuerpo\",\"creaci\u00f3n de moda\",\"dise\u00f1ador\",\"ense\u00f1anza de patronaje\",\"escuela de moda\",\"pantal\u00f3n\",\"pantal\u00f3n cl\u00e1sico\",\"patron\",\"patronaje\",\"patronajemoda\",\"patr\u00f3nbase\",\"patronbase\",\"patrones\",\"sastrer\u00eda\",\"t\u00e9cnica de patronaje\",\"tele virtual patronage\",\"televirtualpatronage\",\"transformacionesdepatron\",\"tutorial patonaje\"],\"articleSection\":[\"Archivo\",\"Patr\u00f3n\",\"Patr\u00f3n base\",\"Patr\u00f3n del pantal\u00f3n\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-bolsillo-revolver-del-pantalon\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-bolsillo-revolver-del-pantalon\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-bolsillo-revolver-del-pantalon\\\/\",\"name\":\"El bolsillo rev\u00f3lver del pantal\u00f3n - Tele Virtual Patronage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-bolsillo-revolver-del-pantalon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-bolsillo-revolver-del-pantalon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/130914_05.jpg\",\"datePublished\":\"2025-10-24T19:36:23+00:00\",\"dateModified\":\"2025-10-24T19:38:57+00:00\",\"description\":\"Aprende a trazar, descomponer y montar el bolsillo rev\u00f3lver del pantal\u00f3n, con vistas, fondo y despiece completo ilustrado\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-bolsillo-revolver-del-pantalon\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-bolsillo-revolver-del-pantalon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-bolsillo-revolver-del-pantalon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/130914_05.jpg\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/130914_05.jpg\",\"width\":2393,\"height\":2105,\"caption\":\"Conjunto de piezas del patr\u00f3n del bolsillo rev\u00f3lver, incluyendo delantero, fondo, vistas interior y exterior\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-bolsillo-revolver-del-pantalon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El bolsillo rev\u00f3lver del pantal\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"name\":\"Tele Virtual Patronage\",\"description\":\"Tevipa\",\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\",\"name\":\"Tele Virtual Patronage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"width\":512,\"height\":512,\"caption\":\"Tele Virtual Patronage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\",\"name\":\"Tele Virtual Patronage\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"caption\":\"Tele Virtual Patronage\"},\"sameAs\":[\"https:\\\/\\\/tevipa.com\\\/blog\"],\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/author\\\/tvpadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El bolsillo rev\u00f3lver del pantal\u00f3n - Tele Virtual Patronage","description":"Aprende a trazar, descomponer y montar el bolsillo rev\u00f3lver del pantal\u00f3n, con vistas, fondo y despiece completo ilustrado","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tevipa.com\/blog\/el-bolsillo-revolver-del-pantalon\/","og_locale":"it_IT","og_type":"article","og_title":"El bolsillo rev\u00f3lver del pantal\u00f3n - Tele Virtual Patronage","og_description":"Aprende a trazar, descomponer y montar el bolsillo rev\u00f3lver del pantal\u00f3n, con vistas, fondo y despiece completo ilustrado","og_url":"https:\/\/tevipa.com\/blog\/el-bolsillo-revolver-del-pantalon\/","og_site_name":"Tele Virtual Patronage","article_published_time":"2025-10-24T19:36:23+00:00","article_modified_time":"2025-10-24T19:38:57+00:00","og_image":[{"width":2393,"height":2105,"url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_05.jpg","type":"image\/jpeg"}],"author":"Tele Virtual Patronage","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Tele Virtual Patronage","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tevipa.com\/blog\/el-bolsillo-revolver-del-pantalon\/#article","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/el-bolsillo-revolver-del-pantalon\/"},"author":{"name":"Tele Virtual Patronage","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c"},"headline":"El bolsillo rev\u00f3lver del pantal\u00f3n","datePublished":"2025-10-24T19:36:23+00:00","dateModified":"2025-10-24T19:38:57+00:00","mainEntityOfPage":{"@id":"https:\/\/tevipa.com\/blog\/el-bolsillo-revolver-del-pantalon\/"},"wordCount":538,"commentCount":0,"publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"image":{"@id":"https:\/\/tevipa.com\/blog\/el-bolsillo-revolver-del-pantalon\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_05.jpg","keywords":["como cubrir un cuerpo","comocubriruncuerpo","creaci\u00f3n de moda","dise\u00f1ador","ense\u00f1anza de patronaje","escuela de moda","pantal\u00f3n","pantal\u00f3n cl\u00e1sico","patron","patronaje","patronajemoda","patr\u00f3nbase","patronbase","patrones","sastrer\u00eda","t\u00e9cnica de patronaje","tele virtual patronage","televirtualpatronage","transformacionesdepatron","tutorial patonaje"],"articleSection":["Archivo","Patr\u00f3n","Patr\u00f3n base","Patr\u00f3n del pantal\u00f3n"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tevipa.com\/blog\/el-bolsillo-revolver-del-pantalon\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tevipa.com\/blog\/el-bolsillo-revolver-del-pantalon\/","url":"https:\/\/tevipa.com\/blog\/el-bolsillo-revolver-del-pantalon\/","name":"El bolsillo rev\u00f3lver del pantal\u00f3n - Tele Virtual Patronage","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tevipa.com\/blog\/el-bolsillo-revolver-del-pantalon\/#primaryimage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/el-bolsillo-revolver-del-pantalon\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_05.jpg","datePublished":"2025-10-24T19:36:23+00:00","dateModified":"2025-10-24T19:38:57+00:00","description":"Aprende a trazar, descomponer y montar el bolsillo rev\u00f3lver del pantal\u00f3n, con vistas, fondo y despiece completo ilustrado","breadcrumb":{"@id":"https:\/\/tevipa.com\/blog\/el-bolsillo-revolver-del-pantalon\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tevipa.com\/blog\/el-bolsillo-revolver-del-pantalon\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/el-bolsillo-revolver-del-pantalon\/#primaryimage","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_05.jpg","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130914_05.jpg","width":2393,"height":2105,"caption":"Conjunto de piezas del patr\u00f3n del bolsillo rev\u00f3lver, incluyendo delantero, fondo, vistas interior y exterior"},{"@type":"BreadcrumbList","@id":"https:\/\/tevipa.com\/blog\/el-bolsillo-revolver-del-pantalon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tevipa.com\/blog\/"},{"@type":"ListItem","position":2,"name":"El bolsillo rev\u00f3lver del pantal\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/tevipa.com\/blog\/#website","url":"https:\/\/tevipa.com\/blog\/","name":"Tele Virtual Patronage","description":"Tevipa","publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tevipa.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/tevipa.com\/blog\/#organization","name":"Tele Virtual Patronage","url":"https:\/\/tevipa.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","width":512,"height":512,"caption":"Tele Virtual Patronage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c","name":"Tele Virtual Patronage","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","caption":"Tele Virtual Patronage"},"sameAs":["https:\/\/tevipa.com\/blog"],"url":"https:\/\/tevipa.com\/blog\/author\/tvpadm\/"}]}},"_links":{"self":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/2930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/comments?post=2930"}],"version-history":[{"count":2,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/2930\/revisions"}],"predecessor-version":[{"id":2938,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/2930\/revisions\/2938"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media\/2935"}],"wp:attachment":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media?parent=2930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/categories?post=2930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/tags?post=2930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}