{"id":2719,"date":"2025-10-15T18:52:12","date_gmt":"2025-10-15T16:52:12","guid":{"rendered":"https:\/\/tevipa.com\/blog\/?p=2719"},"modified":"2025-10-16T16:22:31","modified_gmt":"2025-10-16T14:22:31","slug":"el-pantalon-definicion-y-apuntes-de-historia","status":"publish","type":"post","link":"https:\/\/tevipa.com\/blog\/el-pantalon-definicion-y-apuntes-de-historia\/","title":{"rendered":"El pantal\u00f3n definici\u00f3n\u00a0y apuntes de historia"},"content":{"rendered":"\n<p class=\"has-text-align-right has-small-font-size wp-block-paragraph\"><sup><em>Publicado originalmente el\u00a0<strong>12 Agosto 2014<\/strong><\/em><\/sup><\/p>\n\n\n<style>.kb-image2719_b136da-48 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image2719_b136da-48 is-style-default\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"222\" height=\"300\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg\" alt=\"Logo C\u00f3mo Cubrir un Cuerpo\" class=\"kb-img wp-image-68\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg 222w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-757x1024.jpg 757w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-768x1039.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1135x1536.jpg 1135w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1514x2048.jpg 1514w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran.jpg 1821w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/><\/figure><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\" style=\"font-size:27px\"><strong><strong>El pantal\u00f3n<\/strong><\/strong><br><strong>definici\u00f3n&nbsp;y apuntes de historia<\/strong><\/h1>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Etimol\u00f3gicamente \u201cpantal\u00f3n\u201d es un galicismo, que a su vez es bebe del t\u00e9rmino italiano \u201cpantalone\u201d. En italiano la palabra \u201cpantalone\u201d proviene de \u201cPantaleone\u201d que es un personaje de la&nbsp;<em>Commedia dell\u2019 arte.<\/em><\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Pantaleone caracterizaba un veneciano viejo y avaro, que vest\u00eda unos calzones largos.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"660\" height=\"887\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130812.jpg\" alt=\"Pantalone, personaje veneciano de la Commedia dell\u2019Arte con calzones largos rojos, origen etimol\u00f3gico del t\u00e9rmino \u201cpantal\u00f3n\u201d\" class=\"wp-image-2721\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130812.jpg 660w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130812-223x300.jpg 223w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">En \u00faltima instancia podr\u00eda venir del griego \u03c0\u03b1v\u03c4\u03b5\u03bb\u03b5\u03ae\u03bc\u03c9\u03bd (<em>panteleemon),&nbsp;<\/em>o sea, \u201c<em>el que se compadece de todos\u201d<\/em><\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Los venecianos eran muy devotos de San Pantale\u00f3n&nbsp; de Nicomedia&nbsp;(Izmit, Turqu\u00eda) que hab\u00eda llegado a ser m\u00e9dico de los emperadores Maximino&nbsp;y Galerio&nbsp;a finales del S. III.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Fue martirizado en el 305 y su veneraci\u00f3n se extendi\u00f3 por las iglesias orientales del cristianismo donde goz\u00f3 de gran predicamento como santo taumaturgo, patrono de la medicina&nbsp; y la obstetricia y sanador de los t\u00edsicos y los bisojos.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"320\" height=\"432\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130812_02.jpg\" alt=\"Icono bizantino de San Pantale\u00f3n, patrono de los m\u00e9dicos y m\u00e1rtir cristiano del siglo IV\" class=\"wp-image-2723\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130812_02.jpg 320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130812_02-222x300.jpg 222w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Los venecianos, que en la Edad Media tuvieron el monopolio mediterr\u00e1neo del comercio del Levante, introdujeron su culto en la iglesia romana, y repartieron por doquier sus supuestas reliquias, que fueron codiciado objeto de transacciones y obsequios reales: Ampollas con su sangre hay en Estambul, Ravello&nbsp;(Salerno,Campania), Montauro&nbsp;(Catanzaro, Calabria), la ermita de San Pantale\u00f3n de Losa (Burgos, Castilla&nbsp;la Vieja) y Madrid (Monasterio de la Encarnaci\u00f3n), cada una de las cuales realiza el milagro de la licuefacci\u00f3n en su debido tiempo (la sangre de la ampolla de Madrid se lic\u00faa la v\u00edspera del d\u00eda del santo, cada 27 de julio). Su cabeza fue a parar a Lyon, y huesos suyos hay en much\u00edsimos sitios, desde el Mausoleo de los Reyes de Francia en la Bas\u00edlica de San<br>Dionisio&nbsp;(Saint Denis) de Par\u00eds, hasta la iglesia de San Pantale\u00f3n del barrio de Matadero en Buenos Aires, y no pod\u00edan faltar en Venecia en la iglesia de San \u201c<em>Pantalon<\/em>\u201d (as\u00ed se dice en dialecto veneciano San&nbsp;<em>Pantaleone<\/em>).<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Los venecianos que eran devotos de San Pantaleone, los identificaban por toda Italia como portadores de la vestimenta caracter\u00edstica de origen turquesco, el calz\u00f3n largo que llevaba el personaje de la&nbsp;<em>Commedia dell\u2019 Arte<\/em>&nbsp;( que recordemos no es de origen veneciana sino bergamasca) llamado don Pantaleone, caricatura de los venecianos, a los que coloquialmente se les llamaba&nbsp;<em>i pantaloni (los pantalones)<\/em>. \u00c9ste fue el motivo de que, cuando, tras la Revoluci\u00f3n Francesa, se abandon\u00f3 el uso del calz\u00f3n corto (las llamadas \u201c<em>culottes\u201d<\/em>) a favor del calz\u00f3n largo, primero les llamaron \u201c<em>sansculottes<\/em>\u201d, literalmente \u201csin calz\u00f3n (corto)\u201d, luego todo el mundo en Europa y Am\u00e9rica-, a este calz\u00f3n se le llamara&nbsp;<em>pantal\u00f3n<\/em>.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Seg\u00fan una etimolog\u00eda popular viene de&nbsp;<em>piantaleone<\/em>, o sea&nbsp;<em>pianta-leone<\/em>&nbsp;(planta de le\u00f3n), recordemos que el le\u00f3n (San Marco) es el s\u00edmbolo de Venecia, por lo tanto pianta&nbsp;leone quiere decir planta de veneciano.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Actualmente podemos definir el pantal\u00f3n como: prenda de&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Indumentaria\">vestir<\/a>&nbsp;que se ajusta a la cintura y llega generalmente hasta el pie, cubriendo cada pierna separadamente (a diferencia de las&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Falda\">faldas<\/a>).<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Se confecciona con distintos materiales (<a href=\"http:\/\/es.wikipedia.org\/wiki\/Algod%C3%B3n\">algod\u00f3n<\/a>,&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Denim\">mezclilla<\/a>,&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Poli%C3%A9ster\">poli\u00e9ster<\/a>,&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Pana\">pana<\/a>, etc.) tiene tres aberturas; una de ellas se ajusta a la cintura y las otras dos en cada una de las piernas. Los pantalones pueden ser largos, en cuyo caso las bocas de las piernas llegan a la altura de los tobillos o incluso m\u00e1s abajo, o pueden ser cortos en distintas graduaciones, que van desde la&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Pantorrilla\">pantorrilla<\/a>&nbsp; hasta la rodilla o la ingle.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Esta vestimenta es usada tanto por&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Var%C3%B3n\">hombres<\/a>&nbsp;como por&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Mujer\">mujeres<\/a>, y suele tener tambi\u00e9n accesorios tales como bolsillos para guardar elementos personales,&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Cremallera_(textil)\">cremallera<\/a>&nbsp;(<a href=\"http:\/\/es.wikipedia.org\/wiki\/Bragueta\">bragueta<\/a>&nbsp;en el caso en que la cremallera se&nbsp; sit\u00fae en la mitad delante), para poder vestir m\u00e1s f\u00e1cilmente aquellos de materiales menos flexibles, y&nbsp;<a href=\"http:\/\/es.wikipedia.org\/w\/index.php?title=Pasacintos&amp;action=edit&amp;redlink=1\">pasa cintas<\/a>, para poder sostener aquellos que sean holgados de cintura.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Los precedentes de los pantalones los encontramos ya en los troyanos, los&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Frigios\">frigios<\/a>, los habitantes de la&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Taurida\">Taurida<\/a>, y en una palabra, todos los b\u00e1rbaros aparecen en los monumentos griegos con calzones semejantes a nuestros pantalones, pero m\u00e1s largos y m\u00e1s arrugados. Los galos se distinguieron con aquella parte de su vestido llamada por los latinos&nbsp;<em>bracece<\/em>, lo que hizo llamar a una parte de las galias&nbsp;<em>gallia&nbsp;braccata<\/em>&nbsp;(bragada)<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Los griegos no los llevaban, como vemos por dos pasajes de&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Teofrasto\">Teofrasto<\/a>. Hallamos en&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Ovidio\">Ovidio<\/a>&nbsp;algunos versos en los que dice expresamente que este adorno o abrigo de los b\u00e1rbaros era desconocido a los griegos y echa en cara a los habitantes del&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Ponto\">Ponto<\/a>, que se vanagloriaban de ser griegos de origen, el haber adoptado los calzones de los&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Persas\">persas<\/a>, sus mortales enemigos. Solamente los atletas llevaban una faja o zona en la cintura para cubrir su desnudez. Se parec\u00eda esta a un&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Mandil\">mandil<\/a>&nbsp;o delantal cerrado, al campestre de los romanos y al&nbsp;<em>subligaculum<\/em>, que propiamente era lo mismo.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">En los primeros tiempos de Roma no se llevaban calzones, porque la&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/T%C3%BAnica\">t\u00fanica<\/a>&nbsp;llegaba hasta las rodillas y la&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Toga_(vestimenta)\">toga<\/a>&nbsp;hasta media pierna. Se supl\u00edan \u00e9stos cuando se llevaban las armas o se ten\u00eda&nbsp; fr\u00edo con ciertas vendas,&nbsp;<em>fascice&nbsp;crurales<\/em>, con las que se envolv\u00edan los muslos. Pero m\u00e1s adelante, tras haberse mezclado los galos, los germanos y&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Godos\">godos<\/a>&nbsp;con los romanos, adoptaron estos en general los calzones largos de aquellos.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">De un pasaje de&nbsp;<a href=\"http:\/\/es.wikipedia.org\/w\/index.php?title=Trebelio&amp;action=edit&amp;redlink=1\">Trebelio<\/a>&nbsp;resulta que los soldados llevaban tambi\u00e9n un campestre. Los oficiales se representan en diferentes monumentos antiguos con calzones que les llegan hasta la rodilla o un poco m\u00e1s abajo.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Todos los que sal\u00edan a los teatros de Roma estaban obligados a llevar por decencia unos calzones largos, como se ve por&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Cicer%C3%B3n\">Cicer\u00f3n<\/a>&nbsp;y por otros monumentos de la antig\u00fcedad. Ordinariamente en los&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Ba%C3%B1o_p%C3%BAblico\">ba\u00f1os p\u00fablicos<\/a>&nbsp;se llevaba el campestre o el&nbsp;<em>subligaculum<\/em>, como se desprende de unos versos de&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Marcial\">Marcial<\/a>.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Las Bragas medievales evolucionaron&nbsp; en las calzas y calzones,&nbsp; y de \u00e9stos naci\u00f3 el pantal\u00f3n como lo conocemos hoy.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"327\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130812_03-327x1024.jpg\" alt=\"Dibujo anat\u00f3mico de hombre con bragas medievales, antecesoras de las calzas y del pantal\u00f3n moderno\" class=\"wp-image-2724\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130812_03-327x1024.jpg 327w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130812_03-96x300.jpg 96w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130812_03-768x2408.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130812_03-490x1536.jpg 490w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130812_03-scaled.jpg 817w\" sizes=\"auto, (max-width: 327px) 100vw, 327px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Requiere una especial menci\u00f3n el pantal\u00f3n Yin o m\u00e1s conocido con la graf\u00eda inglesa Jeans.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">El pantal\u00f3n vaquero, de mezclilla, tejano, yin, pitusa,<sup>[]<\/sup>&nbsp;mahones,&nbsp;<em>jeans<\/em>&nbsp;o&nbsp;<em>blue&nbsp;jean<\/em>, adaptado al espa\u00f1ol como bluy\u00edn, son un tipo de&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Pantal%C3%B3n\">pantal\u00f3n<\/a>&nbsp;hecho con un tejido de algod\u00f3n bastante&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Ropa_de_protecci%C3%B3n\">resistente<\/a>&nbsp;llamado&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Mezclilla\">mezclilla<\/a>&nbsp;o&nbsp;<em>denim<\/em>. Originalmente esta era una prenda de trabajo, pero a partir de la&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/A%C3%B1os_1950\">d\u00e9cada de 1950<\/a>&nbsp;se empezaron a imponer como prenda juvenil.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Actualmente, los t\u00e9rminos&nbsp;<em>blue&nbsp;jean<\/em>&nbsp;o&nbsp;<em>jeans<\/em>&nbsp;son anglicismos aceptados por las Academias de la Lengua Espa\u00f1ola, siempre y cuando se escriban con la graf\u00eda adaptada \u00abbluy\u00edn\u00bb o&nbsp;\u00abyin\u00bb o \u00abyines\u00bb<a href=\"http:\/\/es.wikipedia.org\/wiki\/Pantal%C3%B3n_vaquero#cite_note-3\"><sup>]<\/sup><\/a><\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">El primer antecedente de las prendas vaqueras apareceen&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/G%C3%A9nova\">G\u00e9nova<\/a>&nbsp;(<a href=\"http:\/\/es.wikipedia.org\/wiki\/Italia\">Italia<\/a>) en el&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Siglo_XII\">siglo XII<\/a>, el&nbsp;<a href=\"http:\/\/es.wikipedia.org\/w\/index.php?title=Fust%C3%A1n&amp;action=edit&amp;redlink=1\"><em>fustaneum<\/em><\/a>&nbsp;(\u2018fust\u00e1n\u2019 o fust\u00e1n genov\u00e9s; conocido como&nbsp;<em>gene&nbsp;<\/em>en Francia (de G\u00eanes, G\u00e9nova en franc\u00e9s), de donde deriv\u00f3 en Inglaterra a&nbsp;<em>jene&nbsp;<\/em>y&nbsp;<em>jean<\/em>), por ser originario de&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Al-Fustat\">Al-Fustat<\/a>&nbsp;(<a href=\"http:\/\/es.wikipedia.org\/wiki\/Egipto\">Egipto<\/a>), en el tiempo en que \u00e9sta era una rep\u00fablica independiente y una potencia naval. Se trataba de un tejido resistente de algod\u00f3n. Los primeros vaqueros, como los conocemos hoy, se hicieron para la armada genovesa, porque necesitaban un pantal\u00f3n de todo-uso para sus marineros que pudiera llevarse tanto seco como mojado, y cuyas perneras se pudieran remangar&nbsp;f\u00e1cilmente para no entorpecer las piernas al limpiar la cubierta ni para nadar. Estos pantalones se pod\u00edan lavar arrastr\u00e1ndolos en grandes redes bajo el barco y el agua marina los dejaba blancos. Poco despu\u00e9s los genoveses se encargaron de te\u00f1ir la tela en un caracter\u00edstico color azul \u00edndigo procedente de la India. El primer denim&nbsp;era orginario de N\u00eemes (Francia) y de ah\u00ed el nombre (<em>de N\u00eemes<\/em>&nbsp;se pronuncia como&nbsp;<em>denim<\/em>).<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Los pantalones vaqueros se desarrollaron en&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Estados_Unidos\">Estados Unidos<\/a>&nbsp;alrededor de 1872.&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Levi_Strauss\">Levi&nbsp;Strauss<\/a>&nbsp;era por entonces un comerciante que viv\u00eda en&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/San_Francisco_(California)\">San Francisco<\/a>, pens\u00f3 en utilizar las lonas que se utilizaban en la fabricaci\u00f3n de tiendas de campa\u00f1a para hacer ropas de trabajo a los mineros, ropas que resistieran la vida a la intemperie y el peso en los bolsillos del mineral encontrado, eran todos del color marr\u00f3n usado para las tiendas y sin bolsillos traseros.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Uno de los clientes de Levi&nbsp;Strauss, un sastre que le compraba rollos de tela llamado Jacob&nbsp;Davis, cansado de comprar tela para remendar los pantalones rotos, pens\u00f3 en reforzarlos con remaches de cobre en algunos puntos de especial tensi\u00f3n, tales como los extremos de los bolsillos o la base de la&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Bragueta\">bragueta<\/a>. Como Jacobs&nbsp;no ten\u00eda dinero para patentar la idea, le propuso a Levi&nbsp;hacer negocios juntos. Levi acept\u00f3 y el 20 de mayo de 1873 recibieron la patente #139,121 de la Oficina de patentes y marcas estadounidenses y naci\u00f3 el vaquero tal y como lo conocemos.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">En su origen, los pantalones vaqueros, por su resistencia, los usaban los trabajadores manuales, sobre todo en trabajos pesados como los&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Minero\">mineros<\/a>, o&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Agricultor\">agricultores<\/a>&nbsp;de principios del&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Siglo_XX\">siglo XX<\/a>. En los&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Estados_Unidos\">Estados Unidos<\/a>&nbsp;en la d\u00e9cada de los&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/A%C3%B1os_50\">50<\/a>, los&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Adolescente\">adolescentes<\/a>&nbsp;y&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Joven\">j\u00f3venes<\/a>&nbsp;empezaron a ponerse vaqueros como forma sutil de protesta contra el conformismo. El hecho se consider\u00f3 una provocaci\u00f3n; por ejemplo en algunos cines no se permit\u00eda entrar al que llevase vaqueros. En la d\u00e9cada de los&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/A%C3%B1os_1960\">60<\/a>, los vaqueros ganaron aceptaci\u00f3n y para la d\u00e9cada de los&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/A%C3%B1os_1970\">70<\/a>&nbsp;se hab\u00edan convertido en un art\u00edculo corriente en los EE.UU., al menos para vestir informalmente. Su aceptaci\u00f3n ha seguido creciendo hasta el punto en que ahora forma parte del fondo de&nbsp;<a href=\"http:\/\/es.wikipedia.org\/wiki\/Armario\">armario<\/a>, y en promedio cada estadounidense posee 7 pares.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Este post sigue en \u00ab<a href=\"https:\/\/tevipa.com\/blog\/el-punal-del-pantalon\/\">El pu\u00f1al del pantal\u00f3n<\/a>\u00bb y \u00ab<a href=\"https:\/\/tevipa.com\/blog\/la-horquilla-del-pantalon\/\">La horquilla del pantal\u00f3n<\/a>\u00ab<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"390\" height=\"750\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130812_04.jpg\" alt=\"Pantal\u00f3n vaquero negro con cintur\u00f3n, prenda s\u00edmbolo de la moda contempor\u00e1nea\" class=\"wp-image-2725\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130812_04.jpg 390w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130812_04-156x300.jpg 156w\" sizes=\"auto, (max-width: 390px) 100vw, 390px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Un recorrido apasionante por la historia y la etimolog\u00eda del pantal\u00f3n: desde el veneciano Pantaleone de la Commedia dell\u2019Arte hasta los jeans de Levi Strauss. Descubre c\u00f3mo esta prenda, s\u00edmbolo universal del vestir, evolucion\u00f3 de los calzones de los antiguos b\u00e1rbaros a los bluyines contempor\u00e1neos<\/p>\n","protected":false},"author":1,"featured_media":2725,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1018,23,1461],"tags":[44,30,34,674,90,1463,80,362,372,672,40,42,676,1465],"class_list":["post-2719","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo","category-patron","category-patron-del-pantalon","tag-como-cubrir-un-cuerpo","tag-comocubriruncuerpo","tag-disenador","tag-ensenanza-de-patronaje","tag-escuela-de-moda","tag-pantalon","tag-patronaje","tag-patronajemoda","tag-sastreria","tag-tecnica-de-patronaje","tag-tele-virtual-patronage","tag-televirtualpatronage","tag-tutorial-patonaje","tag-vaqueros"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El pantal\u00f3n definici\u00f3n\u00a0y apuntes de historia - Tele Virtual Patronage<\/title>\n<meta name=\"description\" content=\"Descubre el origen del pantal\u00f3n, su evoluci\u00f3n desde la Antig\u00fcedad hasta los jeans modernos y su relaci\u00f3n con la cultura veneciana y San Pantale\u00f3n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tevipa.com\/blog\/el-pantalon-definicion-y-apuntes-de-historia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El pantal\u00f3n definici\u00f3n\u00a0y apuntes de historia - Tele Virtual Patronage\" \/>\n<meta property=\"og:description\" content=\"Descubre el origen del pantal\u00f3n, su evoluci\u00f3n desde la Antig\u00fcedad hasta los jeans modernos y su relaci\u00f3n con la cultura veneciana y San Pantale\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tevipa.com\/blog\/el-pantalon-definicion-y-apuntes-de-historia\/\" \/>\n<meta property=\"og:site_name\" content=\"Tele Virtual Patronage\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-15T16:52:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-16T14:22:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130812_04.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"390\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tele Virtual Patronage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tele Virtual Patronage\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-pantalon-definicion-y-apuntes-de-historia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-pantalon-definicion-y-apuntes-de-historia\\\/\"},\"author\":{\"name\":\"Tele Virtual Patronage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\"},\"headline\":\"El pantal\u00f3n definici\u00f3n\u00a0y apuntes de historia\",\"datePublished\":\"2025-10-15T16:52:12+00:00\",\"dateModified\":\"2025-10-16T14:22:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-pantalon-definicion-y-apuntes-de-historia\\\/\"},\"wordCount\":1799,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-pantalon-definicion-y-apuntes-de-historia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/130812_04.jpg\",\"keywords\":[\"como cubrir un cuerpo\",\"comocubriruncuerpo\",\"dise\u00f1ador\",\"ense\u00f1anza de patronaje\",\"escuela de moda\",\"pantal\u00f3n\",\"patronaje\",\"patronajemoda\",\"sastrer\u00eda\",\"t\u00e9cnica de patronaje\",\"tele virtual patronage\",\"televirtualpatronage\",\"tutorial patonaje\",\"vaqueros\"],\"articleSection\":[\"Archivo\",\"Patr\u00f3n\",\"Patr\u00f3n del pantal\u00f3n\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-pantalon-definicion-y-apuntes-de-historia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-pantalon-definicion-y-apuntes-de-historia\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-pantalon-definicion-y-apuntes-de-historia\\\/\",\"name\":\"El pantal\u00f3n definici\u00f3n\u00a0y apuntes de historia - Tele Virtual Patronage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-pantalon-definicion-y-apuntes-de-historia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-pantalon-definicion-y-apuntes-de-historia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/130812_04.jpg\",\"datePublished\":\"2025-10-15T16:52:12+00:00\",\"dateModified\":\"2025-10-16T14:22:31+00:00\",\"description\":\"Descubre el origen del pantal\u00f3n, su evoluci\u00f3n desde la Antig\u00fcedad hasta los jeans modernos y su relaci\u00f3n con la cultura veneciana y San Pantale\u00f3n\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-pantalon-definicion-y-apuntes-de-historia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-pantalon-definicion-y-apuntes-de-historia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-pantalon-definicion-y-apuntes-de-historia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/130812_04.jpg\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/130812_04.jpg\",\"width\":390,\"height\":750,\"caption\":\"Pantal\u00f3n vaquero negro con cintur\u00f3n, prenda s\u00edmbolo de la moda contempor\u00e1nea\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-pantalon-definicion-y-apuntes-de-historia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El pantal\u00f3n definici\u00f3n\u00a0y apuntes de historia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"name\":\"Tele Virtual Patronage\",\"description\":\"Tevipa\",\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\",\"name\":\"Tele Virtual Patronage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"width\":512,\"height\":512,\"caption\":\"Tele Virtual Patronage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\",\"name\":\"Tele Virtual Patronage\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"caption\":\"Tele Virtual Patronage\"},\"sameAs\":[\"https:\\\/\\\/tevipa.com\\\/blog\"],\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/author\\\/tvpadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El pantal\u00f3n definici\u00f3n\u00a0y apuntes de historia - Tele Virtual Patronage","description":"Descubre el origen del pantal\u00f3n, su evoluci\u00f3n desde la Antig\u00fcedad hasta los jeans modernos y su relaci\u00f3n con la cultura veneciana y San Pantale\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tevipa.com\/blog\/el-pantalon-definicion-y-apuntes-de-historia\/","og_locale":"it_IT","og_type":"article","og_title":"El pantal\u00f3n definici\u00f3n\u00a0y apuntes de historia - Tele Virtual Patronage","og_description":"Descubre el origen del pantal\u00f3n, su evoluci\u00f3n desde la Antig\u00fcedad hasta los jeans modernos y su relaci\u00f3n con la cultura veneciana y San Pantale\u00f3n","og_url":"https:\/\/tevipa.com\/blog\/el-pantalon-definicion-y-apuntes-de-historia\/","og_site_name":"Tele Virtual Patronage","article_published_time":"2025-10-15T16:52:12+00:00","article_modified_time":"2025-10-16T14:22:31+00:00","og_image":[{"width":390,"height":750,"url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130812_04.jpg","type":"image\/jpeg"}],"author":"Tele Virtual Patronage","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Tele Virtual Patronage","Tempo di lettura stimato":"10 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tevipa.com\/blog\/el-pantalon-definicion-y-apuntes-de-historia\/#article","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/el-pantalon-definicion-y-apuntes-de-historia\/"},"author":{"name":"Tele Virtual Patronage","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c"},"headline":"El pantal\u00f3n definici\u00f3n\u00a0y apuntes de historia","datePublished":"2025-10-15T16:52:12+00:00","dateModified":"2025-10-16T14:22:31+00:00","mainEntityOfPage":{"@id":"https:\/\/tevipa.com\/blog\/el-pantalon-definicion-y-apuntes-de-historia\/"},"wordCount":1799,"commentCount":0,"publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"image":{"@id":"https:\/\/tevipa.com\/blog\/el-pantalon-definicion-y-apuntes-de-historia\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130812_04.jpg","keywords":["como cubrir un cuerpo","comocubriruncuerpo","dise\u00f1ador","ense\u00f1anza de patronaje","escuela de moda","pantal\u00f3n","patronaje","patronajemoda","sastrer\u00eda","t\u00e9cnica de patronaje","tele virtual patronage","televirtualpatronage","tutorial patonaje","vaqueros"],"articleSection":["Archivo","Patr\u00f3n","Patr\u00f3n del pantal\u00f3n"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tevipa.com\/blog\/el-pantalon-definicion-y-apuntes-de-historia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tevipa.com\/blog\/el-pantalon-definicion-y-apuntes-de-historia\/","url":"https:\/\/tevipa.com\/blog\/el-pantalon-definicion-y-apuntes-de-historia\/","name":"El pantal\u00f3n definici\u00f3n\u00a0y apuntes de historia - Tele Virtual Patronage","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tevipa.com\/blog\/el-pantalon-definicion-y-apuntes-de-historia\/#primaryimage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/el-pantalon-definicion-y-apuntes-de-historia\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130812_04.jpg","datePublished":"2025-10-15T16:52:12+00:00","dateModified":"2025-10-16T14:22:31+00:00","description":"Descubre el origen del pantal\u00f3n, su evoluci\u00f3n desde la Antig\u00fcedad hasta los jeans modernos y su relaci\u00f3n con la cultura veneciana y San Pantale\u00f3n","breadcrumb":{"@id":"https:\/\/tevipa.com\/blog\/el-pantalon-definicion-y-apuntes-de-historia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tevipa.com\/blog\/el-pantalon-definicion-y-apuntes-de-historia\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/el-pantalon-definicion-y-apuntes-de-historia\/#primaryimage","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130812_04.jpg","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/130812_04.jpg","width":390,"height":750,"caption":"Pantal\u00f3n vaquero negro con cintur\u00f3n, prenda s\u00edmbolo de la moda contempor\u00e1nea"},{"@type":"BreadcrumbList","@id":"https:\/\/tevipa.com\/blog\/el-pantalon-definicion-y-apuntes-de-historia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tevipa.com\/blog\/"},{"@type":"ListItem","position":2,"name":"El pantal\u00f3n definici\u00f3n\u00a0y apuntes de historia"}]},{"@type":"WebSite","@id":"https:\/\/tevipa.com\/blog\/#website","url":"https:\/\/tevipa.com\/blog\/","name":"Tele Virtual Patronage","description":"Tevipa","publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tevipa.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/tevipa.com\/blog\/#organization","name":"Tele Virtual Patronage","url":"https:\/\/tevipa.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","width":512,"height":512,"caption":"Tele Virtual Patronage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c","name":"Tele Virtual Patronage","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","caption":"Tele Virtual Patronage"},"sameAs":["https:\/\/tevipa.com\/blog"],"url":"https:\/\/tevipa.com\/blog\/author\/tvpadm\/"}]}},"_links":{"self":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/2719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/comments?post=2719"}],"version-history":[{"count":6,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/2719\/revisions"}],"predecessor-version":[{"id":2783,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/2719\/revisions\/2783"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media\/2725"}],"wp:attachment":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media?parent=2719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/categories?post=2719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/tags?post=2719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}