{"id":2618,"date":"2025-10-12T12:19:27","date_gmt":"2025-10-12T10:19:27","guid":{"rendered":"https:\/\/tevipa.com\/blog\/?p=2618"},"modified":"2025-10-12T12:19:29","modified_gmt":"2025-10-12T10:19:29","slug":"el-volumen-del-mirinaque","status":"publish","type":"post","link":"https:\/\/tevipa.com\/blog\/el-volumen-del-mirinaque\/","title":{"rendered":"El volumen del miri\u00f1aque"},"content":{"rendered":"\n<p class=\"has-text-align-right has-small-font-size\"><sup><em>Publicado originalmente el&nbsp;<strong>20 Septiembre 2014<\/strong><\/em><\/sup><\/p>\n\n\n<style>.kb-image2618_b362ef-4a .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image2618_b362ef-4a is-style-default\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"222\" height=\"300\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg\" alt=\"Logo C\u00f3mo Cubrir un Cuerpo\" class=\"kb-img wp-image-68\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg 222w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-757x1024.jpg 757w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-768x1039.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1135x1536.jpg 1135w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1514x2048.jpg 1514w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran.jpg 1821w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/><\/figure><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\" style=\"font-size:27px\"><strong>El volumen del miri\u00f1aque<\/strong><\/h1>\n\n\n\n<p class=\"text-justify\">En este post analizaremos el volumen de los miri\u00f1aques y de las crinolinas.<\/p>\n\n\n\n<p class=\"text-justify\">Las formas que podemos dar a las crinolinas son infinitas.<\/p>\n\n\n\n<p class=\"text-justify\">En este post hemos dibujado los aros de forma poligonal, como un dodec\u00e1gono, si la varilla que utilizamos no la marcamos y cosemos bien sus puntas con el procedimiento que explicamos en el post anterior el dodec\u00e1gono se convertir\u00e1 en c\u00edrculo. En el caso de que queramos una forma el\u00edptica podemos utilizar varilla met\u00e1lica y darle la forma deseada. Por el contrario, &nbsp;si queremos que nuestras faldas marquen \u00e1ngulos y aristas las varillas del miri\u00f1aque deber\u00e1n coserse por partes en un pasaballenas o cubrevarillas o bien deberemos marcarlas con calor en el caso de que sean de PVC o bien doblarlas en el caso de que sean met\u00e1licas.<\/p>\n\n\n\n<p class=\"text-justify\">El volumen del miri\u00f1aque viene determinado por:<\/p>\n\n\n\n<p class=\"text-justify\">a.- La distancia entre los aros de la falda<\/p>\n\n\n\n<p class=\"text-justify\">Con los mismos aros que utilizamos en una falda, coloc\u00e1ndolos a alturas diferentes conseguimos vol\u00famenes diferentes.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"842\" height=\"238\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/volumenmirinaque-01.gif\" alt=\"Serie de maniqu\u00edes con estructuras de miri\u00f1aque que muestran c\u00f3mo var\u00eda el volumen al cambiar la altura de los aros\" class=\"wp-image-2620\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify\">En esta primera ilustraci\u00f3n mostramos la estructura del post precedente <a href=\"https:\/\/tevipa.com\/blog\/crinolina-o-mirinaque\/\">&#8220;Crinolina o miri\u00f1aque&#8221;<\/a>, colocando los aros a diferentes alturas regulares<\/p>\n\n\n\n<p class=\"text-justify\">En la ilustraci\u00f3n que sigue vemos los mismos aros distribuidos siempre de menor a mayor per\u00edmetro desde la cintura hasta el \u00faltimo aro del miri\u00f1aque con alturas diferentes.<\/p>\n\n\n\n<p class=\"text-justify\">Variando las alturas nos aparecer\u00e1n miri\u00f1aques de forma totalmente diferentes.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"842\" height=\"238\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/volumenmirinaque-02.gif\" alt=\"Serie de maniqu\u00edes con miri\u00f1aques que muestran diferentes alturas y per\u00edmetros de aros para comparar el volumen de la falda\" class=\"wp-image-2621\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify\">b.- El n\u00famero de aros de la falda<\/p>\n\n\n\n<p class=\"text-justify\">En n\u00famero de los aros de la falda nos dar\u00e1n la posibilidad de redondear la costura lateral, a m\u00e1s aros m\u00e1s redondeada ser\u00e1 nuestra costura lateral, si s\u00f3lo colocamos un aro nos encontraremos con una falda con forma de cono truncado o pir\u00e1mide trunca.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"842\" height=\"238\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/volumenmirinaque-03.gif\" alt=\"Serie de maniqu\u00edes con miri\u00f1aques que muestran c\u00f3mo var\u00eda la redondez lateral al aumentar el n\u00famero de aros\" class=\"wp-image-2622\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify\">c.- Per\u00edmetro de los aros de la falda.<\/p>\n\n\n\n<p class=\"text-justify\">El per\u00edmetro de los aros del miri\u00f1aque influye de dos formas:<\/p>\n\n\n\n<p class=\"text-justify\">C1.- Uno dando mayor o menor amplitud a la falda<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"842\" height=\"238\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/volumenmirinaque-04.gif\" alt=\"Serie de maniqu\u00edes con miri\u00f1aques que muestran diferentes per\u00edmetros de aros para comparar la amplitud de la falda\" class=\"wp-image-2623\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify\">C2.-Dando formas regulares o irregulares a la falda.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"842\" height=\"238\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/volumenmirinaque-05.gif\" alt=\"Serie de maniqu\u00edes con miri\u00f1aques que muestran estructuras regulares e irregulares para modificar la forma de la falda\" class=\"wp-image-2624\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify\">Podemos darles tambi\u00e9n formas irregulares, para lo cual ser\u00e1 interesante estudiar los desarrollos de los cuerpos geom\u00e9tricos.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"137\" height=\"238\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/volumenmirinaque-06.gif\" alt=\"Maniqu\u00ed con estructura de miri\u00f1aque formada por varillas que crean un cuerpo geom\u00e9trico tipo icosaedro\" class=\"wp-image-2625\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify\">En la ilustraci\u00f3n anterior hemos mostrado un miri\u00f1aque con la forma de un icosaedro.<\/p>\n\n\n\n<p class=\"text-justify\">En las pr\u00f3ximos post estudiaremos como desarrollar los partrones de las crinolinas o c\u00f3mo montar las crinolinas de los tipos estudiados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El volumen del miri\u00f1aque depende de la distancia, el n\u00famero y el per\u00edmetro de los aros que lo componen. Este post analiza c\u00f3mo var\u00eda la forma y el volumen de las crinolinas seg\u00fan su estructura y disposici\u00f3n<\/p>\n","protected":false},"author":1,"featured_media":2623,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1018,23,1181],"tags":[44,30,38,34,90,1449,80,372,40,42],"class_list":["post-2618","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo","category-patron","category-patron-faldas","tag-como-cubrir-un-cuerpo","tag-comocubriruncuerpo","tag-creacion-de-moda","tag-disenador","tag-escuela-de-moda","tag-mirinaque","tag-patronaje","tag-sastreria","tag-tele-virtual-patronage","tag-televirtualpatronage"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El volumen del miri\u00f1aque - Tele Virtual Patronage<\/title>\n<meta name=\"description\" content=\"Aprende qu\u00e9 factores determinan el volumen de un miri\u00f1aque y c\u00f3mo var\u00eda seg\u00fan la distancia, n\u00famero y forma de los aros\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tevipa.com\/blog\/el-volumen-del-mirinaque\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El volumen del miri\u00f1aque - Tele Virtual Patronage\" \/>\n<meta property=\"og:description\" content=\"Aprende qu\u00e9 factores determinan el volumen de un miri\u00f1aque y c\u00f3mo var\u00eda seg\u00fan la distancia, n\u00famero y forma de los aros\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tevipa.com\/blog\/el-volumen-del-mirinaque\/\" \/>\n<meta property=\"og:site_name\" content=\"Tele Virtual Patronage\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-12T10:19:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-12T10:19:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/volumenmirinaque-04.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"842\" \/>\n\t<meta property=\"og:image:height\" content=\"238\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"Tele Virtual Patronage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tele Virtual Patronage\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-volumen-del-mirinaque\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-volumen-del-mirinaque\\\/\"},\"author\":{\"name\":\"Tele Virtual Patronage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\"},\"headline\":\"El volumen del miri\u00f1aque\",\"datePublished\":\"2025-10-12T10:19:27+00:00\",\"dateModified\":\"2025-10-12T10:19:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-volumen-del-mirinaque\\\/\"},\"wordCount\":418,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-volumen-del-mirinaque\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/volumenmirinaque-04.gif\",\"keywords\":[\"como cubrir un cuerpo\",\"comocubriruncuerpo\",\"creaci\u00f3n de moda\",\"dise\u00f1ador\",\"escuela de moda\",\"miri\u00f1aque\",\"patronaje\",\"sastrer\u00eda\",\"tele virtual patronage\",\"televirtualpatronage\"],\"articleSection\":[\"Archivo\",\"Patr\u00f3n\",\"Patr\u00f3n faldas\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-volumen-del-mirinaque\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-volumen-del-mirinaque\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-volumen-del-mirinaque\\\/\",\"name\":\"El volumen del miri\u00f1aque - Tele Virtual Patronage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-volumen-del-mirinaque\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-volumen-del-mirinaque\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/volumenmirinaque-04.gif\",\"datePublished\":\"2025-10-12T10:19:27+00:00\",\"dateModified\":\"2025-10-12T10:19:29+00:00\",\"description\":\"Aprende qu\u00e9 factores determinan el volumen de un miri\u00f1aque y c\u00f3mo var\u00eda seg\u00fan la distancia, n\u00famero y forma de los aros\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-volumen-del-mirinaque\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-volumen-del-mirinaque\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-volumen-del-mirinaque\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/volumenmirinaque-04.gif\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/volumenmirinaque-04.gif\",\"width\":842,\"height\":238,\"caption\":\"Serie de maniqu\u00edes con miri\u00f1aques que muestran diferentes per\u00edmetros de aros para comparar la amplitud de la falda\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-volumen-del-mirinaque\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El volumen del miri\u00f1aque\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"name\":\"Tele Virtual Patronage\",\"description\":\"Tevipa\",\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\",\"name\":\"Tele Virtual Patronage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"width\":512,\"height\":512,\"caption\":\"Tele Virtual Patronage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\",\"name\":\"Tele Virtual Patronage\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"caption\":\"Tele Virtual Patronage\"},\"sameAs\":[\"https:\\\/\\\/tevipa.com\\\/blog\"],\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/author\\\/tvpadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El volumen del miri\u00f1aque - Tele Virtual Patronage","description":"Aprende qu\u00e9 factores determinan el volumen de un miri\u00f1aque y c\u00f3mo var\u00eda seg\u00fan la distancia, n\u00famero y forma de los aros","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tevipa.com\/blog\/el-volumen-del-mirinaque\/","og_locale":"it_IT","og_type":"article","og_title":"El volumen del miri\u00f1aque - Tele Virtual Patronage","og_description":"Aprende qu\u00e9 factores determinan el volumen de un miri\u00f1aque y c\u00f3mo var\u00eda seg\u00fan la distancia, n\u00famero y forma de los aros","og_url":"https:\/\/tevipa.com\/blog\/el-volumen-del-mirinaque\/","og_site_name":"Tele Virtual Patronage","article_published_time":"2025-10-12T10:19:27+00:00","article_modified_time":"2025-10-12T10:19:29+00:00","og_image":[{"width":842,"height":238,"url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/volumenmirinaque-04.gif","type":"image\/gif"}],"author":"Tele Virtual Patronage","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Tele Virtual Patronage","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tevipa.com\/blog\/el-volumen-del-mirinaque\/#article","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/el-volumen-del-mirinaque\/"},"author":{"name":"Tele Virtual Patronage","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c"},"headline":"El volumen del miri\u00f1aque","datePublished":"2025-10-12T10:19:27+00:00","dateModified":"2025-10-12T10:19:29+00:00","mainEntityOfPage":{"@id":"https:\/\/tevipa.com\/blog\/el-volumen-del-mirinaque\/"},"wordCount":418,"commentCount":0,"publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"image":{"@id":"https:\/\/tevipa.com\/blog\/el-volumen-del-mirinaque\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/volumenmirinaque-04.gif","keywords":["como cubrir un cuerpo","comocubriruncuerpo","creaci\u00f3n de moda","dise\u00f1ador","escuela de moda","miri\u00f1aque","patronaje","sastrer\u00eda","tele virtual patronage","televirtualpatronage"],"articleSection":["Archivo","Patr\u00f3n","Patr\u00f3n faldas"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tevipa.com\/blog\/el-volumen-del-mirinaque\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tevipa.com\/blog\/el-volumen-del-mirinaque\/","url":"https:\/\/tevipa.com\/blog\/el-volumen-del-mirinaque\/","name":"El volumen del miri\u00f1aque - Tele Virtual Patronage","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tevipa.com\/blog\/el-volumen-del-mirinaque\/#primaryimage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/el-volumen-del-mirinaque\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/volumenmirinaque-04.gif","datePublished":"2025-10-12T10:19:27+00:00","dateModified":"2025-10-12T10:19:29+00:00","description":"Aprende qu\u00e9 factores determinan el volumen de un miri\u00f1aque y c\u00f3mo var\u00eda seg\u00fan la distancia, n\u00famero y forma de los aros","breadcrumb":{"@id":"https:\/\/tevipa.com\/blog\/el-volumen-del-mirinaque\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tevipa.com\/blog\/el-volumen-del-mirinaque\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/el-volumen-del-mirinaque\/#primaryimage","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/volumenmirinaque-04.gif","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/volumenmirinaque-04.gif","width":842,"height":238,"caption":"Serie de maniqu\u00edes con miri\u00f1aques que muestran diferentes per\u00edmetros de aros para comparar la amplitud de la falda"},{"@type":"BreadcrumbList","@id":"https:\/\/tevipa.com\/blog\/el-volumen-del-mirinaque\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tevipa.com\/blog\/"},{"@type":"ListItem","position":2,"name":"El volumen del miri\u00f1aque"}]},{"@type":"WebSite","@id":"https:\/\/tevipa.com\/blog\/#website","url":"https:\/\/tevipa.com\/blog\/","name":"Tele Virtual Patronage","description":"Tevipa","publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tevipa.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/tevipa.com\/blog\/#organization","name":"Tele Virtual Patronage","url":"https:\/\/tevipa.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","width":512,"height":512,"caption":"Tele Virtual Patronage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c","name":"Tele Virtual Patronage","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","caption":"Tele Virtual Patronage"},"sameAs":["https:\/\/tevipa.com\/blog"],"url":"https:\/\/tevipa.com\/blog\/author\/tvpadm\/"}]}},"_links":{"self":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/2618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/comments?post=2618"}],"version-history":[{"count":2,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/2618\/revisions"}],"predecessor-version":[{"id":2626,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/2618\/revisions\/2626"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media\/2623"}],"wp:attachment":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media?parent=2618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/categories?post=2618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/tags?post=2618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}