{"id":2505,"date":"2025-10-11T19:37:21","date_gmt":"2025-10-11T17:37:21","guid":{"rendered":"https:\/\/tevipa.com\/blog\/?p=2505"},"modified":"2025-10-11T21:44:29","modified_gmt":"2025-10-11T19:44:29","slug":"vestidos-flamencos-la-bata-de-cola","status":"publish","type":"post","link":"https:\/\/tevipa.com\/blog\/vestidos-flamencos-la-bata-de-cola\/","title":{"rendered":"Vestidos flamencos &#8211; La bata de cola"},"content":{"rendered":"\n<p class=\"has-text-align-right has-small-font-size wp-block-paragraph\"><sup><em>Publicado originalmente el&nbsp;<strong>2 Enero 2014<\/strong><\/em><\/sup><\/p>\n\n\n<style>.kb-image2505_7e623e-0d .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image2505_7e623e-0d is-style-default\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"222\" height=\"300\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg\" alt=\"Logo C\u00f3mo Cubrir un Cuerpo\" class=\"kb-img wp-image-68\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg 222w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-757x1024.jpg 757w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-768x1039.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1135x1536.jpg 1135w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1514x2048.jpg 1514w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran.jpg 1821w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/><\/figure><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\" style=\"font-size:27px\"><strong>Vestidos flamencos<\/strong><br>La bata de cola<\/h1>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"770\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_paula-770x1024.jpg\" alt=\"Ilustraci\u00f3n de un vestido flamenco rojo con bata de cola y volantes, vista frontal y trasera\" class=\"wp-image-2507\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_paula-770x1024.jpg 770w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_paula-225x300.jpg 225w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_paula-768x1022.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_paula-1154x1536.jpg 1154w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_paula-1539x2048.jpg 1539w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_paula-1320x1756.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_paula-scaled.jpg 1924w\" sizes=\"auto, (max-width: 770px) 100vw, 770px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">En este post ense\u00f1aremos a patronar una bata de cola. Este modelo es interesante para aprender a patronar las faldas a volantes. Adem\u00e1s de ser la base de las batas de cola, sirven para multitud de vestidos de fiesta y de boda. \u00a0 Vamos a tomar el patr\u00f3n base del vestido femenino como base de la bata de cola. Recordemos que las medidas del patr\u00f3n del vestido femenino son:<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Cintura&nbsp;&nbsp;&nbsp; 34 cm<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Cadera&nbsp;&nbsp;&nbsp;&nbsp; 47.5 cm<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Ancho espalda 35 cm<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Largo espalda&nbsp;&nbsp;&nbsp; 38.5 cm<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Largo delante 43.5 cm<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Largo pierna 97.5 cm<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Entrepierna 73 cm<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">DVP =&nbsp; 5 cm<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">DHP=2.5 cm<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Montante= 24,5 cm<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">L\u00ednea de caderas = = 16.3333 cm<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Rodilla = 54.8437 cm<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Daremos a 10 cent\u00edmetros por encima del nivel de rodilla el mismo acho hasta el bajo.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"497\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_01-497x1024.jpg\" alt=\"Patr\u00f3n t\u00e9cnico del vestido femenino usado como base para la bata de cola flamenca\" class=\"wp-image-2509\" style=\"width:497px;height:auto\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_01-497x1024.jpg 497w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_01-146x300.jpg 146w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_01-768x1583.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_01-745x1536.jpg 745w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_01-993x2048.jpg 993w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_01-1320x2722.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_01-scaled.jpg 1242w\" sizes=\"auto, (max-width: 497px) 100vw, 497px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Juntaremos los dos partes inferiores y las separaremos del patr\u00f3n: Mediremos el contorno de la base del rect\u00e1ngulo y el largo del rect\u00e1ngulo, en nuestro caso\u00a0 la base del rect\u00e1ngulo ser\u00e1 de 47.03 cm t el largo de 61.91 cm. El siguiente paso ser\u00e1 calcular el radio necesario para obtener una media circunferencia cuyo per\u00edmetro sea el valor del ancho de la rodilla. El radio hallado despejando la\u00a0 f\u00f3rmula\u00a0 2\u03c0r para hallar el per\u00edmetro de una circunferencia entera, en tal caso ser\u00eda de 7.53 cm en nuestro caso, del hecho que queremos una capa completa y no una doble capa deberemos multiplicar el radio por dos: 15.0658 cm.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_02-724x1024.jpg\" alt=\"Patr\u00f3n t\u00e9cnico del fald\u00f3n de la bata de cola con medidas y c\u00e1lculo del radio para la media circunferencia\" class=\"wp-image-2510\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_02-724x1024.jpg 724w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_02-212x300.jpg 212w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_02-768x1086.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_02-1086x1536.jpg 1086w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_02-1448x2048.jpg 1448w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_02-1320x1867.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_02-scaled.jpg 1810w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Trazaremos una media circunferencia de radio 15.0658 cm. Esta media circunferencia ser\u00e1 el principio del fald\u00f3n de la bata de cola. A partir de los extremos de esta media circunferencia acotaremos sobre la prolongaci\u00f3n del di\u00e1metro la medida del largo del rect\u00e1ngulo. En nuestro caso 61.91 cm. A partir del centro trazaremos una segunda media circunferencia que ser\u00e1 el bajo del fald\u00f3n.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"651\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_03-1024x651.jpg\" alt=\"Media circunferencia del fald\u00f3n de la bata de cola con medidas y radios indicados para el trazado del patr\u00f3n\" class=\"wp-image-2511\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_03-1024x651.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_03-300x191.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_03-768x488.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_03-1536x977.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_03-2048x1302.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_03-1320x839.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Daremos al fald\u00f3n una cola igual a la altura del rect\u00e1ngulo. Para trazar la cola trazaremos una media elipse cuyo sub eje menor sea igual al radio de la circunferencia del bajo, el sub eje mayor ser\u00e1 el mismo radio incrementado del alto del rect\u00e1ngulo.\u00a0 Explicamos en el post de c\u00f3mo patronar la gorra Gatsby c\u00f3mo trazar una media elipse, a ese post nos remitimos: \u00ab<a href=\"https:\/\/tevipa.com\/blog\/patron-gorra-gatsby-proporcional\/\">Patr\u00f3n gorra Gatsby proporcional<\/a>\u00bb de la p\u00e1gina C\u00f3mo patronar un cuerpo.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"370\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_04-1024x370.jpg\" alt=\"Patr\u00f3n t\u00e9cnico del fald\u00f3n con cola el\u00edptica de la bata de cola flamenca, mostrando los ejes y medidas de referencia\" class=\"wp-image-2512\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_04-1024x370.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_04-300x108.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_04-768x277.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_04-1536x554.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_04-2048x739.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_04-1320x476.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Reservaremos una parte de la semicircunferencia y la otra mitad de la elipse. Dividiremos el fald\u00f3n entre seis partes en la media circunferencia, en la parte de la media elipse dividiremos la cola es 12 partes. Como mostramos en la imagen.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"552\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_05-1024x552.jpg\" alt=\"Patr\u00f3n t\u00e9cnico del fald\u00f3n y la cola de la bata de cola flamenca dividido en seis y doce partes respectivamente\" class=\"wp-image-2513\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_05-1024x552.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_05-300x162.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_05-768x414.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_05-1536x828.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_05-2048x1104.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_05-1320x712.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Trazaremos seis circunferencias conc\u00e9ntricas a una distancia de 10.3183 mayor que la del radio anterior. Una vez que lleguemos a la sexta circunferencia (la del bajo del fald\u00f3n) trazaremos paralelas al cuarto de circunferencia siempre a 10.3183 hasta llegar al final de la cola. Hemos calculado la mitad de cada uno de los arcos, la suma del doble todos ellos ser\u00e1 l per\u00edmetro que necesitaremos de volantes, en nuestro caso 2671.3514 cm o sea 26.71 metros. Antes de cortarlo reservaremos este patr\u00f3n ya que nos servir\u00e1 como patr\u00f3n del forro de la cola de la bata.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"581\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_06-581x1024-1.jpg\" alt=\"Patr\u00f3n t\u00e9cnico con circunferencias conc\u00e9ntricas para calcular los volantes del fald\u00f3n y la cola de una bata de cola flamenca\" class=\"wp-image-2514\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_06-581x1024-1.jpg 581w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_06-581x1024-1-170x300.jpg 170w\" sizes=\"auto, (max-width: 581px) 100vw, 581px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">En la siguiente ilustraci\u00f3n mostramos el fald\u00f3n con cola con todos los cortes.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_07-724x1024.jpg\" alt=\"Patr\u00f3n completo del fald\u00f3n con cola de una bata de cola flamenca, mostrando todos los cortes y l\u00edneas conc\u00e9ntricas\" class=\"wp-image-2515\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_07-724x1024.jpg 724w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_07-212x300.jpg 212w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_07-768x1086.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_07-1086x1536.jpg 1086w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_07-1448x2048.jpg 1448w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_07-1320x1867.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_07-scaled.jpg 1810w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Separaremos los cortes, en la siguiente ilustraci\u00f3n los hemos separados entre s\u00ed y los hemos partido por la mitad, en el caso en que no se ajusten al metraje de la tela se pueden tambi\u00e9n cortar en 4 partes.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"585\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_08-585x1024.jpg\" alt=\"Patr\u00f3n t\u00e9cnico con los cortes del fald\u00f3n y la cola de una bata de cola flamenca separados y divididos por la mitad\" class=\"wp-image-2516\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_08-585x1024.jpg 585w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_08-171x300.jpg 171w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_08-768x1345.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_08-877x1536.jpg 877w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_08-1169x2048.jpg 1169w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_08-1320x2312.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_08-scaled.jpg 1461w\" sizes=\"auto, (max-width: 585px) 100vw, 585px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Para trazar los volantes podemos patronarlos de muchas formas. Las dos primeras formas son trazadas con bandas rectas, sea trazadas al recto hilo o bien al bi\u00e9s. Si cortamos los volantes al derecho hilo quedar\u00e1n bastante r\u00edgidos y disparados, si los cortamos al bies tendr\u00e1n algo m\u00e1s de cayente. En ambos casos el desarrollo del bajo del volante ser\u00e1 el que nosotros demos de rizo al mismo. Las otras dos formas de patronar el volante tienen una peculiaridad: el lado exterior que no va cosido al vestido es m\u00e1s largo ya que est\u00e1 cortado en forma circular. La primera de las formas de cortar los volantes circulares es el corte de \u201ccaracolillos\u201d. Esta forma de cortarlos tiene una ventaja, est\u00e1n cortados en circular y no incorporan muchas costuras, pero tiene una desventaja, m\u00e1s largo es el caracolillo tiene menos desarrollo de largos. Para cortar este tipo de volantes hay varias formas,&nbsp;aqu\u00ed mostraremos una de ellas aunque no es la m\u00e1s correcta.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Pr\u00f3ximamente dedicaremos un post dedicado a c\u00f3mo patronar un volante de caracolillo. La versi\u00f3n que&nbsp;damos en la siguiente ilustraci\u00f3n es m\u00e1s f\u00e1cil de cortar pero tiene el inconveniente que el volante no es siempre del mismo ancho, sobretodo en la primera vuelta de la espiral.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Empezaremos trazando una circunferencia cuyo radio sea igual al ancho del volante, al llegar a los \u00be de del circunferencia pondremos otra vez el ancho del volante encima del inicio del trazado y a partir de este punto seguiremos trazando la l\u00ednea paralela a la l\u00ednea trazada&nbsp; al ancho del volante, al hacerlo estaremos trazando una espiral.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"941\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_09-941x1024.jpg\" alt=\"Trazado del volante en espiral\" class=\"wp-image-2517\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_09-941x1024.jpg 941w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_09-276x300.jpg 276w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_09-768x836.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_09-1411x1536.jpg 1411w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_09-1882x2048.jpg 1882w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_09-1320x1437.jpg 1320w\" sizes=\"auto, (max-width: 941px) 100vw, 941px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">En la pr\u00f3xima ilustraci\u00f3n mostramos mediante una l\u00ednea continua negra la parte de la espiral que se coser\u00e1,&nbsp; de este caracolillo de un volante de 10,3183 cuyas dimensiones son de&nbsp; 83 cm\u00ad\u00ad\u00ad x&nbsp; 83 cm.\u00ad\u00ad nos dar\u00e1 un largo de 361.2448 (3m y 61 cm) por lo que para completar el fald\u00f3n (361.2248) de la bata de cola, pensando que el rizo normal de montaje es de 2,5 cm, hacen falta 18.4871 caracolillos, o sea 19.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">+(2671.3514\/361,2448)*2.5=18,4871<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"943\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_10-943x1024.jpg\" alt=\"Dibujo t\u00e9cnico del caracolillo de un volante flamenco de 83 \u00d7 83 cm, con l\u00ednea roja exterior y trazo negro indicando la zona de costura\" class=\"wp-image-2518\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_10-943x1024.jpg 943w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_10-276x300.jpg 276w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_10-768x834.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_10-1415x1536.jpg 1415w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_10-1886x2048.jpg 1886w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_10-1320x1433.jpg 1320w\" sizes=\"auto, (max-width: 943px) 100vw, 943px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">La segunda forma de cortar los volantes circulares es mediante c\u00edrculos curo radio sea el ancho del volante. Estas circunferencias se abrir\u00e1n por el radio hasta el centro y se coser\u00e1n entre ellas, para calcular los metros de desarrollo deberemos calcular: Para la primera, el di\u00e1metro de la circunferencia y para las sucesivas el radio. Para completar el fald\u00f3n de la bata de cola que estamos patronando, si cortamos las circunferencias de esta forma necesitaremos: +((2671.3514*2.5)\/20.6)-1= \u00a0332 circunferencias. El gasto de tela es mucho mayor pero su resultado es espectacular, el \u00fanico inconveniente es que a cada per\u00edmetro encontramos una circunferencia (en nuestro caso cada 64.71 cm).<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"748\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_11-748x1024.jpg\" alt=\"Dibujo t\u00e9cnico de volantes circulares cortados en circunferencias de radio 10,3 cm, abiertos hasta el centro para su costura\" class=\"wp-image-2519\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_11-748x1024.jpg 748w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_11-219x300.jpg 219w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_11-768x1051.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_11.jpg 1122w\" sizes=\"auto, (max-width: 748px) 100vw, 748px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">En este ejemplo utilizaremos los dos tipos de volantes: los caracolillos los pondremos en el fald\u00f3n de la bata y los de medio c\u00edrculo en la manga y en el escote. Ahora patronaremos el escote de la espalda y prepararemos la pinza, para ello retomaremos los patrones superiores del patr\u00f3n. Empezaremos por el descote de espalda que lo dejaremos a unos dos o tres cent\u00edmetros por encima de la l\u00ednea de sisa para que quien lleve el vestido pueda lucirlo sin prescindir de los sujetadores, abriremos el escote hasta un tercio del hombro, necesitaremos\u00a0 una porci\u00f3n un tanto ancha del largo del hombro para poder esconder el tirante del sujetador y para montar las mangas. \u00ad\u00ad\u00adReportaremos el ancho del hombro detr\u00e1s al hombro delante.\u00a0 Tal y como mostramos en la ilustraci\u00f3n siguiente.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_12-724x1024.jpg\" alt=\"Dibujo t\u00e9cnico del patr\u00f3n superior de la bata de cola flamenca con l\u00edneas rojas que indican el nuevo escote de la espalda y la correcci\u00f3n de la pinza delantera\" class=\"wp-image-2520\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_12-724x1024.jpg 724w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_12-212x300.jpg 212w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_12-768x1086.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_12-1086x1536.jpg 1086w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_12-1448x2048.jpg 1448w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_12-1320x1867.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_12-scaled.jpg 1810w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Cerraremos la pinza de sisa y la de hombro, cerrando por la mueva marca que hemos hecho desde el hombro hasta el pez\u00f3n o punta de pecho. Tal y como se muestra en la siguiente ilustraci\u00f3n. Marcaremos el trazo definitivo desde la punta del hombro hasta la intersecci\u00f3n de mitad de cuerpo con la mitad delante, acabaremos de abrir la pieza del delantero prolongando el centro de la pina del entalle delante hasta el final del patr\u00f3n, tal y como se muestra en la siguiente ilustraci\u00f3n.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_13-724x1024.jpg\" alt=\"Patr\u00f3n del cuerpo de la bata de cola flamenca con l\u00edneas rojas que indican el cierre de la pinza de sisa y de hombro, y la apertura definitiva del delantero\" class=\"wp-image-2521\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_13-724x1024.jpg 724w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_13-212x300.jpg 212w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_13-768x1086.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_13-1086x1536.jpg 1086w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_13-1448x2048.jpg 1448w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_13-1320x1867.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_13-scaled.jpg 1810w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Cortaremos la parte superior del delantero que hemos despreciado.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_14-724x1024.jpg\" alt=\"Patr\u00f3n del cuerpo de la bata de cola flamenca con l\u00edneas rojas que indican el corte de la parte superior del delantero\" class=\"wp-image-2522\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_14-724x1024.jpg 724w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_14-212x300.jpg 212w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_14-768x1086.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_14-1086x1536.jpg 1086w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_14-1448x2048.jpg 1448w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_14-1320x1867.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_14-scaled.jpg 1810w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Cerraremos otra vez la pinza. Trazaremos una paralela al escote que hemos trazado que pase por la punta de pecho, mediremos la distancia que hay entre las dos l\u00edneas paralelas y trazaremos una paralela al escote detr\u00e1s a la misma distancia, tal y como se ve en la pr\u00f3xima\u00a0 ilustraci\u00f3n. Aprovecharemos para alargar\u00a0 el centro las dos pinzas de entalle de la espalda, las alargaremos desde el corte del escote hasta el final del patr\u00f3n.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"937\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_15-937x1024.jpg\" alt=\"Patr\u00f3n del cuerpo de la bata de cola flamenca con l\u00edneas rojas que muestran el trazado de l\u00edneas paralelas al escote y el alargamiento de las pinzas de entalle\" class=\"wp-image-2523\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_15-937x1024.jpg 937w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_15-274x300.jpg 274w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_15-768x840.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_15-1405x1536.jpg 1405w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_15-1873x2048.jpg 1873w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_15-1320x1443.jpg 1320w\" sizes=\"auto, (max-width: 937px) 100vw, 937px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Abriremos los cortes que hemos trazado, como se muestra en la ilustraci\u00f3n siguiente:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"827\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_16-827x1024.jpg\" alt=\"Patr\u00f3n del cuerpo de la bata de cola flamenca con l\u00edneas rojas que indican la apertura de los cortes en el delantero y la espalda\" class=\"wp-image-2524\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_16-827x1024.jpg 827w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_16-242x300.jpg 242w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_16-768x951.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_16-1240x1536.jpg 1240w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_16-1654x2048.jpg 1654w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_16-1320x1635.jpg 1320w\" sizes=\"auto, (max-width: 827px) 100vw, 827px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Juntaremos los dos hombros por patronaje, es interesante juntar las dos piezas de escote seg\u00fan los materiales que utilicemos para el montaje de la bata de cola. Imaginemos que queremos hacer todo el escote en puntilla y no queremos casar las costuras de la puntilla para ocultar la costura del hombro. Muchas veces las batas de cola llevan volantes en el escote, en tal caso este paso os lo podemos ahorrar.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"901\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_17-901x1024.jpg\" alt=\"Patr\u00f3n de la bata de cola flamenca con los hombros y el escote unidos por patronaje, mostrando la disposici\u00f3n completa de las piezas delanteras y traseras\" class=\"wp-image-2525\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_17-901x1024.jpg 901w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_17-264x300.jpg 264w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_17-768x873.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_17-1351x1536.jpg 1351w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_17-1802x2048.jpg 1802w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_17-1320x1500.jpg 1320w\" sizes=\"auto, (max-width: 901px) 100vw, 901px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Trazaremos una manga camisera sobre la sisa del patr\u00f3n base. En nuestro caso la sisa mide 35.65 cuya mitad es de 17.825 cm. Patronaremos una manga cuyo largo sea por encima del codo, en nuestro caso 25 cm. El contorno a pie de codo ser\u00e1 de 22 cm. Para el patr\u00f3n de la manga camisera pod\u00e9is consultar los post sobre la camisa, especialmente: \u201c<a href=\"https:\/\/tevipa.com\/blog\/trazado-base-de-la-camisa-la-manga\/\">Trazado base de la camisa &#8211; La manga<\/a>\u201d<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1003\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_18-1003x1024.jpg\" alt=\"Patr\u00f3n t\u00e9cnico que muestra el trazado de una manga camisera basada en la sisa del cuerpo del vestido flamenco, con medidas y proporciones indicadas\" class=\"wp-image-2526\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_18-1003x1024.jpg 1003w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_18-294x300.jpg 294w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_18-768x784.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_18-1505x1536.jpg 1505w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_18-2007x2048.jpg 2007w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_18-1320x1347.jpg 1320w\" sizes=\"auto, (max-width: 1003px) 100vw, 1003px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Para los volantes de la manga, que ser\u00e1n del mismo ancho que la de los faldones (10.3 cm) y el rizo que colocaremos a un frunce de X2,5, necesitaremos 55cm\/10.3= 5.33 menos uno: 4.33 que redondearemos a 5 piezas; 10piezas para las dos mangas. En el caso en que queramos cortar volantes circulares para el escote,\u00a0 sabiendo que el medio escote delantero y espalda es de 46.153 o sea el escote completo ser\u00e1 de: 92.306cm\/10.3= son 20.6 c\u00edrculos menos uno, 19.6 que redondeamos a 20 c\u00edrculos. El despiece de la bata de cola con los volantes del fald\u00f3n de caracolillo y los de las mangas y del escote de volantes circulares, ser\u00e1 el siguiente:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"810\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_19-810x1024.jpg\" alt=\"Despiece t\u00e9cnico del patr\u00f3n de la bata de cola flamenca que incluye volantes caracolillo para el fald\u00f3n y volantes circulares para las mangas y el escote\" class=\"wp-image-2527\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_19-810x1024.jpg 810w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_19-237x300.jpg 237w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_19-768x971.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_19-1214x1536.jpg 1214w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_19-1619x2048.jpg 1619w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_19-1320x1670.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_19-scaled.jpg 2024w\" sizes=\"auto, (max-width: 810px) 100vw, 810px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">En el caso de hacer los volantes con c\u00edrculos:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"790\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_20-790x1024.jpg\" alt=\"Despiece t\u00e9cnico del patr\u00f3n de la bata de cola flamenca con volantes circulares distribuidos por el fald\u00f3n, las mangas y el escote\" class=\"wp-image-2528\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_20-790x1024.jpg 790w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_20-231x300.jpg 231w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_20-768x996.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_20-1185x1536.jpg 1185w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_20-1580x2048.jpg 1580w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_20-1320x1711.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_20-scaled.jpg 1975w\" sizes=\"auto, (max-width: 790px) 100vw, 790px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Aprende a patronar una bata de cola flamenca paso a paso.<br \/>\nDesde el trazado del fald\u00f3n y la cola hasta el c\u00e1lculo de volantes circulares y caracolillos, con base en el patr\u00f3n del vestido femenino.<\/p>\n","protected":false},"author":1,"featured_media":2507,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1018,23,1293],"tags":[1329,44,30,38,34,674,90,1305,92,104,80,362,82,746,372,672,40,42,676,1327],"class_list":["post-2505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo","category-patron","category-vestido","tag-bata-de-cola","tag-como-cubrir-un-cuerpo","tag-comocubriruncuerpo","tag-creacion-de-moda","tag-disenador","tag-ensenanza-de-patronaje","tag-escuela-de-moda","tag-flamenco","tag-gradacion-o-escalado","tag-patron","tag-patronaje","tag-patronajemoda","tag-patrones","tag-ropa-de-baile","tag-sastreria","tag-tecnica-de-patronaje","tag-tele-virtual-patronage","tag-televirtualpatronage","tag-tutorial-patonaje","tag-vestido-flamenco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vestidos flamencos - La bata de cola - Tele Virtual Patronage<\/title>\n<meta name=\"description\" content=\"Patronamos una bata de cola flamenca paso a paso, desde el trazado del fald\u00f3n y la cola hasta el c\u00e1lculo de volantes circulares y caracolillos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tevipa.com\/blog\/vestidos-flamencos-la-bata-de-cola\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vestidos flamencos - La bata de cola - Tele Virtual Patronage\" \/>\n<meta property=\"og:description\" content=\"Patronamos una bata de cola flamenca paso a paso, desde el trazado del fald\u00f3n y la cola hasta el c\u00e1lculo de volantes circulares y caracolillos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tevipa.com\/blog\/vestidos-flamencos-la-bata-de-cola\/\" \/>\n<meta property=\"og:site_name\" content=\"Tele Virtual Patronage\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-11T17:37:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-11T19:44:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_paula-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1924\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tele Virtual Patronage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tele Virtual Patronage\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/vestidos-flamencos-la-bata-de-cola\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/vestidos-flamencos-la-bata-de-cola\\\/\"},\"author\":{\"name\":\"Tele Virtual Patronage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\"},\"headline\":\"Vestidos flamencos &#8211; La bata de cola\",\"datePublished\":\"2025-10-11T17:37:21+00:00\",\"dateModified\":\"2025-10-11T19:44:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/vestidos-flamencos-la-bata-de-cola\\\/\"},\"wordCount\":1667,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/vestidos-flamencos-la-bata-de-cola\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/140101_-vestidos-flamencos-La-bata-de-cola-_paula-scaled.jpg\",\"keywords\":[\"bata de cola\",\"como cubrir un cuerpo\",\"comocubriruncuerpo\",\"creaci\u00f3n de moda\",\"dise\u00f1ador\",\"ense\u00f1anza de patronaje\",\"escuela de moda\",\"flamenco\",\"gradaci\u00f3n o escalado\",\"patron\",\"patronaje\",\"patronajemoda\",\"patrones\",\"ropa de baile\",\"sastrer\u00eda\",\"t\u00e9cnica de patronaje\",\"tele virtual patronage\",\"televirtualpatronage\",\"tutorial patonaje\",\"vestido flamenco\"],\"articleSection\":[\"Archivo\",\"Patr\u00f3n\",\"Vestido\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/vestidos-flamencos-la-bata-de-cola\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/vestidos-flamencos-la-bata-de-cola\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/vestidos-flamencos-la-bata-de-cola\\\/\",\"name\":\"Vestidos flamencos - La bata de cola - Tele Virtual Patronage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/vestidos-flamencos-la-bata-de-cola\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/vestidos-flamencos-la-bata-de-cola\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/140101_-vestidos-flamencos-La-bata-de-cola-_paula-scaled.jpg\",\"datePublished\":\"2025-10-11T17:37:21+00:00\",\"dateModified\":\"2025-10-11T19:44:29+00:00\",\"description\":\"Patronamos una bata de cola flamenca paso a paso, desde el trazado del fald\u00f3n y la cola hasta el c\u00e1lculo de volantes circulares y caracolillos\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/vestidos-flamencos-la-bata-de-cola\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/vestidos-flamencos-la-bata-de-cola\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/vestidos-flamencos-la-bata-de-cola\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/140101_-vestidos-flamencos-La-bata-de-cola-_paula-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/140101_-vestidos-flamencos-La-bata-de-cola-_paula-scaled.jpg\",\"width\":1924,\"height\":2560,\"caption\":\"Ilustraci\u00f3n de un vestido flamenco rojo con bata de cola y volantes, vista frontal y trasera\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/vestidos-flamencos-la-bata-de-cola\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vestidos flamencos &#8211; La bata de cola\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"name\":\"Tele Virtual Patronage\",\"description\":\"Tevipa\",\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\",\"name\":\"Tele Virtual Patronage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"width\":512,\"height\":512,\"caption\":\"Tele Virtual Patronage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\",\"name\":\"Tele Virtual Patronage\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"caption\":\"Tele Virtual Patronage\"},\"sameAs\":[\"https:\\\/\\\/tevipa.com\\\/blog\"],\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/author\\\/tvpadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vestidos flamencos - La bata de cola - Tele Virtual Patronage","description":"Patronamos una bata de cola flamenca paso a paso, desde el trazado del fald\u00f3n y la cola hasta el c\u00e1lculo de volantes circulares y caracolillos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tevipa.com\/blog\/vestidos-flamencos-la-bata-de-cola\/","og_locale":"it_IT","og_type":"article","og_title":"Vestidos flamencos - La bata de cola - Tele Virtual Patronage","og_description":"Patronamos una bata de cola flamenca paso a paso, desde el trazado del fald\u00f3n y la cola hasta el c\u00e1lculo de volantes circulares y caracolillos","og_url":"https:\/\/tevipa.com\/blog\/vestidos-flamencos-la-bata-de-cola\/","og_site_name":"Tele Virtual Patronage","article_published_time":"2025-10-11T17:37:21+00:00","article_modified_time":"2025-10-11T19:44:29+00:00","og_image":[{"width":1924,"height":2560,"url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_paula-scaled.jpg","type":"image\/jpeg"}],"author":"Tele Virtual Patronage","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Tele Virtual Patronage","Tempo di lettura stimato":"14 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tevipa.com\/blog\/vestidos-flamencos-la-bata-de-cola\/#article","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/vestidos-flamencos-la-bata-de-cola\/"},"author":{"name":"Tele Virtual Patronage","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c"},"headline":"Vestidos flamencos &#8211; La bata de cola","datePublished":"2025-10-11T17:37:21+00:00","dateModified":"2025-10-11T19:44:29+00:00","mainEntityOfPage":{"@id":"https:\/\/tevipa.com\/blog\/vestidos-flamencos-la-bata-de-cola\/"},"wordCount":1667,"commentCount":0,"publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"image":{"@id":"https:\/\/tevipa.com\/blog\/vestidos-flamencos-la-bata-de-cola\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_paula-scaled.jpg","keywords":["bata de cola","como cubrir un cuerpo","comocubriruncuerpo","creaci\u00f3n de moda","dise\u00f1ador","ense\u00f1anza de patronaje","escuela de moda","flamenco","gradaci\u00f3n o escalado","patron","patronaje","patronajemoda","patrones","ropa de baile","sastrer\u00eda","t\u00e9cnica de patronaje","tele virtual patronage","televirtualpatronage","tutorial patonaje","vestido flamenco"],"articleSection":["Archivo","Patr\u00f3n","Vestido"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tevipa.com\/blog\/vestidos-flamencos-la-bata-de-cola\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tevipa.com\/blog\/vestidos-flamencos-la-bata-de-cola\/","url":"https:\/\/tevipa.com\/blog\/vestidos-flamencos-la-bata-de-cola\/","name":"Vestidos flamencos - La bata de cola - Tele Virtual Patronage","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tevipa.com\/blog\/vestidos-flamencos-la-bata-de-cola\/#primaryimage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/vestidos-flamencos-la-bata-de-cola\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_paula-scaled.jpg","datePublished":"2025-10-11T17:37:21+00:00","dateModified":"2025-10-11T19:44:29+00:00","description":"Patronamos una bata de cola flamenca paso a paso, desde el trazado del fald\u00f3n y la cola hasta el c\u00e1lculo de volantes circulares y caracolillos","breadcrumb":{"@id":"https:\/\/tevipa.com\/blog\/vestidos-flamencos-la-bata-de-cola\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tevipa.com\/blog\/vestidos-flamencos-la-bata-de-cola\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/vestidos-flamencos-la-bata-de-cola\/#primaryimage","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_paula-scaled.jpg","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140101_-vestidos-flamencos-La-bata-de-cola-_paula-scaled.jpg","width":1924,"height":2560,"caption":"Ilustraci\u00f3n de un vestido flamenco rojo con bata de cola y volantes, vista frontal y trasera"},{"@type":"BreadcrumbList","@id":"https:\/\/tevipa.com\/blog\/vestidos-flamencos-la-bata-de-cola\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tevipa.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Vestidos flamencos &#8211; La bata de cola"}]},{"@type":"WebSite","@id":"https:\/\/tevipa.com\/blog\/#website","url":"https:\/\/tevipa.com\/blog\/","name":"Tele Virtual Patronage","description":"Tevipa","publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tevipa.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/tevipa.com\/blog\/#organization","name":"Tele Virtual Patronage","url":"https:\/\/tevipa.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","width":512,"height":512,"caption":"Tele Virtual Patronage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c","name":"Tele Virtual Patronage","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","caption":"Tele Virtual Patronage"},"sameAs":["https:\/\/tevipa.com\/blog"],"url":"https:\/\/tevipa.com\/blog\/author\/tvpadm\/"}]}},"_links":{"self":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/2505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/comments?post=2505"}],"version-history":[{"count":6,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/2505\/revisions"}],"predecessor-version":[{"id":2578,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/2505\/revisions\/2578"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media\/2507"}],"wp:attachment":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media?parent=2505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/categories?post=2505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/tags?post=2505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}