{"id":2240,"date":"2025-10-09T14:25:09","date_gmt":"2025-10-09T12:25:09","guid":{"rendered":"https:\/\/tevipa.com\/blog\/?p=2240"},"modified":"2025-10-09T15:22:26","modified_gmt":"2025-10-09T13:22:26","slug":"el-cuerpo-humano-y-las-formas-geometricas-2","status":"publish","type":"post","link":"https:\/\/tevipa.com\/blog\/el-cuerpo-humano-y-las-formas-geometricas-2\/","title":{"rendered":"El cuerpo humano y las formas geom\u00e9tricas 2"},"content":{"rendered":"\n<p class=\"has-text-align-right has-small-font-size wp-block-paragraph\"><sup><em>Publicado originalmente el&nbsp;<strong>14 Mayo 2013<\/strong><\/em><\/sup><\/p>\n\n\n<style>.kb-image2240_d2e15f-fe .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image2240_d2e15f-fe is-style-default\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"222\" height=\"300\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg\" alt=\"Logo C\u00f3mo Cubrir un Cuerpo\" class=\"kb-img wp-image-68\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg 222w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-757x1024.jpg 757w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-768x1039.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1135x1536.jpg 1135w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1514x2048.jpg 1514w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran.jpg 1821w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/><\/figure><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\" style=\"font-size:27px\"><strong>El cuerpo humano y las formas geom\u00e9tricas 2<\/strong><\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">En el \u00faltimo post vimos c\u00f3mo dos conos troncos pod\u00edan darnos el volumen requerido para realizar un patr\u00f3n que se adaptara a una parte del cuerpo humano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Partimos del c\u00edrculo como base para nuestros cuerpos geom\u00e9tricos. En realidad hubi\u00e9ramos tenido que partir de la elipse, ya que las secciones del cuerpo humano se acercan m\u00e1s a la elipse que al c\u00edrculo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Elegir entre uno u otra no es de vital importancia ya que el material con que construiremos los vestidos, la tela, es d\u00factil y tiene una serie de elasticidades. Seg\u00fan su ligamento o estructura tiene mayor o menor capacidad de adaptabilidad, en el caso de los g\u00e9neros de punto la adaptabilidad crece.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este blog retomaremos el anterior, pero partiendo no del cilindro y del cono, sino del prisma y de la pir\u00e1mide.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El circunferencia es un pol\u00edgono de infinitos lados, el concepto lo podemos ver claro observando la imagen que sigue.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/piramide-a-cono-724x1024.jpg\" alt=\"Evoluci\u00f3n geom\u00e9trica de la pir\u00e1mide al cono y sus desarrollos planos\" class=\"wp-image-2242\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/piramide-a-cono-724x1024.jpg 724w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/piramide-a-cono-212x300.jpg 212w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/piramide-a-cono-768x1086.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/piramide-a-cono-1086x1536.jpg 1086w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/piramide-a-cono-1448x2048.jpg 1448w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/piramide-a-cono-1320x1867.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/piramide-a-cono-scaled.jpg 1810w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Si nos fijamos bien, los cuerpos que se basan en pol\u00edgonos: el prisma la pir\u00e1mide y la pir\u00e1mide trunca son iguales a los del cilindro, cono y cono trunco, la \u00fanica diferencia es que tienen menos lados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El desarrollo de estos tres cuerpos no tendr\u00e1 ning\u00fan arco, por lo que podremos juntar, por ejemplo dos pir\u00e1mides truncas con suma facilidad colocando ordenadamente su desarrollo sobre una recta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este hecho nos facilitar\u00e1 el poder hacer desaparecer costuras, y manipular pinzas, aunque no hacerlas desaparecer (para eso ruego que acudan a la&nbsp;<em>Academia de la Ignorancia<\/em>, all\u00ed son expertos en este menester)<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/piramide-doble-724x1024.jpg\" alt=\"Desarrollo geom\u00e9trico de dos pir\u00e1mides truncadas unidas para formar un volumen continuo sin costuras\" class=\"wp-image-2244\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/piramide-doble-724x1024.jpg 724w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/piramide-doble-212x300.jpg 212w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/piramide-doble-768x1086.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/piramide-doble-1086x1536.jpg 1086w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/piramide-doble-1448x2048.jpg 1448w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/piramide-doble-1320x1867.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/piramide-doble-scaled.jpg 1810w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">En el patronaje&nbsp;utilizaremos tanto uno como otro, y una forma h\u00edbrida. La forma h\u00edbrida&nbsp;la encontraremos en el momento&nbsp;en que afinemos los trazos de un patr\u00f3n con la l\u00ednea de curvas. Al redondear un&nbsp; \u00e1ngulo, por ejemplo las piezas del delantero de un cuerpo de mujer, al redondear la punta de pecho l que estamos haciendo es pasar de un prisma a un cono. Otro ejemplo es el dar un cent\u00edmetro suplementario en el lago de una manga camisera en su centro para trazar redondeado el pu\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este post sigue en &#8220;<a href=\"https:\/\/tevipa.com\/blog\/formas-geometricas-3-el-cono-trunco-irregular\/\">Formas geom\u00e9tricas 3 &#8211; El cono trunco irregular<\/a>&#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En esta segunda parte profundizamos en la relaci\u00f3n entre el cuerpo humano y las formas geom\u00e9tricas, pasando del cilindro y el cono al prisma y la pir\u00e1mide.<br \/>\nAnalizamos c\u00f3mo los vol\u00famenes poligonales permiten comprender mejor la estructura del cuerpo y la construcci\u00f3n de patrones planos.<br \/>\nEl post explica por qu\u00e9 la forma el\u00edptica es m\u00e1s realista que la circular y c\u00f3mo las telas, por su elasticidad, permiten adaptar estas figuras al cuerpo humano.<br \/>\nAdem\u00e1s, introduce el concepto de forma h\u00edbrida entre geometr\u00eda poligonal y curva, base esencial del patronaje avanzado.<\/p>\n","protected":false},"author":1,"featured_media":2242,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1018,1],"tags":[44,30,90,92,80,958,40,42],"class_list":["post-2240","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo","category-medidas","tag-como-cubrir-un-cuerpo","tag-comocubriruncuerpo","tag-escuela-de-moda","tag-gradacion-o-escalado","tag-patronaje","tag-tablas-de-medidas","tag-tele-virtual-patronage","tag-televirtualpatronage"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El cuerpo humano y las formas geom\u00e9tricas 2 - Tele Virtual Patronage<\/title>\n<meta name=\"description\" content=\"Del cilindro al prisma, del cono a la pir\u00e1mide: descubre c\u00f3mo las formas geom\u00e9tricas definen el cuerpo humano y los patrones en el patronaje\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tevipa.com\/blog\/el-cuerpo-humano-y-las-formas-geometricas-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El cuerpo humano y las formas geom\u00e9tricas 2 - Tele Virtual Patronage\" \/>\n<meta property=\"og:description\" content=\"Del cilindro al prisma, del cono a la pir\u00e1mide: descubre c\u00f3mo las formas geom\u00e9tricas definen el cuerpo humano y los patrones en el patronaje\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tevipa.com\/blog\/el-cuerpo-humano-y-las-formas-geometricas-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Tele Virtual Patronage\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-09T12:25:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-09T13:22:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/piramide-a-cono-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1810\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tele Virtual Patronage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tele Virtual Patronage\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-cuerpo-humano-y-las-formas-geometricas-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-cuerpo-humano-y-las-formas-geometricas-2\\\/\"},\"author\":{\"name\":\"Tele Virtual Patronage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\"},\"headline\":\"El cuerpo humano y las formas geom\u00e9tricas 2\",\"datePublished\":\"2025-10-09T12:25:09+00:00\",\"dateModified\":\"2025-10-09T13:22:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-cuerpo-humano-y-las-formas-geometricas-2\\\/\"},\"wordCount\":404,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-cuerpo-humano-y-las-formas-geometricas-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/piramide-a-cono-scaled.jpg\",\"keywords\":[\"como cubrir un cuerpo\",\"comocubriruncuerpo\",\"escuela de moda\",\"gradaci\u00f3n o escalado\",\"patronaje\",\"tablas de medidas\",\"tele virtual patronage\",\"televirtualpatronage\"],\"articleSection\":[\"Archivo\",\"Medidas\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-cuerpo-humano-y-las-formas-geometricas-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-cuerpo-humano-y-las-formas-geometricas-2\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-cuerpo-humano-y-las-formas-geometricas-2\\\/\",\"name\":\"El cuerpo humano y las formas geom\u00e9tricas 2 - Tele Virtual Patronage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-cuerpo-humano-y-las-formas-geometricas-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-cuerpo-humano-y-las-formas-geometricas-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/piramide-a-cono-scaled.jpg\",\"datePublished\":\"2025-10-09T12:25:09+00:00\",\"dateModified\":\"2025-10-09T13:22:26+00:00\",\"description\":\"Del cilindro al prisma, del cono a la pir\u00e1mide: descubre c\u00f3mo las formas geom\u00e9tricas definen el cuerpo humano y los patrones en el patronaje\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-cuerpo-humano-y-las-formas-geometricas-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-cuerpo-humano-y-las-formas-geometricas-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-cuerpo-humano-y-las-formas-geometricas-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/piramide-a-cono-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/piramide-a-cono-scaled.jpg\",\"width\":1810,\"height\":2560,\"caption\":\"Evoluci\u00f3n geom\u00e9trica de la pir\u00e1mide al cono y sus desarrollos planos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/el-cuerpo-humano-y-las-formas-geometricas-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El cuerpo humano y las formas geom\u00e9tricas 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"name\":\"Tele Virtual Patronage\",\"description\":\"Tevipa\",\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\",\"name\":\"Tele Virtual Patronage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"width\":512,\"height\":512,\"caption\":\"Tele Virtual Patronage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\",\"name\":\"Tele Virtual Patronage\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"caption\":\"Tele Virtual Patronage\"},\"sameAs\":[\"https:\\\/\\\/tevipa.com\\\/blog\"],\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/author\\\/tvpadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El cuerpo humano y las formas geom\u00e9tricas 2 - Tele Virtual Patronage","description":"Del cilindro al prisma, del cono a la pir\u00e1mide: descubre c\u00f3mo las formas geom\u00e9tricas definen el cuerpo humano y los patrones en el patronaje","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tevipa.com\/blog\/el-cuerpo-humano-y-las-formas-geometricas-2\/","og_locale":"it_IT","og_type":"article","og_title":"El cuerpo humano y las formas geom\u00e9tricas 2 - Tele Virtual Patronage","og_description":"Del cilindro al prisma, del cono a la pir\u00e1mide: descubre c\u00f3mo las formas geom\u00e9tricas definen el cuerpo humano y los patrones en el patronaje","og_url":"https:\/\/tevipa.com\/blog\/el-cuerpo-humano-y-las-formas-geometricas-2\/","og_site_name":"Tele Virtual Patronage","article_published_time":"2025-10-09T12:25:09+00:00","article_modified_time":"2025-10-09T13:22:26+00:00","og_image":[{"width":1810,"height":2560,"url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/piramide-a-cono-scaled.jpg","type":"image\/jpeg"}],"author":"Tele Virtual Patronage","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Tele Virtual Patronage","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tevipa.com\/blog\/el-cuerpo-humano-y-las-formas-geometricas-2\/#article","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/el-cuerpo-humano-y-las-formas-geometricas-2\/"},"author":{"name":"Tele Virtual Patronage","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c"},"headline":"El cuerpo humano y las formas geom\u00e9tricas 2","datePublished":"2025-10-09T12:25:09+00:00","dateModified":"2025-10-09T13:22:26+00:00","mainEntityOfPage":{"@id":"https:\/\/tevipa.com\/blog\/el-cuerpo-humano-y-las-formas-geometricas-2\/"},"wordCount":404,"commentCount":0,"publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"image":{"@id":"https:\/\/tevipa.com\/blog\/el-cuerpo-humano-y-las-formas-geometricas-2\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/piramide-a-cono-scaled.jpg","keywords":["como cubrir un cuerpo","comocubriruncuerpo","escuela de moda","gradaci\u00f3n o escalado","patronaje","tablas de medidas","tele virtual patronage","televirtualpatronage"],"articleSection":["Archivo","Medidas"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tevipa.com\/blog\/el-cuerpo-humano-y-las-formas-geometricas-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tevipa.com\/blog\/el-cuerpo-humano-y-las-formas-geometricas-2\/","url":"https:\/\/tevipa.com\/blog\/el-cuerpo-humano-y-las-formas-geometricas-2\/","name":"El cuerpo humano y las formas geom\u00e9tricas 2 - Tele Virtual Patronage","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tevipa.com\/blog\/el-cuerpo-humano-y-las-formas-geometricas-2\/#primaryimage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/el-cuerpo-humano-y-las-formas-geometricas-2\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/piramide-a-cono-scaled.jpg","datePublished":"2025-10-09T12:25:09+00:00","dateModified":"2025-10-09T13:22:26+00:00","description":"Del cilindro al prisma, del cono a la pir\u00e1mide: descubre c\u00f3mo las formas geom\u00e9tricas definen el cuerpo humano y los patrones en el patronaje","breadcrumb":{"@id":"https:\/\/tevipa.com\/blog\/el-cuerpo-humano-y-las-formas-geometricas-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tevipa.com\/blog\/el-cuerpo-humano-y-las-formas-geometricas-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/el-cuerpo-humano-y-las-formas-geometricas-2\/#primaryimage","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/piramide-a-cono-scaled.jpg","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/piramide-a-cono-scaled.jpg","width":1810,"height":2560,"caption":"Evoluci\u00f3n geom\u00e9trica de la pir\u00e1mide al cono y sus desarrollos planos"},{"@type":"BreadcrumbList","@id":"https:\/\/tevipa.com\/blog\/el-cuerpo-humano-y-las-formas-geometricas-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tevipa.com\/blog\/"},{"@type":"ListItem","position":2,"name":"El cuerpo humano y las formas geom\u00e9tricas 2"}]},{"@type":"WebSite","@id":"https:\/\/tevipa.com\/blog\/#website","url":"https:\/\/tevipa.com\/blog\/","name":"Tele Virtual Patronage","description":"Tevipa","publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tevipa.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/tevipa.com\/blog\/#organization","name":"Tele Virtual Patronage","url":"https:\/\/tevipa.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","width":512,"height":512,"caption":"Tele Virtual Patronage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c","name":"Tele Virtual Patronage","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","caption":"Tele Virtual Patronage"},"sameAs":["https:\/\/tevipa.com\/blog"],"url":"https:\/\/tevipa.com\/blog\/author\/tvpadm\/"}]}},"_links":{"self":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/2240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/comments?post=2240"}],"version-history":[{"count":6,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/2240\/revisions"}],"predecessor-version":[{"id":2273,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/2240\/revisions\/2273"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media\/2242"}],"wp:attachment":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media?parent=2240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/categories?post=2240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/tags?post=2240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}