{"id":2204,"date":"2025-10-09T13:42:20","date_gmt":"2025-10-09T11:42:20","guid":{"rendered":"https:\/\/tevipa.com\/blog\/?p=2204"},"modified":"2025-10-09T13:42:22","modified_gmt":"2025-10-09T11:42:22","slug":"medidas-verticales-a-partir-de-la-estatura","status":"publish","type":"post","link":"https:\/\/tevipa.com\/blog\/medidas-verticales-a-partir-de-la-estatura\/","title":{"rendered":"Medidas verticales a partir de la estatura"},"content":{"rendered":"\n<p class=\"has-text-align-right has-small-font-size wp-block-paragraph\"><sup><em>Publicado originalmente el&nbsp;<strong>25 Junio 2014<\/strong><\/em><\/sup><\/p>\n\n\n<style>.kb-image2204_f1e66c-50 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image2204_f1e66c-50 is-style-default\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"222\" height=\"300\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg\" alt=\"Logo C\u00f3mo Cubrir un Cuerpo\" class=\"kb-img wp-image-68\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg 222w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-757x1024.jpg 757w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-768x1039.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1135x1536.jpg 1135w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1514x2048.jpg 1514w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran.jpg 1821w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/><\/figure><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\" style=\"font-size:27px\"><strong>Medidas verticales a partir de la estatura<\/strong><\/h1>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">Previos: la proporci\u00f3n \u00e1urea y Erns Neufert<\/h2>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">En este post examinaremos las proporciones \u00e1ureas&nbsp; del cuerpo humano propuestas por Erns Neufert (1900-1986) del que ya hablamos en post anteriores.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">En esta ocasi\u00f3n vamos a desglosar las proporciones \u00e1ureas que encontramos en el cuerpo humano de forma que podamos usarlas para poder deducir las medidas verticales.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Este estudio se basar\u00e1 en la estatura y en la primera parte de este post reduciremos la estatura total de la persona a la altura de s\u00e9ptima vertical hasta suelo, luego buscaremos la altura de la entrepierna para as\u00ed poder centrarnos en el torso (desde la s\u00e9ptima cervical hasta la pr\u00f3stata)<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Luego hallaremos la cintura y la l\u00ednea de sisa.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Evidentemente no debemos tomar estas medidas al pie de la letra pero pueden ser muy \u00fatiles para poder deducir medidas que no podemos encontrar en las tablas.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Cabe recordar a\u00fan una vez m\u00e1s que el hombre perfecto no existe y que cada cuerpo es un mundo, pero dado en que vivimos en una era en que la costura a medida no da lugar, debemos encontrar una serie de prototipos proporcionales que sirvan para los cuerpos de una mayor\u00eda.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Al final del post incluimos una lista con los resultados de todas las operaciones que deducimos, algunas son secundarias, otras no y nos pueden facilitar mucho nuestra labor.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">No os asust\u00e9is por las f\u00f3rmulas, en verdad son simples, parecen muy complicadas por los par\u00e9ntesis pero es la \u00fanica forma en que podemos escribirlas para que aparezcan en WordPress.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Si os fij\u00e1is en la tabla ver\u00e9is como es mucho m\u00e1s simple de lo que parece.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">El n\u00famero \u03c6 (phi)<\/h2>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Citando Wikipedia nos define el <a href=\"http:\/\/es.wikipedia.org\/wiki\/N%C3%BAmero_%C3%A1ureo\">n\u00famero Phi<\/a> como:<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">El <strong>n\u00famero \u00e1ureo<\/strong> o de oro (tambi\u00e9n llamado <strong>raz\u00f3n extrema y media<\/strong>,<strong>raz\u00f3n \u00e1urea<\/strong>, <strong>raz\u00f3n dorada<\/strong>, <strong>media \u00e1urea<\/strong>, <strong>proporci\u00f3n \u00e1urea<\/strong> y <strong>divina proporci\u00f3n<\/strong> representado por la letra griega \u03c6 (phi) (en min\u00fascula) o \u03a6 (Phi) (en may\u00fascula), en honor al escultor griego Fidias, es un n\u00famero irracional.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Se trata de un n\u00famero algebraico irracional (su representaci\u00f3n decimal no tiene per\u00edodo) que posee muchas propiedades interesantes y que fue descubierto en la antig\u00fcedad, no como una expresi\u00f3n aritm\u00e9tica sino como relaci\u00f3n o proporci\u00f3n entre dos segmentos de una recta; o sea, una construcci\u00f3n geom\u00e9trica. Esta proporci\u00f3n se encuentra tanto en algunas figuras geom\u00e9tricas como en la naturaleza: en las nervaduras de las hojas de algunos \u00e1rboles, en el grosor de las ramas, en el caparaz\u00f3n de un caracol, en los fl\u00f3sculos de los girasoles, etc.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Asimismo, se atribuye un car\u00e1cter est\u00e9tico a los objetos cuyas medidas guardan la proporci\u00f3n \u00e1urea. Algunos incluso creen que posee una importancia m\u00edstica. A lo largo de la historia, se ha atribuido su inclusi\u00f3n en el dise\u00f1o de diversas obras de arquitectura y otras artes, aunque algunos de estos casos han sido cuestionados por los estudiosos de las matem\u00e1ticas y el arte.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\"><sup>]<\/sup>Recordemos antes de empezar que el n\u00famero <strong>\u03c6<\/strong> es igual a <strong>1.61803398874989\u2026<\/strong>, nosotros consideraremos s\u00f3lo los tres primero s decimales: <strong>1.618<\/strong>.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Podemos trazar directamente el n\u00famero \u03c6 sin necesidad de calcularlo, en la siguiente ilustraci\u00f3n mostramos c\u00f3mo hacerlo:<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">En la parte m\u00e1s a la izquierda de la ilustraci\u00f3n mostramos un segmento. En esta ilustraci\u00f3n mostraremos como dividir este segmento en dos que mantengan entre ellos&nbsp; la proporci\u00f3n \u00e1urea.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Para empezar dividiremos el segmento en dos partes iguales (segunda imagen de la siguiente ilustraci\u00f3n) y desde una de las bases del segmento trazaremos un arco cuyo radio sea igual a la mitad del recorrido del segmento trazaremos una perpendicular al segmento original hasta que cruce con el arco (tercera imagen de la siguiente ilustraci\u00f3n).<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Uniremos el punto en que se cruza el arco con la perpendicular hecha al segmento original con el punto del segmento opuesto al que hemos utilizado como centro del arco (cuarta imagen de la siguiente ilustraci\u00f3n). Desde el punto en que se cruza el arco con el segmento original trazaremos un arco cuyo recorrido sea igual al recorrido de la perpendicular hasta que corte la l\u00ednea inclinada.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Desde el punto en que se cruza la l\u00ednea inclinada con el segmento original trazaremos un arco cuyo radio sea igual a la distancia entre su centro y el punto en que se cruza el segundo arco trazado sobre la l\u00ednea diagonal. El punto en que se cruza este \u00faltimo arco con el segmento original ser\u00e1 el punto que dividir\u00e1 el segmento original en dos (a y b) que mantendr\u00e1n entre ellos la proporci\u00f3n \u00e1urea.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"796\" height=\"346\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140622-Medidas-verticales-a-partir-de-la-estatura-000.gif\" alt=\"Construcci\u00f3n geom\u00e9trica paso a paso para dividir un segmento seg\u00fan la proporci\u00f3n \u00e1urea \u03c6\" class=\"wp-image-2206\"\/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">Deducci\u00f3n de las medidas verticales a trav\u00e9s del n\u00famero \u03c6<\/h2>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Si dividimos la estatura <strong>(e)<\/strong> por el n\u00famero <strong>\u03c6 <\/strong>\u00a0nos dar\u00e1 un valor: <strong>+(e\/\u03c6) <\/strong>obtendremos la medida de <strong>suelo a<\/strong> <strong>ombligo<\/strong>, que por la parte de la espalda coincide con la l\u00ednea de ri\u00f1ones. Esta l\u00ednea horizontal nos sirve para entallar las piezas de cintura: las levitas, los\u00a0 fracs, spencers, \u00a0etc.<\/li>\n\n\n\n<li>Si restamos de la estatura la medida anterior obtendremos la medida desde la <strong>coronilla a ombligo<\/strong>:<br><center><strong>+(e-(e\/\u03c6))<\/strong><\/center><\/li>\n\n\n\n<li>Si dividimos por <strong>\u03c6 <\/strong>la medida anterior obtendremos la distancia entre el <strong>ombligo y s\u00e9ptima v\u00e9rtebra<\/strong>:<br><center><strong>+((e-(e\/\u03c6))\/\u03c6)<\/strong><\/center><\/li>\n\n\n\n<li>Si restamos la medida ombligo coronilla de la distancia ombligo s\u00e9ptima v\u00e9rtebra obtendremos la medida <strong>s\u00e9ptima v\u00e9rtebra coronilla<\/strong>:<br><center><strong>+((e-(e\/\u03c6))- ((e-(e\/\u03c6))\/\u03c6))<\/strong><\/center><\/li>\n\n\n\n<li>Si restamos la estatura de la medida anterior obtendremos la medida desde <strong>la s\u00e9ptima vertebra al suelo<\/strong>:<br><center><strong>+(e-((e-(e\/\u03c6))- ((e-(e\/\u03c6))\/\u03c6)))<\/strong><\/center><\/li>\n<\/ol>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"405\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140622-Medidas-verticales-a-partir-de-la-estatura-001r-1024x405.gif\" alt=\"Comparaci\u00f3n entre esqueleto y figura humana con l\u00edneas de proporci\u00f3n \u00e1urea aplicadas a la estatura\" class=\"wp-image-2207\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140622-Medidas-verticales-a-partir-de-la-estatura-001r-1024x405.gif 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140622-Medidas-verticales-a-partir-de-la-estatura-001r-300x119.gif 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140622-Medidas-verticales-a-partir-de-la-estatura-001r-768x304.gif 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140622-Medidas-verticales-a-partir-de-la-estatura-001r-1320x523.gif 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<ol start=\"6\" class=\"wp-block-list\">\n<li>Si dividimos por \u03c6 la medida suelo ombligo obtendremos <strong>la medida de ombligo a rodilla<\/strong>:<br><center><strong>+((e\/\u03c6)\/\u03c6))<\/strong><\/center><\/li>\n\n\n\n<li>Si restamos la medida que acabamos de obtener a la medida de suelo ombligo obtendremos la medida <strong>suelo- rodilla<\/strong>:<br><center><strong>+((e\/\u03c6) <\/strong>&#8211;<strong> ((e\/\u03c6)\/\u03c6)))<\/strong><\/center><\/li>\n\n\n\n<li>Si dividimos la medida de ombligo a rodilla por el n\u00famero \u03c6 obtendremos la <strong>medida de&nbsp; desarrollo de muslo a ombligo<\/strong>:<br><center><strong>+(((e\/\u03c6)\/\u03c6))\/\u03c6)<\/strong><\/center><\/li>\n\n\n\n<li>Si restamos la medida anterior de la medida de ombligo rodilla obtendremos el valor de <strong>rodilla a desarrollo de muslo<\/strong>:<br><center><strong>+(((e\/\u03c6)\/\u03c6))- (((e\/\u03c6)\/\u03c6))\/\u03c6))<\/strong><\/center><\/li>\n\n\n\n<li>Si dividimos la medida de desarrollo de muslo a ombligo por el n\u00famero \u03c6, obtendremos el valor de <strong>ombligo a entrepierna<\/strong>:<br><center><strong> +((((e\/\u03c6)\/\u03c6))\/\u03c6)<\/strong><\/center><\/li>\n\n\n\n<li>Si restamos el desarrollo de muslo a ombligo de la medida de ombligo a entrepierna encontraremos la medida de <strong>&nbsp;desarrollo de muslo a entrepierna:<br><\/strong><center><strong>+((((e\/\u03c6)\/\u03c6))\/\u03c6))- ((((e\/\u03c6)\/\u03c6))\/\u03c6)<\/strong><\/center><\/li>\n\n\n\n<li>Si sumamos el valor de ombligo a s\u00e9ptima cervical al valor de ombligo entrepierna obtendremos el valor de <strong>tronco:<\/strong><br><center><strong>+(((e-(e\/\u03c6))\/\u03c6)+((((e\/\u03c6)\/\u03c6))\/\u03c6)\/\u03c6))<\/strong><\/center><\/li>\n\n\n\n<li>Si sumamos el valor de suelo rodilla al de rodilla desarrollo de muslo y&nbsp; el valor de desarrollo de muslo entrepierna hallaremos el valor entero de la <strong>entrepierna:<br><\/strong><center><strong>+(((e\/\u03c6) <\/strong>&#8211;<strong> ((e\/\u03c6)\/\u03c6)))+(((e\/\u03c6)\/\u03c6))- (((e\/\u03c6)\/\u03c6))\/\u03c6))+ (((e\/\u03c6)\/\u03c6))-(((e\/\u03c6)\/\u03c6))\/\u03c6)))<\/strong><\/center><\/li>\n<\/ol>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"552\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140622-Medidas-verticales-a-partir-de-la-estatura-002-1024x552.gif\" alt=\"Diagrama del cuerpo humano con indicaci\u00f3n de las medidas de tronco y entrepierna seg\u00fan la proporci\u00f3n \u00e1urea\" class=\"wp-image-2209\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140622-Medidas-verticales-a-partir-de-la-estatura-002-1024x552.gif 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140622-Medidas-verticales-a-partir-de-la-estatura-002-300x162.gif 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140622-Medidas-verticales-a-partir-de-la-estatura-002-768x414.gif 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">En los 13 n\u00fameros anteriores hemos podido aislar el tronco de la estatura dividiendo el cierpo humano en tres partes: la cabeza (desde la coronilla hasta la s\u00e9ptima vertical), el tronco desde la s\u00e9ptima vertical hasta la pr\u00f3stata) y el entrepierna (desde la pr\u00f3stata hasta el suelo.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Ahora nos centraremos en el tronco.<\/p>\n\n\n\n<ol start=\"14\" class=\"wp-block-list\">\n<li>Si dividimos la medida de tronco por el n\u00famero \u03c6 nos encontraremos el nivel desde la s\u00e9ptima v\u00e9rtebra hasta el punto m\u00e1s salido de la cresta il\u00edaca. Sabemos que la cresta il\u00edaca se alza de un cent\u00edmetro y medio por encima de la l\u00ednea de cintura. La l\u00ednea de cintura la colocamos encima de los patrones al nivel de la medida del largo pierna detr\u00e1s, que es un cent\u00edmetro y medio m\u00e1s corto que el largo pierna lateral por ello esta medida la llamaremos <strong>s\u00e9ptima-cresta il\u00edaca:<br><\/strong><center><strong>+((((e-(e\/\u03c6))\/\u03c6)+((((e\/\u03c6)\/\u03c6))\/\u03c6)\/\u03c6))\/\u03c6)<\/strong><\/center><\/li>\n\n\n\n<li><strong>Medida de Busto detr\u00e1s: <\/strong>ser\u00e1 la medida anterior m\u00e1s un cent\u00edmetro y medio:<br><center><strong>+(((((e-(e\/\u03c6))\/\u03c6)+((((e\/\u03c6)\/\u03c6))\/\u03c6)\/\u03c6))\/\u03c6)+1.5)<\/strong><\/center><\/li>\n\n\n\n<li>Si restamos de la medida de tronco&nbsp; la medida de s\u00e9ptima-cresta il\u00edaca obtendremos la medida de <strong>entrepierna a cresta il\u00edaca<\/strong>:<br><center><strong>+((((e-(e\/\u03c6))\/\u03c6)+((((e\/\u03c6)\/\u03c6))\/\u03c6)\/\u03c6))-((((e-(e\/\u03c6))\/\u03c6)+((((e\/\u03c6)\/\u03c6))\/\u03c6)\/\u03c6))\/\u03c6))<\/strong><\/center><\/li>\n\n\n\n<li><strong>Medida de montante de pantal\u00f3n: <\/strong>ser\u00e1 la medida anterior menos un cent\u00edmetro y medio del alzamiento de la cresta il\u00edaca:<br><center><strong>+(((((e-(e\/\u03c6))\/\u03c6)+((((e\/\u03c6)\/\u03c6))\/\u03c6)\/\u03c6))-((((e-(e\/\u03c6))\/\u03c6)+((((e\/\u03c6)\/\u03c6))\/\u03c6)\/\u03c6))\/\u03c6))-1.5)<\/strong><\/center><\/li>\n<\/ol>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"572\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140622-Medidas-verticales-a-partir-de-la-estatura-003-1024x572.gif\" alt=\"Cuerpo humano y esqueleto con referencia a la medida del montante del pantal\u00f3n seg\u00fan la proporci\u00f3n \u00e1urea\" class=\"wp-image-2210\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140622-Medidas-verticales-a-partir-de-la-estatura-003-1024x572.gif 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140622-Medidas-verticales-a-partir-de-la-estatura-003-300x168.gif 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140622-Medidas-verticales-a-partir-de-la-estatura-003-768x429.gif 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">En la pr\u00f3xima ilustraci\u00f3n mostramos el montante en tres tercios iguales que nos situar\u00e1n el nivel de las \u201cpetites hanches\u201d y de la cadera respectivamente desde la l\u00ednea de cintura que se toma a partir de la medida de largo de pierna detr\u00e1s.&nbsp; (l\u00edneas discontinuas con los trazos m\u00e1s cortos)<\/p>\n\n\n\n<ol start=\"18\" class=\"wp-block-list\">\n<li><strong>Medida de altura de las \u201cPetites Hanches\u201d<\/strong>, se sit\u00faa en el primer tercio del montante partiendo la l\u00ednea de cintura hacia el entrepierna.<br><center><strong>+(((((e-(e\/\u03c6))\/\u03c6)+((((e\/\u03c6)\/\u03c6))\/\u03c6)\/\u03c6))-((((e-(e\/\u03c6))\/\u03c6)+((((e\/\u03c6)\/\u03c6))\/\u03c6)\/\u03c6))\/\u03c6))+1,5)\/3<\/strong><\/center><\/li>\n\n\n\n<li>Medida de altura de cadera, se sit\u00faa a dos tercios del montante partiendo de la l\u00ednea de cintura hacia el entrepierna:<br><center><strong>+2(((((e-(e\/\u03c6))\/\u03c6)+((((e\/\u03c6)\/\u03c6))\/\u03c6)\/\u03c6))-((((e-(e\/\u03c6))\/\u03c6)+((((e\/\u03c6)\/\u03c6))\/\u03c6)\/\u03c6))\/\u03c6))+1,5)\/3<\/strong><\/center><\/li>\n<\/ol>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"943\" height=\"597\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140622-Medidas-verticales-a-partir-de-la-estatura-004.gif\" alt=\"Esquema del cuerpo humano con divisiones en tercios que indican la altura de cadera seg\u00fan el montante\" class=\"wp-image-2211\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Ahora nos concentraremos en la distancia entre el nivel del ombligo y el nivel de la s\u00e9ptima cervical.<\/p>\n\n\n\n<ol start=\"20\" class=\"wp-block-list\">\n<li>Si dividimos la distancia entre el ombligo y la s\u00e9ptima cervical por \u03c6 el resultado nos marcar\u00e1 la <strong>medida entre la s\u00e9ptima cervical &nbsp;y la punta del ap\u00e9ndice xifoides del estern\u00f3n<\/strong>:<br><center><strong>+(((e-(e\/\u03c6))\/\u03c6)\/\u03c6)<\/strong><\/center><\/li>\n\n\n\n<li>Si dividimos esta \u00faltima medida (medida entre la s\u00e9ptima cervical&nbsp; y la punta del ap\u00e9ndice xifoides del estern\u00f3n) por el n\u00famero \u03c6 nos dar\u00e1 <strong>la medida desde la s\u00e9ptima cervical hasta la altura de la l\u00ednea de sisa:<br><center>+((((e-(e\/\u03c6))\/\u03c6)\/\u03c6)\/ \u03c6)<\/center><\/strong><\/li>\n<\/ol>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1003\" height=\"597\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140622-Medidas-verticales-a-partir-de-la-estatura-005.gif\" alt=\"Cuerpo humano con l\u00edneas de referencia entre la s\u00e9ptima v\u00e9rtebra cervical y la l\u00ednea de sisa seg\u00fan la proporci\u00f3n \u00e1urea\" class=\"wp-image-2213\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">A continuaci\u00f3n mostramos una tabla con todas las f\u00f3rmulas que hemos utilizado en este post<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"612\" height=\"350\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140622-Medidas-verticales-a-partir-de-la-estatura-006-r.gif\" alt=\"Tabla con las f\u00f3rmulas para calcular las medidas verticales del cuerpo humano usando la proporci\u00f3n \u00e1urea \u03c6\" class=\"wp-image-2215\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">En la tabla siguiente damos las medidas calculadas desde la estatura 150 hasta la de 200 cm.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"630\" height=\"363\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140622-Medidas-verticales-a-partir-de-la-estatura-007.gif\" alt=\"Tabla con las medidas verticales del cuerpo humano calculadas desde estaturas de 150 a 200 cent\u00edmetros seg\u00fan la proporci\u00f3n \u00e1urea\" class=\"wp-image-2216\"\/><\/figure>\n<\/div>\n\n\n<p class=\"text-justify wp-block-paragraph\">Al utilizarlas debemos tener presente que son una indicaci\u00f3n, siempre ser\u00e1 mejor utilizar una serie de medidas de una tabla comprobada.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Repetimos otra vez aqu\u00ed que las medidas estandarizadas no tienen porque corresponder a un cuerpo concreto, ya que las tablas de medidas se basan en unas proporciones o en una muestra de un grupo social, el cuerpo concreto que se viste puede o no responder a estas proporciones o estar fuera del grupo que hemos tomado como muestra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En este art\u00edculo analizamos c\u00f3mo deducir las medidas verticales del cuerpo humano a partir de la estatura utilizando la proporci\u00f3n \u00e1urea \u03c6, seg\u00fan las proporciones propuestas por Ernst Neufert.<br \/>\nA trav\u00e9s de f\u00f3rmulas sencillas y representaciones gr\u00e1ficas, se explican los m\u00e9todos para calcular alturas como la de la entrepierna, el tronco, la cintura o la l\u00ednea de sisa.<br \/>\nEl post incluye esquemas, tablas de referencia y c\u00e1lculos aplicados a estaturas entre 150 cm y 200 cm, ofreciendo una herramienta \u00fatil para el dise\u00f1o de patrones, estudios anat\u00f3micos y proporciones humanas en sastrer\u00eda y dise\u00f1o t\u00e9cnico<\/p>\n","protected":false},"author":1,"featured_media":2206,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1018,1],"tags":[44,30,90,92,382,80,958,40,42],"class_list":["post-2204","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo","category-medidas","tag-como-cubrir-un-cuerpo","tag-comocubriruncuerpo","tag-escuela-de-moda","tag-gradacion-o-escalado","tag-moda","tag-patronaje","tag-tablas-de-medidas","tag-tele-virtual-patronage","tag-televirtualpatronage"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Medidas verticales a partir de la estatura - Tele Virtual Patronage<\/title>\n<meta name=\"description\" content=\"Medidas verticales a partir de la estatura, forma de deducir las medidas verticales a partir de la estatura vali\u00e9ndose del n\u00famero Phi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tevipa.com\/blog\/medidas-verticales-a-partir-de-la-estatura\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Medidas verticales a partir de la estatura - Tele Virtual Patronage\" \/>\n<meta property=\"og:description\" content=\"Medidas verticales a partir de la estatura, forma de deducir las medidas verticales a partir de la estatura vali\u00e9ndose del n\u00famero Phi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tevipa.com\/blog\/medidas-verticales-a-partir-de-la-estatura\/\" \/>\n<meta property=\"og:site_name\" content=\"Tele Virtual Patronage\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-09T11:42:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-09T11:42:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140622-Medidas-verticales-a-partir-de-la-estatura-000.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"796\" \/>\n\t<meta property=\"og:image:height\" content=\"346\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"Tele Virtual Patronage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tele Virtual Patronage\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-verticales-a-partir-de-la-estatura\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-verticales-a-partir-de-la-estatura\\\/\"},\"author\":{\"name\":\"Tele Virtual Patronage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\"},\"headline\":\"Medidas verticales a partir de la estatura\",\"datePublished\":\"2025-10-09T11:42:20+00:00\",\"dateModified\":\"2025-10-09T11:42:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-verticales-a-partir-de-la-estatura\\\/\"},\"wordCount\":1741,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-verticales-a-partir-de-la-estatura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/140622-Medidas-verticales-a-partir-de-la-estatura-000.gif\",\"keywords\":[\"como cubrir un cuerpo\",\"comocubriruncuerpo\",\"escuela de moda\",\"gradaci\u00f3n o escalado\",\"moda\",\"patronaje\",\"tablas de medidas\",\"tele virtual patronage\",\"televirtualpatronage\"],\"articleSection\":[\"Archivo\",\"Medidas\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-verticales-a-partir-de-la-estatura\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-verticales-a-partir-de-la-estatura\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-verticales-a-partir-de-la-estatura\\\/\",\"name\":\"Medidas verticales a partir de la estatura - Tele Virtual Patronage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-verticales-a-partir-de-la-estatura\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-verticales-a-partir-de-la-estatura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/140622-Medidas-verticales-a-partir-de-la-estatura-000.gif\",\"datePublished\":\"2025-10-09T11:42:20+00:00\",\"dateModified\":\"2025-10-09T11:42:22+00:00\",\"description\":\"Medidas verticales a partir de la estatura, forma de deducir las medidas verticales a partir de la estatura vali\u00e9ndose del n\u00famero Phi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-verticales-a-partir-de-la-estatura\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-verticales-a-partir-de-la-estatura\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-verticales-a-partir-de-la-estatura\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/140622-Medidas-verticales-a-partir-de-la-estatura-000.gif\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/140622-Medidas-verticales-a-partir-de-la-estatura-000.gif\",\"width\":796,\"height\":346,\"caption\":\"Construcci\u00f3n geom\u00e9trica paso a paso para dividir un segmento seg\u00fan la proporci\u00f3n \u00e1urea \u03c6\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-verticales-a-partir-de-la-estatura\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Medidas verticales a partir de la estatura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"name\":\"Tele Virtual Patronage\",\"description\":\"Tevipa\",\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\",\"name\":\"Tele Virtual Patronage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"width\":512,\"height\":512,\"caption\":\"Tele Virtual Patronage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\",\"name\":\"Tele Virtual Patronage\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"caption\":\"Tele Virtual Patronage\"},\"sameAs\":[\"https:\\\/\\\/tevipa.com\\\/blog\"],\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/author\\\/tvpadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Medidas verticales a partir de la estatura - Tele Virtual Patronage","description":"Medidas verticales a partir de la estatura, forma de deducir las medidas verticales a partir de la estatura vali\u00e9ndose del n\u00famero Phi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tevipa.com\/blog\/medidas-verticales-a-partir-de-la-estatura\/","og_locale":"it_IT","og_type":"article","og_title":"Medidas verticales a partir de la estatura - Tele Virtual Patronage","og_description":"Medidas verticales a partir de la estatura, forma de deducir las medidas verticales a partir de la estatura vali\u00e9ndose del n\u00famero Phi.","og_url":"https:\/\/tevipa.com\/blog\/medidas-verticales-a-partir-de-la-estatura\/","og_site_name":"Tele Virtual Patronage","article_published_time":"2025-10-09T11:42:20+00:00","article_modified_time":"2025-10-09T11:42:22+00:00","og_image":[{"width":796,"height":346,"url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140622-Medidas-verticales-a-partir-de-la-estatura-000.gif","type":"image\/gif"}],"author":"Tele Virtual Patronage","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Tele Virtual Patronage","Tempo di lettura stimato":"11 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tevipa.com\/blog\/medidas-verticales-a-partir-de-la-estatura\/#article","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/medidas-verticales-a-partir-de-la-estatura\/"},"author":{"name":"Tele Virtual Patronage","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c"},"headline":"Medidas verticales a partir de la estatura","datePublished":"2025-10-09T11:42:20+00:00","dateModified":"2025-10-09T11:42:22+00:00","mainEntityOfPage":{"@id":"https:\/\/tevipa.com\/blog\/medidas-verticales-a-partir-de-la-estatura\/"},"wordCount":1741,"commentCount":0,"publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"image":{"@id":"https:\/\/tevipa.com\/blog\/medidas-verticales-a-partir-de-la-estatura\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140622-Medidas-verticales-a-partir-de-la-estatura-000.gif","keywords":["como cubrir un cuerpo","comocubriruncuerpo","escuela de moda","gradaci\u00f3n o escalado","moda","patronaje","tablas de medidas","tele virtual patronage","televirtualpatronage"],"articleSection":["Archivo","Medidas"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tevipa.com\/blog\/medidas-verticales-a-partir-de-la-estatura\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tevipa.com\/blog\/medidas-verticales-a-partir-de-la-estatura\/","url":"https:\/\/tevipa.com\/blog\/medidas-verticales-a-partir-de-la-estatura\/","name":"Medidas verticales a partir de la estatura - Tele Virtual Patronage","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tevipa.com\/blog\/medidas-verticales-a-partir-de-la-estatura\/#primaryimage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/medidas-verticales-a-partir-de-la-estatura\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140622-Medidas-verticales-a-partir-de-la-estatura-000.gif","datePublished":"2025-10-09T11:42:20+00:00","dateModified":"2025-10-09T11:42:22+00:00","description":"Medidas verticales a partir de la estatura, forma de deducir las medidas verticales a partir de la estatura vali\u00e9ndose del n\u00famero Phi.","breadcrumb":{"@id":"https:\/\/tevipa.com\/blog\/medidas-verticales-a-partir-de-la-estatura\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tevipa.com\/blog\/medidas-verticales-a-partir-de-la-estatura\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/medidas-verticales-a-partir-de-la-estatura\/#primaryimage","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140622-Medidas-verticales-a-partir-de-la-estatura-000.gif","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/140622-Medidas-verticales-a-partir-de-la-estatura-000.gif","width":796,"height":346,"caption":"Construcci\u00f3n geom\u00e9trica paso a paso para dividir un segmento seg\u00fan la proporci\u00f3n \u00e1urea \u03c6"},{"@type":"BreadcrumbList","@id":"https:\/\/tevipa.com\/blog\/medidas-verticales-a-partir-de-la-estatura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tevipa.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Medidas verticales a partir de la estatura"}]},{"@type":"WebSite","@id":"https:\/\/tevipa.com\/blog\/#website","url":"https:\/\/tevipa.com\/blog\/","name":"Tele Virtual Patronage","description":"Tevipa","publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tevipa.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/tevipa.com\/blog\/#organization","name":"Tele Virtual Patronage","url":"https:\/\/tevipa.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","width":512,"height":512,"caption":"Tele Virtual Patronage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c","name":"Tele Virtual Patronage","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","caption":"Tele Virtual Patronage"},"sameAs":["https:\/\/tevipa.com\/blog"],"url":"https:\/\/tevipa.com\/blog\/author\/tvpadm\/"}]}},"_links":{"self":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/2204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/comments?post=2204"}],"version-history":[{"count":6,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/2204\/revisions"}],"predecessor-version":[{"id":2218,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/2204\/revisions\/2218"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media\/2206"}],"wp:attachment":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media?parent=2204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/categories?post=2204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/tags?post=2204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}