{"id":1690,"date":"2025-09-30T21:37:42","date_gmt":"2025-09-30T19:37:42","guid":{"rendered":"https:\/\/tevipa.com\/blog\/?p=1690"},"modified":"2025-10-04T17:58:11","modified_gmt":"2025-10-04T15:58:11","slug":"medidas-10-medidas-de-largos-secundarias-y-otras-medidas","status":"publish","type":"post","link":"https:\/\/tevipa.com\/blog\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\/","title":{"rendered":"Medidas 10 &#8211; Medidas de largos secundarias y otras medidas"},"content":{"rendered":"\n<p class=\"has-text-align-right has-small-font-size wp-block-paragraph\"><sup><em>Publicado originalmente el&nbsp;<strong>24 Abril 2013<\/strong><\/em><\/sup><\/p>\n\n\n<style>.kb-image1690_ef2a2e-b4 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image1690_ef2a2e-b4 is-style-default\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"222\" height=\"300\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg\" alt=\"Logo C\u00f3mo Cubrir un Cuerpo\" class=\"kb-img wp-image-68\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg 222w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-757x1024.jpg 757w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-768x1039.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1135x1536.jpg 1135w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1514x2048.jpg 1514w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran.jpg 1821w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/><\/figure><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\" style=\"font-size:27px\"><strong>Medidas 10<\/strong><br>Medidas de largos secundarias y otras medidas<\/h1>\n\n\n\n<p class=\"wp-block-paragraph\">En este art\u00edculo explicamos c\u00f3mo tomar <strong>largos secundarias y otras medidas<\/strong> en patronaje, empezando por la estatura.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">a.- Estatura<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"text-justify\">Altura de la persona de pie descalza, medida desde el plano superior de la cabeza hasta el suelo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"text-justify\">&nbsp;Esta medida se suele utilizar para el largo de las prendas con capucha. Generalmente la cota le largos m\u00e1s alejada del suelo suele ser la s\u00e9ptima v\u00e9rtebra &nbsp;que ya hemos visto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">b.- Ca\u00edda de hombro delante y ca\u00edda de hombro detr\u00e1s<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"665\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/caida-hombro-1024x665.jpg\" alt=\"ca\u00edda de hombro delantera y trasera en patronaje\" class=\"wp-image-1899\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/caida-hombro-1024x665.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/caida-hombro-300x195.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/caida-hombro-768x499.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/caida-hombro-1536x997.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/caida-hombro-2048x1330.jpg 2048w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/caida-hombro-1320x857.jpg 1320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\" id=\"text-justify\">Es la distancia entre el \u00e1pex acromial&nbsp; y la cintura en la parte delantera y posterior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"text-justify\">Es la medida que nos dar\u00e1 el \u00e1ngulo de la ca\u00edda de hombro, esta medida muchas veces la encontramos en las tablas expresadas en grados.<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">c.- Consideraci\u00f3n de los tres diferentes largos de pantal\u00f3n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"text-justify\">Es conveniente tomar los tres largos del pantal\u00f3n, el delantero, el de mitad espalda y el lateral ya que las tres medidas ser\u00e1n diferentes del hecho que la cintura no es paralela al suelo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"text-justify\">Esta triple medida sirve sobre todo para las prendas que se apoyan en la cintura, como la falda o el pantal\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"text-justify\">Cuando se necesita una de los tres largos se tomar\u00e1&nbsp; la distancia del largo del pantal\u00f3n detr\u00e1s, exceptuando en la sastrer\u00eda cl\u00e1sica que se toma la medida del largo delante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"text-justify\">Sobre el tema ya hemos hablado en el ep\u00edgrafe de la cintura como medida horizontal.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"467\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/3-largos-467x1024.jpg\" alt=\"esquema de los tres largos de pantal\u00f3n en patronaje\" class=\"wp-image-1898\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/3-largos-467x1024.jpg 467w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/3-largos-137x300.jpg 137w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/3-largos-768x1683.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/3-largos-701x1536.jpg 701w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/3-largos-934x2048.jpg 934w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/3-largos-1320x2893.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/3-largos-scaled.jpg 1168w\" sizes=\"auto, (max-width: 467px) 100vw, 467px\" \/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">d.- Largo de americana<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"742\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/largo-am-742x1024.jpg\" alt=\"largo de americana en patronaje cl\u00e1sico\" class=\"wp-image-1901\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/largo-am-742x1024.jpg 742w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/largo-am-217x300.jpg 217w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/largo-am-768x1060.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/largo-am-1112x1536.jpg 1112w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/largo-am-1483x2048.jpg 1483w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/largo-am-1320x1823.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/largo-am.jpg 1681w\" sizes=\"auto, (max-width: 742px) 100vw, 742px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\" id=\"text-justify\">Aunque no es una medida del cuerpo, es una medida cl\u00e1sica y por eso hemos querido incluirla en este apartado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"text-justify\">Hay dos formas de hallar la medida:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li id=\"text-justify\">La mitad del largo desde la s\u00e9ptima v\u00e9rtebra hasta el suelo.<\/li>\n\n\n\n<li id=\"text-justify\">Desde la s\u00e9ptima v\u00e9rtebra hasta el nivel del pu\u00f1o cerrado con el brazo relajado. <\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">e.- Largo hombro<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"693\" height=\"533\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/largo-hombro.jpg\" alt=\"medida del largo de hombro en patronaje\" class=\"wp-image-1902\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/largo-hombro.jpg 693w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/largo-hombro-300x231.jpg 300w\" sizes=\"auto, (max-width: 693px) 100vw, 693px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\" id=\"text-justify\">Esta medida se toma a partir de una sexta parte (un octavo de pecho m\u00e1s dos cm en las tallas grandes)&nbsp; de pecho a partir&nbsp; del recorrido del cuello empezando desde la s\u00e9ptima v\u00e9rtebra ( que nos fijar\u00e1 la posici\u00f3n de la costura lateral) hasta&nbsp; el \u00e1pex acromial (el hueso del hombro).<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-medium-font-size\">f.- El pu\u00f1al o la carga del pantal\u00f3n masculino<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"371\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/carga-1024x371.jpg\" alt=\"medida de carga o pu\u00f1al en pantalones masculinos\" class=\"wp-image-1900\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/carga-1024x371.jpg 1024w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/carga-300x109.jpg 300w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/carga-768x279.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/carga-1536x557.jpg 1536w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/carga-1320x479.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/carga.jpg 1552w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\" id=\"text-justify\">La carga, tambi\u00e9n llamada pu\u00f1al del pantal\u00f3n se utiliza exclusivamente en Sastrer\u00eda cl\u00e1sica en caso en que&nbsp; el cliente suela vestir boxers en vez de slips. En los pantalones ajustados y los pinzados de tiro alto se suele dar una holgura para que los genitales del hombre no marquen en el delantero del pantal\u00f3n, por ello, en el caso de tomar medidas a un cliente de sastrer\u00eda cl\u00e1sica se debe anotar el lado de la carga: izquierda o derecha.&nbsp; ( el 80% de los hombres cargan a la derecha, y el otro 20% cargan a la izquierda).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este art\u00edculo explica c\u00f3mo tomar medidas de largos secundarios y otras espec\u00edficas en patronaje. Se incluyen la estatura, la ca\u00edda de hombro (delantera y trasera), los tres largos del pantal\u00f3n (delantero, mitad espalda y lateral), el largo de americana, el largo de hombro y la medida de la carga o pu\u00f1al en pantalones masculinos. Cada una de estas medidas tiene aplicaciones concretas en sastrer\u00eda y confecci\u00f3n, y su correcta toma garantiza precisi\u00f3n en el dise\u00f1o y ajuste de las prendas<\/p>\n","protected":false},"author":1,"featured_media":1901,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1018,1],"tags":[44,30,38,36,92,80,372,40,42],"class_list":["post-1690","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo","category-medidas","tag-como-cubrir-un-cuerpo","tag-comocubriruncuerpo","tag-creacion-de-moda","tag-estilismo","tag-gradacion-o-escalado","tag-patronaje","tag-sastreria","tag-tele-virtual-patronage","tag-televirtualpatronage"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Medidas 10 - Medidas de largos secundarias y otras medidas - Tele Virtual Patronage<\/title>\n<meta name=\"description\" content=\"Aprende a tomar la medida en patronaje: largos secundarias y otras medidas como estatura, ca\u00edda de hombro, largo de pantal\u00f3n y americana\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tevipa.com\/blog\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Medidas 10 - Medidas de largos secundarias y otras medidas - Tele Virtual Patronage\" \/>\n<meta property=\"og:description\" content=\"Aprende a tomar la medida en patronaje: largos secundarias y otras medidas como estatura, ca\u00edda de hombro, largo de pantal\u00f3n y americana\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tevipa.com\/blog\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\/\" \/>\n<meta property=\"og:site_name\" content=\"Tele Virtual Patronage\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-30T19:37:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-04T15:58:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/largo-am.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1681\" \/>\n\t<meta property=\"og:image:height\" content=\"2321\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tele Virtual Patronage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tele Virtual Patronage\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\\\/\"},\"author\":{\"name\":\"Tele Virtual Patronage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\"},\"headline\":\"Medidas 10 &#8211; Medidas de largos secundarias y otras medidas\",\"datePublished\":\"2025-09-30T19:37:42+00:00\",\"dateModified\":\"2025-10-04T15:58:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\\\/\"},\"wordCount\":517,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/largo-am.jpg\",\"keywords\":[\"como cubrir un cuerpo\",\"comocubriruncuerpo\",\"creaci\u00f3n de moda\",\"estilismo\",\"gradaci\u00f3n o escalado\",\"patronaje\",\"sastrer\u00eda\",\"tele virtual patronage\",\"televirtualpatronage\"],\"articleSection\":[\"Archivo\",\"Medidas\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\\\/\",\"name\":\"Medidas 10 - Medidas de largos secundarias y otras medidas - Tele Virtual Patronage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/largo-am.jpg\",\"datePublished\":\"2025-09-30T19:37:42+00:00\",\"dateModified\":\"2025-10-04T15:58:11+00:00\",\"description\":\"Aprende a tomar la medida en patronaje: largos secundarias y otras medidas como estatura, ca\u00edda de hombro, largo de pantal\u00f3n y americana\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/largo-am.jpg\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/largo-am.jpg\",\"width\":1681,\"height\":2321,\"caption\":\"largo de americana en patronaje cl\u00e1sico\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Medidas 10 &#8211; Medidas de largos secundarias y otras medidas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"name\":\"Tele Virtual Patronage\",\"description\":\"Tevipa\",\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\",\"name\":\"Tele Virtual Patronage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"width\":512,\"height\":512,\"caption\":\"Tele Virtual Patronage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\",\"name\":\"Tele Virtual Patronage\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"caption\":\"Tele Virtual Patronage\"},\"sameAs\":[\"https:\\\/\\\/tevipa.com\\\/blog\"],\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/author\\\/tvpadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Medidas 10 - Medidas de largos secundarias y otras medidas - Tele Virtual Patronage","description":"Aprende a tomar la medida en patronaje: largos secundarias y otras medidas como estatura, ca\u00edda de hombro, largo de pantal\u00f3n y americana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tevipa.com\/blog\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\/","og_locale":"it_IT","og_type":"article","og_title":"Medidas 10 - Medidas de largos secundarias y otras medidas - Tele Virtual Patronage","og_description":"Aprende a tomar la medida en patronaje: largos secundarias y otras medidas como estatura, ca\u00edda de hombro, largo de pantal\u00f3n y americana","og_url":"https:\/\/tevipa.com\/blog\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\/","og_site_name":"Tele Virtual Patronage","article_published_time":"2025-09-30T19:37:42+00:00","article_modified_time":"2025-10-04T15:58:11+00:00","og_image":[{"width":1681,"height":2321,"url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/largo-am.jpg","type":"image\/jpeg"}],"author":"Tele Virtual Patronage","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Tele Virtual Patronage","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tevipa.com\/blog\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\/#article","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\/"},"author":{"name":"Tele Virtual Patronage","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c"},"headline":"Medidas 10 &#8211; Medidas de largos secundarias y otras medidas","datePublished":"2025-09-30T19:37:42+00:00","dateModified":"2025-10-04T15:58:11+00:00","mainEntityOfPage":{"@id":"https:\/\/tevipa.com\/blog\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\/"},"wordCount":517,"commentCount":0,"publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"image":{"@id":"https:\/\/tevipa.com\/blog\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/largo-am.jpg","keywords":["como cubrir un cuerpo","comocubriruncuerpo","creaci\u00f3n de moda","estilismo","gradaci\u00f3n o escalado","patronaje","sastrer\u00eda","tele virtual patronage","televirtualpatronage"],"articleSection":["Archivo","Medidas"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tevipa.com\/blog\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tevipa.com\/blog\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\/","url":"https:\/\/tevipa.com\/blog\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\/","name":"Medidas 10 - Medidas de largos secundarias y otras medidas - Tele Virtual Patronage","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tevipa.com\/blog\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\/#primaryimage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/largo-am.jpg","datePublished":"2025-09-30T19:37:42+00:00","dateModified":"2025-10-04T15:58:11+00:00","description":"Aprende a tomar la medida en patronaje: largos secundarias y otras medidas como estatura, ca\u00edda de hombro, largo de pantal\u00f3n y americana","breadcrumb":{"@id":"https:\/\/tevipa.com\/blog\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tevipa.com\/blog\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\/#primaryimage","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/largo-am.jpg","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/largo-am.jpg","width":1681,"height":2321,"caption":"largo de americana en patronaje cl\u00e1sico"},{"@type":"BreadcrumbList","@id":"https:\/\/tevipa.com\/blog\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tevipa.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Medidas 10 &#8211; Medidas de largos secundarias y otras medidas"}]},{"@type":"WebSite","@id":"https:\/\/tevipa.com\/blog\/#website","url":"https:\/\/tevipa.com\/blog\/","name":"Tele Virtual Patronage","description":"Tevipa","publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tevipa.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/tevipa.com\/blog\/#organization","name":"Tele Virtual Patronage","url":"https:\/\/tevipa.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","width":512,"height":512,"caption":"Tele Virtual Patronage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c","name":"Tele Virtual Patronage","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","caption":"Tele Virtual Patronage"},"sameAs":["https:\/\/tevipa.com\/blog"],"url":"https:\/\/tevipa.com\/blog\/author\/tvpadm\/"}]}},"_links":{"self":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/1690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/comments?post=1690"}],"version-history":[{"count":3,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/1690\/revisions"}],"predecessor-version":[{"id":2037,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/1690\/revisions\/2037"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media\/1901"}],"wp:attachment":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media?parent=1690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/categories?post=1690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/tags?post=1690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}