{"id":1687,"date":"2025-09-30T21:07:19","date_gmt":"2025-09-30T19:07:19","guid":{"rendered":"https:\/\/tevipa.com\/blog\/?p=1687"},"modified":"2025-10-04T18:00:26","modified_gmt":"2025-10-04T16:00:26","slug":"medidas-9-largo-brazo-codo-y-puno","status":"publish","type":"post","link":"https:\/\/tevipa.com\/blog\/medidas-9-largo-brazo-codo-y-puno\/","title":{"rendered":"Medidas 9 &#8211; Largo brazo codo y pu\u00f1o"},"content":{"rendered":"\n<p class=\"has-text-align-right has-small-font-size wp-block-paragraph\"><sup><em>Publicado originalmente el&nbsp;<strong>20 Abril 2013<\/strong><\/em><\/sup><\/p>\n\n\n<style>.kb-image1687_bf19e8-88 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image1687_bf19e8-88 is-style-default\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"222\" height=\"300\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg\" alt=\"Logo C\u00f3mo Cubrir un Cuerpo\" class=\"kb-img wp-image-68\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg 222w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-757x1024.jpg 757w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-768x1039.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1135x1536.jpg 1135w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1514x2048.jpg 1514w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran.jpg 1821w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/><\/figure><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center\" style=\"font-size:27px\"><strong>Medidas 9<\/strong><br><strong>Largo brazo codo y pu\u00f1o<\/strong><\/h1>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"text-justify\">Hay dos maneras de tomar la medida del brazo: una desde la punta del hombro hasta el pu\u00f1o y la otra desde la mitad de espalda hasta el pu\u00f1o.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"711\" height=\"1024\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/medida_brazo-711x1024.jpg\" alt=\"esquema t\u00e9cnico de largo de manga en patronaje\" class=\"wp-image-1895\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/medida_brazo-711x1024.jpg 711w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/medida_brazo-208x300.jpg 208w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/medida_brazo-768x1106.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/medida_brazo-1067x1536.jpg 1067w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/medida_brazo-1423x2048.jpg 1423w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/medida_brazo-1320x1900.jpg 1320w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/medida_brazo-scaled.jpg 1778w\" sizes=\"auto, (max-width: 711px) 100vw, 711px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\" id=\"text-justify\">Vemos en la ilustraci\u00f3n las <strong>dos formas<\/strong> de tomar la medida de la manga.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"text-justify\">La<strong> primera &nbsp;<\/strong>(a la derecha de la ilustraci\u00f3n) es la m\u00e1s evidente pero la menos exacta, ya que no tenemos ninguna referencia del cuerpo si no es la costura o la punta del hombro (el&nbsp; \u00c1pex acromial). El \u00e1pex acromial&nbsp; muchas veces no es f\u00e1cil individualizarlo sobre todo si el cliente&nbsp; est\u00e1 un poco en carnes o tiene el hombro redondo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"text-justify\">En el caso de tomar la medida de esta forma, pondremos la punta de la cinta m\u00e9trica bajaremos hasta tomar el codo y luego hasta el hueso que sobresale m\u00e1s de la mu\u00f1eca ( el c\u00fabito). Es importante que el brazo y el antebrazo formen un \u00e1ngulo de 90\u00ba &nbsp;para poder dar del desarrollo suficiente al largo de la manga<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"text-justify\">La<strong> segunda forma <\/strong>(a la izquierda de la ilustraci\u00f3n)&nbsp;de tomar el largo de la manga es m\u00e1s compleja pero es mucho m\u00e1s exacta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"text-justify\">Partiremos de la mitad espalda, de encima de la columna vertebral colocando la punta de la cinta m\u00e9trica. A partir de este punto y a&nbsp; escuadra de la columna iremos a medir el codo y de \u00e9ste (siempre a 90 grados) mediremos el final de la manga, hasta el c\u00fabito, el hueso que sobresale m\u00e1s de la mu\u00f1eca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\" id=\"text-justify\">La segunda forma de tomar el largo de la manga suele ser la que se utiliza en sastrer\u00eda cl\u00e1sica. Tiene la ventaja que fija con exactitud el codo y el pu\u00f1o de la manga, de esta medida deberemos quitar el ancho de espalda y a\u00f1adir la profundidad de sisa.&nbsp; Este procedimiento lo veremos m\u00e1s adelante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este post continua en &#8220;<a href=\"https:\/\/tevipa.com\/blog\/medidas-10-medidas-de-largos-secundarias-y-otras-medidas\/\">Medidas 10 &#8211; Medidas de largos secundarias y otras medidas<\/a>&#8220;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En este cap\u00edtulo se explican dos formas de tomar la medida del largo de manga en patronaje.<br \/>\nLa primera, desde el hombro hasta el pu\u00f1o, es sencilla pero poco precisa porque depende de localizar el \u00e1pex acromial. La segunda, desde la mitad de la espalda hasta el pu\u00f1o, es m\u00e1s exacta y es la que se usa en sastrer\u00eda cl\u00e1sica, ya que fija mejor la posici\u00f3n del codo y del pu\u00f1o. En ambos casos el brazo debe estar en \u00e1ngulo de 90\u00b0 para asegurar el desarrollo correcto de la manga<\/p>\n","protected":false},"author":1,"featured_media":1895,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1018,1],"tags":[44,30,38,36,92,80,372,40,42],"class_list":["post-1687","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo","category-medidas","tag-como-cubrir-un-cuerpo","tag-comocubriruncuerpo","tag-creacion-de-moda","tag-estilismo","tag-gradacion-o-escalado","tag-patronaje","tag-sastreria","tag-tele-virtual-patronage","tag-televirtualpatronage"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Medidas 9 - Largo brazo codo y pu\u00f1o - Tele Virtual Patronage<\/title>\n<meta name=\"description\" content=\"Aprende c\u00f3mo medir el largo de brazo, codo y pu\u00f1o para un patronaje preciso en prendas masculinas y femeninas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tevipa.com\/blog\/medidas-9-largo-brazo-codo-y-puno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Medidas 9 - Largo brazo codo y pu\u00f1o - Tele Virtual Patronage\" \/>\n<meta property=\"og:description\" content=\"Aprende c\u00f3mo medir el largo de brazo, codo y pu\u00f1o para un patronaje preciso en prendas masculinas y femeninas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tevipa.com\/blog\/medidas-9-largo-brazo-codo-y-puno\/\" \/>\n<meta property=\"og:site_name\" content=\"Tele Virtual Patronage\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-30T19:07:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-04T16:00:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/medida_brazo-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1778\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tele Virtual Patronage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tele Virtual Patronage\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-9-largo-brazo-codo-y-puno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-9-largo-brazo-codo-y-puno\\\/\"},\"author\":{\"name\":\"Tele Virtual Patronage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\"},\"headline\":\"Medidas 9 &#8211; Largo brazo codo y pu\u00f1o\",\"datePublished\":\"2025-09-30T19:07:19+00:00\",\"dateModified\":\"2025-10-04T16:00:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-9-largo-brazo-codo-y-puno\\\/\"},\"wordCount\":361,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-9-largo-brazo-codo-y-puno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/medida_brazo-scaled.jpg\",\"keywords\":[\"como cubrir un cuerpo\",\"comocubriruncuerpo\",\"creaci\u00f3n de moda\",\"estilismo\",\"gradaci\u00f3n o escalado\",\"patronaje\",\"sastrer\u00eda\",\"tele virtual patronage\",\"televirtualpatronage\"],\"articleSection\":[\"Archivo\",\"Medidas\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-9-largo-brazo-codo-y-puno\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-9-largo-brazo-codo-y-puno\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-9-largo-brazo-codo-y-puno\\\/\",\"name\":\"Medidas 9 - Largo brazo codo y pu\u00f1o - Tele Virtual Patronage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-9-largo-brazo-codo-y-puno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-9-largo-brazo-codo-y-puno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/medida_brazo-scaled.jpg\",\"datePublished\":\"2025-09-30T19:07:19+00:00\",\"dateModified\":\"2025-10-04T16:00:26+00:00\",\"description\":\"Aprende c\u00f3mo medir el largo de brazo, codo y pu\u00f1o para un patronaje preciso en prendas masculinas y femeninas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-9-largo-brazo-codo-y-puno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-9-largo-brazo-codo-y-puno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-9-largo-brazo-codo-y-puno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/medida_brazo-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/medida_brazo-scaled.jpg\",\"width\":1778,\"height\":2560,\"caption\":\"esquema t\u00e9cnico de largo de manga en patronaje\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/medidas-9-largo-brazo-codo-y-puno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Medidas 9 &#8211; Largo brazo codo y pu\u00f1o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"name\":\"Tele Virtual Patronage\",\"description\":\"Tevipa\",\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\",\"name\":\"Tele Virtual Patronage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"width\":512,\"height\":512,\"caption\":\"Tele Virtual Patronage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\",\"name\":\"Tele Virtual Patronage\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"caption\":\"Tele Virtual Patronage\"},\"sameAs\":[\"https:\\\/\\\/tevipa.com\\\/blog\"],\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/author\\\/tvpadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Medidas 9 - Largo brazo codo y pu\u00f1o - Tele Virtual Patronage","description":"Aprende c\u00f3mo medir el largo de brazo, codo y pu\u00f1o para un patronaje preciso en prendas masculinas y femeninas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tevipa.com\/blog\/medidas-9-largo-brazo-codo-y-puno\/","og_locale":"it_IT","og_type":"article","og_title":"Medidas 9 - Largo brazo codo y pu\u00f1o - Tele Virtual Patronage","og_description":"Aprende c\u00f3mo medir el largo de brazo, codo y pu\u00f1o para un patronaje preciso en prendas masculinas y femeninas","og_url":"https:\/\/tevipa.com\/blog\/medidas-9-largo-brazo-codo-y-puno\/","og_site_name":"Tele Virtual Patronage","article_published_time":"2025-09-30T19:07:19+00:00","article_modified_time":"2025-10-04T16:00:26+00:00","og_image":[{"width":1778,"height":2560,"url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/medida_brazo-scaled.jpg","type":"image\/jpeg"}],"author":"Tele Virtual Patronage","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Tele Virtual Patronage","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tevipa.com\/blog\/medidas-9-largo-brazo-codo-y-puno\/#article","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/medidas-9-largo-brazo-codo-y-puno\/"},"author":{"name":"Tele Virtual Patronage","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c"},"headline":"Medidas 9 &#8211; Largo brazo codo y pu\u00f1o","datePublished":"2025-09-30T19:07:19+00:00","dateModified":"2025-10-04T16:00:26+00:00","mainEntityOfPage":{"@id":"https:\/\/tevipa.com\/blog\/medidas-9-largo-brazo-codo-y-puno\/"},"wordCount":361,"commentCount":0,"publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"image":{"@id":"https:\/\/tevipa.com\/blog\/medidas-9-largo-brazo-codo-y-puno\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/medida_brazo-scaled.jpg","keywords":["como cubrir un cuerpo","comocubriruncuerpo","creaci\u00f3n de moda","estilismo","gradaci\u00f3n o escalado","patronaje","sastrer\u00eda","tele virtual patronage","televirtualpatronage"],"articleSection":["Archivo","Medidas"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tevipa.com\/blog\/medidas-9-largo-brazo-codo-y-puno\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tevipa.com\/blog\/medidas-9-largo-brazo-codo-y-puno\/","url":"https:\/\/tevipa.com\/blog\/medidas-9-largo-brazo-codo-y-puno\/","name":"Medidas 9 - Largo brazo codo y pu\u00f1o - Tele Virtual Patronage","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tevipa.com\/blog\/medidas-9-largo-brazo-codo-y-puno\/#primaryimage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/medidas-9-largo-brazo-codo-y-puno\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/medida_brazo-scaled.jpg","datePublished":"2025-09-30T19:07:19+00:00","dateModified":"2025-10-04T16:00:26+00:00","description":"Aprende c\u00f3mo medir el largo de brazo, codo y pu\u00f1o para un patronaje preciso en prendas masculinas y femeninas","breadcrumb":{"@id":"https:\/\/tevipa.com\/blog\/medidas-9-largo-brazo-codo-y-puno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tevipa.com\/blog\/medidas-9-largo-brazo-codo-y-puno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/medidas-9-largo-brazo-codo-y-puno\/#primaryimage","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/medida_brazo-scaled.jpg","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/10\/medida_brazo-scaled.jpg","width":1778,"height":2560,"caption":"esquema t\u00e9cnico de largo de manga en patronaje"},{"@type":"BreadcrumbList","@id":"https:\/\/tevipa.com\/blog\/medidas-9-largo-brazo-codo-y-puno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tevipa.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Medidas 9 &#8211; Largo brazo codo y pu\u00f1o"}]},{"@type":"WebSite","@id":"https:\/\/tevipa.com\/blog\/#website","url":"https:\/\/tevipa.com\/blog\/","name":"Tele Virtual Patronage","description":"Tevipa","publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tevipa.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/tevipa.com\/blog\/#organization","name":"Tele Virtual Patronage","url":"https:\/\/tevipa.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","width":512,"height":512,"caption":"Tele Virtual Patronage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c","name":"Tele Virtual Patronage","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","caption":"Tele Virtual Patronage"},"sameAs":["https:\/\/tevipa.com\/blog"],"url":"https:\/\/tevipa.com\/blog\/author\/tvpadm\/"}]}},"_links":{"self":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/1687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/comments?post=1687"}],"version-history":[{"count":4,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/1687\/revisions"}],"predecessor-version":[{"id":2036,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/1687\/revisions\/2036"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media\/1895"}],"wp:attachment":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media?parent=1687"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/categories?post=1687"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/tags?post=1687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}