{"id":124,"date":"2025-07-09T19:38:35","date_gmt":"2025-07-09T17:38:35","guid":{"rendered":"https:\/\/tevipa.com\/blog\/?p=124"},"modified":"2025-10-05T18:39:43","modified_gmt":"2025-10-05T16:39:43","slug":"formazione-tecnica-nella-moda","status":"publish","type":"post","link":"https:\/\/tevipa.com\/blog\/it\/formazione-tecnica-nella-moda\/","title":{"rendered":"Presentazione"},"content":{"rendered":"\n<p class=\"has-text-align-right has-small-font-size wp-block-paragraph\"><sup><em>Publicato originariamente il&nbsp;<strong>2 Febbraio 2013<\/strong><\/em><\/sup><\/p>\n\n\n<style>.kb-image124_6de01d-07 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image124_6de01d-07 is-style-default\"><figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"222\" height=\"300\" src=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg\" alt=\"Logo C\u00f3mo Cubrir un Cuerpo\" class=\"kb-img wp-image-68\" srcset=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-222x300.jpg 222w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-757x1024.jpg 757w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-768x1039.jpg 768w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1135x1536.jpg 1135w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran-1514x2048.jpg 1514w, https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran.jpg 1821w\" sizes=\"auto, (max-width: 222px) 100vw, 222px\" \/><\/figure><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center has-medium-font-size\">Presentazione del progetto &#8220;C\u00f3mo cubrir un cuerpo&#8221;<br>formazione tecnica nella moda<\/h1>\n\n\n\n<h3 class=\"wp-block-heading\" style=\"font-size:16px\">Una piattaforma per la moda consapevole<\/h3>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">La formazione tecnica nella moda \u00e8 il cuore del progetto \u201c<a href=\"https:\/\/comocubriruncuerpo.org\">C\u00f3mo cubrir un cuerpo<\/a>\u201d (in italiano <strong>Como coprire un corpo<\/strong>), una piattaforma che promuove conoscenza, consapevolezza e critica costruttiva nel settore moda.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">L\u2019idea nasce dalla constatazione della profonda disinformazione che esiste tra gli studenti di molte scuole riguardo ai fondamenti tecnici della moda. Il nostro obiettivo \u00e8 offrire conoscenze utili allo sviluppo professionale e personale di chi desidera lavorare nel settore moda.<\/p>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-124_9c6ceb-d1 .kt-block-spacer{height:60px;}.wp-block-kadence-spacer.kt-block-spacer-124_9c6ceb-d1 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-124_9c6ceb-d1\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" style=\"font-size:16px\">La situazione attuale nelle scuole<\/h3>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Con stupore, ho constatato che molti studenti che a malapena sanno modellare in piano e realizzare alcune trasformazioni di base si autodefiniscono stilisti, anche frequentando scuole in cui si insegna esclusivamente modellistica.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Molti di loro, una volta diplomati, non sono in grado di finalizzare le cuciture di un cartamodello per consegnarlo a una catena di montaggio, nel caso in cui la loro &#8220;collezione&#8221; voglia essere pr\u00eat-\u00e0-porter; oppure, nel caso dell\u2019alta sartoria, non sanno nemmeno aprire correttamente una pince di petto su un capo aderente posato su uno stiramaniche.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Non dico che i centri formativi o gli studenti non siano validi, ma osservo che esiste un problema. Con ogni probabilit\u00e0, molti dei titoli rilasciati non bastano a preparare adeguatamente a un percorso professionale nel mondo della moda, e gli studenti stessi non ne sono consapevoli.<\/p>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-124_179fb0-bd .kt-block-spacer{height:60px;}.wp-block-kadence-spacer.kt-block-spacer-124_179fb0-bd .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-124_179fb0-bd\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" style=\"font-size:16px\">Il bisogno di una formazione completa<\/h3>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Per affrontare il mondo della moda con seriet\u00e0 serve una visione ampia. Questa include aver la dominanza di tutte le fasi a partire dalla creazione con l&#8217;ideazione e progettazione passando per la modellistica, il cucito fino ad arrivare alla stiratura finale.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\"><em><strong>Solo la conoscenza tecnica dell&#8217;intero flusso lavorativo offre la vera libert\u00e0 creativa.<\/strong><\/em><\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Alcuni studenti, anche in scuole prestigiose e costose, passano mesi a copiare disegni in scala. Quando chiedono spiegazioni, si sentono dire: &#8220;Per ora copia, poi capirai&#8221;. Ma quel &#8220;poi&#8221;, dopo quote scolastiche costose, spesso non arriva mai.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Nelle scuole pubbliche, invece, ci sono insegnanti eccellenti. Tuttavia, anche loro, a volte, propongono come alternativa all&#8217;apprendimento teorico l\u2019acquisto di riviste di moda con cartamodelli gi\u00e0 pronti indicando ad esempio una rivista di moda molto conosciuta.<\/p>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-124_ecfc89-f5 .kt-block-spacer{height:60px;}.wp-block-kadence-spacer.kt-block-spacer-124_ecfc89-f5 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-124_ecfc89-f5\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" style=\"font-size:16px\">Illusioni e realt\u00e0<\/h3>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Gli studenti di tutte queste scuole, pubbliche o private, condividono due aspetti:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"text-justify\">non conoscono l&#8217;intero processo della creazione di moda<\/li>\n\n\n\n<li class=\"text-justify\">sperano che un software, usato a volte da terze persone, possa colmare tutte le loro lacune<\/li>\n<\/ul>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Dopo gli studi, molti si considerano stilisti a tutti gli effetti. Parlano delle loro collezioni con poca umilt\u00e0, dimenticando quanto fossero umili i grandi maestri della moda.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Oggi dominano piume, glamour e il &#8220;<em><strong>molto nulla<\/strong><\/em>&#8220;, ma spesso \u00e8 solo fumo negli occhi.<\/p>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-124_bb52af-b3 .kt-block-spacer{height:60px;}.wp-block-kadence-spacer.kt-block-spacer-124_bb52af-b3 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-124_bb52af-b3\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" style=\"font-size:16px\">La fase pi\u00f9 delicata: la realizzazione tecnica<\/h3>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">La mancanza di informazione \u00e8 ci\u00f2 che porta a questa mancanza di umilt\u00e0 e al disprezzo per tutte le fasi tecniche della creazione che non siano il disegno. Eppure, la materializzazione di un\u2019idea \u2014 cio\u00e8 il modellismo, la gradazione e la realizzazione del prototipo \u2014 \u00e8 la fase pi\u00f9 delicata dell\u2019intero processo creativo nella moda.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Anche la migliore idea, tradotta nella migliore illustrazione, pu\u00f2 risultare un fallimento totale se non viene concretizzata correttamente.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Il lavoro del creatore di moda dovrebbe arrivare fino alla stiratura finale del prototipo e, nel caso di una collezione pr\u00eat-\u00e0-porter, includere anche la prova delle taglie campione. \u00c8 dunque indispensabile che padroneggi anche la tecnica della gradazione.<\/p>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-124_ae53d6-58 .kt-block-spacer{height:60px;}.wp-block-kadence-spacer.kt-block-spacer-124_ae53d6-58 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-124_ae53d6-58\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" style=\"font-size:16px\">Il valore della tecnica e della conoscenza<\/h3>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Gli studenti di oggi sono eccellenti, se motivati. La loro creativit\u00e0 \u00e8 un vulcano in eruzione. Ma senza conoscenza tecnica e senza la storia della moda, non possono esprimersi pienamente.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Solo una formazione completa pu\u00f2 dare vita a veri creatori di moda. Molti stilisti emergenti durano solo poche stagioni perch\u00e9 non sanno rigenerarsi. Mancano di fondamenta per rigenerare la loro creativit\u00e0.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">La vera Fenice della moda si chiama conoscenza tecnica: \u00e8 la cenere da cui rinasce ogni nuova creazione senza far perdere la propria identit\u00e0.<\/p>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-124_1c80ed-e1 .kt-block-spacer{height:60px;}.wp-block-kadence-spacer.kt-block-spacer-124_1c80ed-e1 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-124_1c80ed-e1\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" style=\"font-size:16px\">Un invito alla consapevolezza<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Come diceva <em>Abraham Lincoln<\/em>:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"text-justify wp-block-paragraph\">&#8220;Si pu\u00f2 ingannare tutti per un po\u2019 di tempo e qualcuno per sempre, ma non si pu\u00f2 ingannare tutti per sempre&#8221;<\/p>\n<\/blockquote>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">I clienti smettono di comprare se non sono convinti. E la ripetizione senza creativit\u00e0 \u00e8 un inganno. E l\u2019inganno nella moda non si perdona.<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">C\u00f2mo Cubrir Un cuerpo vuole dare un piccolo contributo a chi si sente cieco in questo settore. Speriamo di riuscire nel nostro intento.<\/p>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-124_5a77dc-5a .kt-block-spacer{height:60px;}.wp-block-kadence-spacer.kt-block-spacer-124_5a77dc-5a .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-124_5a77dc-5a\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" style=\"font-size:16px\">Domande aperte<\/h3>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Perch\u00e9 la moda in Spagna, e a Barcellona in particolare, non funziona pi\u00f9?<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Cosa accadr\u00e0 con il cambio generazionale?<\/p>\n\n\n\n<p class=\"text-justify wp-block-paragraph\">Ah s\u00ec\u2026 oggi ci sono i computer e le riviste con cartamodelli. Usare la ruota dentata \u00e8 ancora considerato artigianato\u2026 Peccato che il computer non sia in grado di farlo da solo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Publicato originariamente il&nbsp;2 Febbraio 2013 Presentazione del progetto &#8220;C\u00f3mo cubrir un cuerpo&#8221;formazione tecnica nella moda Una piattaforma per la moda consapevole La formazione tecnica nella moda \u00e8 il cuore del progetto \u201cC\u00f3mo cubrir un cuerpo\u201d (in italiano Como coprire un&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1382,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1020,623],"tags":[62,70,143,151,175,46,54],"class_list":["post-124","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio","category-presentazione","tag-como-cubrir-un-cuerpo-it","tag-comocubriruncuerpo-it","tag-creazione-di-moda","tag-designer","tag-stilismo","tag-tele-virtual-patronage-it","tag-televirtualpatronage-it"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Formazione tecnica nella moda - Tele Virtual Patronage<\/title>\n<meta name=\"description\" content=\"Una piattaforma sulla formazione tecnica nella moda che promuove conoscenza, libert\u00e0 creativa e consapevolezza per chi vuole fare moda sul serio\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tevipa.com\/blog\/it\/formazione-tecnica-nella-moda\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Formazione tecnica nella moda - Tele Virtual Patronage\" \/>\n<meta property=\"og:description\" content=\"Una piattaforma sulla formazione tecnica nella moda che promuove conoscenza, libert\u00e0 creativa e consapevolezza per chi vuole fare moda sul serio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tevipa.com\/blog\/it\/formazione-tecnica-nella-moda\/\" \/>\n<meta property=\"og:site_name\" content=\"Tele Virtual Patronage\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-09T17:38:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-05T16:39:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1821\" \/>\n\t<meta property=\"og:image:height\" content=\"2464\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Tele Virtual Patronage\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tele Virtual Patronage\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/formazione-tecnica-nella-moda\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/formazione-tecnica-nella-moda\\\/\"},\"author\":{\"name\":\"Tele Virtual Patronage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\"},\"headline\":\"Presentazione\",\"datePublished\":\"2025-07-09T17:38:35+00:00\",\"dateModified\":\"2025-10-05T16:39:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/formazione-tecnica-nella-moda\\\/\"},\"wordCount\":791,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/formazione-tecnica-nella-moda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo-cc1c-def-gran.jpg\",\"keywords\":[\"como cubrir un cuerpo\",\"comocubriruncuerpo\",\"creazione di moda\",\"designer\",\"stilismo\",\"tele virtual patronage\",\"televirtualpatronage\"],\"articleSection\":[\"Archivio\",\"Presentazione\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/formazione-tecnica-nella-moda\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/formazione-tecnica-nella-moda\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/formazione-tecnica-nella-moda\\\/\",\"name\":\"Formazione tecnica nella moda - Tele Virtual Patronage\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/formazione-tecnica-nella-moda\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/formazione-tecnica-nella-moda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo-cc1c-def-gran.jpg\",\"datePublished\":\"2025-07-09T17:38:35+00:00\",\"dateModified\":\"2025-10-05T16:39:43+00:00\",\"description\":\"Una piattaforma sulla formazione tecnica nella moda che promuove conoscenza, libert\u00e0 creativa e consapevolezza per chi vuole fare moda sul serio\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/formazione-tecnica-nella-moda\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/formazione-tecnica-nella-moda\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/formazione-tecnica-nella-moda\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo-cc1c-def-gran.jpg\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo-cc1c-def-gran.jpg\",\"width\":1821,\"height\":2464,\"caption\":\"Logo C\u00f3mo Cubrir un Cuerpo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/it\\\/formazione-tecnica-nella-moda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presentazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"name\":\"Tele Virtual Patronage\",\"description\":\"Tevipa\",\"publisher\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#organization\",\"name\":\"Tele Virtual Patronage\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"contentUrl\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logo512.png\",\"width\":512,\"height\":512,\"caption\":\"Tele Virtual Patronage\"},\"image\":{\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/#\\\/schema\\\/person\\\/439309947df9751f9c1a5ea04c9dfa0c\",\"name\":\"Tele Virtual Patronage\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g\",\"caption\":\"Tele Virtual Patronage\"},\"sameAs\":[\"https:\\\/\\\/tevipa.com\\\/blog\"],\"url\":\"https:\\\/\\\/tevipa.com\\\/blog\\\/author\\\/tvpadm\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Formazione tecnica nella moda - Tele Virtual Patronage","description":"Una piattaforma sulla formazione tecnica nella moda che promuove conoscenza, libert\u00e0 creativa e consapevolezza per chi vuole fare moda sul serio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tevipa.com\/blog\/it\/formazione-tecnica-nella-moda\/","og_locale":"it_IT","og_type":"article","og_title":"Formazione tecnica nella moda - Tele Virtual Patronage","og_description":"Una piattaforma sulla formazione tecnica nella moda che promuove conoscenza, libert\u00e0 creativa e consapevolezza per chi vuole fare moda sul serio","og_url":"https:\/\/tevipa.com\/blog\/it\/formazione-tecnica-nella-moda\/","og_site_name":"Tele Virtual Patronage","article_published_time":"2025-07-09T17:38:35+00:00","article_modified_time":"2025-10-05T16:39:43+00:00","og_image":[{"width":1821,"height":2464,"url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran.jpg","type":"image\/jpeg"}],"author":"Tele Virtual Patronage","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Tele Virtual Patronage","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tevipa.com\/blog\/it\/formazione-tecnica-nella-moda\/#article","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/it\/formazione-tecnica-nella-moda\/"},"author":{"name":"Tele Virtual Patronage","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c"},"headline":"Presentazione","datePublished":"2025-07-09T17:38:35+00:00","dateModified":"2025-10-05T16:39:43+00:00","mainEntityOfPage":{"@id":"https:\/\/tevipa.com\/blog\/it\/formazione-tecnica-nella-moda\/"},"wordCount":791,"commentCount":0,"publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"image":{"@id":"https:\/\/tevipa.com\/blog\/it\/formazione-tecnica-nella-moda\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran.jpg","keywords":["como cubrir un cuerpo","comocubriruncuerpo","creazione di moda","designer","stilismo","tele virtual patronage","televirtualpatronage"],"articleSection":["Archivio","Presentazione"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tevipa.com\/blog\/it\/formazione-tecnica-nella-moda\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tevipa.com\/blog\/it\/formazione-tecnica-nella-moda\/","url":"https:\/\/tevipa.com\/blog\/it\/formazione-tecnica-nella-moda\/","name":"Formazione tecnica nella moda - Tele Virtual Patronage","isPartOf":{"@id":"https:\/\/tevipa.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tevipa.com\/blog\/it\/formazione-tecnica-nella-moda\/#primaryimage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/it\/formazione-tecnica-nella-moda\/#primaryimage"},"thumbnailUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran.jpg","datePublished":"2025-07-09T17:38:35+00:00","dateModified":"2025-10-05T16:39:43+00:00","description":"Una piattaforma sulla formazione tecnica nella moda che promuove conoscenza, libert\u00e0 creativa e consapevolezza per chi vuole fare moda sul serio","breadcrumb":{"@id":"https:\/\/tevipa.com\/blog\/it\/formazione-tecnica-nella-moda\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tevipa.com\/blog\/it\/formazione-tecnica-nella-moda\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/it\/formazione-tecnica-nella-moda\/#primaryimage","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran.jpg","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo-cc1c-def-gran.jpg","width":1821,"height":2464,"caption":"Logo C\u00f3mo Cubrir un Cuerpo"},{"@type":"BreadcrumbList","@id":"https:\/\/tevipa.com\/blog\/it\/formazione-tecnica-nella-moda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tevipa.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Presentazione"}]},{"@type":"WebSite","@id":"https:\/\/tevipa.com\/blog\/#website","url":"https:\/\/tevipa.com\/blog\/","name":"Tele Virtual Patronage","description":"Tevipa","publisher":{"@id":"https:\/\/tevipa.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tevipa.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/tevipa.com\/blog\/#organization","name":"Tele Virtual Patronage","url":"https:\/\/tevipa.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","contentUrl":"https:\/\/tevipa.com\/blog\/wp-content\/uploads\/2025\/07\/logo512.png","width":512,"height":512,"caption":"Tele Virtual Patronage"},"image":{"@id":"https:\/\/tevipa.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tevipa.com\/blog\/#\/schema\/person\/439309947df9751f9c1a5ea04c9dfa0c","name":"Tele Virtual Patronage","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f607bbe11e9269431a07eb31aed42fdc6b68e5e5e6723f93ea63a815f4ec6134?s=96&d=mm&r=g","caption":"Tele Virtual Patronage"},"sameAs":["https:\/\/tevipa.com\/blog"],"url":"https:\/\/tevipa.com\/blog\/author\/tvpadm\/"}]}},"_links":{"self":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/comments?post=124"}],"version-history":[{"count":29,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/124\/revisions"}],"predecessor-version":[{"id":2121,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/posts\/124\/revisions\/2121"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media\/1382"}],"wp:attachment":[{"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/media?parent=124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/categories?post=124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tevipa.com\/blog\/wp-json\/wp\/v2\/tags?post=124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}